{"id":9575,"date":"2021-07-01T07:00:29","date_gmt":"2021-07-01T07:00:29","guid":{"rendered":"https:\/\/\/moniteur-de-tension-a-fenetre-avec-autotest-integre-pour-les-systemes-avances-daide-a-la-conduite\/"},"modified":"2021-07-01T07:00:29","modified_gmt":"2021-07-01T07:00:29","slug":"moniteur-de-tension-a-fenetre-avec-autotest-integre-pour-les-systemes-avances-daide-a-la-conduite","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/moniteur-de-tension-a-fenetre-avec-autotest-integre-pour-les-systemes-avances-daide-a-la-conduite\/","title":{"rendered":"Moniteur de tension \u00e0 fen\u00eatre avec autotest int\u00e9gr\u00e9 pour les syst\u00e8mes avanc\u00e9s d\u2019aide \u00e0 la conduite"},"content":{"rendered":"<p>Les concepteurs travaillant pour la s\u00e9curit\u00e9 automobile fonctionnelle dans les syst\u00e8mes avanc\u00e9s d\u2019aide \u00e0 la conduite (ADAS) sont d\u00e9sormais en mesure de r\u00e9duire la taille de la solution et la complexit\u00e9 avec un moniteur de tension \u00e0 fen\u00eatre unique et un autotest int\u00e9gr\u00e9 (BIST) de Maxim Integrated Products. Ce CI moniteur \u00e0 fen\u00eatre offre une protection robuste en surveillant les niveaux de sous-tension et de surtension avec une pr\u00e9cision \u00e0 1 pour cent pr\u00e8s, permettant aux concepteurs d\u2019acc\u00e9l\u00e9rer la s\u00e9curit\u00e9 fonctionnelle de l\u2019ensemble du syst\u00e8me, en fournissant des diagnostics avanc\u00e9s et des fonctions de r\u00e9initialisation. Le MAX16137 r\u00e9duit \u00e9galement la taille de la solution de moiti\u00e9 tout en simplifiant le concept.<br \/>\nLes normes de s\u00e9curit\u00e9 fonctionnelle dirigent la direction de la conception dans l\u2019espace automobile. Les moniteurs de tension jouent un r\u00f4le cl\u00e9 dans la bonne sant\u00e9 des alimentations. En outre, ces syst\u00e8mes doivent inclure des circuits tests pour garantir la fiabilit\u00e9 des op\u00e9rations. Le MAX16137 fournit aussi bien le diagnostic que le BIST au niveau de la puce pour permettre aux concepteurs de garantir plus rapidement la s\u00e9curit\u00e9 fonctionnelle sur l\u2019ensemble du syst\u00e8me pour l\u2019ADAS et d\u2019autres applications de conduite autonome.<br \/>\nLes fonctions BIST du MAX16137 v\u00e9rifient la fonctionnalit\u00e9 du moniteur sans circuits ext\u00e9rieurs, ce qui permet de simplifier le concept. Le MAX16137 r\u00e9duit donc la taille de la solution de 50 pour cent par rapport \u00e0 la solution la plus concurrentielle. Le CI de supervision peut \u00eatre con\u00e7u pour toute une s\u00e9rie de syst\u00e8mes automobiles, tels que l\u2019infodivertissement, l\u2019\u00e9lectronique de bord, l\u2019alimentation, le groupe motopropulseur des v\u00e9hicules \u00e9lectriques, et les syst\u00e8mes IoT.<\/p>\n<p><a href=\"http:\/\/www.maximintegrated.com\">www.maximintegrated.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les concepteurs travaillant pour la s\u00e9curit\u00e9 automobile fonctionnelle dans les syst\u00e8mes avanc\u00e9s d\u2019aide \u00e0 la conduite (ADAS) sont d\u00e9sormais en mesure de r\u00e9duire la taille de la solution et la complexit\u00e9 avec un moniteur de tension \u00e0 fen\u00eatre unique et un autotest int\u00e9gr\u00e9 (BIST) de Maxim Integrated Products. <\/p>\n","protected":false},"author":9,"featured_media":9576,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-9575","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Moniteur de tension \u00e0 fen\u00eatre avec autotest int\u00e9gr\u00e9 pour le...<\/title>\n<meta name=\"description\" content=\"Les concepteurs travaillant pour la s\u00e9curit\u00e9 automobile fonctionnelle dans les syst\u00e8mes avanc\u00e9s d\u2019aide \u00e0 la conduite (ADAS) sont d\u00e9sormais en mesure...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/9575\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Moniteur de tension \u00e0 fen\u00eatre avec autotest int\u00e9gr\u00e9 pour les syst\u00e8mes avanc\u00e9s d\u2019aide \u00e0 la conduite\" \/>\n<meta property=\"og:description\" content=\"Les concepteurs travaillant pour la s\u00e9curit\u00e9 automobile fonctionnelle dans les syst\u00e8mes avanc\u00e9s d\u2019aide \u00e0 la conduite (ADAS) sont d\u00e9sormais en mesure de r\u00e9duire la taille de la solution et la complexit\u00e9 avec un moniteur de tension \u00e0 fen\u00eatre unique et un autotest int\u00e9gr\u00e9 (BIST) de Maxim Integrated Products.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/9575\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-01T07:00:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9330_maxim.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/moniteur-de-tension-a-fenetre-avec-autotest-integre-pour-les-systemes-avances-daide-a-la-conduite\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/moniteur-de-tension-a-fenetre-avec-autotest-integre-pour-les-systemes-avances-daide-a-la-conduite\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Moniteur de tension \u00e0 fen\u00eatre avec autotest int\u00e9gr\u00e9 pour les syst\u00e8mes avanc\u00e9s d\u2019aide \u00e0 la conduite\",\"datePublished\":\"2021-07-01T07:00:29+00:00\",\"dateModified\":\"2021-07-01T07:00:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/moniteur-de-tension-a-fenetre-avec-autotest-integre-pour-les-systemes-avances-daide-a-la-conduite\/\"},\"wordCount\":320,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/moniteur-de-tension-a-fenetre-avec-autotest-integre-pour-les-systemes-avances-daide-a-la-conduite\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/moniteur-de-tension-a-fenetre-avec-autotest-integre-pour-les-systemes-avances-daide-a-la-conduite\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/moniteur-de-tension-a-fenetre-avec-autotest-integre-pour-les-systemes-avances-daide-a-la-conduite\/\",\"name\":\"Moniteur de tension \u00e0 fen\u00eatre avec autotest int\u00e9gr\u00e9 pour les syst\u00e8mes avanc\u00e9s d\u2019aide \u00e0 la conduite -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2021-07-01T07:00:29+00:00\",\"dateModified\":\"2021-07-01T07:00:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/moniteur-de-tension-a-fenetre-avec-autotest-integre-pour-les-systemes-avances-daide-a-la-conduite\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/moniteur-de-tension-a-fenetre-avec-autotest-integre-pour-les-systemes-avances-daide-a-la-conduite\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/moniteur-de-tension-a-fenetre-avec-autotest-integre-pour-les-systemes-avances-daide-a-la-conduite\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Moniteur de tension \u00e0 fen\u00eatre avec autotest int\u00e9gr\u00e9 pour les syst\u00e8mes avanc\u00e9s d\u2019aide \u00e0 la conduite\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Moniteur de tension \u00e0 fen\u00eatre avec autotest int\u00e9gr\u00e9 pour le...","description":"Les concepteurs travaillant pour la s\u00e9curit\u00e9 automobile fonctionnelle dans les syst\u00e8mes avanc\u00e9s d\u2019aide \u00e0 la conduite (ADAS) sont d\u00e9sormais en mesure...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/9575\/","og_locale":"fr_FR","og_type":"article","og_title":"Moniteur de tension \u00e0 fen\u00eatre avec autotest int\u00e9gr\u00e9 pour les syst\u00e8mes avanc\u00e9s d\u2019aide \u00e0 la conduite","og_description":"Les concepteurs travaillant pour la s\u00e9curit\u00e9 automobile fonctionnelle dans les syst\u00e8mes avanc\u00e9s d\u2019aide \u00e0 la conduite (ADAS) sont d\u00e9sormais en mesure de r\u00e9duire la taille de la solution et la complexit\u00e9 avec un moniteur de tension \u00e0 fen\u00eatre unique et un autotest int\u00e9gr\u00e9 (BIST) de Maxim Integrated Products.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/9575\/","og_site_name":"EENewsEurope","article_published_time":"2021-07-01T07:00:29+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9330_maxim.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/moniteur-de-tension-a-fenetre-avec-autotest-integre-pour-les-systemes-avances-daide-a-la-conduite\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/moniteur-de-tension-a-fenetre-avec-autotest-integre-pour-les-systemes-avances-daide-a-la-conduite\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Moniteur de tension \u00e0 fen\u00eatre avec autotest int\u00e9gr\u00e9 pour les syst\u00e8mes avanc\u00e9s d\u2019aide \u00e0 la conduite","datePublished":"2021-07-01T07:00:29+00:00","dateModified":"2021-07-01T07:00:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/moniteur-de-tension-a-fenetre-avec-autotest-integre-pour-les-systemes-avances-daide-a-la-conduite\/"},"wordCount":320,"commentCount":0,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ecinews.fr\/fr\/moniteur-de-tension-a-fenetre-avec-autotest-integre-pour-les-systemes-avances-daide-a-la-conduite\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/moniteur-de-tension-a-fenetre-avec-autotest-integre-pour-les-systemes-avances-daide-a-la-conduite\/","url":"https:\/\/www.ecinews.fr\/fr\/moniteur-de-tension-a-fenetre-avec-autotest-integre-pour-les-systemes-avances-daide-a-la-conduite\/","name":"Moniteur de tension \u00e0 fen\u00eatre avec autotest int\u00e9gr\u00e9 pour les syst\u00e8mes avanc\u00e9s d\u2019aide \u00e0 la conduite -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2021-07-01T07:00:29+00:00","dateModified":"2021-07-01T07:00:29+00:00","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/moniteur-de-tension-a-fenetre-avec-autotest-integre-pour-les-systemes-avances-daide-a-la-conduite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/moniteur-de-tension-a-fenetre-avec-autotest-integre-pour-les-systemes-avances-daide-a-la-conduite\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/moniteur-de-tension-a-fenetre-avec-autotest-integre-pour-les-systemes-avances-daide-a-la-conduite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Moniteur de tension \u00e0 fen\u00eatre avec autotest int\u00e9gr\u00e9 pour les syst\u00e8mes avanc\u00e9s d\u2019aide \u00e0 la conduite"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/9575"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=9575"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/9575\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/9576"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=9575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=9575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=9575"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=9575"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=9575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}