{"id":82044,"date":"2019-07-08T21:30:44","date_gmt":"2019-07-08T21:30:44","guid":{"rendered":"https:\/\/\/creation-dun-laboratoire-commun-cea-leti-radiall\/"},"modified":"2019-07-08T21:30:44","modified_gmt":"2019-07-08T21:30:44","slug":"creation-dun-laboratoire-commun-cea-leti-radiall","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/creation-dun-laboratoire-commun-cea-leti-radiall\/","title":{"rendered":"Cr\u00e9ation d&rsquo;un laboratoire commun CEA-Leti Radiall"},"content":{"rendered":"<p>Les r\u00e9seaux 5G requi\u00e8rent des communications \u00e0 grande vitesse, de point \u00e0 point, \u00e0 des fr\u00e9quences millim\u00e9triques. L&rsquo;augmentation fulgurante des syst\u00e8mes 5G \u00e0 infrastructure ultra-dense n\u00e9cessite d&rsquo;h\u00e9berger un trafic important de donn\u00e9es mobiles \u00e0 grande vitesse pendant que les donn\u00e9es de l&rsquo;Internet des objets g\u00e9n\u00e8rent, en retour, une demande en sous-syst\u00e8mes RF \u00e9conomiques, robustes et fiables, comme les antennes compactes et reconfigurables, qui peuvent \u00eatre int\u00e9gr\u00e9es aux b\u00e2timents et mobilier urbains \u00e0 moindre co\u00fbt.&nbsp;Avec des fr\u00e9quences millim\u00e9triques situ\u00e9es entre 30 et 300 GHz, les pertes importantes en trajet doivent \u00eatre compens\u00e9es par les antennes \u00e0 gain \u00e9lev\u00e9 mises en \u0153uvre dans les conceptions \u00e0 r\u00e9seau d&rsquo;\u00e9missions. S&rsquo;appuyant sur son expertise dans la conception d&rsquo;antennes, le CEA-Leti a d\u00e9j\u00e0 collabor\u00e9 avec Radiall sur le d\u00e9veloppement des r\u00e9seaux d&rsquo;\u00e9missions. Cette collaboration a permis la cr\u00e9ation d&rsquo;une bande V (57-66 GHz) \u00e0 gain \u00e9lev\u00e9 (32 dBi) fournissant jusqu&rsquo;\u00e0 20 Gb\/s, que Radiall a ajout\u00e9e \u00e0 sa ligne de produits.<\/p>\n<p>La r\u00e9duction de l&rsquo;\u00e9paisseur d&rsquo;antenne, le maintien de la stabilit\u00e9 du gain sur toute la largeur de bande et le contr\u00f4le des niveaux du lobe lat\u00e9ral sont les atouts de l&rsquo;architecture multi-sources \u00e0 r\u00e9seaux d&rsquo;\u00e9missions qui propose une solution prometteuse pour relever ce d\u00e9fi.&nbsp;<\/p>\n<p>\u00ab&nbsp;Radiall et le CEA-Leti ont lanc\u00e9 un laboratoire commun sur cinq ans afin de cr\u00e9er un groupe de travail d\u00e9di\u00e9 qui aura pour but d&rsquo;acc\u00e9l\u00e9rer le d\u00e9veloppement des antennes \u00e0 capacit\u00e9 et couverture \u00e9lev\u00e9es, afin de r\u00e9pondre \u00e0 un app\u00e9tit croissant pour des t\u00e9l\u00e9communications fiables \u00e0 grande vitesse, comme aujourd&rsquo;hui la g\u00e9n\u00e9ration 5G et les technologies futures, a d\u00e9clar\u00e9 Emmanuel Sabonnadi\u00e8re, Directeur du Leti. L&rsquo;objectif est \u00e9galement d&rsquo;\u00e9largir le cadre de la collaboration au d\u00e9veloppement d&rsquo;autres technologies, comme les filtres RF ou les composants photoniques pour raccorder les r\u00e9seaux 5G entre eux.&nbsp;\u00bb<\/p>\n<p>\u00ab&nbsp;La cr\u00e9ativit\u00e9 combin\u00e9e des ing\u00e9nieurs de recherche du CEA-Leti et des ing\u00e9nieurs de production et de R&amp;D de Radiall, pour d\u00e9velopper des produits de pointe \u00e0 des prix comp\u00e9titifs, a \u00e9t\u00e9 clairement d\u00e9montr\u00e9e avec le d\u00e9veloppement de l&rsquo;antenne \u00e0 bande V, a pr\u00e9cis\u00e9 Dominique Buttin, chef d&rsquo;exploitation chez Radiall. Ce laboratoire commun permet \u00e0 Radiall d&rsquo;acc\u00e9der \u00e0 la grande expertise du CEA-Leti en micro\u00e9lectronique et technologie RF et aussi de se positionner, dans la r\u00e9alisation toujours plus rapide de produits innovants destin\u00e9s \u00e0 la 5G, ainsi que sur des march\u00e9s verticaux, comme l&rsquo;a\u00e9ronautique ou les transports.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le CEA-Leti et Radiall, fabricant mondial de solutions d&rsquo;interconnexions \u00e0 la pointe de la technologie, ont annonc\u00e9 la cr\u00e9ation d&rsquo;un laboratoire commun dans le but de concevoir des antennes innovantes et des composants radiofr\u00e9quence (RF) pour r\u00e9pondre aux exigences d&rsquo;infrastructure des r\u00e9seaux 5G, ainsi que des composants photoniques pour les environnements difficiles. Annonc\u00e9 au cours des Leti Innovation Days 2019, ce laboratoire commun d\u00e9veloppera des solutions d&rsquo;antennes profil bas \u00e0 ondes millim\u00e9triques pour les applications backhaul\/fronthaul.<\/p>\n","protected":false},"author":9,"featured_media":82045,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-82044","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Cr\u00e9ation d&#039;un laboratoire commun CEA-Leti Radiall ...<\/title>\n<meta name=\"description\" content=\"Le CEA-Leti et Radiall, fabricant mondial de solutions d&#039;interconnexions \u00e0 la pointe de la technologie, ont annonc\u00e9 la cr\u00e9ation d&#039;un laboratoire commun...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/82044\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cr\u00e9ation d&#039;un laboratoire commun CEA-Leti Radiall\" \/>\n<meta property=\"og:description\" content=\"Le CEA-Leti et Radiall, fabricant mondial de solutions d&#039;interconnexions \u00e0 la pointe de la technologie, ont annonc\u00e9 la cr\u00e9ation d&#039;un laboratoire commun dans le but de concevoir des antennes innovantes et des composants radiofr\u00e9quence (RF) pour r\u00e9pondre aux exigences d&#039;infrastructure des r\u00e9seaux 5G, ainsi que des composants photoniques pour les environnements difficiles. Annonc\u00e9 au cours des Leti Innovation Days 2019, ce laboratoire commun d\u00e9veloppera des solutions d&#039;antennes profil bas \u00e0 ondes millim\u00e9triques pour les applications backhaul\/fronthaul.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/82044\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-08T21:30:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8056_cea_actu.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"335\" \/>\n\t<meta property=\"og:image:height\" content=\"212\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/creation-dun-laboratoire-commun-cea-leti-radiall\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/creation-dun-laboratoire-commun-cea-leti-radiall\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Cr\u00e9ation d&rsquo;un laboratoire commun CEA-Leti Radiall\",\"datePublished\":\"2019-07-08T21:30:44+00:00\",\"dateModified\":\"2019-07-08T21:30:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/creation-dun-laboratoire-commun-cea-leti-radiall\/\"},\"wordCount\":467,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/creation-dun-laboratoire-commun-cea-leti-radiall\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/creation-dun-laboratoire-commun-cea-leti-radiall\/\",\"name\":\"Cr\u00e9ation d'un laboratoire commun CEA-Leti Radiall -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2019-07-08T21:30:44+00:00\",\"dateModified\":\"2019-07-08T21:30:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/creation-dun-laboratoire-commun-cea-leti-radiall\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/creation-dun-laboratoire-commun-cea-leti-radiall\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/creation-dun-laboratoire-commun-cea-leti-radiall\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cr\u00e9ation d&rsquo;un laboratoire commun CEA-Leti Radiall\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Cr\u00e9ation d'un laboratoire commun CEA-Leti Radiall ...","description":"Le CEA-Leti et Radiall, fabricant mondial de solutions d'interconnexions \u00e0 la pointe de la technologie, ont annonc\u00e9 la cr\u00e9ation d'un laboratoire commun...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/82044\/","og_locale":"fr_FR","og_type":"article","og_title":"Cr\u00e9ation d'un laboratoire commun CEA-Leti Radiall","og_description":"Le CEA-Leti et Radiall, fabricant mondial de solutions d'interconnexions \u00e0 la pointe de la technologie, ont annonc\u00e9 la cr\u00e9ation d'un laboratoire commun dans le but de concevoir des antennes innovantes et des composants radiofr\u00e9quence (RF) pour r\u00e9pondre aux exigences d'infrastructure des r\u00e9seaux 5G, ainsi que des composants photoniques pour les environnements difficiles. Annonc\u00e9 au cours des Leti Innovation Days 2019, ce laboratoire commun d\u00e9veloppera des solutions d'antennes profil bas \u00e0 ondes millim\u00e9triques pour les applications backhaul\/fronthaul.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/82044\/","og_site_name":"EENewsEurope","article_published_time":"2019-07-08T21:30:44+00:00","og_image":[{"width":335,"height":212,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8056_cea_actu.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/creation-dun-laboratoire-commun-cea-leti-radiall\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/creation-dun-laboratoire-commun-cea-leti-radiall\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Cr\u00e9ation d&rsquo;un laboratoire commun CEA-Leti Radiall","datePublished":"2019-07-08T21:30:44+00:00","dateModified":"2019-07-08T21:30:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/creation-dun-laboratoire-commun-cea-leti-radiall\/"},"wordCount":467,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/creation-dun-laboratoire-commun-cea-leti-radiall\/","url":"https:\/\/www.ecinews.fr\/fr\/creation-dun-laboratoire-commun-cea-leti-radiall\/","name":"Cr\u00e9ation d'un laboratoire commun CEA-Leti Radiall -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2019-07-08T21:30:44+00:00","dateModified":"2019-07-08T21:30:44+00:00","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/creation-dun-laboratoire-commun-cea-leti-radiall\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/creation-dun-laboratoire-commun-cea-leti-radiall\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/creation-dun-laboratoire-commun-cea-leti-radiall\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Cr\u00e9ation d&rsquo;un laboratoire commun CEA-Leti Radiall"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/82044"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=82044"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/82044\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/82045"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=82044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=82044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=82044"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=82044"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=82044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}