{"id":78876,"date":"2019-08-11T22:31:44","date_gmt":"2019-08-11T22:31:44","guid":{"rendered":"https:\/\/\/suivi-de-tension-pour-capteurs-et-modules-externes-dans-les-applications-automobiles%e2%80%a8\/"},"modified":"2019-08-11T22:31:44","modified_gmt":"2019-08-11T22:31:44","slug":"suivi-de-tension-pour-capteurs-et-modules-externes-dans-les-applications-automobiles%e2%80%a8","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/suivi-de-tension-pour-capteurs-et-modules-externes-dans-les-applications-automobiles%e2%80%a8\/","title":{"rendered":"Suivi de tension pour capteurs et modules externes dans les applications automobiles\u2028"},"content":{"rendered":"<p>Les nouveaux v\u00e9hicules automobiles sont \u00e9quip\u00e9s d\u2019un nombre croissant de syst\u00e8mes \u00e9lectroniques destin\u00e9s \u00e0 diverses applications&nbsp;; tous ces circuits doivent \u00eatre aliment\u00e9s par une source de tension primaire vers une source secondaire inf\u00e9rieure. La gestion de l&rsquo;alimentation est g\u00e9n\u00e9ralement effectu\u00e9e par une alimentation \u00e9lectrique int\u00e9gr\u00e9e, mais des capteurs et des modules externes doivent \u00eatre c\u00e2bl\u00e9s dans tout le v\u00e9hicule et sont expos\u00e9s \u00e0 des conditions difficiles. Il faut veiller \u00e0 ce que l\u2019alimentation principale reste op\u00e9rationnelle en cas de d\u00e9faillance des appareils externes et \u00e0 ce que le processeur ECU ou les autres circuits essentiels continuent de s\u2019acquitter de leur t\u00e2che. Par cons\u00e9quent, il est courant d&rsquo;utiliser des suivis de tension dans lesquels une tension de r\u00e9f\u00e9rence est r\u00e9pliqu\u00e9e avec une pr\u00e9cision de suivi \u00e9lev\u00e9e, et le niveau de s\u00e9curit\u00e9 du syst\u00e8me \u00e9lectronique est g\u00e9n\u00e9ralement accru.<\/p>\n<p>Le R1540 poss\u00e8de une large plage de tensions d&rsquo;entr\u00e9e allant de 3,5 \u00e0 42&nbsp;V, ce qui permet d&rsquo;utiliser le suivi de tension dans de nombreux cas.&nbsp;<\/p>\n<p>La tension de sortie du r\u00e9gulateur peut varier en raison des interf\u00e9rences \u00e9lectromagn\u00e9tiques (EMI). Une technologie avanc\u00e9e est int\u00e9gr\u00e9e pour \u00e9viter une telle variation de tension. Les tests rigoureux men\u00e9s dans nos laboratoires confirment que le R1540 pr\u00e9sente une immunit\u00e9 sup\u00e9rieure au bruit EMI sur une large bande de fr\u00e9quences (150&nbsp;kHz \u00e0 1&nbsp;GHz). De plus, il pr\u00e9sente un taux de r\u00e9jection d&rsquo;ondulation \u00e9lev\u00e9 de 80&nbsp;dB et une r\u00e9ponse rapide aux r\u00e9gimes transitoires en entr\u00e9e et en charge.<\/p>\n<p>Certains capteurs n\u00e9cessitent une tension d\u2019alimentation tr\u00e8s pr\u00e9cise pour effectuer des mesures sensibles. Par cons\u00e9quent, le suiveur de tension fournit une pr\u00e9cision de suivi de \u00b1 15&nbsp;mV. Le fil de broche CE\/ADJ combin\u00e9 sert \u00e0 deux choses&nbsp;; il fournit la tension d\u2019entr\u00e9e comme r\u00e9f\u00e9rence pour la sortie et il peut \u00eatre abaiss\u00e9 pour contr\u00f4ler l\u2019appareil en mode veille.<\/p>\n<p>Le R1540 est dot\u00e9 d&rsquo;un ensemble de fonctions de s\u00e9curit\u00e9 qui prot\u00e8gent le suiveur de tension et les autres composants de l&rsquo;application contre les dommages et les d\u00e9faillances potentiels.<\/p>\n<ul>\n<li>Protection contre les surintensit\u00e9s, limitant le courant de sortie en cas de surcharge.<\/li>\n<li>Protection courte. Un circuit de limitation de courant court repli\u00e9 int\u00e9gr\u00e9 d\u00e9tecte un court-circuit et diminue le courant de sortie \u00e0 un niveau s\u00e9curis\u00e9 de 40&nbsp;mA. Une fois le court-circuit \u00e9limin\u00e9, le r\u00e9gulateur reprend automatiquement son fonctionnement normal.<\/li>\n<li>La protection thermique incorpor\u00e9e d\u00e9sactive la tension de sortie si une temp\u00e9rature de plus de 165 \u00b0C est d\u00e9tect\u00e9e, et reprend son fonctionnement normal d\u00e8s que la temp\u00e9rature de 135 \u00b0C est atteinte.<\/li>\n<li>Disposition prot\u00e9g\u00e9e des broches. Une disposition sp\u00e9ciale a \u00e9t\u00e9 mise en place pour le R1540S dans HSOP-8E afin d\u2019\u00e9viter un dysfonctionnement lorsque des broches adjacentes sont mises en court-circuit. Les quatre bornes sont isol\u00e9es avec des broches adjacentes non connect\u00e9es.<\/li>\n<\/ul>\n<p>Le R1540 est disponible dans deux packages&nbsp;: un package SOT-23-5 standard et un package sup\u00e9rieur HSOP-8E. Des \u00e9chantillons et des cartes d&rsquo;\u00e9valuation sont disponibles aupr\u00e8s de notre r\u00e9seau mondial de distributeurs locaux, et des distributeurs en ligne Mouser et Chip1Stop.<\/p>\n<p><a href=\"http:\/\/www.e-devices.ricoh.co.jp\/en\/products\/power\/vr_ldo\/r1540\/\">www.e-devices.ricoh.co.jp\/en\/products\/power\/vr_ldo\/r1540\/<\/a><\/p>\n<p><a href=\"http:\/\/www.e-devices.ricoh.co.jp\/en\/\">www.e-devices.ricoh.co.jp\/en\/<\/a><\/p>\n<h3 class=\"title\"><a href=\"https:\/\/www.electronique-eci.com\/news\/ricoh-propose-deux-convertisseurs-buck-cccc-en-mode-vfm-tres-basse-tension-de-sortie\">Ricoh propose deux convertisseurs Buck CC\/CC en mode VFM \u00e0 tr\u00e8s basse tension de sortie<\/a><\/h3>\n<h3 class=\"title\"><a href=\"https:\/\/www.electronique-eci.com\/news\/ricoh-annonce-un-partenariat-strategique-avec-iee\">Ricoh annonce un partenariat strat\u00e9gique avec IEE<\/a><\/h3>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ricoh Electronic Devices Co., propose un circuit int\u00e9gr\u00e9 de suivi de tension largement utilis\u00e9 dans les applications automobiles. Il est principalement con\u00e7u comme une alimentation pour les capteurs et les modules externes et renforce la s\u00e9curit\u00e9 afin de maintenir l&rsquo;alimentation principale et les circuits critiques associ\u00e9s op\u00e9rationnels en permanence.<\/p>\n","protected":false},"author":9,"featured_media":78877,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-78876","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Suivi de tension pour capteurs et modules externes dans les app...<\/title>\n<meta name=\"description\" content=\"Ricoh Electronic Devices Co., propose un circuit int\u00e9gr\u00e9 de suivi de tension largement utilis\u00e9 dans les applications automobiles. Il est principalement...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/78876\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Suivi de tension pour capteurs et modules externes dans les applications automobiles\u2028\" \/>\n<meta property=\"og:description\" content=\"Ricoh Electronic Devices Co., propose un circuit int\u00e9gr\u00e9 de suivi de tension largement utilis\u00e9 dans les applications automobiles. Il est principalement con\u00e7u comme une alimentation pour les capteurs et les modules externes et renforce la s\u00e9curit\u00e9 afin de maintenir l&#039;alimentation principale et les circuits critiques associ\u00e9s op\u00e9rationnels en permanence.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/78876\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-11T22:31:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8104_ricoh.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/suivi-de-tension-pour-capteurs-et-modules-externes-dans-les-applications-automobiles%e2%80%a8\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/suivi-de-tension-pour-capteurs-et-modules-externes-dans-les-applications-automobiles%e2%80%a8\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Suivi de tension pour capteurs et modules externes dans les applications automobiles\\u2028\",\"datePublished\":\"2019-08-11T22:31:44+00:00\",\"dateModified\":\"2019-08-11T22:31:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/suivi-de-tension-pour-capteurs-et-modules-externes-dans-les-applications-automobiles%e2%80%a8\/\"},\"wordCount\":641,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/suivi-de-tension-pour-capteurs-et-modules-externes-dans-les-applications-automobiles%e2%80%a8\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/suivi-de-tension-pour-capteurs-et-modules-externes-dans-les-applications-automobiles%e2%80%a8\/\",\"name\":\"Suivi de tension pour capteurs et modules externes dans les applications automobiles\\u2028 -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2019-08-11T22:31:44+00:00\",\"dateModified\":\"2019-08-11T22:31:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/suivi-de-tension-pour-capteurs-et-modules-externes-dans-les-applications-automobiles%e2%80%a8\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/suivi-de-tension-pour-capteurs-et-modules-externes-dans-les-applications-automobiles%e2%80%a8\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/suivi-de-tension-pour-capteurs-et-modules-externes-dans-les-applications-automobiles%e2%80%a8\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Suivi de tension pour capteurs et modules externes dans les applications automobiles\\u2028\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Suivi de tension pour capteurs et modules externes dans les app...","description":"Ricoh Electronic Devices Co., propose un circuit int\u00e9gr\u00e9 de suivi de tension largement utilis\u00e9 dans les applications automobiles. Il est principalement...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/78876\/","og_locale":"fr_FR","og_type":"article","og_title":"Suivi de tension pour capteurs et modules externes dans les applications automobiles\u2028","og_description":"Ricoh Electronic Devices Co., propose un circuit int\u00e9gr\u00e9 de suivi de tension largement utilis\u00e9 dans les applications automobiles. Il est principalement con\u00e7u comme une alimentation pour les capteurs et les modules externes et renforce la s\u00e9curit\u00e9 afin de maintenir l'alimentation principale et les circuits critiques associ\u00e9s op\u00e9rationnels en permanence.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/78876\/","og_site_name":"EENewsEurope","article_published_time":"2019-08-11T22:31:44+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8104_ricoh.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/suivi-de-tension-pour-capteurs-et-modules-externes-dans-les-applications-automobiles%e2%80%a8\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/suivi-de-tension-pour-capteurs-et-modules-externes-dans-les-applications-automobiles%e2%80%a8\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Suivi de tension pour capteurs et modules externes dans les applications automobiles\u2028","datePublished":"2019-08-11T22:31:44+00:00","dateModified":"2019-08-11T22:31:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/suivi-de-tension-pour-capteurs-et-modules-externes-dans-les-applications-automobiles%e2%80%a8\/"},"wordCount":641,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/suivi-de-tension-pour-capteurs-et-modules-externes-dans-les-applications-automobiles%e2%80%a8\/","url":"https:\/\/www.ecinews.fr\/fr\/suivi-de-tension-pour-capteurs-et-modules-externes-dans-les-applications-automobiles%e2%80%a8\/","name":"Suivi de tension pour capteurs et modules externes dans les applications automobiles\u2028 -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2019-08-11T22:31:44+00:00","dateModified":"2019-08-11T22:31:44+00:00","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/suivi-de-tension-pour-capteurs-et-modules-externes-dans-les-applications-automobiles%e2%80%a8\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/suivi-de-tension-pour-capteurs-et-modules-externes-dans-les-applications-automobiles%e2%80%a8\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/suivi-de-tension-pour-capteurs-et-modules-externes-dans-les-applications-automobiles%e2%80%a8\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Suivi de tension pour capteurs et modules externes dans les applications automobiles\u2028"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/78876"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=78876"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/78876\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/78877"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=78876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=78876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=78876"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=78876"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=78876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}