{"id":78088,"date":"2019-08-20T22:31:44","date_gmt":"2019-08-20T22:31:44","guid":{"rendered":"https:\/\/\/cassettes-19-inserables-de-dimensions-variables\/"},"modified":"2019-08-20T22:31:44","modified_gmt":"2019-08-20T22:31:44","slug":"cassettes-19-inserables-de-dimensions-variables","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/cassettes-19-inserables-de-dimensions-variables\/","title":{"rendered":"Cassettes 19&Prime; ins\u00e9rables de dimensions variables"},"content":{"rendered":"<p>Les rainures en T pour les tiges filet\u00e9es, les \u00e9crous coulissants ou les t\u00eates de vis facilitent la fixation des composants \u00e9lectroniques. Les canaux de vis externes pour la fixation des parois avant et arri\u00e8re emp\u00eachent les courts-circuits dus \u00e0 la chute \u00e9ventuelle de copeaux de vis.<\/p>\n<p>Les formats standard de cassette type G sont de 3 U de hauteur, une profondeur d\u2019insertion pour les cartes Euro de 160 mm ou 220 mm et cinq largeurs diff\u00e9rentes (10, 12, 14, 16 et 20 TE). Les diff\u00e9rentes d\u00e9coupes de panneau arri\u00e8re du portefeuille standard ainsi que les ouvertures sp\u00e9cifiques au client permettent diff\u00e9rentes fonctions de la cassette. Fischer Elektronik propose en option une plaque de recouvrement &nbsp;perfor\u00e9e pour une meilleure ventilation de l&rsquo;\u00e9lectronique. Le retrait et l&rsquo;insertion faciles de la cassette dans le rack 19&Prime; sont possibles gr\u00e2ce aux poign\u00e9es optionnelles en plastique ou en aluminium.<\/p>\n<p>La cassette de type G est disponible avec trois traitements de surface diff\u00e9rents: anodis\u00e9 naturel (ME), anodis\u00e9 noir (SA) ou passiv\u00e9 transparent \u00e9lectriquement conducteur (TP). \u00c9tant donn\u00e9 que Fischer Elektronik offre \u00e0 ses clients la plus grande flexibilit\u00e9 possible pour les produits, autres traitements de surface, impressions ou traitements m\u00e9caniques suppl\u00e9mentaires sont, bien entendu, possibles selon les sp\u00e9cifications du client.D&rsquo;autres modifications ou versions sp\u00e9ciales sont r\u00e9alis\u00e9es selon les sp\u00e9cifications du client.&nbsp;<\/p>\n<p><a href=\"http:\/\/www.fischerelektronik.de\/\">www.fischerelektronik.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Toutes les cartes de circuit imprim\u00e9 et tous les composants \u00e9lectroniques ne sont pas compatibles avec les tailles standard de cassettes 19&Prime;. Fischer Elektronik propose une cassette 19&Prime; \u00e0 dimensions variables. Avec la nouvelle cassette de type G, il est possible de r\u00e9aliser toutes les tailles standard mais \u00e9galement toutes les tailles sp\u00e9cifiques. Ceci est rendu possible par quatre profil\u00e9s d&rsquo;angle avec rainures int\u00e9gr\u00e9es pour recevoir les panneaux lat\u00e9raux ainsi que les panneaux sup\u00e9rieur et inf\u00e9rieur. <\/p>\n","protected":false},"author":9,"featured_media":78089,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-78088","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Cassettes 19&quot; ins\u00e9rables de dimensions variables ...<\/title>\n<meta name=\"description\" content=\"Toutes les cartes de circuit imprim\u00e9 et tous les composants \u00e9lectroniques ne sont pas compatibles avec les tailles standard de cassettes 19&quot;. Fischer...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/78088\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cassettes 19&quot; ins\u00e9rables de dimensions variables\" \/>\n<meta property=\"og:description\" content=\"Toutes les cartes de circuit imprim\u00e9 et tous les composants \u00e9lectroniques ne sont pas compatibles avec les tailles standard de cassettes 19&quot;. Fischer Elektronik propose une cassette 19&quot; \u00e0 dimensions variables. Avec la nouvelle cassette de type G, il est possible de r\u00e9aliser toutes les tailles standard mais \u00e9galement toutes les tailles sp\u00e9cifiques. Ceci est rendu possible par quatre profil\u00e9s d&#039;angle avec rainures int\u00e9gr\u00e9es pour recevoir les panneaux lat\u00e9raux ainsi que les panneaux sup\u00e9rieur et inf\u00e9rieur.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/78088\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-20T22:31:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8115_fischer_elektronik.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1535\" \/>\n\t<meta property=\"og:image:height\" content=\"1063\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/cassettes-19-inserables-de-dimensions-variables\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/cassettes-19-inserables-de-dimensions-variables\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Cassettes 19&Prime; ins\u00e9rables de dimensions variables\",\"datePublished\":\"2019-08-20T22:31:44+00:00\",\"dateModified\":\"2019-08-20T22:31:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/cassettes-19-inserables-de-dimensions-variables\/\"},\"wordCount\":242,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/cassettes-19-inserables-de-dimensions-variables\/\",\"url\":\"https:\/\/www.eenewseurope.com\/fr\/cassettes-19-inserables-de-dimensions-variables\/\",\"name\":\"Cassettes 19\\\" ins\u00e9rables de dimensions variables -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2019-08-20T22:31:44+00:00\",\"dateModified\":\"2019-08-20T22:31:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/cassettes-19-inserables-de-dimensions-variables\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eenewseurope.com\/fr\/cassettes-19-inserables-de-dimensions-variables\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/cassettes-19-inserables-de-dimensions-variables\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cassettes 19&Prime; ins\u00e9rables de dimensions variables\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Cassettes 19\" ins\u00e9rables de dimensions variables ...","description":"Toutes les cartes de circuit imprim\u00e9 et tous les composants \u00e9lectroniques ne sont pas compatibles avec les tailles standard de cassettes 19\". Fischer...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/78088\/","og_locale":"fr_FR","og_type":"article","og_title":"Cassettes 19\" ins\u00e9rables de dimensions variables","og_description":"Toutes les cartes de circuit imprim\u00e9 et tous les composants \u00e9lectroniques ne sont pas compatibles avec les tailles standard de cassettes 19\". Fischer Elektronik propose une cassette 19\" \u00e0 dimensions variables. Avec la nouvelle cassette de type G, il est possible de r\u00e9aliser toutes les tailles standard mais \u00e9galement toutes les tailles sp\u00e9cifiques. Ceci est rendu possible par quatre profil\u00e9s d'angle avec rainures int\u00e9gr\u00e9es pour recevoir les panneaux lat\u00e9raux ainsi que les panneaux sup\u00e9rieur et inf\u00e9rieur.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/78088\/","og_site_name":"EENewsEurope","article_published_time":"2019-08-20T22:31:44+00:00","og_image":[{"width":1535,"height":1063,"url":"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8115_fischer_elektronik.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eenewseurope.com\/fr\/cassettes-19-inserables-de-dimensions-variables\/#article","isPartOf":{"@id":"https:\/\/www.eenewseurope.com\/fr\/cassettes-19-inserables-de-dimensions-variables\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Cassettes 19&Prime; ins\u00e9rables de dimensions variables","datePublished":"2019-08-20T22:31:44+00:00","dateModified":"2019-08-20T22:31:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eenewseurope.com\/fr\/cassettes-19-inserables-de-dimensions-variables\/"},"wordCount":242,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.eenewseurope.com\/fr\/cassettes-19-inserables-de-dimensions-variables\/","url":"https:\/\/www.eenewseurope.com\/fr\/cassettes-19-inserables-de-dimensions-variables\/","name":"Cassettes 19\" ins\u00e9rables de dimensions variables -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2019-08-20T22:31:44+00:00","dateModified":"2019-08-20T22:31:44+00:00","breadcrumb":{"@id":"https:\/\/www.eenewseurope.com\/fr\/cassettes-19-inserables-de-dimensions-variables\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eenewseurope.com\/fr\/cassettes-19-inserables-de-dimensions-variables\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eenewseurope.com\/fr\/cassettes-19-inserables-de-dimensions-variables\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Cassettes 19&Prime; ins\u00e9rables de dimensions variables"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/78088"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=78088"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/78088\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/78089"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=78088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=78088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=78088"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=78088"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=78088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}