{"id":7603,"date":"2021-07-22T17:03:40","date_gmt":"2021-07-22T17:03:40","guid":{"rendered":"https:\/\/\/reference-de-systeme-de-charge-sans-fil-pour-developpement-de-chargeurs-qi\/"},"modified":"2021-07-22T17:03:40","modified_gmt":"2021-07-22T17:03:40","slug":"reference-de-systeme-de-charge-sans-fil-pour-developpement-de-chargeurs-qi","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/reference-de-systeme-de-charge-sans-fil-pour-developpement-de-chargeurs-qi\/","title":{"rendered":"R\u00e9f\u00e9rence de syst\u00e8me de charge sans fil pour d\u00e9veloppement de chargeurs Qi"},"content":{"rendered":"<p>Pour les concepteurs de syst\u00e8mes de charge sans fil qui doivent d\u00e9velopper des chargeurs certifi\u00e9s Qi&nbsp;1.3 dans des d\u00e9lais serr\u00e9s, le mod\u00e8le de r\u00e9f\u00e9rence Qi&nbsp;1.3 \u00e0 trois bobines de Microchip est un formidable moyen de gagner du temps. Ce mod\u00e8le de r\u00e9f\u00e9rence int\u00e8gre tout le logiciel du sous-syst\u00e8me de stockage s\u00e9curis\u00e9 et le microcontr\u00f4leur (MCU) du syst\u00e8me de charge sans fil, et constitue une solution tr\u00e8s souple, permettant des topologies personnalis\u00e9es et la d\u00e9tection des corps \u00e9trangers (FOD) pr\u00e9sents dans le champ.<\/p>\n<p>En tant que membre permanent du Wireless Power Consortium (WPC), qui \u00e9tablit les normes mondiales pour la charge sans fil d\u2019appareils mobiles, Microchip a apport\u00e9 son expertise lors du d\u00e9veloppement de la sp\u00e9cification Qi&nbsp;1.3 r\u00e9cemment publi\u00e9e. La norme Qi&nbsp;1.3 est une \u00e9volution importante de la norme Qi&nbsp;1.2.4, qui oblige d\u00e9sormais l&rsquo;authentification mat\u00e9rielle entre appareils chargeurs et r\u00e9cepteurs pour les transferts de puissance sup\u00e9rieurs \u00e0 5&nbsp;W. En adh\u00e9rant \u00e0 la nouvelle norme d&rsquo;authentification, les concepteurs peuvent s&rsquo;assurer que les t\u00e9l\u00e9phones recevant 15&nbsp;W re\u00e7oivent cette puissance d&rsquo;un chargeur authentifi\u00e9 et certifi\u00e9 Qi, afin de garantir la s\u00e9curit\u00e9.<\/p>\n<p>\u00ab&nbsp;La charge sans fil permet aux utilisateurs de charger facilement et confortablement leurs appareils et, par cons\u00e9quent, la demande pour ces syst\u00e8mes dans les secteurs automobile et grand public est en hausse,&nbsp;\u00bb d\u00e9clare Joe Thomsen, Vice-Pr\u00e9sident de la division MCU16.<\/p>\n<p>\u00ab&nbsp;Le mod\u00e8le de r\u00e9f\u00e9rence Qi&nbsp;1.3, les outils et l\u2019assistance de Microchip aident les concepteurs \u00e0 r\u00e9pondre aux exigences de d\u00e9veloppement, qui \u00e9voluent rapidement et permettent de certifier facilement les nouveaux designs de chargeurs Qi&nbsp;1.3, ce qui facilite la certification des produits finaux et en acc\u00e9l\u00e8re la commercialisation.&nbsp;\u00bb<\/p>\n<p>Tous les \u00e9l\u00e9ments n\u00e9cessaires sont inclus dans le mod\u00e8le de r\u00e9f\u00e9rence de syst\u00e8me de charge sans fil Microchip&nbsp;: Contr\u00f4leur Qi, logiciel d&rsquo;application Qi, contr\u00f4leur d&rsquo;authentification (qui est un sous-syst\u00e8me de stockage s\u00e9curis\u00e9 agr\u00e9\u00e9 WPC), et biblioth\u00e8ques de logiciels de chiffrement tournant sur le contr\u00f4leur Qi. Le mod\u00e8le de r\u00e9f\u00e9rence comprend tous les sch\u00e9mas, la nomenclature, le logiciel et les directives de conception. Microchip s&rsquo;est associ\u00e9 \u00e0 Avnet pour mettre \u00e0 la disposition de plusieurs clients du monde entier des cartes d&rsquo;\u00e9valuation pour le mod\u00e8le de r\u00e9f\u00e9rence Qi.<\/p>\n<p>Pour soutenir sa solution de charge sans fil Qi&nbsp;1.3, Microchip fournit la famille de dispositifs dsPIC33C pour ex\u00e9cuter le logiciel d&rsquo;application Qi et le sous-syst\u00e8me de stockage s\u00e9curis\u00e9 ECC608\/TA100 fourni par Microchip en tant qu&rsquo;autorit\u00e9 de certification de fabrication sous licence WPC. S\u2019agissant d\u2019une solution syst\u00e8me compl\u00e8te, ce mod\u00e8le de r\u00e9f\u00e9rence int\u00e8gre aussi des drivers de MOSFET MIC4605 et MCP14700, des r\u00e9gulateurs MCP16331 et MCP1725, un dispositif de d\u00e9tection de courant MCP6C02, un \u00e9metteur-r\u00e9cepteur CAN ATA6563 et un capteur de temp\u00e9rature MCP9700.<\/p>\n<p>&nbsp;<a href=\"http:\/\/www.microchip.com\/wireless-power\">www.microchip.com\/wireless-power<\/a><\/p>\n<p style=\"margin-right:-25.7pt\"><span style=\"font-family:arial,sans-serif;font-size:10.0pt\">&nbsp;<\/span><\/p>\n<p><strong><span style=\"font-family:arial,sans-serif;font-size:1.0pt\">&nbsp;<\/span><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Wireless Power Consortium (WPC) a r\u00e9cemment publi\u00e9 la sp\u00e9cification Qi 1.3, qui requiert une authentification pour plus de s\u00e9curit\u00e9 lors de la transmission d&rsquo;une puissance pouvant atteindre 15 W entre chargeur et r\u00e9cepteur. Pour r\u00e9pondre aux exigences de la sp\u00e9cification, Microchip Technology Inc. a annonc\u00e9 un nouveau mod\u00e8le de r\u00e9f\u00e9rence de syst\u00e8me de charge sans fil Qi 1.3 qui fournit aux concepteurs de syst\u00e8mes de charge sans fil pour applications automobiles et grand public, les outils et l\u2019assistance n\u00e9cessaires \u00e0 l&rsquo;int\u00e9gration et \u00e0 la certification sans faille de produits de nouvelle g\u00e9n\u00e9ration.<\/p>\n","protected":false},"author":9,"featured_media":7604,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-7603","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","domains-electronique-eci"],"acf":[],"yoast_head":"<title>R\u00e9f\u00e9rence de syst\u00e8me de charge sans fil pour d\u00e9veloppement ...<\/title>\n<meta name=\"description\" content=\"Le Wireless Power Consortium (WPC) a r\u00e9cemment publi\u00e9 la sp\u00e9cification Qi 1.3, qui requiert une authentification pour plus de s\u00e9curit\u00e9 lors de la...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/7603\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9f\u00e9rence de syst\u00e8me de charge sans fil pour d\u00e9veloppement de chargeurs Qi\" \/>\n<meta property=\"og:description\" content=\"Le Wireless Power Consortium (WPC) a r\u00e9cemment publi\u00e9 la sp\u00e9cification Qi 1.3, qui requiert une authentification pour plus de s\u00e9curit\u00e9 lors de la transmission d&#039;une puissance pouvant atteindre 15 W entre chargeur et r\u00e9cepteur. Pour r\u00e9pondre aux exigences de la sp\u00e9cification, Microchip Technology Inc. a annonc\u00e9 un nouveau mod\u00e8le de r\u00e9f\u00e9rence de syst\u00e8me de charge sans fil Qi 1.3 qui fournit aux concepteurs de syst\u00e8mes de charge sans fil pour applications automobiles et grand public, les outils et l\u2019assistance n\u00e9cessaires \u00e0 l&#039;int\u00e9gration et \u00e0 la certification sans faille de produits de nouvelle g\u00e9n\u00e9ration.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/7603\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-22T17:03:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9676_microchip-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1422\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/reference-de-systeme-de-charge-sans-fil-pour-developpement-de-chargeurs-qi\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/reference-de-systeme-de-charge-sans-fil-pour-developpement-de-chargeurs-qi\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"R\u00e9f\u00e9rence de syst\u00e8me de charge sans fil pour d\u00e9veloppement de chargeurs Qi\",\"datePublished\":\"2021-07-22T17:03:40+00:00\",\"dateModified\":\"2021-07-22T17:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/reference-de-systeme-de-charge-sans-fil-pour-developpement-de-chargeurs-qi\/\"},\"wordCount\":558,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/reference-de-systeme-de-charge-sans-fil-pour-developpement-de-chargeurs-qi\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/reference-de-systeme-de-charge-sans-fil-pour-developpement-de-chargeurs-qi\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/reference-de-systeme-de-charge-sans-fil-pour-developpement-de-chargeurs-qi\/\",\"name\":\"R\u00e9f\u00e9rence de syst\u00e8me de charge sans fil pour d\u00e9veloppement de chargeurs Qi -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2021-07-22T17:03:40+00:00\",\"dateModified\":\"2021-07-22T17:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/reference-de-systeme-de-charge-sans-fil-pour-developpement-de-chargeurs-qi\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/reference-de-systeme-de-charge-sans-fil-pour-developpement-de-chargeurs-qi\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/reference-de-systeme-de-charge-sans-fil-pour-developpement-de-chargeurs-qi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9f\u00e9rence de syst\u00e8me de charge sans fil pour d\u00e9veloppement de chargeurs Qi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"R\u00e9f\u00e9rence de syst\u00e8me de charge sans fil pour d\u00e9veloppement ...","description":"Le Wireless Power Consortium (WPC) a r\u00e9cemment publi\u00e9 la sp\u00e9cification Qi 1.3, qui requiert une authentification pour plus de s\u00e9curit\u00e9 lors de la...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/7603\/","og_locale":"fr_FR","og_type":"article","og_title":"R\u00e9f\u00e9rence de syst\u00e8me de charge sans fil pour d\u00e9veloppement de chargeurs Qi","og_description":"Le Wireless Power Consortium (WPC) a r\u00e9cemment publi\u00e9 la sp\u00e9cification Qi 1.3, qui requiert une authentification pour plus de s\u00e9curit\u00e9 lors de la transmission d'une puissance pouvant atteindre 15 W entre chargeur et r\u00e9cepteur. Pour r\u00e9pondre aux exigences de la sp\u00e9cification, Microchip Technology Inc. a annonc\u00e9 un nouveau mod\u00e8le de r\u00e9f\u00e9rence de syst\u00e8me de charge sans fil Qi 1.3 qui fournit aux concepteurs de syst\u00e8mes de charge sans fil pour applications automobiles et grand public, les outils et l\u2019assistance n\u00e9cessaires \u00e0 l'int\u00e9gration et \u00e0 la certification sans faille de produits de nouvelle g\u00e9n\u00e9ration.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/7603\/","og_site_name":"EENewsEurope","article_published_time":"2021-07-22T17:03:40+00:00","og_image":[{"width":2560,"height":1422,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9676_microchip-scaled.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/reference-de-systeme-de-charge-sans-fil-pour-developpement-de-chargeurs-qi\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/reference-de-systeme-de-charge-sans-fil-pour-developpement-de-chargeurs-qi\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"R\u00e9f\u00e9rence de syst\u00e8me de charge sans fil pour d\u00e9veloppement de chargeurs Qi","datePublished":"2021-07-22T17:03:40+00:00","dateModified":"2021-07-22T17:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/reference-de-systeme-de-charge-sans-fil-pour-developpement-de-chargeurs-qi\/"},"wordCount":558,"commentCount":0,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ecinews.fr\/fr\/reference-de-systeme-de-charge-sans-fil-pour-developpement-de-chargeurs-qi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/reference-de-systeme-de-charge-sans-fil-pour-developpement-de-chargeurs-qi\/","url":"https:\/\/www.ecinews.fr\/fr\/reference-de-systeme-de-charge-sans-fil-pour-developpement-de-chargeurs-qi\/","name":"R\u00e9f\u00e9rence de syst\u00e8me de charge sans fil pour d\u00e9veloppement de chargeurs Qi -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2021-07-22T17:03:40+00:00","dateModified":"2021-07-22T17:03:40+00:00","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/reference-de-systeme-de-charge-sans-fil-pour-developpement-de-chargeurs-qi\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/reference-de-systeme-de-charge-sans-fil-pour-developpement-de-chargeurs-qi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/reference-de-systeme-de-charge-sans-fil-pour-developpement-de-chargeurs-qi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"R\u00e9f\u00e9rence de syst\u00e8me de charge sans fil pour d\u00e9veloppement de chargeurs Qi"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/7603"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=7603"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/7603\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/7604"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=7603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=7603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=7603"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=7603"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=7603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}