{"id":75942,"date":"2019-09-17T06:31:44","date_gmt":"2019-09-17T06:31:44","guid":{"rendered":"https:\/\/\/ansys-et-edge-case-research-ameliorent-la-surete-des-vehicules-autonomes\/"},"modified":"2019-09-17T06:31:44","modified_gmt":"2019-09-17T06:31:44","slug":"ansys-et-edge-case-research-ameliorent-la-surete-des-vehicules-autonomes","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/ansys-et-edge-case-research-ameliorent-la-surete-des-vehicules-autonomes\/","title":{"rendered":"Ansys et Edge Case Research am\u00e9liorent la s\u00fbret\u00e9 des v\u00e9hicules autonomes"},"content":{"rendered":"<p>Les v\u00e9hicules autonomes d\u2019aujourd\u2019hui embarquent des algorithmes de perception bas\u00e9s sur de l\u2019IA con\u00e7us pour prendre des d\u00e9cisions critiques en mati\u00e8re de s\u00e9curit\u00e9 routi\u00e8re. Un v\u00e9hicule autonome, aussi sophistiqu\u00e9 soit-il, peut ne pas d\u00e9tecter certains sc\u00e9narios de conduite dangereuse appel\u00e9s \u00ab&nbsp;cas-limites&nbsp;\u00bb, car son entra\u00eenement algorithmique ne l\u2019a pas pr\u00e9par\u00e9 aux nombreuses situations de conduite inhabituelles auxquelles il peut \u00eatre confront\u00e9 dans le monde r\u00e9el. Pour en garantir la s\u00fbret\u00e9 maximale et faire des v\u00e9hicules enti\u00e8rement autonomes une r\u00e9alit\u00e9, les d\u00e9veloppeurs ont besoin d\u2019outils permettant d\u2019identifier ces cas-limites automatiquement et d\u2019une mani\u00e8re beaucoup plus \u00e9volutive qu\u2019en \u00e9tiquetant manuellement les donn\u00e9es.<\/p>\n<p>Dans le cadre de cette collaboration, Edge&nbsp;Case&nbsp;Research, leader mondial des logiciels d\u2019\u00e9valuation de la s\u00fbret\u00e9 des VA, int\u00e9grera Hologram \u00e0 la solution ouverte de simulation&nbsp;d\u2019ANSYS pour les v\u00e9hicules autonomes. Cette fonctionnalit\u00e9 compl\u00e8te et in\u00e9gal\u00e9e analysera les algorithmes de conduite autonome afin de d\u00e9tecter les cas-limites et de contribuer au d\u00e9veloppement et \u00e0 la validation des algorithmes de perception des v\u00e9hicules autonomes les plus avanc\u00e9s. Hologram peut \u00e9galement s\u2019appliquer \u00e0 d\u2019autres industries telles que l\u2019a\u00e9rospatiale et la d\u00e9fense, le secteur minier, l\u2019agriculture, la robotique industrielle ainsi que tout autre domaine s\u2019appuyant sur des logiciels de vision et de perception bas\u00e9s sur l\u2019IA.<\/p>\n<p>\u00ab&nbsp;Nous sommes tr\u00e8s heureux de rejoindre l\u2019\u00e9cosyst\u00e8me ANSYS&nbsp;pour les v\u00e9hicules autonomes. Nous avons d\u00e9cid\u00e9 de nous associer \u00e0 ANSYS en raison de leur grande expertise en mati\u00e8re de s\u00fbret\u00e9, un aspect essentiel pour comprendre comment des produits comme Hologram, VRXPERIENCE et SCADE peuvent \u00eatre combin\u00e9s afin d\u2019apporter leur soutien aux dossiers de s\u00fbret\u00e9 des produits autonomes&nbsp;\u00bb,&nbsp;explique Mike&nbsp;Wagner, PDG d\u2019Edge&nbsp;Case&nbsp;Research. \u00ab&nbsp;ANSYS et Edge&nbsp;Case&nbsp;Research vont apporter une capacit\u00e9 de protection in\u00e9dite \u00e0 la prochaine g\u00e9n\u00e9ration de syst\u00e8mes de conduite autonomes&nbsp;\u00bb.<\/p>\n<p>\u00ab&nbsp;Edge&nbsp;Case&nbsp;Research fournit une puissante plateforme de test et d\u2019analyse des donn\u00e9es qui tire le meilleur parti des p\u00e9taoctets de donn\u00e9es de conduite routi\u00e8re enregistr\u00e9es par les v\u00e9hicules autonomes, dans le but de trouver les cas extr\u00eames. Ceci acc\u00e9l\u00e8re consid\u00e9rablement le d\u00e9veloppement d\u2019un logiciel de perception plus s\u00fbr bas\u00e9 sur l\u2019IA.&nbsp;Ces fonctionnalit\u00e9s fondamentales ont \u00e9t\u00e9 incorpor\u00e9es \u00e0 notre collaboration r\u00e9cemment annonc\u00e9e avec BMW&nbsp;\u00bb,&nbsp;d\u00e9clare \u00c9ric&nbsp;Bantegnie, vice-pr\u00e9sident et directeur g\u00e9n\u00e9ral d\u2019ANSYS.&nbsp;\u00ab&nbsp;Ensemble, nous allons inaugurer une nouvelle \u00e8re pour l\u2019IA et fa\u00e7onner l\u2019avenir de la conduite autonome s\u00fbre&nbsp;\u00bb.<\/p>\n<p><a href=\"http:\/\/www.ansys.com\/%20\/t%20_blank\">www.ansys.com<\/a><\/p>\n<h3 class=\"title\"><a href=\"https:\/\/www.electronique-eci.com\/news\/ansys-accompagne-linnovation-des-startups-linternational-grace-son-programme-dedie\">ANSYS accompagne l\u2019innovation des startups \u00e0 l\u2019international gr\u00e2ce \u00e0 son programme d\u00e9di\u00e9<\/a><\/h3>\n<h3 class=\"title\"><a href=\"https:\/\/www.electronique-eci.com\/news\/ansys-ndeg1-de-la-simulation-pour-vehicules-autonomes\">ANSYS N\u00b01 de la simulation pour v\u00e9hicules autonomes<\/a><\/h3>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ansys con\u00e7oit avec Edge Case Research la prochaine g\u00e9n\u00e9ration de v\u00e9hicules autonomes dot\u00e9s de fonctionnalit\u00e9s de pointe in\u00e9gal\u00e9es en termes de d\u00e9tection des dangers. Gr\u00e2ce \u00e0 un nouvel accord OEM, Edge Case Research int\u00e8gre Hologram, son puissant moteur de stress-test et d\u2019analyse des risques appliqu\u00e9s \u00e0 la perception, bas\u00e9 sur l\u2019intelligence artificielle (IA) embarqu\u00e9e dans les syst\u00e8mes autonomes, \u00e0 la solution de simulation compl\u00e8te d\u2019ANSYS pour les v\u00e9hicules autonomes, aux fins de maximiser leur s\u00fbret\u00e9.<\/p>\n","protected":false},"author":9,"featured_media":75943,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-75942","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Ansys et Edge Case Research am\u00e9liorent la s\u00fbret\u00e9 des v\u00e9hicu...<\/title>\n<meta name=\"description\" content=\"Ansys con\u00e7oit avec Edge Case Research la prochaine g\u00e9n\u00e9ration de v\u00e9hicules autonomes dot\u00e9s de fonctionnalit\u00e9s de pointe in\u00e9gal\u00e9es en termes de...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/75942\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ansys et Edge Case Research am\u00e9liorent la s\u00fbret\u00e9 des v\u00e9hicules autonomes\" \/>\n<meta property=\"og:description\" content=\"Ansys con\u00e7oit avec Edge Case Research la prochaine g\u00e9n\u00e9ration de v\u00e9hicules autonomes dot\u00e9s de fonctionnalit\u00e9s de pointe in\u00e9gal\u00e9es en termes de d\u00e9tection des dangers. Gr\u00e2ce \u00e0 un nouvel accord OEM, Edge Case Research int\u00e8gre Hologram, son puissant moteur de stress-test et d\u2019analyse des risques appliqu\u00e9s \u00e0 la perception, bas\u00e9 sur l\u2019intelligence artificielle (IA) embarqu\u00e9e dans les syst\u00e8mes autonomes, \u00e0 la solution de simulation compl\u00e8te d\u2019ANSYS pour les v\u00e9hicules autonomes, aux fins de maximiser leur s\u00fbret\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/75942\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-17T06:31:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8157_ansys_actu.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"643\" \/>\n\t<meta property=\"og:image:height\" content=\"542\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/ansys-et-edge-case-research-ameliorent-la-surete-des-vehicules-autonomes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/ansys-et-edge-case-research-ameliorent-la-surete-des-vehicules-autonomes\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Ansys et Edge Case Research am\u00e9liorent la s\u00fbret\u00e9 des v\u00e9hicules autonomes\",\"datePublished\":\"2019-09-17T06:31:44+00:00\",\"dateModified\":\"2019-09-17T06:31:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/ansys-et-edge-case-research-ameliorent-la-surete-des-vehicules-autonomes\/\"},\"wordCount\":532,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/ansys-et-edge-case-research-ameliorent-la-surete-des-vehicules-autonomes\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/ansys-et-edge-case-research-ameliorent-la-surete-des-vehicules-autonomes\/\",\"name\":\"Ansys et Edge Case Research am\u00e9liorent la s\u00fbret\u00e9 des v\u00e9hicules autonomes -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2019-09-17T06:31:44+00:00\",\"dateModified\":\"2019-09-17T06:31:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/ansys-et-edge-case-research-ameliorent-la-surete-des-vehicules-autonomes\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/ansys-et-edge-case-research-ameliorent-la-surete-des-vehicules-autonomes\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/ansys-et-edge-case-research-ameliorent-la-surete-des-vehicules-autonomes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ansys et Edge Case Research am\u00e9liorent la s\u00fbret\u00e9 des v\u00e9hicules autonomes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Ansys et Edge Case Research am\u00e9liorent la s\u00fbret\u00e9 des v\u00e9hicu...","description":"Ansys con\u00e7oit avec Edge Case Research la prochaine g\u00e9n\u00e9ration de v\u00e9hicules autonomes dot\u00e9s de fonctionnalit\u00e9s de pointe in\u00e9gal\u00e9es en termes de...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/75942\/","og_locale":"fr_FR","og_type":"article","og_title":"Ansys et Edge Case Research am\u00e9liorent la s\u00fbret\u00e9 des v\u00e9hicules autonomes","og_description":"Ansys con\u00e7oit avec Edge Case Research la prochaine g\u00e9n\u00e9ration de v\u00e9hicules autonomes dot\u00e9s de fonctionnalit\u00e9s de pointe in\u00e9gal\u00e9es en termes de d\u00e9tection des dangers. Gr\u00e2ce \u00e0 un nouvel accord OEM, Edge Case Research int\u00e8gre Hologram, son puissant moteur de stress-test et d\u2019analyse des risques appliqu\u00e9s \u00e0 la perception, bas\u00e9 sur l\u2019intelligence artificielle (IA) embarqu\u00e9e dans les syst\u00e8mes autonomes, \u00e0 la solution de simulation compl\u00e8te d\u2019ANSYS pour les v\u00e9hicules autonomes, aux fins de maximiser leur s\u00fbret\u00e9.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/75942\/","og_site_name":"EENewsEurope","article_published_time":"2019-09-17T06:31:44+00:00","og_image":[{"width":643,"height":542,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8157_ansys_actu.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/ansys-et-edge-case-research-ameliorent-la-surete-des-vehicules-autonomes\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/ansys-et-edge-case-research-ameliorent-la-surete-des-vehicules-autonomes\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Ansys et Edge Case Research am\u00e9liorent la s\u00fbret\u00e9 des v\u00e9hicules autonomes","datePublished":"2019-09-17T06:31:44+00:00","dateModified":"2019-09-17T06:31:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/ansys-et-edge-case-research-ameliorent-la-surete-des-vehicules-autonomes\/"},"wordCount":532,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/ansys-et-edge-case-research-ameliorent-la-surete-des-vehicules-autonomes\/","url":"https:\/\/www.ecinews.fr\/fr\/ansys-et-edge-case-research-ameliorent-la-surete-des-vehicules-autonomes\/","name":"Ansys et Edge Case Research am\u00e9liorent la s\u00fbret\u00e9 des v\u00e9hicules autonomes -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2019-09-17T06:31:44+00:00","dateModified":"2019-09-17T06:31:44+00:00","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/ansys-et-edge-case-research-ameliorent-la-surete-des-vehicules-autonomes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/ansys-et-edge-case-research-ameliorent-la-surete-des-vehicules-autonomes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/ansys-et-edge-case-research-ameliorent-la-surete-des-vehicules-autonomes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Ansys et Edge Case Research am\u00e9liorent la s\u00fbret\u00e9 des v\u00e9hicules autonomes"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/75942"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=75942"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/75942\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/75943"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=75942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=75942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=75942"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=75942"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=75942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}