{"id":74672,"date":"2019-10-03T09:31:44","date_gmt":"2019-10-03T09:31:44","guid":{"rendered":"https:\/\/\/collaboration-strategique-rosenberger-osi-assemble-les-connecteurs-de-3m\/"},"modified":"2019-10-03T09:31:44","modified_gmt":"2019-10-03T09:31:44","slug":"collaboration-strategique-rosenberger-osi-assemble-les-connecteurs-de-3m","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/collaboration-strategique-rosenberger-osi-assemble-les-connecteurs-de-3m\/","title":{"rendered":"Collaboration strat\u00e9gique : Rosenberger OSI assemble les connecteurs de 3M"},"content":{"rendered":"<p>Gr\u00e2ce au syst\u00e8me optique \u00e0 faisceau \u00e9largi, le connecteur d\u00e9velopp\u00e9 par 3M est moins sensible \u00e0 la salet\u00e9, de sorte que plusieurs raccordements sont possibles avec une action&nbsp;de&nbsp;nettoyage minimale.&nbsp;L&rsquo;Expanded&nbsp;Beam Optical Interconnect&nbsp;offre des valeurs d&rsquo;att\u00e9nuation exceptionnelles pour les&nbsp;applications&nbsp;monomode&nbsp;&#8211; perte d&rsquo;insertion&nbsp;(att\u00e9nuation)&nbsp;: &lt;&nbsp;0,70 dB et&nbsp;r\u00e9flectance&nbsp;: &gt;&nbsp;55 dB. Optimis\u00e9 pour la prochaine g\u00e9n\u00e9ration de&nbsp;data&nbsp;centers, le connecteur \u00e0 faisceau \u00e9tendu est \u00e9quip\u00e9 d&rsquo;une virole&nbsp;prenant&nbsp;en charge&nbsp;12 fibres&nbsp;monomode&nbsp;ou multimode.<\/p>\n<p><strong><u>\u00c0&nbsp;propos de Rosenberger OSI :<\/u><\/strong><\/p>\n<p>Depuis 1991, Rosenberger Optical Solutions &amp; Infrastructure (Rosenberger OSI) est un expert dans la fabrication de syst\u00e8mes de c\u00e2blage innovants en fibre optique et dans la fourniture de services associ\u00e9s pour les march\u00e9s des&nbsp;data centers, des t\u00e9l\u00e9communications et de l&rsquo;industrie. Ces solutions se retrouvent dans un grand nombre de secteurs o\u00f9 de gros volumes de donn\u00e9es doivent \u00eatre \u00e9chang\u00e9s rapidement et de mani\u00e8re s\u00e9curis\u00e9e. En plus du d\u00e9veloppement et de la production d&rsquo;une&nbsp;large gamme de syst\u00e8mes de c\u00e2blage fibre optique et cuivre, la soci\u00e9t\u00e9 fournit \u00e9galement une vari\u00e9t\u00e9 de services li\u00e9s \u00e0 la planification, \u00e0 l&rsquo;installation et \u00e0 la maintenance d&rsquo;infrastructures de&nbsp;c\u00e2blage. Rosenberger OSI&nbsp;emploie un peu plus de 600 personnes en Europe et fait partie du groupe mondial&nbsp;Rosenberger&nbsp;depuis 1998. Rosenberger est une soci\u00e9t\u00e9 allemande de 10 000 personnes pr\u00e9sente dans 32 pays. Ses solutions hautes fr\u00e9quences, haute&nbsp;tension,&nbsp;et liaisons&nbsp;fibre optique et cuivre sont reconnues pour&nbsp;leur fiabilit\u00e9 et leurs performances.&nbsp;<\/p>\n<p><a href=\"http:\/\/www.rosenberger.com\/osi%20\/t%20_blank\">www.rosenberger.com\/osi<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rosenberger Optical Solutions &amp; Infrastructure, fabricant d&rsquo;infrastructures de c\u00e2blage en fibre optique innovantes en Europe, annonce une nouvelle coop\u00e9ration de grande envergure avec 3M. Rosenberger OSI est la premi\u00e8re entreprise \u00e0 assembler le connecteur Expanded Beam Optical Interconnect de 3M avec des c\u00e2bles fibre optique. Ce connecteur atteint d&rsquo;excellentes valeurs d&rsquo;att\u00e9nuation en particulier dans les applications monomodes.<\/p>\n","protected":false},"author":9,"featured_media":74673,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-74672","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Collaboration strat\u00e9gique : Rosenberger OSI assemble les conne...<\/title>\n<meta name=\"description\" content=\"Rosenberger Optical Solutions &amp; Infrastructure, fabricant d&#039;infrastructures de c\u00e2blage en fibre optique innovantes en Europe, annonce une nouvelle...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/74672\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Collaboration strat\u00e9gique : Rosenberger OSI assemble les connecteurs de 3M\" \/>\n<meta property=\"og:description\" content=\"Rosenberger Optical Solutions &amp; Infrastructure, fabricant d&#039;infrastructures de c\u00e2blage en fibre optique innovantes en Europe, annonce une nouvelle coop\u00e9ration de grande envergure avec 3M. Rosenberger OSI est la premi\u00e8re entreprise \u00e0 assembler le connecteur Expanded Beam Optical Interconnect de 3M avec des c\u00e2bles fibre optique. Ce connecteur atteint d&#039;excellentes valeurs d&#039;att\u00e9nuation en particulier dans les applications monomodes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/74672\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-03T09:31:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8180_rosenberger.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2362\" \/>\n\t<meta property=\"og:image:height\" content=\"1076\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/collaboration-strategique-rosenberger-osi-assemble-les-connecteurs-de-3m\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/collaboration-strategique-rosenberger-osi-assemble-les-connecteurs-de-3m\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Collaboration strat\u00e9gique : Rosenberger OSI assemble les connecteurs de 3M\",\"datePublished\":\"2019-10-03T09:31:44+00:00\",\"dateModified\":\"2019-10-03T09:31:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/collaboration-strategique-rosenberger-osi-assemble-les-connecteurs-de-3m\/\"},\"wordCount\":312,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/collaboration-strategique-rosenberger-osi-assemble-les-connecteurs-de-3m\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/collaboration-strategique-rosenberger-osi-assemble-les-connecteurs-de-3m\/\",\"name\":\"Collaboration strat\u00e9gique : Rosenberger OSI assemble les connecteurs de 3M -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2019-10-03T09:31:44+00:00\",\"dateModified\":\"2019-10-03T09:31:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/collaboration-strategique-rosenberger-osi-assemble-les-connecteurs-de-3m\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/collaboration-strategique-rosenberger-osi-assemble-les-connecteurs-de-3m\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/collaboration-strategique-rosenberger-osi-assemble-les-connecteurs-de-3m\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Collaboration strat\u00e9gique : Rosenberger OSI assemble les connecteurs de 3M\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Collaboration strat\u00e9gique : Rosenberger OSI assemble les conne...","description":"Rosenberger Optical Solutions &amp; Infrastructure, fabricant d'infrastructures de c\u00e2blage en fibre optique innovantes en Europe, annonce une nouvelle...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/74672\/","og_locale":"fr_FR","og_type":"article","og_title":"Collaboration strat\u00e9gique : Rosenberger OSI assemble les connecteurs de 3M","og_description":"Rosenberger Optical Solutions &amp; Infrastructure, fabricant d'infrastructures de c\u00e2blage en fibre optique innovantes en Europe, annonce une nouvelle coop\u00e9ration de grande envergure avec 3M. Rosenberger OSI est la premi\u00e8re entreprise \u00e0 assembler le connecteur Expanded Beam Optical Interconnect de 3M avec des c\u00e2bles fibre optique. Ce connecteur atteint d'excellentes valeurs d'att\u00e9nuation en particulier dans les applications monomodes.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/74672\/","og_site_name":"EENewsEurope","article_published_time":"2019-10-03T09:31:44+00:00","og_image":[{"width":2362,"height":1076,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8180_rosenberger.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/collaboration-strategique-rosenberger-osi-assemble-les-connecteurs-de-3m\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/collaboration-strategique-rosenberger-osi-assemble-les-connecteurs-de-3m\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Collaboration strat\u00e9gique : Rosenberger OSI assemble les connecteurs de 3M","datePublished":"2019-10-03T09:31:44+00:00","dateModified":"2019-10-03T09:31:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/collaboration-strategique-rosenberger-osi-assemble-les-connecteurs-de-3m\/"},"wordCount":312,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/collaboration-strategique-rosenberger-osi-assemble-les-connecteurs-de-3m\/","url":"https:\/\/www.ecinews.fr\/fr\/collaboration-strategique-rosenberger-osi-assemble-les-connecteurs-de-3m\/","name":"Collaboration strat\u00e9gique : Rosenberger OSI assemble les connecteurs de 3M -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2019-10-03T09:31:44+00:00","dateModified":"2019-10-03T09:31:44+00:00","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/collaboration-strategique-rosenberger-osi-assemble-les-connecteurs-de-3m\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/collaboration-strategique-rosenberger-osi-assemble-les-connecteurs-de-3m\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/collaboration-strategique-rosenberger-osi-assemble-les-connecteurs-de-3m\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Collaboration strat\u00e9gique : Rosenberger OSI assemble les connecteurs de 3M"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/74672"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=74672"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/74672\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/74673"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=74672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=74672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=74672"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=74672"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=74672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}