{"id":74080,"date":"2019-10-08T22:31:44","date_gmt":"2019-10-08T22:31:44","guid":{"rendered":"https:\/\/\/clairitec-signe-un-accord-de-distribution-mondiale-avec-mouser-electronics\/"},"modified":"2019-10-08T22:31:44","modified_gmt":"2019-10-08T22:31:44","slug":"clairitec-signe-un-accord-de-distribution-mondiale-avec-mouser-electronics","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/clairitec-signe-un-accord-de-distribution-mondiale-avec-mouser-electronics\/","title":{"rendered":"Clairitec signe un accord de distribution mondiale avec Mouser Electronics"},"content":{"rendered":"<p>Mouser, leader de l\u2019industrie dans l\u2019Introduction de Nouveaux Produits (NPI)&nbsp;&nbsp;proposant&nbsp;le plus large choix de semi-conducteurs et de composants \u00e9lectroniques, livre \u00e0 l\u2019\u00e9chelle mondiale \u00e0 plus de 600000 clients r\u00e9partis dans plus de 220 pays et territoires depuis son si\u00e8ge mondial et son centre de distribution \u00e0 la pointe de la technologie.<\/p>\n<p>Clairitec&nbsp;a la particularit\u00e9 de proposer des produits IHM&nbsp;se connectant directement \u00e0 l\u2019application m\u00e9tier des industriels via une simple liaison s\u00e9rie permettant d\u2019envoyer des commandes d\u2019affichage ou de gestion d\u2019E\/S. L\u2019IHM est cr\u00e9\u00e9e de fa\u00e7on enti\u00e8rement personnalis\u00e9e gr\u00e2ce au logiciel PC&nbsp;GraphConverter&nbsp;en faisant glisser les \u00e9l\u00e9ments sur les diff\u00e9rents \u00e9crans constituant l\u2019interface graphique (qui peut \u00eatre tactile).&nbsp;Clairitec&nbsp;adapte \u00e9galement ses produits en fonction des besoins de ses clients, en ajoutant par exemple du verre tremp\u00e9 anti-vandalisme pour les applications ext\u00e9rieures ou en ajoutant des modules de communication sans fil (GSM, Bluetooth, Wi-Fi\u2026) pour le march\u00e9 grandissant de l\u2019Internet des objets (IoT).<\/p>\n<p>A travers cet accord,&nbsp;Mouser&nbsp;distribue d\u00e9sormais les produits&nbsp;Clairitec&nbsp;qui offrent une simplicit\u00e9 d\u2019utilisation, une robustesse industrielle (pr\u00e9qualification CEM, microprocesseur automobile) et une longue p\u00e9rennit\u00e9 commerciale (10 ans) dans un monde ou l\u2019obsolescence s\u2019accentue. Et aussi parce que&nbsp;Clairitec&nbsp;est l\u2019unique soci\u00e9t\u00e9 proposant des produits sur \u00e9tag\u00e8re directement compatible avec le protocole de communication CAN, de plus en plus utilis\u00e9 dans l\u2019industrie pour sa fiabilit\u00e9.<\/p>\n<p>&nbsp;\u00ab&nbsp;La puissance de distribution de&nbsp;Mouser&nbsp;et sa forte notori\u00e9t\u00e9 aupr\u00e8s des ing\u00e9nieurs en \u00e9lectronique permettra \u00e0&nbsp;Clairitec&nbsp;d\u2019acc\u00e9der \u00e0 de nouveaux march\u00e9s et d\u2019accentuer sa croissance sur la sc\u00e8ne internationale. Ce partenariat va aider les entreprises du monde entier \u00e0 acc\u00e9l\u00e9rer le \u00ab&nbsp;time to&nbsp;market&nbsp;\u00bb de leurs nouveaux produits en se d\u00e9chargeant, en toute confiance, de la partie graphique de leur projet&nbsp;\u00bb&nbsp;d\u00e9clare Thomas&nbsp;Debuisser, fondateur et PDG de&nbsp;Clairitec.<\/p>\n<p><a href=\"http:\/\/www.clairitec.com\">www.clairitec.com<\/a><\/p>\n<h3 class=\"title\"><a href=\"https:\/\/www.electronique-eci.com\/Learning-center\/une-ihm-d%C3%A9velopp%C3%A9e-en-4-semaines-et-qualifi%C3%A9e-cem-pour-un-usage-industriel\">Une IHM d\u00e9velopp\u00e9e en 4 semaines et qualifi\u00e9e CEM pour un usage industriel<\/a><\/h3>\n<h3 class=\"title\"><a href=\"https:\/\/www.electronique-eci.com\/news\/carte-ihm-avec-une-r%C3%A9solution-inf%C3%A9rieure-ou-%C3%A9gale-au-vga\">Carte IHM avec une r\u00e9solution inf\u00e9rieure ou \u00e9gale au VGA<\/a><\/h3>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sp\u00e9cialis\u00e9e depuis plus de 20 ans dans la cr\u00e9ation d\u2019une solution compl\u00e8te permettant de d\u00e9velopper rapidement et facilement des IHM (Interfaces Homme-Machine) tout en pilotant des \u00e9quipements gr\u00e2ce \u00e0 la gestion int\u00e9gr\u00e9e de plusieurs entr\u00e9es\/sorties, Clairitec annonce la signature d\u2019un accord de distribution mondiale avec Mouser Electronics.<\/p>\n","protected":false},"author":9,"featured_media":74081,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-74080","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Clairitec signe un accord de distribution mondiale avec Mouser ...<\/title>\n<meta name=\"description\" content=\"Sp\u00e9cialis\u00e9e depuis plus de 20 ans dans la cr\u00e9ation d\u2019une solution compl\u00e8te permettant de d\u00e9velopper rapidement et facilement des IHM (Interfaces...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/74080\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Clairitec signe un accord de distribution mondiale avec Mouser Electronics\" \/>\n<meta property=\"og:description\" content=\"Sp\u00e9cialis\u00e9e depuis plus de 20 ans dans la cr\u00e9ation d\u2019une solution compl\u00e8te permettant de d\u00e9velopper rapidement et facilement des IHM (Interfaces Homme-Machine) tout en pilotant des \u00e9quipements gr\u00e2ce \u00e0 la gestion int\u00e9gr\u00e9e de plusieurs entr\u00e9es\/sorties, Clairitec annonce la signature d\u2019un accord de distribution mondiale avec Mouser Electronics.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/74080\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-08T22:31:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8202_clairitec_actu.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"260\" \/>\n\t<meta property=\"og:image:height\" content=\"165\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/clairitec-signe-un-accord-de-distribution-mondiale-avec-mouser-electronics\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/clairitec-signe-un-accord-de-distribution-mondiale-avec-mouser-electronics\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Clairitec signe un accord de distribution mondiale avec Mouser Electronics\",\"datePublished\":\"2019-10-08T22:31:44+00:00\",\"dateModified\":\"2019-10-08T22:31:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/clairitec-signe-un-accord-de-distribution-mondiale-avec-mouser-electronics\/\"},\"wordCount\":398,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/clairitec-signe-un-accord-de-distribution-mondiale-avec-mouser-electronics\/\",\"url\":\"https:\/\/www.eenewseurope.com\/fr\/clairitec-signe-un-accord-de-distribution-mondiale-avec-mouser-electronics\/\",\"name\":\"Clairitec signe un accord de distribution mondiale avec Mouser Electronics -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2019-10-08T22:31:44+00:00\",\"dateModified\":\"2019-10-08T22:31:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/clairitec-signe-un-accord-de-distribution-mondiale-avec-mouser-electronics\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eenewseurope.com\/fr\/clairitec-signe-un-accord-de-distribution-mondiale-avec-mouser-electronics\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/clairitec-signe-un-accord-de-distribution-mondiale-avec-mouser-electronics\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Clairitec signe un accord de distribution mondiale avec Mouser Electronics\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Clairitec signe un accord de distribution mondiale avec Mouser ...","description":"Sp\u00e9cialis\u00e9e depuis plus de 20 ans dans la cr\u00e9ation d\u2019une solution compl\u00e8te permettant de d\u00e9velopper rapidement et facilement des IHM (Interfaces...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/74080\/","og_locale":"fr_FR","og_type":"article","og_title":"Clairitec signe un accord de distribution mondiale avec Mouser Electronics","og_description":"Sp\u00e9cialis\u00e9e depuis plus de 20 ans dans la cr\u00e9ation d\u2019une solution compl\u00e8te permettant de d\u00e9velopper rapidement et facilement des IHM (Interfaces Homme-Machine) tout en pilotant des \u00e9quipements gr\u00e2ce \u00e0 la gestion int\u00e9gr\u00e9e de plusieurs entr\u00e9es\/sorties, Clairitec annonce la signature d\u2019un accord de distribution mondiale avec Mouser Electronics.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/74080\/","og_site_name":"EENewsEurope","article_published_time":"2019-10-08T22:31:44+00:00","og_image":[{"width":260,"height":165,"url":"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8202_clairitec_actu.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eenewseurope.com\/fr\/clairitec-signe-un-accord-de-distribution-mondiale-avec-mouser-electronics\/#article","isPartOf":{"@id":"https:\/\/www.eenewseurope.com\/fr\/clairitec-signe-un-accord-de-distribution-mondiale-avec-mouser-electronics\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Clairitec signe un accord de distribution mondiale avec Mouser Electronics","datePublished":"2019-10-08T22:31:44+00:00","dateModified":"2019-10-08T22:31:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eenewseurope.com\/fr\/clairitec-signe-un-accord-de-distribution-mondiale-avec-mouser-electronics\/"},"wordCount":398,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.eenewseurope.com\/fr\/clairitec-signe-un-accord-de-distribution-mondiale-avec-mouser-electronics\/","url":"https:\/\/www.eenewseurope.com\/fr\/clairitec-signe-un-accord-de-distribution-mondiale-avec-mouser-electronics\/","name":"Clairitec signe un accord de distribution mondiale avec Mouser Electronics -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2019-10-08T22:31:44+00:00","dateModified":"2019-10-08T22:31:44+00:00","breadcrumb":{"@id":"https:\/\/www.eenewseurope.com\/fr\/clairitec-signe-un-accord-de-distribution-mondiale-avec-mouser-electronics\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eenewseurope.com\/fr\/clairitec-signe-un-accord-de-distribution-mondiale-avec-mouser-electronics\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eenewseurope.com\/fr\/clairitec-signe-un-accord-de-distribution-mondiale-avec-mouser-electronics\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Clairitec signe un accord de distribution mondiale avec Mouser Electronics"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/74080"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=74080"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/74080\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/74081"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=74080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=74080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=74080"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=74080"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=74080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}