{"id":7291,"date":"2021-07-26T21:28:57","date_gmt":"2021-07-26T21:28:57","guid":{"rendered":"https:\/\/\/leurope-peut-elle-devenir-une-des-premieres-puissances-mondiales-de-la-production-de-batteries\/"},"modified":"2021-07-26T21:28:57","modified_gmt":"2021-07-26T21:28:57","slug":"leurope-peut-elle-devenir-une-des-premieres-puissances-mondiales-de-la-production-de-batteries","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/leurope-peut-elle-devenir-une-des-premieres-puissances-mondiales-de-la-production-de-batteries\/","title":{"rendered":"L&rsquo;Europe peut-elle devenir une des premi\u00e8res puissances mondiales de la production de batteries ?"},"content":{"rendered":"<p style=\"margin-left:0cm;margin-right:0cm\"><span style=\"color:black;font-family:arial,sans-serif;font-size:10.0pt\">Dans un contexte o\u00f9 la demande globale en batteries sera multipli\u00e9e par 14 d&rsquo;ici \u00e0 2030, la France se place au premier plan des nations europ\u00e9ennes.<br \/>\n&#8211; 74 % des entreprises fran\u00e7aises interrog\u00e9es envisagent de rapprocher g\u00e9ographiquement certaines parties de leur cha\u00eene d&rsquo;approvisionnement&nbsp;de leur base de fabrication&nbsp;dans les douze prochains mois.<\/span><\/p>\n<p style=\"margin-left:0cm;margin-right:0cm\"><span style=\"color:black;font-family:arial,sans-serif;font-size:10.0pt\">&#8211; 84 % pr\u00e9voient de lancer un nouveau produit ou syst\u00e8me de stockage par batterie dans le m\u00eame laps de temps.<\/span><\/p>\n<p style=\"margin-left:0cm;margin-right:0cm\"><span style=\"color:black;font-family:arial,sans-serif;font-size:10.0pt\">&#8211; 71% des participants fran\u00e7ais sont d&rsquo;accord avec le fait que l&rsquo;Europe doit intensifier la r\u00e9utilisation et le recyclage des batteries et des mat\u00e9riaux pour r\u00e9pondre \u00e0 la demande croissante.<\/span><\/p>\n<p style=\"margin-left:0cm;margin-right:0cm\"><u><span style=\"color:black;font-family:arial,sans-serif;font-size:10.0pt\">L&rsquo;Europe est d\u00e9sormais le plus gros march\u00e9 mondial des v\u00e9hicules \u00e9lectriques<\/span><\/u><\/p>\n<p style=\"margin-left:0cm;margin-right:0cm\"><span style=\"color:black;font-family:arial,sans-serif;font-size:10.0pt\">On estime qu&rsquo;il y a actuellement 1,8 million de v\u00e9hicules \u00e9lectriques (VE) sur les routes d&rsquo;Europe. Si l&rsquo;Union&nbsp;Europ\u00e9enne&nbsp;arrive \u00e0 ses fins, il y en aura au moins 30 millions d&rsquo;ici la fin de la d\u00e9cennie.<\/span><span style=\"color:black;font-family:arial,sans-serif;font-size:10.0pt\"> <\/span><span style=\"color:black;font-family:arial,sans-serif;font-size:10.0pt\">Cette \u00e9volution sera en grande partie due aux r\u00e9glementations, aux objectifs et aux financements de la Commission europ\u00e9enne, qui visent \u00e0 orienter les pays, les entreprises et les consommateurs dans une direction plus durable. Ce changement spectaculaire se refl\u00e8te dans la demande.<\/span><span style=\"color:black;font-family:arial,sans-serif;font-size:10.0pt\"> <\/span><span style=\"color:black;font-family:arial,sans-serif;font-size:10.0pt\">\u00ab\u00a0Nous constatons aujourd&rsquo;hui une formidable acc\u00e9l\u00e9ration vers une p\u00e9n\u00e9tration de 70 % de voitures enti\u00e8rement \u00e9lectriques d&rsquo;ici 2030\u00a0\u00bb, d\u00e9clare Francisco Carranza, vice-pr\u00e9sident des ventes et du marketing chez Automotive&nbsp;Cells&nbsp;Company&nbsp;(ACC), une&nbsp;joint venture&nbsp;de Total et du Groupe PSA. \u00ab\u00a0L&rsquo;industrie des batteries a \u00e9t\u00e9 incit\u00e9e \u00e0 r\u00e9pondre \u00e0 cette acc\u00e9l\u00e9ration, en mettant l&rsquo;accent sur ses capacit\u00e9s europ\u00e9ennes.\u00a0\u00bb<\/span><span style=\"color:black;font-family:arial,sans-serif;font-size:10.0pt\"> <\/span><span style=\"color:black;font-family:arial,sans-serif;font-size:10.0pt\">La forte demande des consommateurs contribue \u00e0 stimuler la fabrication de batteries et de syst\u00e8mes de stockage de batteries en Europe. La France, dans le cadre de son Plan de relance de la fili\u00e8re automobile, se veut en t\u00eate de pont des nations europ\u00e9ennes des v\u00e9hicules propres. Cela se traduit notamment par une volont\u00e9 conjointe du gouvernement et des industriels de produire non-seulement des VE mais \u00e9galement les batteries sur le sol fran\u00e7ais.<\/span><\/p>\n<p style=\"margin-left:0cm;margin-right:0cm\"><u><span style=\"color:black;font-family:arial,sans-serif;font-size:10.0pt\">Des batteries europ\u00e9ennes plus ch\u00e8res mais plus fiables&nbsp;?<\/span><\/u><\/p>\n<p style=\"margin-left:0cm;margin-right:0cm\"><span style=\"color:black;font-family:arial,sans-serif;font-size:10.0pt\">Incapables de battre la Chine en volume dans un avenir proche, les&nbsp;industriels&nbsp;europ\u00e9ens concentrent leurs efforts sur la fabrication de batteries ultra-performantes et durables. Au c\u0153ur de cet effort se trouve l&rsquo;innovation, dans laquelle les r\u00e9pondants&nbsp;fran\u00e7ais&nbsp;ont exprim\u00e9 une grande confiance.<\/span><span style=\"color:black;font-family:arial,sans-serif;font-size:10.0pt\"> <\/span><span style=\"color:black;font-family:arial,sans-serif;font-size:10.0pt\">\u00ab\u00a0Avec&nbsp;seulement 6 % de&nbsp;la fabrication de batteries en Europe, nous sommes toujours fortement d\u00e9pendants des importations de cellules de batteries et, avec la demande de v\u00e9hicules \u00e9lectriques qui&nbsp;augmente rapidement, il est clair que cela doit changer\u00a0\u00bb, a expliqu\u00e9&nbsp;Bjoern&nbsp;Klaas, vice-pr\u00e9sident et directeur g\u00e9n\u00e9ral de&nbsp;Protolabs&nbsp;Europe.<\/span><span style=\"color:black;font-family:arial,sans-serif;font-size:10.0pt\"> <\/span><span style=\"color:black;font-family:arial,sans-serif;font-size:10.0pt\">Il ajoute<\/span><span style=\"color:black;font-family:arial,sans-serif;font-size:10.0pt\">&nbsp;<\/span><span style=\"color:black;font-family:arial,sans-serif;font-size:10.0pt\">:&nbsp;\u00ab\u00a0L&rsquo;ambition&nbsp;de la France&nbsp;d&rsquo;\u00eatre \u00e0 la pointe de la course \u00e0 l&rsquo;\u00e9lectrification est clairement \u00e9vidente, mais la d\u00e9termination \u00e0 cr\u00e9er des cha\u00eenes d&rsquo;approvisionnement nationales plus fortes, capables de soutenir le d\u00e9veloppement et la production de batteries, est de plus en plus&nbsp;encourageante. La&nbsp;gigafactory&nbsp;des Hauts-de France en est la parfaire illustration et&nbsp;son<\/span><span style=\"color:black;font-family:arial,sans-serif;font-size:10.0pt\">&nbsp;choix&nbsp;de localisation n&rsquo;est pas un hasard, avec la pr\u00e9sence de 3 constructeurs mondiaux (Toyota, PSA et Renault) sur le territoire, mais \u00e9galement d&rsquo;un&nbsp;\u00e9co-syst\u00e8me&nbsp;de plus de 550 fournisseurs, sous-traitants et prestataires.<\/span><span style=\"color:black;font-family:arial,sans-serif;font-size:10.0pt\">&nbsp;<\/span><span style=\"color:black;font-family:arial,sans-serif;font-size:10.0pt\">\u00ab\u00a0.<\/span><span style=\"font-family:arial,sans-serif;font-size:10.0pt\">&nbsp;<\/span><\/p>\n<p style=\"margin-left:0cm;margin-right:0cm\"><u><span style=\"color:black;font-family:arial,sans-serif;font-size:10.0pt\">\u00c0&nbsp;propos du rapport \u00ab&nbsp;In charge&nbsp;\u00bb<\/span><\/u><\/p>\n<p style=\"margin-left:0cm;margin-right:0cm\"><span style=\"color:black;font-family:arial,sans-serif;font-size:10.0pt\">Protolabs, le leader mondial de la fabrication num\u00e9rique de prototypes personnalis\u00e9s et de pi\u00e8ces de production \u00e0 faible volume,&nbsp;a finalis\u00e9&nbsp;son \u00e9tude&nbsp;\u00ab\u00a0In Charge\u00a0\u00bb au printemps 2021.<\/span><span style=\"color:black;font-family:arial,sans-serif;font-size:10.0pt\"> <\/span><span style=\"color:black;font-family:arial,sans-serif;font-size:10.0pt\">L&rsquo;\u00e9tude a \u00e9t\u00e9&nbsp;men\u00e9e aupr\u00e8s de 200&nbsp;dirigeants&nbsp;de&nbsp;l&rsquo;industrie europ\u00e9enne&nbsp;dans 7 pays<\/span><span style=\"color:black;font-family:arial,sans-serif;font-size:10.0pt\">&nbsp;<\/span><span style=\"color:black;font-family:arial,sans-serif;font-size:10.0pt\">:&nbsp;Royaume-Uni,&nbsp;France, Allemagne, Italie, Espagne, Hollande et Norv\u00e8ge.<\/span><span style=\"color:black;font-family:arial,sans-serif;font-size:10.0pt\">&nbsp;<\/span><\/p>\n<p style=\"margin-left:0cm;margin-right:0cm\"><span style=\"color:black;font-family:arial,sans-serif;font-size:10.0pt\">Retrouvez tous les chiffres de l&rsquo;\u00e9tude en cliquant sur&nbsp;:<\/span><\/p>\n<p style=\"margin-left:0cm;margin-right:0cm\"><span style=\"color:black\"><a href=\"https:\/\/obtenir.protolabs.fr\/batteries\/in-charge\/\">Protolabs &#8211; In charge: Can Europe become a battery power in the electric age?<\/a><\/span><span style=\"color:black;font-family:arial,sans-serif;font-size:10.0pt\">&nbsp;<\/span><\/p>\n<p style=\"margin-left:0cm;margin-right:0cm\"><u><span style=\"color:black;font-family:arial,sans-serif;font-size:10.0pt\">\u00c0&nbsp;propos de&nbsp;Protolabs&nbsp;:<\/span><\/u><\/p>\n<p style=\"margin-left:0cm;margin-right:0cm\"><span style=\"color:black;font-family:arial,sans-serif;font-size:10.0pt\">Fond\u00e9e aux Etats-Unis en 1999 par Larry&nbsp;Lukis,&nbsp;Protolabs&nbsp;est leader mondial en mati\u00e8re de prototypage rapide et de production de petites s\u00e9ries en impression 3D, usinage CNC et moulage par injection. L&rsquo;entreprise garantit aux concepteurs et ing\u00e9nieurs du monde entier une vitesse de mise sur le march\u00e9 sans pr\u00e9c\u00e9dent. Elle s&rsquo;adresse \u00e0 tous types d&rsquo;acteurs (de la start-up aux grands groupes internationaux), issus de tous secteurs (automobile, m\u00e9dical, a\u00e9ronautique, \u00e9lectronique, \u00e9quipement industriel&#8230;).<\/span><span style=\"color:black;font-family:arial,sans-serif;font-size:10.0pt\"> <\/span><span style=\"color:black;font-family:arial,sans-serif;font-size:10.0pt\">L&rsquo;entreprise dispose de onze implantations dans le monde, dont une en France (Le Bourget du Lac &#8211; 73). En Europe, ses centres de production sont bas\u00e9s \u00e0 Telford (UK) pour l&rsquo;usinage CNC et le moulage par injection, et pr\u00e8s de Munich (DE) pour l&rsquo;impression 3D.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Selon un nouveau rapport, \u00ab In charge \u00bb, publi\u00e9 par Protolabs, la volont\u00e9 de l&rsquo;Europe en g\u00e9n\u00e9ral et de la France en particulier de devenir un leader mondial de l&rsquo;\u00e9lectrification devrait cr\u00e9er une opportunit\u00e9 majeure de relocalisation. <\/p>\n","protected":false},"author":9,"featured_media":7292,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-7291","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","domains-electronique-eci"],"acf":[],"yoast_head":"<title>L&#039;Europe peut-elle devenir une des premi\u00e8res puissances mondia...<\/title>\n<meta name=\"description\" content=\"Selon un nouveau rapport, \u00ab In charge \u00bb, publi\u00e9 par Protolabs, la volont\u00e9 de l&#039;Europe en g\u00e9n\u00e9ral et de la France en particulier de devenir un leader...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/7291\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;Europe peut-elle devenir une des premi\u00e8res puissances mondiales de la production de batteries ?\" \/>\n<meta property=\"og:description\" content=\"Selon un nouveau rapport, \u00ab In charge \u00bb, publi\u00e9 par Protolabs, la volont\u00e9 de l&#039;Europe en g\u00e9n\u00e9ral et de la France en particulier de devenir un leader mondial de l&#039;\u00e9lectrification devrait cr\u00e9er une opportunit\u00e9 majeure de relocalisation.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/7291\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-26T21:28:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9679_protolabs-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/leurope-peut-elle-devenir-une-des-premieres-puissances-mondiales-de-la-production-de-batteries\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/leurope-peut-elle-devenir-une-des-premieres-puissances-mondiales-de-la-production-de-batteries\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"L&rsquo;Europe peut-elle devenir une des premi\u00e8res puissances mondiales de la production de batteries ?\",\"datePublished\":\"2021-07-26T21:28:57+00:00\",\"dateModified\":\"2021-07-26T21:28:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/leurope-peut-elle-devenir-une-des-premieres-puissances-mondiales-de-la-production-de-batteries\/\"},\"wordCount\":858,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/leurope-peut-elle-devenir-une-des-premieres-puissances-mondiales-de-la-production-de-batteries\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/leurope-peut-elle-devenir-une-des-premieres-puissances-mondiales-de-la-production-de-batteries\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/leurope-peut-elle-devenir-une-des-premieres-puissances-mondiales-de-la-production-de-batteries\/\",\"name\":\"L'Europe peut-elle devenir une des premi\u00e8res puissances mondiales de la production de batteries ? -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2021-07-26T21:28:57+00:00\",\"dateModified\":\"2021-07-26T21:28:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/leurope-peut-elle-devenir-une-des-premieres-puissances-mondiales-de-la-production-de-batteries\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/leurope-peut-elle-devenir-une-des-premieres-puissances-mondiales-de-la-production-de-batteries\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/leurope-peut-elle-devenir-une-des-premieres-puissances-mondiales-de-la-production-de-batteries\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&rsquo;Europe peut-elle devenir une des premi\u00e8res puissances mondiales de la production de batteries ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"L'Europe peut-elle devenir une des premi\u00e8res puissances mondia...","description":"Selon un nouveau rapport, \u00ab In charge \u00bb, publi\u00e9 par Protolabs, la volont\u00e9 de l'Europe en g\u00e9n\u00e9ral et de la France en particulier de devenir un leader...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/7291\/","og_locale":"fr_FR","og_type":"article","og_title":"L'Europe peut-elle devenir une des premi\u00e8res puissances mondiales de la production de batteries ?","og_description":"Selon un nouveau rapport, \u00ab In charge \u00bb, publi\u00e9 par Protolabs, la volont\u00e9 de l'Europe en g\u00e9n\u00e9ral et de la France en particulier de devenir un leader mondial de l'\u00e9lectrification devrait cr\u00e9er une opportunit\u00e9 majeure de relocalisation.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/7291\/","og_site_name":"EENewsEurope","article_published_time":"2021-07-26T21:28:57+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9679_protolabs-scaled.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/leurope-peut-elle-devenir-une-des-premieres-puissances-mondiales-de-la-production-de-batteries\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/leurope-peut-elle-devenir-une-des-premieres-puissances-mondiales-de-la-production-de-batteries\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"L&rsquo;Europe peut-elle devenir une des premi\u00e8res puissances mondiales de la production de batteries ?","datePublished":"2021-07-26T21:28:57+00:00","dateModified":"2021-07-26T21:28:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/leurope-peut-elle-devenir-une-des-premieres-puissances-mondiales-de-la-production-de-batteries\/"},"wordCount":858,"commentCount":0,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ecinews.fr\/fr\/leurope-peut-elle-devenir-une-des-premieres-puissances-mondiales-de-la-production-de-batteries\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/leurope-peut-elle-devenir-une-des-premieres-puissances-mondiales-de-la-production-de-batteries\/","url":"https:\/\/www.ecinews.fr\/fr\/leurope-peut-elle-devenir-une-des-premieres-puissances-mondiales-de-la-production-de-batteries\/","name":"L'Europe peut-elle devenir une des premi\u00e8res puissances mondiales de la production de batteries ? -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2021-07-26T21:28:57+00:00","dateModified":"2021-07-26T21:28:57+00:00","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/leurope-peut-elle-devenir-une-des-premieres-puissances-mondiales-de-la-production-de-batteries\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/leurope-peut-elle-devenir-une-des-premieres-puissances-mondiales-de-la-production-de-batteries\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/leurope-peut-elle-devenir-une-des-premieres-puissances-mondiales-de-la-production-de-batteries\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"L&rsquo;Europe peut-elle devenir une des premi\u00e8res puissances mondiales de la production de batteries ?"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/7291"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=7291"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/7291\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/7292"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=7291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=7291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=7291"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=7291"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=7291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}