{"id":72356,"date":"2019-10-27T23:31:44","date_gmt":"2019-10-27T23:31:44","guid":{"rendered":"https:\/\/\/elektrobit-accelere-le-developpement-des-systemes-adas-et-ad\/"},"modified":"2019-10-27T23:31:44","modified_gmt":"2019-10-27T23:31:44","slug":"elektrobit-accelere-le-developpement-des-systemes-adas-et-ad","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/elektrobit-accelere-le-developpement-des-systemes-adas-et-ad\/","title":{"rendered":"Elektrobit acc\u00e9l\u00e8re le d\u00e9veloppement des syst\u00e8mes ADAS et AD"},"content":{"rendered":"<p>De nos jours, les \u00e9quipes d&rsquo;ing\u00e9nierie automobile sont contraintes d&rsquo;utiliser de multiples outils, souvent&nbsp;incoh\u00e9rents,&nbsp;pour g\u00e9rer l&rsquo;ensemble du processus de validation et de v\u00e9rification. Les syst\u00e8mes automobiles devenant de plus en plus complexes et gourmands en donn\u00e9es, le processus devient \u00e9galement de plus en plus difficile et complexe. Faire \u00e9voluer ces syst\u00e8mes complexes est particuli\u00e8rement probl\u00e9matique. Les personnes impliqu\u00e9es dans le processus&nbsp;&#8211;&nbsp;des ing\u00e9nieurs aux pilotes d&rsquo;essais en passant,&nbsp;des&nbsp;sp\u00e9cialistes des donn\u00e9es, informaticiens et chefs de projets&nbsp;&#8211;&nbsp;se trouvent g\u00e9n\u00e9ralement dans diff\u00e9rentes parties du monde, ce qui rend l&rsquo;orchestration des donn\u00e9es encore plus difficile.<\/p>\n<p>EB Assist Test Lab offre une approche unique de bout en bout de la validation et de la v\u00e9rification, offrant une solution de type \u00ab&nbsp;guichet unique&nbsp;\u00bb int\u00e9grant les outils d\u00e9j\u00e0 disponibles sur le march\u00e9 et utilis\u00e9s avec des fonctionnalit\u00e9s suppl\u00e9mentaires pour combler les lacunes critiques. Il couvre l&rsquo;ensemble du cycle d&rsquo;essai, de la collecte des donn\u00e9es \u00e0 l&rsquo;analyse des donn\u00e9es, en passant notamment par l&rsquo;optimisation des processus de collaboration, l&rsquo;int\u00e9gration \u00e0 des outils et services tiers ainsi que le traitement et la gestion des donn\u00e9es.&nbsp;Tous les objectifs d&rsquo;am\u00e9lioration du flux de travail, d&rsquo;augmentation de l&rsquo;efficacit\u00e9 et, en fin de compte, d&rsquo;acc\u00e9l\u00e9ration des calendriers sont&nbsp;atteints avec le nouveau produit EB.<\/p>\n<p>&nbsp;\u00ab&nbsp;Nous avons travaill\u00e9 en \u00e9troite collaboration avec nos clients afin d&rsquo;identifier les points faibles du processus d&rsquo;essai actuel et de d\u00e9velopper, \u00e0 partir de z\u00e9ro, un nouveau type de produit qui r\u00e9pond \u00e0 tous les besoins du flux de travail de validation et de v\u00e9rification&nbsp;\u00bb, a d\u00e9clar\u00e9 Martin Schleicher,&nbsp;Executive&nbsp;Vice&nbsp;President, Business Management,&nbsp;Elektrobit. \u00ab&nbsp;De plus, nous avons identifi\u00e9 un r\u00e9seau de fournisseurs de services bas\u00e9s sur le cloud, de technologies de simulation et d&rsquo;intelligence artificielle parmi les meilleurs de leur cat\u00e9gorie, dans le but d&rsquo;offrir&nbsp;\u00e0 nos clients la solution d&rsquo;essai automobile ultime. Nous sommes heureux d&rsquo;annoncer la sortie d&rsquo;EB Assist Test&nbsp;Lab&nbsp;sur Azure&nbsp;avec notre partenaire de longue date, Microsoft. Azure&nbsp;apportera des&nbsp;avantages&nbsp;significatifs \u00e0 nos clients,&nbsp;notamment une \u00e9volutivit\u00e9 globale, une flexibilit\u00e9 in\u00e9gal\u00e9e et&nbsp;une s\u00e9curit\u00e9 d&rsquo;entreprise pour permettre de tester et d&rsquo;analyser rapidement les donn\u00e9es, et&nbsp;donc acc\u00e9l\u00e9rer la mise sur le march\u00e9, \u00e9liminant ainsi le fardeau de la mise en&nbsp;\u0153uvre et de la maintenance des infrastructures&nbsp;\u00bb.<\/p>\n<p>En collaboration avec des partenaires cloud comme Microsoft et des fournisseurs de datacenters comme Equinix, EB Assist Test&nbsp;Lab&nbsp;est \u00e9volutif \u00e0 l&rsquo;infini&nbsp;et est capable&nbsp;de g\u00e9rer les volumes de donn\u00e9es consid\u00e9rables et croissants g\u00e9n\u00e9r\u00e9s par les syst\u00e8mes de plus en plus complexes \u00e9quip\u00e9s de radars, de capteurs Lidar et de cam\u00e9ras haute r\u00e9solution. La collecte de donn\u00e9es par v\u00e9hicule et par jour s&rsquo;\u00e9l\u00e8ve actuellement en moyenne \u00e0 des centaines de m\u00e9gaoctets par seconde et devrait atteindre plusieurs&nbsp;gigaoctets par seconde au cours de la prochaine g\u00e9n\u00e9ration.<\/p>\n<p>&nbsp;\u00ab&nbsp;La collecte et le stockage s\u00e9curis\u00e9s des donn\u00e9es \u00e0&nbsp;grande&nbsp;\u00e9chelle et leur mise \u00e0 disposition o\u00f9 et quand cela est n\u00e9cessaire sont essentiels \u00e0 la fourniture de solutions de conduite autonome&nbsp;\u00bb,&nbsp;a d\u00e9clar\u00e9 Sanjay Ravi, General Manager Automotive&nbsp;Industry&nbsp;chez Microsoft Corp. \u00ab&nbsp;Microsoft travaille avec&nbsp;Elektrobit&nbsp;pour&nbsp;l&rsquo;aider \u00e0 faire face \u00e0 un processus de test et de validation de plus en plus long et difficile, afin d&rsquo;acc\u00e9l\u00e9rer le d\u00e9veloppement d&rsquo;applications de conduite avanc\u00e9es&nbsp;\u00bb.<\/p>\n<p>Avec le d\u00e9veloppement et l&rsquo;int\u00e9gration de logiciels automobiles, le secteur de la validation et de la v\u00e9rification conna\u00eet une croissance \u00e9norme, qui devrait augmenter de 10&nbsp;% par an entre 2020 et 2030, selon une \u00e9tude r\u00e9cente men\u00e9e par McKinsey &amp;&nbsp;Company. En raison des exigences des syst\u00e8mes ADAS et AD qui deviennent de plus en plus sophistiqu\u00e9s, la validation et la v\u00e9rification devraient repr\u00e9senter environ 29&nbsp;% (24&nbsp;milliards d&rsquo;USD) de l&rsquo;ensemble du march\u00e9 des logiciels automobiles en 2030.<\/p>\n<p><a href=\"http:\/\/www.elektrobit.com\/%20\/t%20_blank\">elektrobit.com<\/a><\/p>\n<h3 class=\"title\"><a href=\"https:\/\/www.electronique-eci.com\/news\/elektrobit-ouvre-un-nouveau-laboratoire-pour-la-conception-de-produits-logiciels-pour\">Elektrobit ouvre un nouveau laboratoire pour la conception de produits logiciels pour l\u2019automobile<\/a><\/h3>\n<h3 class=\"title\"><a href=\"https:\/\/www.electronique-eci.com\/Learning-center\/relever-le-defi-de-la-validation-de-la-conduite-automatisee-avec-un-centre-de-test-0\">Relever le d\u00e9fi de la validation de la conduite automatis\u00e9e avec un centre de test complet<\/a><\/h3>\n<h3 class=\"title\"><a href=\"https:\/\/www.electronique-eci.com\/news\/elektrobit-selectionne-par-baidu-pour-activer-la-conduite-autonome-securisee\">Elektrobit s\u00e9lectionn\u00e9 par Baidu pour activer la conduite autonome s\u00e9curis\u00e9e<\/a><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Elektrobit (EB) annonce la sortie d&rsquo;un outil bas\u00e9 sur le cloud destin\u00e9 \u00e0 la validation de bout en bout des syst\u00e8mes avanc\u00e9s d&rsquo;aide \u00e0 la conduite (ADAS) et de conduite autonome (AD). Disponible sur la plate-forme cloud Microsoft Azure, le nouvel EB Assist Test Lab offre aux \u00e9quipes dispers\u00e9es une solution unique pour g\u00e9rer plus facilement les p\u00e9taoctets de donn\u00e9es de sc\u00e8nes de conduite g\u00e9n\u00e9r\u00e9es lors d&rsquo;essais routiers r\u00e9els et simul\u00e9s pendant le processus de validation et de v\u00e9rification, collaborer et, en fin de compte, mettre en production plus rapidement les derni\u00e8res fonctionnalit\u00e9s.<\/p>\n","protected":false},"author":9,"featured_media":72357,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-72356","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Elektrobit acc\u00e9l\u00e8re le d\u00e9veloppement des syst\u00e8mes ADAS et AD ...<\/title>\n<meta name=\"description\" content=\"Elektrobit (EB) annonce la sortie d&#039;un outil bas\u00e9 sur le cloud destin\u00e9 \u00e0 la validation de bout en bout des syst\u00e8mes avanc\u00e9s d&#039;aide \u00e0 la conduite (ADAS)...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/72356\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elektrobit acc\u00e9l\u00e8re le d\u00e9veloppement des syst\u00e8mes ADAS et AD\" \/>\n<meta property=\"og:description\" content=\"Elektrobit (EB) annonce la sortie d&#039;un outil bas\u00e9 sur le cloud destin\u00e9 \u00e0 la validation de bout en bout des syst\u00e8mes avanc\u00e9s d&#039;aide \u00e0 la conduite (ADAS) et de conduite autonome (AD). Disponible sur la plate-forme cloud Microsoft Azure, le nouvel EB Assist Test Lab offre aux \u00e9quipes dispers\u00e9es une solution unique pour g\u00e9rer plus facilement les p\u00e9taoctets de donn\u00e9es de sc\u00e8nes de conduite g\u00e9n\u00e9r\u00e9es lors d&#039;essais routiers r\u00e9els et simul\u00e9s pendant le processus de validation et de v\u00e9rification, collaborer et, en fin de compte, mettre en production plus rapidement les derni\u00e8res fonctionnalit\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/72356\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-27T23:31:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8244_elektrobit.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"488\" \/>\n\t<meta property=\"og:image:height\" content=\"248\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/elektrobit-accelere-le-developpement-des-systemes-adas-et-ad\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/elektrobit-accelere-le-developpement-des-systemes-adas-et-ad\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Elektrobit acc\u00e9l\u00e8re le d\u00e9veloppement des syst\u00e8mes ADAS et AD\",\"datePublished\":\"2019-10-27T23:31:44+00:00\",\"dateModified\":\"2019-10-27T23:31:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/elektrobit-accelere-le-developpement-des-systemes-adas-et-ad\/\"},\"wordCount\":820,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/elektrobit-accelere-le-developpement-des-systemes-adas-et-ad\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/elektrobit-accelere-le-developpement-des-systemes-adas-et-ad\/\",\"name\":\"Elektrobit acc\u00e9l\u00e8re le d\u00e9veloppement des syst\u00e8mes ADAS et AD -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2019-10-27T23:31:44+00:00\",\"dateModified\":\"2019-10-27T23:31:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/elektrobit-accelere-le-developpement-des-systemes-adas-et-ad\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/elektrobit-accelere-le-developpement-des-systemes-adas-et-ad\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/elektrobit-accelere-le-developpement-des-systemes-adas-et-ad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elektrobit acc\u00e9l\u00e8re le d\u00e9veloppement des syst\u00e8mes ADAS et AD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Elektrobit acc\u00e9l\u00e8re le d\u00e9veloppement des syst\u00e8mes ADAS et AD ...","description":"Elektrobit (EB) annonce la sortie d'un outil bas\u00e9 sur le cloud destin\u00e9 \u00e0 la validation de bout en bout des syst\u00e8mes avanc\u00e9s d'aide \u00e0 la conduite (ADAS)...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/72356\/","og_locale":"fr_FR","og_type":"article","og_title":"Elektrobit acc\u00e9l\u00e8re le d\u00e9veloppement des syst\u00e8mes ADAS et AD","og_description":"Elektrobit (EB) annonce la sortie d'un outil bas\u00e9 sur le cloud destin\u00e9 \u00e0 la validation de bout en bout des syst\u00e8mes avanc\u00e9s d'aide \u00e0 la conduite (ADAS) et de conduite autonome (AD). Disponible sur la plate-forme cloud Microsoft Azure, le nouvel EB Assist Test Lab offre aux \u00e9quipes dispers\u00e9es une solution unique pour g\u00e9rer plus facilement les p\u00e9taoctets de donn\u00e9es de sc\u00e8nes de conduite g\u00e9n\u00e9r\u00e9es lors d'essais routiers r\u00e9els et simul\u00e9s pendant le processus de validation et de v\u00e9rification, collaborer et, en fin de compte, mettre en production plus rapidement les derni\u00e8res fonctionnalit\u00e9s.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/72356\/","og_site_name":"EENewsEurope","article_published_time":"2019-10-27T23:31:44+00:00","og_image":[{"width":488,"height":248,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8244_elektrobit.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/elektrobit-accelere-le-developpement-des-systemes-adas-et-ad\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/elektrobit-accelere-le-developpement-des-systemes-adas-et-ad\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Elektrobit acc\u00e9l\u00e8re le d\u00e9veloppement des syst\u00e8mes ADAS et AD","datePublished":"2019-10-27T23:31:44+00:00","dateModified":"2019-10-27T23:31:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/elektrobit-accelere-le-developpement-des-systemes-adas-et-ad\/"},"wordCount":820,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/elektrobit-accelere-le-developpement-des-systemes-adas-et-ad\/","url":"https:\/\/www.ecinews.fr\/fr\/elektrobit-accelere-le-developpement-des-systemes-adas-et-ad\/","name":"Elektrobit acc\u00e9l\u00e8re le d\u00e9veloppement des syst\u00e8mes ADAS et AD -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2019-10-27T23:31:44+00:00","dateModified":"2019-10-27T23:31:44+00:00","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/elektrobit-accelere-le-developpement-des-systemes-adas-et-ad\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/elektrobit-accelere-le-developpement-des-systemes-adas-et-ad\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/elektrobit-accelere-le-developpement-des-systemes-adas-et-ad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Elektrobit acc\u00e9l\u00e8re le d\u00e9veloppement des syst\u00e8mes ADAS et AD"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/72356"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=72356"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/72356\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/72357"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=72356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=72356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=72356"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=72356"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=72356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}