{"id":71212,"date":"2019-11-13T07:31:44","date_gmt":"2019-11-13T07:31:44","guid":{"rendered":"https:\/\/\/renesas-et-altair-semiconductor-annoncent-leur-collaboration-pour-des-solutions-iot-cellulaires\/"},"modified":"2019-11-13T07:31:44","modified_gmt":"2019-11-13T07:31:44","slug":"renesas-et-altair-semiconductor-annoncent-leur-collaboration-pour-des-solutions-iot-cellulaires","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/renesas-et-altair-semiconductor-annoncent-leur-collaboration-pour-des-solutions-iot-cellulaires\/","title":{"rendered":"Renesas et Altair Semiconductor annoncent leur collaboration pour des Solutions IoT Cellulaires"},"content":{"rendered":"<p>\u00ab Nous sommes ravis de collaborer avec Altair pour fournir les meilleures solutions IoT cellulaires au march\u00e9 en pleine expansion de l\u2019IoT \u00bb, a d\u00e9clar\u00e9 Sailesh Chittipeddi, vice-pr\u00e9sident ex\u00e9cutif et directeur g\u00e9n\u00e9ral de la division IoT et infrastructure de Renesas. \u00ab Notre combinaison d\u2019excellence technique et d\u2019IP uniques nous permettra de concevoir la solution cellulaire multi-protocole de puce \u00e0 cloud la plus petite et la moins gourmande en \u00e9nergie pour les applications IoT industrielles souhait\u00e9es par nos clients pour leurs produits de prochaine g\u00e9n\u00e9ration. \u00bb<\/p>\n<p>Avec des milliards de dispositifs devant \u00eatre d\u00e9ploy\u00e9s d&rsquo;ici 2024, le march\u00e9 de l&rsquo;IoT requiert des produits qui fonctionnent de mani\u00e8re transparente et pr\u00eats \u00e0 l&#8217;emploi. Les capteurs, les cam\u00e9ras, les appareils de mesure, de suivi et intelligents reposent tous sur une consommation d&rsquo;\u00e9nergie extr\u00eamement faible, ce qui permet \u00e0 un capteur de fonctionner sur le terrain pendant 10 \u00e0 20 ans sans n\u00e9cessiter de maintenance mat\u00e9rielle.<\/p>\n<p>\u00ab&nbsp;Cette collaboration rend la technologie Altair accessible \u00e0 l\u2019ensemble de l\u2019\u00e9cosyst\u00e8me de partenaires et clients de Renesas&nbsp;\u00bb, a d\u00e9clar\u00e9 Oded Melamed, PDG d\u2019Altair Semiconductor. \u00ab L\u2019int\u00e9gration de la technologie IoT cellulaire distinctif d\u2019Altair dans les microcontr\u00f4leurs leaders du march\u00e9 de Renesas rendra cette technologie formidable imm\u00e9diatement accessible au march\u00e9 de masse des appareils IoT et des fournisseurs de services. \u00bb<\/p>\n<p>En tant que premi\u00e8re \u00e9tape de cette collaboration, Renesas et Altair pr\u00e9voient de d\u00e9velopper des solutions IoT cellulaires avec les technologies et chipsets bi modes CAT-M et NB-IoT. Ils vont \u00e9galement concevoir divers logiciels et outils de d\u00e9veloppement afin de rationaliser l&rsquo;adoption de solutions IoT cellulaires pour les applications industrielles et grand public. Ce partenariat vise \u00e0 atteindre un leadership technique en mati\u00e8re de r\u00e9duction de taille, de consommation d&rsquo;\u00e9nergie et de s\u00e9curit\u00e9 IoT.<\/p>\n<p><a href=\"http:\/\/www.altair-semi.com\/%20\/t%20_blank\">www.altair-semi.com<\/a><\/p>\n<p><a href=\"http:\/\/www.renesas.com\">www.<\/a><a href=\"https:\/\/www.renesas.com\/%20\/t%20_blank\">renesas.com<\/a><\/p>\n<h3 class=\"title\"><a href=\"https:\/\/www.electronique-eci.com\/news\/renesas-elargit-lacces-son-portefeuille-de-licences-ip-avancees\">Renesas \u00e9largit l&rsquo;acc\u00e8s \u00e0 son portefeuille de licences IP avanc\u00e9es<\/a><\/h3>\n<h3 class=\"title\"><a href=\"https:\/\/www.electronique-eci.com\/news\/le-programme-du-consortium-r-car-accelere-linnovation-en-matiere-de-mobilite-automobile\">Le programme du Consortium R-Car acc\u00e9l\u00e8re l&rsquo;innovation en mati\u00e8re de mobilit\u00e9 automobile<\/a><\/h3>\n<h3 class=\"title\"><a href=\"https:\/\/www.electronique-eci.com\/news\/controleur-video-lcd-full-hd-pour-lindustrie-automobile\">Contr\u00f4leur vid\u00e9o LCD Full HD pour l\u2019industrie automobile<\/a><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Renesas Electronics Corporation et Altair Semiconductor ont annonc\u00e9 conjointement un partenariat visant \u00e0 apporter des solutions IoT cellulaires ultra-compactes et \u00e0 tr\u00e8s faible consommation sur le march\u00e9 mondial de l&rsquo;IoT. Les fabricants d\u2019appareils IoT cellulaires pourront utiliser cette combinaison de solutions parmi les meilleures de leur cat\u00e9gorie pour cr\u00e9er des produits et des services IoT. Ces solutions int\u00e9gr\u00e9es seront livr\u00e9es par l\u2019interm\u00e9diaire des canaux de vente de Renesas, ce qui permettra \u00e0 tous ses march\u00e9s adress\u00e9s d\u2019impl\u00e9menter une connectivit\u00e9 cellulaire.<\/p>\n","protected":false},"author":9,"featured_media":71213,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-71212","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Renesas et Altair Semiconductor annoncent leur collaboration po...<\/title>\n<meta name=\"description\" content=\"Renesas Electronics Corporation et Altair Semiconductor ont annonc\u00e9 conjointement un partenariat visant \u00e0 apporter des solutions IoT cellulaires...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/71212\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Renesas et Altair Semiconductor annoncent leur collaboration pour des Solutions IoT Cellulaires\" \/>\n<meta property=\"og:description\" content=\"Renesas Electronics Corporation et Altair Semiconductor ont annonc\u00e9 conjointement un partenariat visant \u00e0 apporter des solutions IoT cellulaires ultra-compactes et \u00e0 tr\u00e8s faible consommation sur le march\u00e9 mondial de l&#039;IoT. Les fabricants d\u2019appareils IoT cellulaires pourront utiliser cette combinaison de solutions parmi les meilleures de leur cat\u00e9gorie pour cr\u00e9er des produits et des services IoT. Ces solutions int\u00e9gr\u00e9es seront livr\u00e9es par l\u2019interm\u00e9diaire des canaux de vente de Renesas, ce qui permettra \u00e0 tous ses march\u00e9s adress\u00e9s d\u2019impl\u00e9menter une connectivit\u00e9 cellulaire.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/71212\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-13T07:31:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8270_renesas_actu_ok.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/renesas-et-altair-semiconductor-annoncent-leur-collaboration-pour-des-solutions-iot-cellulaires\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/renesas-et-altair-semiconductor-annoncent-leur-collaboration-pour-des-solutions-iot-cellulaires\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Renesas et Altair Semiconductor annoncent leur collaboration pour des Solutions IoT Cellulaires\",\"datePublished\":\"2019-11-13T07:31:44+00:00\",\"dateModified\":\"2019-11-13T07:31:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/renesas-et-altair-semiconductor-annoncent-leur-collaboration-pour-des-solutions-iot-cellulaires\/\"},\"wordCount\":372,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/renesas-et-altair-semiconductor-annoncent-leur-collaboration-pour-des-solutions-iot-cellulaires\/\",\"url\":\"https:\/\/www.eenewseurope.com\/fr\/renesas-et-altair-semiconductor-annoncent-leur-collaboration-pour-des-solutions-iot-cellulaires\/\",\"name\":\"Renesas et Altair Semiconductor annoncent leur collaboration pour des Solutions IoT Cellulaires -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2019-11-13T07:31:44+00:00\",\"dateModified\":\"2019-11-13T07:31:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/renesas-et-altair-semiconductor-annoncent-leur-collaboration-pour-des-solutions-iot-cellulaires\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eenewseurope.com\/fr\/renesas-et-altair-semiconductor-annoncent-leur-collaboration-pour-des-solutions-iot-cellulaires\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/renesas-et-altair-semiconductor-annoncent-leur-collaboration-pour-des-solutions-iot-cellulaires\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Renesas et Altair Semiconductor annoncent leur collaboration pour des Solutions IoT Cellulaires\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Renesas et Altair Semiconductor annoncent leur collaboration po...","description":"Renesas Electronics Corporation et Altair Semiconductor ont annonc\u00e9 conjointement un partenariat visant \u00e0 apporter des solutions IoT cellulaires...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/71212\/","og_locale":"fr_FR","og_type":"article","og_title":"Renesas et Altair Semiconductor annoncent leur collaboration pour des Solutions IoT Cellulaires","og_description":"Renesas Electronics Corporation et Altair Semiconductor ont annonc\u00e9 conjointement un partenariat visant \u00e0 apporter des solutions IoT cellulaires ultra-compactes et \u00e0 tr\u00e8s faible consommation sur le march\u00e9 mondial de l'IoT. Les fabricants d\u2019appareils IoT cellulaires pourront utiliser cette combinaison de solutions parmi les meilleures de leur cat\u00e9gorie pour cr\u00e9er des produits et des services IoT. Ces solutions int\u00e9gr\u00e9es seront livr\u00e9es par l\u2019interm\u00e9diaire des canaux de vente de Renesas, ce qui permettra \u00e0 tous ses march\u00e9s adress\u00e9s d\u2019impl\u00e9menter une connectivit\u00e9 cellulaire.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/71212\/","og_site_name":"EENewsEurope","article_published_time":"2019-11-13T07:31:44+00:00","og_image":[{"width":1800,"height":1200,"url":"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8270_renesas_actu_ok.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eenewseurope.com\/fr\/renesas-et-altair-semiconductor-annoncent-leur-collaboration-pour-des-solutions-iot-cellulaires\/#article","isPartOf":{"@id":"https:\/\/www.eenewseurope.com\/fr\/renesas-et-altair-semiconductor-annoncent-leur-collaboration-pour-des-solutions-iot-cellulaires\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Renesas et Altair Semiconductor annoncent leur collaboration pour des Solutions IoT Cellulaires","datePublished":"2019-11-13T07:31:44+00:00","dateModified":"2019-11-13T07:31:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eenewseurope.com\/fr\/renesas-et-altair-semiconductor-annoncent-leur-collaboration-pour-des-solutions-iot-cellulaires\/"},"wordCount":372,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.eenewseurope.com\/fr\/renesas-et-altair-semiconductor-annoncent-leur-collaboration-pour-des-solutions-iot-cellulaires\/","url":"https:\/\/www.eenewseurope.com\/fr\/renesas-et-altair-semiconductor-annoncent-leur-collaboration-pour-des-solutions-iot-cellulaires\/","name":"Renesas et Altair Semiconductor annoncent leur collaboration pour des Solutions IoT Cellulaires -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2019-11-13T07:31:44+00:00","dateModified":"2019-11-13T07:31:44+00:00","breadcrumb":{"@id":"https:\/\/www.eenewseurope.com\/fr\/renesas-et-altair-semiconductor-annoncent-leur-collaboration-pour-des-solutions-iot-cellulaires\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eenewseurope.com\/fr\/renesas-et-altair-semiconductor-annoncent-leur-collaboration-pour-des-solutions-iot-cellulaires\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eenewseurope.com\/fr\/renesas-et-altair-semiconductor-annoncent-leur-collaboration-pour-des-solutions-iot-cellulaires\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Renesas et Altair Semiconductor annoncent leur collaboration pour des Solutions IoT Cellulaires"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/71212"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=71212"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/71212\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/71213"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=71212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=71212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=71212"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=71212"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=71212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}