{"id":69282,"date":"2019-12-04T06:46:36","date_gmt":"2019-12-04T06:46:36","guid":{"rendered":"https:\/\/\/approbation-du-brochage-com-hpc\/"},"modified":"2019-12-04T06:46:36","modified_gmt":"2019-12-04T06:46:36","slug":"approbation-du-brochage-com-hpc","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/approbation-du-brochage-com-hpc\/","title":{"rendered":"Approbation du brochage COM-HPC"},"content":{"rendered":"<p>Jessica Isquith, pr\u00e9sidente du PICMG, est ravie des progr\u00e8s r\u00e9alis\u00e9s sur la sp\u00e9cification COM-HPC : \u00ab\u00a0Au PICMG, nous travaillons actuellement sur la prochaine g\u00e9n\u00e9ration du standard Computer-On-Module qui est d&rsquo;une importance capitale pour le monde de l&rsquo;informatique embarqu\u00e9e et p\u00e9riph\u00e9rique. Apr\u00e8s l&#8217;empreinte physique, le brochage est l\u2019\u00e9tape la plus importante. Elle a pu \u00eatre pr\u00e9-approuv\u00e9e aussi rapidement parce que nous avons r\u00e9ussi \u00e0 r\u00e9unir tous les acteurs cl\u00e9s du march\u00e9, y compris les fabricants de semi-conducteurs comme Intel, autour d&rsquo;une table au sein du sous-comit\u00e9 technique COM-HPC, garantissant ainsi que la norme sera la mieux adapt\u00e9e possible pour les prochaines g\u00e9n\u00e9rations de processeurs\u00a0\u00bb.<\/p>\n<p>Christian Eder, pr\u00e9sident de la commission, est convaincu que la sp\u00e9cification peut \u00eatre officiellement ratifi\u00e9e avant l\u2019introduction des prochains processeurs embarqu\u00e9s haut de gamme sur le march\u00e9 : \u00ab\u00a0Une nouvelle sp\u00e9cification Computer-on-Module est une t\u00e2che complexe qui implique de nombreux acteurs. Cependant, nous avons officiellement commenc\u00e9 notre travail en octobre 2018 et nous sommes sur la bonne voie pour lancer de nouveaux modules COM-HPC, des cartes porteuses et des plates-formes \u00e0 temps pour les prochaines g\u00e9n\u00e9rations de processeurs int\u00e9gr\u00e9s haut de gamme. Ils vont enrichir les standards existants des modules PICMG COM Express avec de nouvelles solutions qui vont dans le sens d&rsquo;un serveur de p\u00e9riph\u00e9rie headless et de solutions clients de p\u00e9riph\u00e9rie multifonctionnelles.\u00a0\u00bb<\/p>\n<p>Avec l&rsquo;adoption du brochage, tous les membres du comit\u00e9 disposent d\u00e9sormais d&rsquo;une solide base de travail \u00e0 partir de laquelle ils peuvent proposer des interfaces prenant en charge jusqu&rsquo;\u00e0 100 GbE et PCIe Gen 4.0 et Gen 5.0 et jusqu&rsquo;\u00e0 huit emplacements DIMM et processeurs haut d\u00e9bit avec plus 200 watts sur des modules COM-HPC standards, et travailler sur des cartes porteuses conformes aux normes.<\/p>\n<p>Les membres du comit\u00e9 PICMG COM-HPC comprennent : l&rsquo;Universit\u00e9 de Bielefeld et Adlink, Advantech, Amphenol, AMI, congatec, Elma Electronic, Emerson Machine Automation Solutions, ept, Fastwel, GE Automation, HEITEC, Intel, Kontron, MEN, MSC Technologies, N.A.T., Samtec, SECO, TE Connectivity, Trenz Electronic et VersaLogic. Adlink, congatec et Kontron sont \u00e9galement sponsors du comit\u00e9. Christian Eder, directeur marketing de congatec, est le pr\u00e9sident du comit\u00e9 COM-HPC. Auparavant, il a particip\u00e9, en tant que r\u00e9dacteur \u00e0 l&rsquo;\u00e9laboration de l\u2019actuel standard COM Express. Stefan Milnor de Kontron et Dylan Lang de Samtec apportent leur soutien \u00e0 Christian Eder dans leurs fonctions respectives de r\u00e9dacteur et secr\u00e9taire du comit\u00e9 PICMG COM-HPC.<\/p>\n<p><a href=\"http:\/\/www.congatec.com\/COM-HPC\">www.congatec.com\/COM-HPC<\/a>&nbsp;&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Congatec annonce que le sous-comit\u00e9 technique COM-HPC du PICMG a approuv\u00e9 le brochage de cette nouvelle sp\u00e9cification Computer-on-Module de haute performance. Le nouveau standard COM-HPC entre maintenant dans la derni\u00e8re ligne droite pour la ratification de la version 1.0 de la sp\u00e9cification, qui est pr\u00e9vue pour le premier semestre 2020. Les fabricants de Computer-on-modules et les concepteurs de cartes-m\u00e8res qui jouent un r\u00f4le actif dans le groupe de travail COM-HPC peuvent maintenant se lancer dans les premi\u00e8res conceptions d&rsquo;informatique en p\u00e9riph\u00e9rie d\u2019apr\u00e8s ces donn\u00e9es pr\u00e9-approuv\u00e9es, avec l&rsquo;espoir de les mettre sur le march\u00e9 en m\u00eame temps que le lancement des nouvelles g\u00e9n\u00e9rations de processeurs int\u00e9gr\u00e9s haut de gamme Intel et AMD l&rsquo;an prochain.<\/p>\n","protected":false},"author":9,"featured_media":69283,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-69282","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Approbation du brochage COM-HPC ...<\/title>\n<meta name=\"description\" content=\"Congatec annonce que le sous-comit\u00e9 technique COM-HPC du PICMG a approuv\u00e9 le brochage de cette nouvelle sp\u00e9cification Computer-on-Module de haute...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/69282\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Approbation du brochage COM-HPC\" \/>\n<meta property=\"og:description\" content=\"Congatec annonce que le sous-comit\u00e9 technique COM-HPC du PICMG a approuv\u00e9 le brochage de cette nouvelle sp\u00e9cification Computer-on-Module de haute performance. Le nouveau standard COM-HPC entre maintenant dans la derni\u00e8re ligne droite pour la ratification de la version 1.0 de la sp\u00e9cification, qui est pr\u00e9vue pour le premier semestre 2020. Les fabricants de Computer-on-modules et les concepteurs de cartes-m\u00e8res qui jouent un r\u00f4le actif dans le groupe de travail COM-HPC peuvent maintenant se lancer dans les premi\u00e8res conceptions d&#039;informatique en p\u00e9riph\u00e9rie d\u2019apr\u00e8s ces donn\u00e9es pr\u00e9-approuv\u00e9es, avec l&#039;espoir de les mettre sur le march\u00e9 en m\u00eame temps que le lancement des nouvelles g\u00e9n\u00e9rations de processeurs int\u00e9gr\u00e9s haut de gamme Intel et AMD l&#039;an prochain.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/69282\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-04T06:46:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8300_congatec.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2427\" \/>\n\t<meta property=\"og:image:height\" content=\"2028\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/fr\/approbation-du-brochage-com-hpc\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/fr\/approbation-du-brochage-com-hpc\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Approbation du brochage COM-HPC\",\"datePublished\":\"2019-12-04T06:46:36+00:00\",\"dateModified\":\"2019-12-04T06:46:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/fr\/approbation-du-brochage-com-hpc\/\"},\"wordCount\":437,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/fr\/approbation-du-brochage-com-hpc\/\",\"url\":\"https:\/\/cdn.eenewseurope.com\/fr\/approbation-du-brochage-com-hpc\/\",\"name\":\"Approbation du brochage COM-HPC -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2019-12-04T06:46:36+00:00\",\"dateModified\":\"2019-12-04T06:46:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/fr\/approbation-du-brochage-com-hpc\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cdn.eenewseurope.com\/fr\/approbation-du-brochage-com-hpc\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/fr\/approbation-du-brochage-com-hpc\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Approbation du brochage COM-HPC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Approbation du brochage COM-HPC ...","description":"Congatec annonce que le sous-comit\u00e9 technique COM-HPC du PICMG a approuv\u00e9 le brochage de cette nouvelle sp\u00e9cification Computer-on-Module de haute...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/69282\/","og_locale":"fr_FR","og_type":"article","og_title":"Approbation du brochage COM-HPC","og_description":"Congatec annonce que le sous-comit\u00e9 technique COM-HPC du PICMG a approuv\u00e9 le brochage de cette nouvelle sp\u00e9cification Computer-on-Module de haute performance. Le nouveau standard COM-HPC entre maintenant dans la derni\u00e8re ligne droite pour la ratification de la version 1.0 de la sp\u00e9cification, qui est pr\u00e9vue pour le premier semestre 2020. Les fabricants de Computer-on-modules et les concepteurs de cartes-m\u00e8res qui jouent un r\u00f4le actif dans le groupe de travail COM-HPC peuvent maintenant se lancer dans les premi\u00e8res conceptions d'informatique en p\u00e9riph\u00e9rie d\u2019apr\u00e8s ces donn\u00e9es pr\u00e9-approuv\u00e9es, avec l'espoir de les mettre sur le march\u00e9 en m\u00eame temps que le lancement des nouvelles g\u00e9n\u00e9rations de processeurs int\u00e9gr\u00e9s haut de gamme Intel et AMD l'an prochain.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/69282\/","og_site_name":"EENewsEurope","article_published_time":"2019-12-04T06:46:36+00:00","og_image":[{"width":2427,"height":2028,"url":"https:\/\/cdn.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8300_congatec.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cdn.eenewseurope.com\/fr\/approbation-du-brochage-com-hpc\/#article","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/fr\/approbation-du-brochage-com-hpc\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Approbation du brochage COM-HPC","datePublished":"2019-12-04T06:46:36+00:00","dateModified":"2019-12-04T06:46:36+00:00","mainEntityOfPage":{"@id":"https:\/\/cdn.eenewseurope.com\/fr\/approbation-du-brochage-com-hpc\/"},"wordCount":437,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/cdn.eenewseurope.com\/fr\/approbation-du-brochage-com-hpc\/","url":"https:\/\/cdn.eenewseurope.com\/fr\/approbation-du-brochage-com-hpc\/","name":"Approbation du brochage COM-HPC -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2019-12-04T06:46:36+00:00","dateModified":"2019-12-04T06:46:36+00:00","breadcrumb":{"@id":"https:\/\/cdn.eenewseurope.com\/fr\/approbation-du-brochage-com-hpc\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cdn.eenewseurope.com\/fr\/approbation-du-brochage-com-hpc\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cdn.eenewseurope.com\/fr\/approbation-du-brochage-com-hpc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Approbation du brochage COM-HPC"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/69282"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=69282"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/69282\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/69283"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=69282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=69282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=69282"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=69282"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=69282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}