{"id":69222,"date":"2019-12-02T20:31:44","date_gmt":"2019-12-02T20:31:44","guid":{"rendered":"https:\/\/\/arrow-electronics-devient-revendeur-de-la-gamme-mindsphere\/"},"modified":"2019-12-02T20:31:44","modified_gmt":"2019-12-02T20:31:44","slug":"arrow-electronics-devient-revendeur-de-la-gamme-mindsphere","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/arrow-electronics-devient-revendeur-de-la-gamme-mindsphere\/","title":{"rendered":"Arrow Electronics devient revendeur de la gamme MindSphere"},"content":{"rendered":"<p>MindSphere, le syst\u00e8me d\u2019exploitation IoT ouvert bas\u00e9 sur le cloud de Siemens, interconnecte produits, usines, syst\u00e8mes et machines, permettant aux entreprises d\u2019exploiter la richesse des donn\u00e9es produites par l\u2019IoT avec des outils d\u2019analyse avanc\u00e9s.<br \/>\nArrow est d\u00e9j\u00e0 bien implant\u00e9 en tant que partenaire de MindSphere, avec de nombreux techniciens form\u00e9s par Siemens dans le cadre du programme technique MindSphere. Siemens est actuellement en train de d\u00e9velopper diverses applications MindSphere et a conclu un accord de commercialisation afin de permettre \u00e0 ses clients d\u2019obtenir une valeur commerciale substantielle gr\u00e2ce \u00e0 la technologie IoT en g\u00e9n\u00e9ral et \u00e0 MindSphere en particulier.<br \/>\nLe nouvel accord de distribution renforce encore la capacit\u00e9 d\u2019Arrow \u00e0 soutenir les entreprises industrielles qui s\u2019engagent sur la voie de l\u2019int\u00e9gration compl\u00e8te de l\u2019IoT et d\u2019Industry&nbsp;4.0. Arrow couvre toutes les couches d\u2019une gamme de solutions IoT, depuis les composants \u00e9lectroniques jusqu\u2019aux solutions informatiques, en passant par le conseil et le d\u00e9veloppement. Le portefeuille d\u2019Arrow comprend des capteurs, des solutions de connectivit\u00e9, de cloud computing, d\u2019analyse, de s\u00e9curit\u00e9 et d\u2019infrastructure informatique.<\/p>\n<p><a href=\"http:\/\/www.arrow.com\/%20\/t%20_blank\">www.arrow.com<\/a><\/p>\n<h3 class=\"title\"><a href=\"https:\/\/www.electronique-eci.com\/news\/arrow-electronics-elargit-sa-gamme-de-capteurs-avec-invensense\">Arrow Electronics \u00e9largit sa gamme de capteurs avec InvenSense <\/a><\/h3>\n<h3 class=\"title\"><a href=\"https:\/\/www.electronique-eci.com\/news\/arrow-electronics-simplifie-la-diffusion-de-lia-avec-la-nouvelle-plateforme-opencl\">Arrow Electronics simplifie la diffusion de l\u2019IA avec la nouvelle plateforme OpenCL <\/a><\/h3>\n<h3 class=\"title\"><a href=\"https:\/\/www.electronique-eci.com\/news\/arrow-electronics-presente-les-modules-sigfox-pour-liot\">Arrow Electronics pr\u00e9sente les modules Sigfox pour l\u2019IoT<\/a><\/h3>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Arrow Electronics a annonc\u00e9 sa nomination en tant que premier revendeur du programme MindSphere pour l\u2019Internet industriel des objets (IIoT) et les fournisseurs de solutions et de technologies dans la r\u00e9gion Europe, Moyen-Orient et Afrique (EMEA). Arrow commercialisera les produits mat\u00e9riels et logiciels de MindSphere, notamment les solutions mat\u00e9rielles MindConnect IoT 2040 et MindConnect Nano.<\/p>\n","protected":false},"author":9,"featured_media":69223,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-69222","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Arrow Electronics devient revendeur de la gamme MindSphere ...<\/title>\n<meta name=\"description\" content=\"Arrow Electronics a annonc\u00e9 sa nomination en tant que premier revendeur du programme MindSphere pour l\u2019Internet industriel des objets (IIoT) et les...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/69222\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arrow Electronics devient revendeur de la gamme MindSphere\" \/>\n<meta property=\"og:description\" content=\"Arrow Electronics a annonc\u00e9 sa nomination en tant que premier revendeur du programme MindSphere pour l\u2019Internet industriel des objets (IIoT) et les fournisseurs de solutions et de technologies dans la r\u00e9gion Europe, Moyen-Orient et Afrique (EMEA). Arrow commercialisera les produits mat\u00e9riels et logiciels de MindSphere, notamment les solutions mat\u00e9rielles MindConnect IoT 2040 et MindConnect Nano.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/69222\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-02T20:31:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8314_arrow_electronics_siemens_mindsphere_smart_city-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2124\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/arrow-electronics-devient-revendeur-de-la-gamme-mindsphere\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/arrow-electronics-devient-revendeur-de-la-gamme-mindsphere\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Arrow Electronics devient revendeur de la gamme MindSphere\",\"datePublished\":\"2019-12-02T20:31:44+00:00\",\"dateModified\":\"2019-12-02T20:31:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/arrow-electronics-devient-revendeur-de-la-gamme-mindsphere\/\"},\"wordCount\":240,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/arrow-electronics-devient-revendeur-de-la-gamme-mindsphere\/\",\"url\":\"https:\/\/www.eenewseurope.com\/fr\/arrow-electronics-devient-revendeur-de-la-gamme-mindsphere\/\",\"name\":\"Arrow Electronics devient revendeur de la gamme MindSphere -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2019-12-02T20:31:44+00:00\",\"dateModified\":\"2019-12-02T20:31:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/arrow-electronics-devient-revendeur-de-la-gamme-mindsphere\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eenewseurope.com\/fr\/arrow-electronics-devient-revendeur-de-la-gamme-mindsphere\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/arrow-electronics-devient-revendeur-de-la-gamme-mindsphere\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arrow Electronics devient revendeur de la gamme MindSphere\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Arrow Electronics devient revendeur de la gamme MindSphere ...","description":"Arrow Electronics a annonc\u00e9 sa nomination en tant que premier revendeur du programme MindSphere pour l\u2019Internet industriel des objets (IIoT) et les...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/69222\/","og_locale":"fr_FR","og_type":"article","og_title":"Arrow Electronics devient revendeur de la gamme MindSphere","og_description":"Arrow Electronics a annonc\u00e9 sa nomination en tant que premier revendeur du programme MindSphere pour l\u2019Internet industriel des objets (IIoT) et les fournisseurs de solutions et de technologies dans la r\u00e9gion Europe, Moyen-Orient et Afrique (EMEA). Arrow commercialisera les produits mat\u00e9riels et logiciels de MindSphere, notamment les solutions mat\u00e9rielles MindConnect IoT 2040 et MindConnect Nano.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/69222\/","og_site_name":"EENewsEurope","article_published_time":"2019-12-02T20:31:44+00:00","og_image":[{"width":2560,"height":2124,"url":"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8314_arrow_electronics_siemens_mindsphere_smart_city-scaled.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eenewseurope.com\/fr\/arrow-electronics-devient-revendeur-de-la-gamme-mindsphere\/#article","isPartOf":{"@id":"https:\/\/www.eenewseurope.com\/fr\/arrow-electronics-devient-revendeur-de-la-gamme-mindsphere\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Arrow Electronics devient revendeur de la gamme MindSphere","datePublished":"2019-12-02T20:31:44+00:00","dateModified":"2019-12-02T20:31:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eenewseurope.com\/fr\/arrow-electronics-devient-revendeur-de-la-gamme-mindsphere\/"},"wordCount":240,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.eenewseurope.com\/fr\/arrow-electronics-devient-revendeur-de-la-gamme-mindsphere\/","url":"https:\/\/www.eenewseurope.com\/fr\/arrow-electronics-devient-revendeur-de-la-gamme-mindsphere\/","name":"Arrow Electronics devient revendeur de la gamme MindSphere -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2019-12-02T20:31:44+00:00","dateModified":"2019-12-02T20:31:44+00:00","breadcrumb":{"@id":"https:\/\/www.eenewseurope.com\/fr\/arrow-electronics-devient-revendeur-de-la-gamme-mindsphere\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eenewseurope.com\/fr\/arrow-electronics-devient-revendeur-de-la-gamme-mindsphere\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eenewseurope.com\/fr\/arrow-electronics-devient-revendeur-de-la-gamme-mindsphere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Arrow Electronics devient revendeur de la gamme MindSphere"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/69222"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=69222"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/69222\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/69223"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=69222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=69222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=69222"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=69222"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=69222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}