{"id":67640,"date":"2019-12-23T22:31:44","date_gmt":"2019-12-23T22:31:44","guid":{"rendered":"https:\/\/\/alimentations-dc-programmables-demi-rack-1u-1500-w\/"},"modified":"2019-12-23T22:31:44","modified_gmt":"2019-12-23T22:31:44","slug":"alimentations-dc-programmables-demi-rack-1u-1500-w","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/alimentations-dc-programmables-demi-rack-1u-1500-w\/","title":{"rendered":"Alimentations DC programmables demi-rack 1U 1500 W"},"content":{"rendered":"<p>Dix mod\u00e8les sont disponibles, d\u2019une tension assign\u00e9e de 0&nbsp;V \u00e0 10&nbsp;V, 20&nbsp;V, 30&nbsp;V, 40&nbsp;V, 60&nbsp;V, 80&nbsp;V, 100&nbsp;V, 150&nbsp;V, 300&nbsp;V et 600&nbsp;V, avec un courant de sortie allant de 0-2,6&nbsp;A \u00e0 0-150&nbsp;A. Tous les mod\u00e8les peuvent fonctionner en mode tension constante, courant constant ou puissance constante. Il est possible de raccorder jusqu\u2019\u00e0 quatre alimentations en parall\u00e8le avec un syst\u00e8me ma\u00eetre\/esclave avanc\u00e9 offrant des caract\u00e9ristiques comparables \u00e0 celles d\u2019une alimentation unique en mati\u00e8re de r\u00e9ponse sur charge dynamique, d\u2019ondulation et de bruit. La plage de tension d\u2019entr\u00e9e s\u2019\u00e9tend de 85&nbsp;Vac \u00e0 265&nbsp;Vac, favorisant ainsi l\u2019utilisation de ces produits dans le monde entier.<\/p>\n<p>Hors barres omnibus, la s\u00e9rie GH1.5kW mesure 214&nbsp;mm de large, 43,6&nbsp;mm (1U) de haut, pour une profondeur de 441,5&nbsp;mm. Il est possible de monter deux modules c\u00f4te \u00e0 c\u00f4te dans un rack standard de 19&nbsp;\u201d gr\u00e2ce au kit GH\/RM en option.&nbsp;Les modules demi-rack GENESYS+\u2122 p\u00e8sent moins de 3,5&nbsp;kg pour faciliter leur installation ou leur d\u00e9placement. Une version \u00e0 panneau avant vierge (sans \u00e9cran ni commande) est disponible lorsque l\u2019acc\u00e8s utilisateur n\u2019est pas indispensable ou doit \u00eatre restreint.&nbsp;Des filtres anti-poussi\u00e8re enclipsables peuvent \u00e9galement \u00eatre ajout\u00e9s en vue de limiter la contamination atmosph\u00e9rique.<\/p>\n<p><a href=\"http:\/\/www.emea.lambda.tdk.com\/fr\">www.emea.lambda.tdk.com\/fr<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TDK Corporation annonce le lancement de la s\u00e9rie d\u2019alimentations DC programmables GH1.5kW d\u2019un demi-rack de large et de 1U de haut, d\u2019une puissance assign\u00e9e de 1 500 W. Ce dernier n\u00e9 de la s\u00e9rie GENESYS+ de TDK-Lambda offre des fonctionnalit\u00e9s et une programmation identiques \u00e0 celles des mod\u00e8les standards de 1,7 kW \u00e0 15 kW en rack entier. Elles peuvent \u00eatre utilis\u00e9es soit sur table soit en baie dans diverses applications comme les Tests &amp; Mesure sur composants (Burn-in), dans l\u2019 automobile et l\u2019a\u00e9ronautique, la fabrication de semi-conducteurs, les simulateurs de batteries et de panneaux solaires, le placage, ou encore le traitement des eaux.<\/p>\n","protected":false},"author":9,"featured_media":67641,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-67640","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Alimentations DC programmables demi-rack 1U 1500 W ...<\/title>\n<meta name=\"description\" content=\"TDK Corporation annonce le lancement de la s\u00e9rie d\u2019alimentations DC programmables GH1.5kW d\u2019un demi-rack de large et de 1U de haut, d\u2019une puissance...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/67640\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alimentations DC programmables demi-rack 1U 1500 W\" \/>\n<meta property=\"og:description\" content=\"TDK Corporation annonce le lancement de la s\u00e9rie d\u2019alimentations DC programmables GH1.5kW d\u2019un demi-rack de large et de 1U de haut, d\u2019une puissance assign\u00e9e de 1 500 W. Ce dernier n\u00e9 de la s\u00e9rie GENESYS+ de TDK-Lambda offre des fonctionnalit\u00e9s et une programmation identiques \u00e0 celles des mod\u00e8les standards de 1,7 kW \u00e0 15 kW en rack entier. Elles peuvent \u00eatre utilis\u00e9es soit sur table soit en baie dans diverses applications comme les Tests &amp; Mesure sur composants (Burn-in), dans l\u2019 automobile et l\u2019a\u00e9ronautique, la fabrication de semi-conducteurs, les simulateurs de batteries et de panneaux solaires, le placage, ou encore le traitement des eaux.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/67640\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-23T22:31:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8345_tdk.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2100\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/alimentations-dc-programmables-demi-rack-1u-1500-w\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/alimentations-dc-programmables-demi-rack-1u-1500-w\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Alimentations DC programmables demi-rack 1U 1500 W\",\"datePublished\":\"2019-12-23T22:31:44+00:00\",\"dateModified\":\"2019-12-23T22:31:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/alimentations-dc-programmables-demi-rack-1u-1500-w\/\"},\"wordCount\":253,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/alimentations-dc-programmables-demi-rack-1u-1500-w\/\",\"url\":\"https:\/\/www.eenewseurope.com\/fr\/alimentations-dc-programmables-demi-rack-1u-1500-w\/\",\"name\":\"Alimentations DC programmables demi-rack 1U 1500 W -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2019-12-23T22:31:44+00:00\",\"dateModified\":\"2019-12-23T22:31:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/alimentations-dc-programmables-demi-rack-1u-1500-w\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eenewseurope.com\/fr\/alimentations-dc-programmables-demi-rack-1u-1500-w\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/alimentations-dc-programmables-demi-rack-1u-1500-w\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alimentations DC programmables demi-rack 1U 1500 W\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Alimentations DC programmables demi-rack 1U 1500 W ...","description":"TDK Corporation annonce le lancement de la s\u00e9rie d\u2019alimentations DC programmables GH1.5kW d\u2019un demi-rack de large et de 1U de haut, d\u2019une puissance...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/67640\/","og_locale":"fr_FR","og_type":"article","og_title":"Alimentations DC programmables demi-rack 1U 1500 W","og_description":"TDK Corporation annonce le lancement de la s\u00e9rie d\u2019alimentations DC programmables GH1.5kW d\u2019un demi-rack de large et de 1U de haut, d\u2019une puissance assign\u00e9e de 1 500 W. Ce dernier n\u00e9 de la s\u00e9rie GENESYS+ de TDK-Lambda offre des fonctionnalit\u00e9s et une programmation identiques \u00e0 celles des mod\u00e8les standards de 1,7 kW \u00e0 15 kW en rack entier. Elles peuvent \u00eatre utilis\u00e9es soit sur table soit en baie dans diverses applications comme les Tests &amp; Mesure sur composants (Burn-in), dans l\u2019 automobile et l\u2019a\u00e9ronautique, la fabrication de semi-conducteurs, les simulateurs de batteries et de panneaux solaires, le placage, ou encore le traitement des eaux.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/67640\/","og_site_name":"EENewsEurope","article_published_time":"2019-12-23T22:31:44+00:00","og_image":[{"width":2100,"height":1500,"url":"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8345_tdk.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eenewseurope.com\/fr\/alimentations-dc-programmables-demi-rack-1u-1500-w\/#article","isPartOf":{"@id":"https:\/\/www.eenewseurope.com\/fr\/alimentations-dc-programmables-demi-rack-1u-1500-w\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Alimentations DC programmables demi-rack 1U 1500 W","datePublished":"2019-12-23T22:31:44+00:00","dateModified":"2019-12-23T22:31:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eenewseurope.com\/fr\/alimentations-dc-programmables-demi-rack-1u-1500-w\/"},"wordCount":253,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.eenewseurope.com\/fr\/alimentations-dc-programmables-demi-rack-1u-1500-w\/","url":"https:\/\/www.eenewseurope.com\/fr\/alimentations-dc-programmables-demi-rack-1u-1500-w\/","name":"Alimentations DC programmables demi-rack 1U 1500 W -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2019-12-23T22:31:44+00:00","dateModified":"2019-12-23T22:31:44+00:00","breadcrumb":{"@id":"https:\/\/www.eenewseurope.com\/fr\/alimentations-dc-programmables-demi-rack-1u-1500-w\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eenewseurope.com\/fr\/alimentations-dc-programmables-demi-rack-1u-1500-w\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eenewseurope.com\/fr\/alimentations-dc-programmables-demi-rack-1u-1500-w\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Alimentations DC programmables demi-rack 1U 1500 W"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/67640"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=67640"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/67640\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/67641"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=67640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=67640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=67640"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=67640"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=67640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}