{"id":67336,"date":"2020-01-06T08:34:44","date_gmt":"2020-01-06T08:34:44","guid":{"rendered":"https:\/\/\/modules-can-fd-robustes-avec-e-s\/"},"modified":"2020-01-06T08:34:44","modified_gmt":"2020-01-06T08:34:44","slug":"modules-can-fd-robustes-avec-e-s","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/modules-can-fd-robustes-avec-e-s\/","title":{"rendered":"Modules CAN FD robustes avec E\/S"},"content":{"rendered":"<p>La carte m\u00e8re PCAN-MicroMod FD Analog 1 met l&rsquo;accent sur les entr\u00e9es et sorties analogiques, parmi lesquelles 8 entr\u00e9es ont une r\u00e9solution de 16 bits. Sur les versions num\u00e9riques des cartes m\u00e8res, 8 sorties sont disponibles sous forme de commutateurs Low-side (Digital 1) ou High-side (Digital 2). Toutes les cartes m\u00e8res ont en commun une entr\u00e9e analogique pour la surveillance de tension jusqu&rsquo;\u00e0 30 Volts et deux sorties fr\u00e9quence suppl\u00e9mentaires jusqu&rsquo;\u00e0 20 kHz.<\/p>\n<p>Les cartes m\u00e8res avec PCAN-MicroMod FD se configurent ais\u00e9ment avec un logiciel Windows fourni et la configuration est ensuite transmise via le bus CAN. Les cartes m\u00e8res fonctionnent alors comme des n\u0153uds CAN ind\u00e9pendants sur le r\u00e9seau. Le c\u00e2blage des appareils s&rsquo;effectue via des connecteurs \u00e0 ressort. Le fonctionnement est possible dans la plage de temp\u00e9rature \u00e9tendue de -40 \u00e0 +85 \u00b0C.<\/p>\n<p><a href=\"http:\/\/www.peak-system.com\">www.peak-system.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En plus d\u2019\u00eatre utilisable comme module enfichable dans les d\u00e9veloppements internes, le nouveau module d&rsquo;E\/S PCAN-MicroMod FD de PEAK-System est d\u00e9sormais \u00e9galement disponible avec des cartes m\u00e8res pr\u00eates \u00e0 l&#8217;emploi, dans des bo\u00eetiers en profil\u00e9s d&rsquo;aluminium noir. Ces modules offrent diff\u00e9rentes variantes de p\u00e9riph\u00e9riques pour r\u00e9pondre aux diverses exigences sp\u00e9cifiques. L&rsquo;\u00e9change de donn\u00e9es s&rsquo;effectue via CAN FD, norme totalement compatible de mani\u00e8re descendante avec CAN 2.0 classique.<\/p>\n","protected":false},"author":9,"featured_media":67337,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-67336","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Modules CAN FD robustes avec E\/S ...<\/title>\n<meta name=\"description\" content=\"En plus d\u2019\u00eatre utilisable comme module enfichable dans les d\u00e9veloppements internes, le nouveau module d&#039;E\/S PCAN-MicroMod FD de PEAK-System est...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/67336\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Modules CAN FD robustes avec E\/S\" \/>\n<meta property=\"og:description\" content=\"En plus d\u2019\u00eatre utilisable comme module enfichable dans les d\u00e9veloppements internes, le nouveau module d&#039;E\/S PCAN-MicroMod FD de PEAK-System est d\u00e9sormais \u00e9galement disponible avec des cartes m\u00e8res pr\u00eates \u00e0 l&#039;emploi, dans des bo\u00eetiers en profil\u00e9s d&#039;aluminium noir. Ces modules offrent diff\u00e9rentes variantes de p\u00e9riph\u00e9riques pour r\u00e9pondre aux diverses exigences sp\u00e9cifiques. L&#039;\u00e9change de donn\u00e9es s&#039;effectue via CAN FD, norme totalement compatible de mani\u00e8re descendante avec CAN 2.0 classique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/67336\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-06T08:34:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8360_peak-system.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1486\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/modules-can-fd-robustes-avec-e-s\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/modules-can-fd-robustes-avec-e-s\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Modules CAN FD robustes avec E\/S\",\"datePublished\":\"2020-01-06T08:34:44+00:00\",\"dateModified\":\"2020-01-06T08:34:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/modules-can-fd-robustes-avec-e-s\/\"},\"wordCount\":154,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/modules-can-fd-robustes-avec-e-s\/\",\"url\":\"https:\/\/www.eenewseurope.com\/fr\/modules-can-fd-robustes-avec-e-s\/\",\"name\":\"Modules CAN FD robustes avec E\/S -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2020-01-06T08:34:44+00:00\",\"dateModified\":\"2020-01-06T08:34:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/modules-can-fd-robustes-avec-e-s\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eenewseurope.com\/fr\/modules-can-fd-robustes-avec-e-s\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/modules-can-fd-robustes-avec-e-s\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Modules CAN FD robustes avec E\/S\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Modules CAN FD robustes avec E\/S ...","description":"En plus d\u2019\u00eatre utilisable comme module enfichable dans les d\u00e9veloppements internes, le nouveau module d'E\/S PCAN-MicroMod FD de PEAK-System est...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/67336\/","og_locale":"fr_FR","og_type":"article","og_title":"Modules CAN FD robustes avec E\/S","og_description":"En plus d\u2019\u00eatre utilisable comme module enfichable dans les d\u00e9veloppements internes, le nouveau module d'E\/S PCAN-MicroMod FD de PEAK-System est d\u00e9sormais \u00e9galement disponible avec des cartes m\u00e8res pr\u00eates \u00e0 l'emploi, dans des bo\u00eetiers en profil\u00e9s d'aluminium noir. Ces modules offrent diff\u00e9rentes variantes de p\u00e9riph\u00e9riques pour r\u00e9pondre aux diverses exigences sp\u00e9cifiques. L'\u00e9change de donn\u00e9es s'effectue via CAN FD, norme totalement compatible de mani\u00e8re descendante avec CAN 2.0 classique.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/67336\/","og_site_name":"EENewsEurope","article_published_time":"2020-01-06T08:34:44+00:00","og_image":[{"width":1920,"height":1486,"url":"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8360_peak-system.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eenewseurope.com\/fr\/modules-can-fd-robustes-avec-e-s\/#article","isPartOf":{"@id":"https:\/\/www.eenewseurope.com\/fr\/modules-can-fd-robustes-avec-e-s\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Modules CAN FD robustes avec E\/S","datePublished":"2020-01-06T08:34:44+00:00","dateModified":"2020-01-06T08:34:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eenewseurope.com\/fr\/modules-can-fd-robustes-avec-e-s\/"},"wordCount":154,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.eenewseurope.com\/fr\/modules-can-fd-robustes-avec-e-s\/","url":"https:\/\/www.eenewseurope.com\/fr\/modules-can-fd-robustes-avec-e-s\/","name":"Modules CAN FD robustes avec E\/S -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2020-01-06T08:34:44+00:00","dateModified":"2020-01-06T08:34:44+00:00","breadcrumb":{"@id":"https:\/\/www.eenewseurope.com\/fr\/modules-can-fd-robustes-avec-e-s\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eenewseurope.com\/fr\/modules-can-fd-robustes-avec-e-s\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eenewseurope.com\/fr\/modules-can-fd-robustes-avec-e-s\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Modules CAN FD robustes avec E\/S"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/67336"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=67336"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/67336\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/67337"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=67336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=67336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=67336"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=67336"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=67336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}