{"id":64342,"date":"2020-02-12T22:45:44","date_gmt":"2020-02-12T22:45:44","guid":{"rendered":"https:\/\/\/microchip-et-arrow-electronics-annoncent-leur-collaboration-dans-le-domaine-de-la-securite-iot\/"},"modified":"2020-02-12T22:45:44","modified_gmt":"2020-02-12T22:45:44","slug":"microchip-et-arrow-electronics-annoncent-leur-collaboration-dans-le-domaine-de-la-securite-iot","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/microchip-et-arrow-electronics-annoncent-leur-collaboration-dans-le-domaine-de-la-securite-iot\/","title":{"rendered":"Microchip et Arrow Electronics annoncent leur collaboration dans le domaine de la s\u00e9curit\u00e9 IoT"},"content":{"rendered":"<p>Selon le NIST, les risques li\u00e9s \u00e0 la cybers\u00e9curit\u00e9 et \u00e0 la protection de la vie priv\u00e9e pour les dispositifs IoT peuvent \u00eatre envisag\u00e9s en fonction de trois objectifs de haut niveau en mati\u00e8re d\u2019att\u00e9nuation des risques, \u00e0 savoir la protection de la s\u00e9curit\u00e9 des dispositifs, la protection de la s\u00e9curit\u00e9 des donn\u00e9es et la protection de la vie priv\u00e9e des personnes. Arrow compl\u00e9tera le portefeuille de micropuces intelligentes, connect\u00e9es et s\u00e9curis\u00e9es par des services d\u2019ing\u00e9nierie afin que les fabricants d\u2019\u00e9quipements d\u2019origine (OEM) puissent r\u00e9duire leur d\u00e9lai de commercialisation et r\u00e9pondre aux exigences de la r\u00e9cente l\u00e9gislation gouvernementale2&nbsp;et des lignes directrices du NIST en mati\u00e8re de s\u00e9curit\u00e9 de l\u2019IoT. \u00ab&nbsp;La technologie, de mani\u00e8re omnipr\u00e9sente, est int\u00e9gr\u00e9e \u00e0 tout. Chaque branche d\u2019activit\u00e9 et chaque syst\u00e8me est fondamentalement fa\u00e7onn\u00e9 par la technologie de pointe connect\u00e9e &#8211; cela se passe dans nos foyers, notre travail et nos usines&nbsp;\u00bb, a d\u00e9clar\u00e9 Mitch Little, vice-pr\u00e9sident principal charg\u00e9 de l\u2019engagement des clients au niveau mondial chez Microchip Technology.&nbsp;\u00ab&nbsp;Ces syst\u00e8mes de pointe intelligents effectuent des op\u00e9rations fondamentales et critiques, et ils doivent \u00eatre s\u00e9curis\u00e9s&nbsp;\u00bb.<\/p>\n<p>La gamme de produits s\u00e9curis\u00e9s de Microchip comprend des fonctions de base&nbsp;et&nbsp;de communication s\u00e9curis\u00e9es, d\u2019authentification crypt\u00e9e, de gestion des certificats, de fourniture de services dans le cloud, de s\u00e9curit\u00e9 des donn\u00e9es, de services de cryptage, de d\u00e9marrage s\u00e9curis\u00e9 et de protection IP.&nbsp;<\/p>\n<p>\u00ab&nbsp;Les \u00e9quipementiers adoptent la collaboration en mati\u00e8re de services d\u2019ing\u00e9nierie afin de pouvoir&nbsp;accroitre&nbsp;les \u00e9quipes de travail internes pour faire face \u00e0 l\u2019int\u00e9gration des nouvelles technologies et r\u00e9duire les risques dans les domaines de la certification et de la conformit\u00e9&nbsp;\u00bb, a d\u00e9clar\u00e9 David West, vice-pr\u00e9sident principal d\u2019Arrow.&nbsp;\u00ab&nbsp;Les applications et les syst\u00e8mes informatiques de pointe doivent maintenant \u00eatre enti\u00e8rement s\u00e9curis\u00e9s, depuis la couche des capteurs jusqu\u2019\u00e0 l\u2019entreprise&nbsp;\u00bb.<\/p>\n<p>La premi\u00e8re plateforme s\u00e9curis\u00e9e de bout en bout issue de cette collaboration est le Shield96.&nbsp;Elle&nbsp;permet aux \u00e9quipementiers d\u2019int\u00e9grer les bases de s\u00e9curit\u00e9 n\u00e9cessaires dans la conception de r\u00e9f\u00e9rences.&nbsp;<\/p>\n<h3 class=\"title\"><a href=\"https:\/\/www.electronique-eci.com\/news\/microchip-simplifie-la-securite-materielle-de-linternet-des-objets\">Microchip simplifie la s\u00e9curit\u00e9 mat\u00e9rielle de l\u2019Internet des objets<\/a><\/h3>\n<h3 class=\"title\"><a href=\"https:\/\/www.electronique-eci.com\/news\/arrow-electronics-elargit-sa-gamme-de-capteurs-avec-invensense\">Arrow Electronics \u00e9largit sa gamme de capteurs avec InvenSense <\/a><\/h3>\n<h3 class=\"title\"><a href=\"https:\/\/www.electronique-eci.com\/news\/microchip-simplifie-les-exigences-de-securite-fonctionnelle-grace-ses-outils-mplab-certifies\">Microchip simplifie les exigences de s\u00e9curit\u00e9 fonctionnelle gr\u00e2ce \u00e0 ses outils MPLAB certifi\u00e9s T\u00dcV S\u00dcD<\/a><\/h3>\n<h3 class=\"title\"><a href=\"https:\/\/www.electronique-eci.com\/news\/solutions-iot-arrow-electronics-collabore-avec-microshare\">Solutions IoT : Arrow Electronics collabore avec Microshare<\/a><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Microchip Technology et Arrow Electronics ont annonc\u00e9 une collaboration dans le domaine des services d\u2019ing\u00e9nierie afin de simplifier la connectivit\u00e9 et la s\u00e9curit\u00e9 sur les march\u00e9s de l\u2019industrie, des b\u00e2timents intelligents et de l\u2019\u00e9nergie. <\/p>\n","protected":false},"author":9,"featured_media":64343,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-64342","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Microchip et Arrow Electronics annoncent leur collaboration dan...<\/title>\n<meta name=\"description\" content=\"Microchip Technology et Arrow Electronics ont annonc\u00e9 une collaboration dans le domaine des services d\u2019ing\u00e9nierie afin de simplifier la connectivit\u00e9 et...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/64342\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Microchip et Arrow Electronics annoncent leur collaboration dans le domaine de la s\u00e9curit\u00e9 IoT\" \/>\n<meta property=\"og:description\" content=\"Microchip Technology et Arrow Electronics ont annonc\u00e9 une collaboration dans le domaine des services d\u2019ing\u00e9nierie afin de simplifier la connectivit\u00e9 et la s\u00e9curit\u00e9 sur les march\u00e9s de l\u2019industrie, des b\u00e2timents intelligents et de l\u2019\u00e9nergie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/64342\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-12T22:45:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8427_microchip_et_arrow-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1703\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/microchip-et-arrow-electronics-annoncent-leur-collaboration-dans-le-domaine-de-la-securite-iot\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/microchip-et-arrow-electronics-annoncent-leur-collaboration-dans-le-domaine-de-la-securite-iot\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Microchip et Arrow Electronics annoncent leur collaboration dans le domaine de la s\u00e9curit\u00e9 IoT\",\"datePublished\":\"2020-02-12T22:45:44+00:00\",\"dateModified\":\"2020-02-12T22:45:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/microchip-et-arrow-electronics-annoncent-leur-collaboration-dans-le-domaine-de-la-securite-iot\/\"},\"wordCount\":472,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/microchip-et-arrow-electronics-annoncent-leur-collaboration-dans-le-domaine-de-la-securite-iot\/\",\"url\":\"https:\/\/www.eenewseurope.com\/fr\/microchip-et-arrow-electronics-annoncent-leur-collaboration-dans-le-domaine-de-la-securite-iot\/\",\"name\":\"Microchip et Arrow Electronics annoncent leur collaboration dans le domaine de la s\u00e9curit\u00e9 IoT -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2020-02-12T22:45:44+00:00\",\"dateModified\":\"2020-02-12T22:45:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/microchip-et-arrow-electronics-annoncent-leur-collaboration-dans-le-domaine-de-la-securite-iot\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eenewseurope.com\/fr\/microchip-et-arrow-electronics-annoncent-leur-collaboration-dans-le-domaine-de-la-securite-iot\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/microchip-et-arrow-electronics-annoncent-leur-collaboration-dans-le-domaine-de-la-securite-iot\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Microchip et Arrow Electronics annoncent leur collaboration dans le domaine de la s\u00e9curit\u00e9 IoT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Microchip et Arrow Electronics annoncent leur collaboration dan...","description":"Microchip Technology et Arrow Electronics ont annonc\u00e9 une collaboration dans le domaine des services d\u2019ing\u00e9nierie afin de simplifier la connectivit\u00e9 et...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/64342\/","og_locale":"fr_FR","og_type":"article","og_title":"Microchip et Arrow Electronics annoncent leur collaboration dans le domaine de la s\u00e9curit\u00e9 IoT","og_description":"Microchip Technology et Arrow Electronics ont annonc\u00e9 une collaboration dans le domaine des services d\u2019ing\u00e9nierie afin de simplifier la connectivit\u00e9 et la s\u00e9curit\u00e9 sur les march\u00e9s de l\u2019industrie, des b\u00e2timents intelligents et de l\u2019\u00e9nergie.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/64342\/","og_site_name":"EENewsEurope","article_published_time":"2020-02-12T22:45:44+00:00","og_image":[{"width":2560,"height":1703,"url":"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8427_microchip_et_arrow-scaled.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eenewseurope.com\/fr\/microchip-et-arrow-electronics-annoncent-leur-collaboration-dans-le-domaine-de-la-securite-iot\/#article","isPartOf":{"@id":"https:\/\/www.eenewseurope.com\/fr\/microchip-et-arrow-electronics-annoncent-leur-collaboration-dans-le-domaine-de-la-securite-iot\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Microchip et Arrow Electronics annoncent leur collaboration dans le domaine de la s\u00e9curit\u00e9 IoT","datePublished":"2020-02-12T22:45:44+00:00","dateModified":"2020-02-12T22:45:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eenewseurope.com\/fr\/microchip-et-arrow-electronics-annoncent-leur-collaboration-dans-le-domaine-de-la-securite-iot\/"},"wordCount":472,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.eenewseurope.com\/fr\/microchip-et-arrow-electronics-annoncent-leur-collaboration-dans-le-domaine-de-la-securite-iot\/","url":"https:\/\/www.eenewseurope.com\/fr\/microchip-et-arrow-electronics-annoncent-leur-collaboration-dans-le-domaine-de-la-securite-iot\/","name":"Microchip et Arrow Electronics annoncent leur collaboration dans le domaine de la s\u00e9curit\u00e9 IoT -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2020-02-12T22:45:44+00:00","dateModified":"2020-02-12T22:45:44+00:00","breadcrumb":{"@id":"https:\/\/www.eenewseurope.com\/fr\/microchip-et-arrow-electronics-annoncent-leur-collaboration-dans-le-domaine-de-la-securite-iot\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eenewseurope.com\/fr\/microchip-et-arrow-electronics-annoncent-leur-collaboration-dans-le-domaine-de-la-securite-iot\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eenewseurope.com\/fr\/microchip-et-arrow-electronics-annoncent-leur-collaboration-dans-le-domaine-de-la-securite-iot\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Microchip et Arrow Electronics annoncent leur collaboration dans le domaine de la s\u00e9curit\u00e9 IoT"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/64342"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=64342"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/64342\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/64343"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=64342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=64342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=64342"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=64342"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=64342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}