{"id":63742,"date":"2020-02-19T14:31:44","date_gmt":"2020-02-19T14:31:44","guid":{"rendered":"https:\/\/\/plateforme-de-reference-de-servovariateur\/"},"modified":"2020-02-19T14:31:44","modified_gmt":"2020-02-19T14:31:44","slug":"plateforme-de-reference-de-servovariateur","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/plateforme-de-reference-de-servovariateur\/","title":{"rendered":"Plateforme de r\u00e9f\u00e9rence de servovariateur"},"content":{"rendered":"<p>Au c\u0153ur de la plateforme Servo Drive RM se trouve un microcontr\u00f4leur Toshiba \u00e0 c\u0153ur Arm Cortex-M4 avec FPU, mont\u00e9 sur une carte d\u2019extension interchangeable. Cela constitue un p\u00e9riph\u00e9rique Advanced Vector Engine. Gr\u00e2ce \u00e0 ce moteur vectoriel avanc\u00e9 qui impl\u00e9mente les calculs vectoriels en dur, ainsi qu&rsquo;\u00e0 son couplage \u00e9troit avec le CAN, le variateur programmable, et le bloc encodeur, la charge du CPU se voit consid\u00e9rablement r\u00e9duite dans les applications de commande moteur. Non seulement cela laisse disponible une grande capacit\u00e9 de traitement pour d&rsquo;autres t\u00e2ches, mais cela r\u00e9duit aussi le temps de d\u00e9veloppement n\u00e9cessaire \u00e0 la mise en oeuvre du micrologiciel de commande vectorielle du moteur.&nbsp;La plateforme de base est extensible et dispose de connecteurs pour jusqu\u2019\u00e0 trois \u00e9tages de puissance, ainsi qu&rsquo;une interface \u00e0 la norme Arduino. La communication avec le syst\u00e8me h\u00f4te peut se faire par le biais de cartes Arduino, d\u2019un bus CAN, d\u2019Ethernet, ou encore gr\u00e2ce au module Bluetooth&nbsp;5 embarqu\u00e9.<\/p>\n<p>Un \u00e9tage de puissance basse tension pour moteurs \u00e0 courant continu sans balais (BLDC pour Brushless DC en anglais) d\u2019une puissance de 20&nbsp;W \u00e0 200&nbsp;W, avec une tension d\u2019alimentation jusqu&rsquo;\u00e0 48&nbsp;V, est \u00e9galement disponible. Il est \u00e9quip\u00e9 de six MOSFET TPW3R70APL issus du processus silicium derni\u00e8re g\u00e9n\u00e9ration U-MOS IX-H, qui pr\u00e9sentent une r\u00e9sistance \u00e0 l\u2019\u00e9tat passant RDS(ON)&nbsp;de 3.7&nbsp;m\u03a9 et qui peuvent dissiper jusqu\u2019\u00e0 170&nbsp;W. Ils sont log\u00e9s en bo\u00eetier compact \u00e0 refroidissement double-face, DSOP Advance de 5,0&nbsp;x&nbsp;6,0&nbsp;x&nbsp;0,73&nbsp;mm.<br \/>\n<a href=\"http:\/\/www.toshiba.semicon-storage.com\/eu\/company\/news.html\">www.toshiba.semicon-storage.com\/eu<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00e9pondant \u00e0 l&rsquo;int\u00e9r\u00eat croissant pour les solutions Industry 4.0 dans lesquelles sont int\u00e9gr\u00e9s des servomoteurs, la plateforme de r\u00e9f\u00e9rence de commande moteur multicanaux modulaire Servo Drive RM annonc\u00e9e par Toshiba Electronics Europe cible aussi les applications n\u00e9cessitant un contr\u00f4le pr\u00e9cis et un bon rendement \u00e9nerg\u00e9tique, comme les technologies d&rsquo;impression 3D additive. <\/p>\n","protected":false},"author":9,"featured_media":63743,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-63742","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Plateforme de r\u00e9f\u00e9rence de servovariateur ...<\/title>\n<meta name=\"description\" content=\"R\u00e9pondant \u00e0 l&#039;int\u00e9r\u00eat croissant pour les solutions Industry 4.0 dans lesquelles sont int\u00e9gr\u00e9s des servomoteurs, la plateforme de r\u00e9f\u00e9rence de...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/63742\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plateforme de r\u00e9f\u00e9rence de servovariateur\" \/>\n<meta property=\"og:description\" content=\"R\u00e9pondant \u00e0 l&#039;int\u00e9r\u00eat croissant pour les solutions Industry 4.0 dans lesquelles sont int\u00e9gr\u00e9s des servomoteurs, la plateforme de r\u00e9f\u00e9rence de commande moteur multicanaux modulaire Servo Drive RM annonc\u00e9e par Toshiba Electronics Europe cible aussi les applications n\u00e9cessitant un contr\u00f4le pr\u00e9cis et un bon rendement \u00e9nerg\u00e9tique, comme les technologies d&#039;impression 3D additive.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/63742\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-19T14:31:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8444_toshiba.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/plateforme-de-reference-de-servovariateur\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/plateforme-de-reference-de-servovariateur\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Plateforme de r\u00e9f\u00e9rence de servovariateur\",\"datePublished\":\"2020-02-19T14:31:44+00:00\",\"dateModified\":\"2020-02-19T14:31:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/plateforme-de-reference-de-servovariateur\/\"},\"wordCount\":288,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/plateforme-de-reference-de-servovariateur\/\",\"url\":\"https:\/\/www.eenewseurope.com\/fr\/plateforme-de-reference-de-servovariateur\/\",\"name\":\"Plateforme de r\u00e9f\u00e9rence de servovariateur -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2020-02-19T14:31:44+00:00\",\"dateModified\":\"2020-02-19T14:31:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/plateforme-de-reference-de-servovariateur\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eenewseurope.com\/fr\/plateforme-de-reference-de-servovariateur\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/plateforme-de-reference-de-servovariateur\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plateforme de r\u00e9f\u00e9rence de servovariateur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Plateforme de r\u00e9f\u00e9rence de servovariateur ...","description":"R\u00e9pondant \u00e0 l'int\u00e9r\u00eat croissant pour les solutions Industry 4.0 dans lesquelles sont int\u00e9gr\u00e9s des servomoteurs, la plateforme de r\u00e9f\u00e9rence de...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/63742\/","og_locale":"fr_FR","og_type":"article","og_title":"Plateforme de r\u00e9f\u00e9rence de servovariateur","og_description":"R\u00e9pondant \u00e0 l'int\u00e9r\u00eat croissant pour les solutions Industry 4.0 dans lesquelles sont int\u00e9gr\u00e9s des servomoteurs, la plateforme de r\u00e9f\u00e9rence de commande moteur multicanaux modulaire Servo Drive RM annonc\u00e9e par Toshiba Electronics Europe cible aussi les applications n\u00e9cessitant un contr\u00f4le pr\u00e9cis et un bon rendement \u00e9nerg\u00e9tique, comme les technologies d'impression 3D additive.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/63742\/","og_site_name":"EENewsEurope","article_published_time":"2020-02-19T14:31:44+00:00","og_image":[{"width":700,"height":500,"url":"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8444_toshiba.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eenewseurope.com\/fr\/plateforme-de-reference-de-servovariateur\/#article","isPartOf":{"@id":"https:\/\/www.eenewseurope.com\/fr\/plateforme-de-reference-de-servovariateur\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Plateforme de r\u00e9f\u00e9rence de servovariateur","datePublished":"2020-02-19T14:31:44+00:00","dateModified":"2020-02-19T14:31:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eenewseurope.com\/fr\/plateforme-de-reference-de-servovariateur\/"},"wordCount":288,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.eenewseurope.com\/fr\/plateforme-de-reference-de-servovariateur\/","url":"https:\/\/www.eenewseurope.com\/fr\/plateforme-de-reference-de-servovariateur\/","name":"Plateforme de r\u00e9f\u00e9rence de servovariateur -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2020-02-19T14:31:44+00:00","dateModified":"2020-02-19T14:31:44+00:00","breadcrumb":{"@id":"https:\/\/www.eenewseurope.com\/fr\/plateforme-de-reference-de-servovariateur\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eenewseurope.com\/fr\/plateforme-de-reference-de-servovariateur\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eenewseurope.com\/fr\/plateforme-de-reference-de-servovariateur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Plateforme de r\u00e9f\u00e9rence de servovariateur"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/63742"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=63742"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/63742\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/63743"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=63742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=63742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=63742"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=63742"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=63742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}