{"id":60495,"date":"2020-03-24T07:31:44","date_gmt":"2020-03-24T07:31:44","guid":{"rendered":"https:\/\/\/systeme-de-cablage-complet-optimise-pour-la-technologie-400gbase-sr8\/"},"modified":"2020-03-24T07:31:44","modified_gmt":"2020-03-24T07:31:44","slug":"systeme-de-cablage-complet-optimise-pour-la-technologie-400gbase-sr8","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/systeme-de-cablage-complet-optimise-pour-la-technologie-400gbase-sr8\/","title":{"rendered":"Syst\u00e8me de c\u00e2blage complet optimis\u00e9 pour la technologie 400GBASE-SR8"},"content":{"rendered":"<p>PreCONNECT&nbsp;SEDECIM est le syst\u00e8me de c\u00e2blage&nbsp;id\u00e9al&nbsp;pour la technologie&nbsp;400GBASE-SR8&nbsp;\u00bb, explique Harald Jungb\u00e4ck,&nbsp;chef&nbsp;produit&nbsp;pour les syst\u00e8mes de c\u00e2blage&nbsp;pour&nbsp;data centers&nbsp;chez Rosenberger OSI.<\/p>\n<p>Seize fibres pour une infrastructure&nbsp;hautes&nbsp;performances&nbsp;dans les&nbsp;data centers<\/p>\n<p>Le syst\u00e8me de connexion du&nbsp;PreCONNECT&nbsp;SEDECIM est le MTP\/MPO&nbsp;16, qui est \u00e9galement&nbsp;l&rsquo;interface&nbsp;d\u00e9pendant&nbsp;du support (MDI) des \u00e9metteurs-r\u00e9cepteurs 400GBASE-SR8. Il est&nbsp;compos\u00e9&nbsp;de&nbsp;16 fibres multimodes OM4 dispos\u00e9es en ligne.&nbsp;L&rsquo;enfichage du connecteur&nbsp;permet le transfert de donn\u00e9es&nbsp;\u00e0&nbsp;400 GBits\/s via huit canaux&nbsp;de transmission&nbsp;full&nbsp;duplex&nbsp;(voies)&nbsp;en&nbsp;parall\u00e8le&nbsp;de&nbsp;50 GBits&nbsp;chacun avec codage PAM4 (8x50G=400G) sur une&nbsp;distance&nbsp;de&nbsp;100 m\u00e8tres.&nbsp;En fonction des exigences&nbsp;de&nbsp;l&rsquo;op\u00e9rateur de&nbsp;datacenter, les syst\u00e8mes de panneaux&nbsp;19&Prime;&nbsp;apportent&nbsp;un gain d&rsquo;espace&nbsp;optimal&nbsp;gr\u00e2ce \u00e0 une densit\u00e9 de ports maximale&nbsp;ainsi qu&rsquo;une maintenance&nbsp;ais\u00e9e&nbsp;gr\u00e2ce&nbsp;aux tiroirs coulissants&nbsp;de la solution&nbsp;Data Center Panel DCP.<\/p>\n<p><a href=\"http:\/\/www.rosenberger.com\/osi%20\/t%20_blank\">www.rosenberger.com\/osi<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La solution PreCONNECT SEDECIM d\u00e9velopp\u00e9 par Rosenberger OSI est un syst\u00e8me complet pour le c\u00e2blage des transmissions de donn\u00e9es optiques structur\u00e9 en parall\u00e8le et optimis\u00e9 pour la technologie 400GBASE-SR8. \u00ab En raison d&rsquo;une demande de d\u00e9bit de transmission en constante augmentation dans les datacenters, les fabricants d&rsquo;\u00e9metteurs-r\u00e9cepteurs mettent constamment sur le march\u00e9 de nouvelles technologies de transmission. <\/p>\n","protected":false},"author":9,"featured_media":60496,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-60495","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Syst\u00e8me de c\u00e2blage complet optimis\u00e9 pour la technologie 400G...<\/title>\n<meta name=\"description\" content=\"La solution PreCONNECT SEDECIM d\u00e9velopp\u00e9 par Rosenberger OSI est un syst\u00e8me complet pour le c\u00e2blage des transmissions de donn\u00e9es optiques structur\u00e9 en...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/60495\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Syst\u00e8me de c\u00e2blage complet optimis\u00e9 pour la technologie 400GBASE-SR8\" \/>\n<meta property=\"og:description\" content=\"La solution PreCONNECT SEDECIM d\u00e9velopp\u00e9 par Rosenberger OSI est un syst\u00e8me complet pour le c\u00e2blage des transmissions de donn\u00e9es optiques structur\u00e9 en parall\u00e8le et optimis\u00e9 pour la technologie 400GBASE-SR8. \u00ab En raison d&#039;une demande de d\u00e9bit de transmission en constante augmentation dans les datacenters, les fabricants d&#039;\u00e9metteurs-r\u00e9cepteurs mettent constamment sur le march\u00e9 de nouvelles technologies de transmission.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/60495\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-24T07:31:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8524_rosenberger_osi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1808\" \/>\n\t<meta property=\"og:image:height\" content=\"1105\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/systeme-de-cablage-complet-optimise-pour-la-technologie-400gbase-sr8\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/systeme-de-cablage-complet-optimise-pour-la-technologie-400gbase-sr8\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Syst\u00e8me de c\u00e2blage complet optimis\u00e9 pour la technologie 400GBASE-SR8\",\"datePublished\":\"2020-03-24T07:31:44+00:00\",\"dateModified\":\"2020-03-24T07:31:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/systeme-de-cablage-complet-optimise-pour-la-technologie-400gbase-sr8\/\"},\"wordCount\":236,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/systeme-de-cablage-complet-optimise-pour-la-technologie-400gbase-sr8\/\",\"url\":\"https:\/\/www.eenewseurope.com\/fr\/systeme-de-cablage-complet-optimise-pour-la-technologie-400gbase-sr8\/\",\"name\":\"Syst\u00e8me de c\u00e2blage complet optimis\u00e9 pour la technologie 400GBASE-SR8 -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2020-03-24T07:31:44+00:00\",\"dateModified\":\"2020-03-24T07:31:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/systeme-de-cablage-complet-optimise-pour-la-technologie-400gbase-sr8\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eenewseurope.com\/fr\/systeme-de-cablage-complet-optimise-pour-la-technologie-400gbase-sr8\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/systeme-de-cablage-complet-optimise-pour-la-technologie-400gbase-sr8\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Syst\u00e8me de c\u00e2blage complet optimis\u00e9 pour la technologie 400GBASE-SR8\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Syst\u00e8me de c\u00e2blage complet optimis\u00e9 pour la technologie 400G...","description":"La solution PreCONNECT SEDECIM d\u00e9velopp\u00e9 par Rosenberger OSI est un syst\u00e8me complet pour le c\u00e2blage des transmissions de donn\u00e9es optiques structur\u00e9 en...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/60495\/","og_locale":"fr_FR","og_type":"article","og_title":"Syst\u00e8me de c\u00e2blage complet optimis\u00e9 pour la technologie 400GBASE-SR8","og_description":"La solution PreCONNECT SEDECIM d\u00e9velopp\u00e9 par Rosenberger OSI est un syst\u00e8me complet pour le c\u00e2blage des transmissions de donn\u00e9es optiques structur\u00e9 en parall\u00e8le et optimis\u00e9 pour la technologie 400GBASE-SR8. \u00ab En raison d'une demande de d\u00e9bit de transmission en constante augmentation dans les datacenters, les fabricants d'\u00e9metteurs-r\u00e9cepteurs mettent constamment sur le march\u00e9 de nouvelles technologies de transmission.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/60495\/","og_site_name":"EENewsEurope","article_published_time":"2020-03-24T07:31:44+00:00","og_image":[{"width":1808,"height":1105,"url":"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8524_rosenberger_osi.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eenewseurope.com\/fr\/systeme-de-cablage-complet-optimise-pour-la-technologie-400gbase-sr8\/#article","isPartOf":{"@id":"https:\/\/www.eenewseurope.com\/fr\/systeme-de-cablage-complet-optimise-pour-la-technologie-400gbase-sr8\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Syst\u00e8me de c\u00e2blage complet optimis\u00e9 pour la technologie 400GBASE-SR8","datePublished":"2020-03-24T07:31:44+00:00","dateModified":"2020-03-24T07:31:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eenewseurope.com\/fr\/systeme-de-cablage-complet-optimise-pour-la-technologie-400gbase-sr8\/"},"wordCount":236,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.eenewseurope.com\/fr\/systeme-de-cablage-complet-optimise-pour-la-technologie-400gbase-sr8\/","url":"https:\/\/www.eenewseurope.com\/fr\/systeme-de-cablage-complet-optimise-pour-la-technologie-400gbase-sr8\/","name":"Syst\u00e8me de c\u00e2blage complet optimis\u00e9 pour la technologie 400GBASE-SR8 -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2020-03-24T07:31:44+00:00","dateModified":"2020-03-24T07:31:44+00:00","breadcrumb":{"@id":"https:\/\/www.eenewseurope.com\/fr\/systeme-de-cablage-complet-optimise-pour-la-technologie-400gbase-sr8\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eenewseurope.com\/fr\/systeme-de-cablage-complet-optimise-pour-la-technologie-400gbase-sr8\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eenewseurope.com\/fr\/systeme-de-cablage-complet-optimise-pour-la-technologie-400gbase-sr8\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Syst\u00e8me de c\u00e2blage complet optimis\u00e9 pour la technologie 400GBASE-SR8"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/60495"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=60495"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/60495\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/60496"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=60495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=60495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=60495"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=60495"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=60495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}