{"id":5853,"date":"2021-08-19T16:15:14","date_gmt":"2021-08-19T16:15:14","guid":{"rendered":"https:\/\/\/carte-click-a-capteur-de-pression-differentielle-pour-la-surveillance-de-debit-dair\/"},"modified":"2021-08-19T16:15:14","modified_gmt":"2021-08-19T16:15:14","slug":"carte-click-a-capteur-de-pression-differentielle-pour-la-surveillance-de-debit-dair","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/carte-click-a-capteur-de-pression-differentielle-pour-la-surveillance-de-debit-dair\/","title":{"rendered":"Carte Click \u00e0 capteur de pression diff\u00e9rentielle pour la surveillance de d\u00e9bit d&rsquo;air"},"content":{"rendered":"<p>Id\u00e9al pour les applications m\u00e9dicales sensibles comme les ventilateurs, les spirom\u00e8tres et les \u00e9quipements de diagnostic du sommeil, ainsi que pour certaines utilisations industrielles de pr\u00e9cision, comme la d\u00e9tection de fuites, le capteur de pression diff\u00e9rentielle 2&nbsp;en&nbsp;1 \u00e0 d\u00e9tection de d\u00e9bit, qui est le c\u0153ur de l&rsquo;Air Flow Click, est fabriqu\u00e9 par First&nbsp;Sensor (TE&nbsp;Connectivity). Le capteur de pression LHDULTRAM012UB3, s\u00e9rie LHD ULTRA, mesure le flux thermique d&rsquo;un gaz par le biais de deux canaux \u00e0 micro-d\u00e9bit int\u00e9gr\u00e9s dans la puce du capteur, afin d\u2019obtenir une plage dynamique de d\u00e9tection tr\u00e8s large, allant de 0 \u00e0 1&nbsp;250&nbsp;Pa. Un MCU embarqu\u00e9 associ\u00e9 \u00e0 un CAN 24&nbsp;bits tr\u00e8s pr\u00e9cis assure le traitement du signal, \u00e0 savoir la r\u00e9ponse des deux \u00e9l\u00e9ments de d\u00e9tection, la lin\u00e9arisation, la compensation barom\u00e9trique et la compensation de temp\u00e9rature.<br \/>\nL\u2019Air Flow Click de MIKROE est support\u00e9 par une biblioth\u00e8que conforme mikroSDK, qui comprend plusieurs fonctions simplifiant le d\u00e9veloppement logiciel. Les cartes Click sont \u00e9quip\u00e9es de la prise standard 16&nbsp;broches mikroBUS, invent\u00e9e par MIKROE il y a une dizaine d\u2019ann\u00e9es. Les cartes Click permettent aux ing\u00e9nieurs d\u2019\u00e9tudes de changer facilement de p\u00e9riph\u00e9riques, et d\u2019\u00e9conomiser ainsi des mois de d\u00e9veloppement.<br \/>\n\u00ab&nbsp;Nous sommes tous sous pression, ces temps-ci, mais pour 25&nbsp;dollars seulement, les concepteurs peuvent acheter l\u2019Air Flow Click, un produit enti\u00e8rement test\u00e9, pr\u00eat \u00e0 utiliser dans leur syst\u00e8me.&nbsp;\u00bb commente Nebojsa Matic, Pr\u00e9sident Ex\u00e9cutif de MIKROE. B\u00e9n\u00e9ficiant de remises par quantit\u00e9s, l&rsquo;Air Flow Click rejoint plus de 1&nbsp;000&nbsp;autres cartes de d\u00e9veloppement de p\u00e9riph\u00e9riques Click.<\/p>\n<p><a href=\"https:\/\/www.mikroe.com\/click\">www.mikroe.com\/click<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>MikroElektronika vient de lancer Air Flow Click, une carte de d\u00e9veloppement de p\u00e9riph\u00e9rique de surveillance de d\u00e9bit d&rsquo;air, destin\u00e9e aux applications n\u00e9cessitant une pr\u00e9cision \u00e9lev\u00e9e, une plage de mesure \u00e9tendue, et le c\u00f4t\u00e9 pratique d&rsquo;un dispositif unique. <\/p>\n","protected":false},"author":9,"featured_media":5854,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-5853","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Carte Click \u00e0 capteur de pression diff\u00e9rentielle pour la surv...<\/title>\n<meta name=\"description\" content=\"MikroElektronika vient de lancer Air Flow Click, une carte de d\u00e9veloppement de p\u00e9riph\u00e9rique de surveillance de d\u00e9bit d&#039;air, destin\u00e9e aux applications...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/5853\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carte Click \u00e0 capteur de pression diff\u00e9rentielle pour la surveillance de d\u00e9bit d&#039;air\" \/>\n<meta property=\"og:description\" content=\"MikroElektronika vient de lancer Air Flow Click, une carte de d\u00e9veloppement de p\u00e9riph\u00e9rique de surveillance de d\u00e9bit d&#039;air, destin\u00e9e aux applications n\u00e9cessitant une pr\u00e9cision \u00e9lev\u00e9e, une plage de mesure \u00e9tendue, et le c\u00f4t\u00e9 pratique d&#039;un dispositif unique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/5853\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-19T16:15:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9706_mikroe.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/carte-click-a-capteur-de-pression-differentielle-pour-la-surveillance-de-debit-dair\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/carte-click-a-capteur-de-pression-differentielle-pour-la-surveillance-de-debit-dair\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Carte Click \u00e0 capteur de pression diff\u00e9rentielle pour la surveillance de d\u00e9bit d&rsquo;air\",\"datePublished\":\"2021-08-19T16:15:14+00:00\",\"dateModified\":\"2021-08-19T16:15:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/carte-click-a-capteur-de-pression-differentielle-pour-la-surveillance-de-debit-dair\/\"},\"wordCount\":322,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.eenewseurope.com\/fr\/carte-click-a-capteur-de-pression-differentielle-pour-la-surveillance-de-debit-dair\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/carte-click-a-capteur-de-pression-differentielle-pour-la-surveillance-de-debit-dair\/\",\"url\":\"https:\/\/www.eenewseurope.com\/fr\/carte-click-a-capteur-de-pression-differentielle-pour-la-surveillance-de-debit-dair\/\",\"name\":\"Carte Click \u00e0 capteur de pression diff\u00e9rentielle pour la surveillance de d\u00e9bit d'air -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2021-08-19T16:15:14+00:00\",\"dateModified\":\"2021-08-19T16:15:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/carte-click-a-capteur-de-pression-differentielle-pour-la-surveillance-de-debit-dair\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eenewseurope.com\/fr\/carte-click-a-capteur-de-pression-differentielle-pour-la-surveillance-de-debit-dair\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/carte-click-a-capteur-de-pression-differentielle-pour-la-surveillance-de-debit-dair\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carte Click \u00e0 capteur de pression diff\u00e9rentielle pour la surveillance de d\u00e9bit d&rsquo;air\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Carte Click \u00e0 capteur de pression diff\u00e9rentielle pour la surv...","description":"MikroElektronika vient de lancer Air Flow Click, une carte de d\u00e9veloppement de p\u00e9riph\u00e9rique de surveillance de d\u00e9bit d'air, destin\u00e9e aux applications...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/5853\/","og_locale":"fr_FR","og_type":"article","og_title":"Carte Click \u00e0 capteur de pression diff\u00e9rentielle pour la surveillance de d\u00e9bit d'air","og_description":"MikroElektronika vient de lancer Air Flow Click, une carte de d\u00e9veloppement de p\u00e9riph\u00e9rique de surveillance de d\u00e9bit d'air, destin\u00e9e aux applications n\u00e9cessitant une pr\u00e9cision \u00e9lev\u00e9e, une plage de mesure \u00e9tendue, et le c\u00f4t\u00e9 pratique d'un dispositif unique.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/5853\/","og_site_name":"EENewsEurope","article_published_time":"2021-08-19T16:15:14+00:00","og_image":[{"width":1920,"height":1200,"url":"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9706_mikroe.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eenewseurope.com\/fr\/carte-click-a-capteur-de-pression-differentielle-pour-la-surveillance-de-debit-dair\/#article","isPartOf":{"@id":"https:\/\/www.eenewseurope.com\/fr\/carte-click-a-capteur-de-pression-differentielle-pour-la-surveillance-de-debit-dair\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Carte Click \u00e0 capteur de pression diff\u00e9rentielle pour la surveillance de d\u00e9bit d&rsquo;air","datePublished":"2021-08-19T16:15:14+00:00","dateModified":"2021-08-19T16:15:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eenewseurope.com\/fr\/carte-click-a-capteur-de-pression-differentielle-pour-la-surveillance-de-debit-dair\/"},"wordCount":322,"commentCount":0,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.eenewseurope.com\/fr\/carte-click-a-capteur-de-pression-differentielle-pour-la-surveillance-de-debit-dair\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.eenewseurope.com\/fr\/carte-click-a-capteur-de-pression-differentielle-pour-la-surveillance-de-debit-dair\/","url":"https:\/\/www.eenewseurope.com\/fr\/carte-click-a-capteur-de-pression-differentielle-pour-la-surveillance-de-debit-dair\/","name":"Carte Click \u00e0 capteur de pression diff\u00e9rentielle pour la surveillance de d\u00e9bit d'air -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2021-08-19T16:15:14+00:00","dateModified":"2021-08-19T16:15:14+00:00","breadcrumb":{"@id":"https:\/\/www.eenewseurope.com\/fr\/carte-click-a-capteur-de-pression-differentielle-pour-la-surveillance-de-debit-dair\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eenewseurope.com\/fr\/carte-click-a-capteur-de-pression-differentielle-pour-la-surveillance-de-debit-dair\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eenewseurope.com\/fr\/carte-click-a-capteur-de-pression-differentielle-pour-la-surveillance-de-debit-dair\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Carte Click \u00e0 capteur de pression diff\u00e9rentielle pour la surveillance de d\u00e9bit d&rsquo;air"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/5853"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=5853"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/5853\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/5854"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=5853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=5853"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=5853"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=5853"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=5853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}