{"id":57345,"date":"2020-04-28T07:31:44","date_gmt":"2020-04-28T07:31:44","guid":{"rendered":"https:\/\/\/mouser-electronics-et-essentra-components-signent-un-accord-de-distribution-mondial\/"},"modified":"2020-04-28T07:31:44","modified_gmt":"2020-04-28T07:31:44","slug":"mouser-electronics-et-essentra-components-signent-un-accord-de-distribution-mondial","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/mouser-electronics-et-essentra-components-signent-un-accord-de-distribution-mondial\/","title":{"rendered":"Mouser Electronics et Essentra Components signent un accord de distribution mondial"},"content":{"rendered":"<p>Les&nbsp;<a href=\"https:\/\/eu.mouser.com\/new\/essentra\/essentra-cable-clips-clamps\/%20\/h\">clips et serre-c\u00e2bles<\/a>&nbsp;de Essentra sont disponibles en versions fixes ou ajustables et la protection et l\u2019acheminement des c\u00e2bles. Ces clips et serre-c\u00e2bles sont propos\u00e9s en divers diam\u00e8tres de faisceau, allant de 1\/16 pouce \u00e0 2-1\/4 pouces, avec de multiples m\u00e9thodes de montage, ainsi que des mod\u00e8les avec adh\u00e9sifs, vis ou \u00e0 encliquetage. Les clips et serre-c\u00e2bles sont disponibles en version plastique et m\u00e9tal et sont id\u00e9aux pour les applications a\u00e9rospatiales, le mat\u00e9riel \u00e9lectrom\u00e9nager et l&rsquo;\u00e9lectronique.<\/p>\n<p>Les&nbsp;<a href=\"https:\/\/eu.mouser.com\/new\/essentra\/essentra-cable-ties\/%20\/h\">colliers de serrage<\/a>&nbsp;de Essentra sont disponibles en longueurs de&nbsp;7,6 cm \u00e0 149 cm&nbsp;, dans une vari\u00e9t\u00e9 de mat\u00e9riaux, y compris du nylon r\u00e9sistant aux intemp\u00e9ries, du polypropyl\u00e8ne et de l&rsquo;acier inoxydable. Ils pr\u00e9sentent des r\u00e9sistances \u00e0 la traction de&nbsp;8 kg \u00e0 113 kg&nbsp;et disposent d&rsquo;attaches moulur\u00e9es et d\u00e9tachables qui sont appropri\u00e9es pour les applications temporaires ou lorsque des changements sont n\u00e9cessaires, tels que les porte-affiches et \u00e9quipements de d\u00e9corations ou de s\u00e9curit\u00e9.<\/p>\n<p>Les&nbsp;<a href=\"https:\/\/eu.mouser.com\/new\/essentra\/essentra-rivets\/%20\/h\">rivets<\/a>&nbsp;de Essentra sont faciles \u00e0 installer \u00e0 la main et sont disponibles en plusieurs tailles de trous et \u00e9paisseurs de panneau pour maintenir plusieurs mat\u00e9riaux ensemble et fixer les articles aux emplacements d\u00e9sign\u00e9s. Ces rivets sont fabriqu\u00e9s en plastique et sont disponibles dans une grande vari\u00e9t\u00e9 de styles, de tailles et de configurations pour s&rsquo;adapter \u00e0 diff\u00e9rents mat\u00e9riaux et dimensions de panneau.<\/p>\n<p>Les&nbsp;<a href=\"https:\/\/eu.mouser.com\/new\/essentra\/essentra-snap-lock-supports\/%20\/h\">supports de verrouillage \u00e0 encliquetage<\/a>&nbsp;servent au support, \u00e0 l&rsquo;espacement, au verrouillage et au guidage des cartes de circuits imprim\u00e9s dans les applications \u00e9lectroniques. Ces supports \u00e9vitent de faire appel \u00e0 des vis et des \u00e9crous, fournissent une isolation \u00e9lectrique et sont disponibles en plusieurs diam\u00e8tres et tailles de panneaux. Les supports de verrouillage \u00e0 encliquetage de Essentra sont con\u00e7us pour \u00eatre install\u00e9s manuellement et ne n\u00e9cessitent pas d&rsquo;\u00e9quipement d&rsquo;assemblage automatis\u00e9.<\/p>\n<p><a href=\"https:\/\/eu.mouser.com\/\">www.mouser.fr.<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mouser Electronics, Inc. annonce un accord de distribution mondial avec Essentra Components, un des principaux fabricants d&rsquo;articles en plastique moul\u00e9 par injection, en vinyle moul\u00e9 par immersion, et en m\u00e9tal. Gr\u00e2ce \u00e0 cet accord, Mouser compte d\u00e9sormais en stock une large s\u00e9lection de garnitures, de hardware, de composants \u00e9lectroniques et de fixations de Essentra, dont les principales cat\u00e9gories de produits de la firme: des clips et serre-c\u00e2bles, des colliers de serrage, des supports \u00e0 encliquetage et des rivets.<\/p>\n","protected":false},"author":9,"featured_media":57346,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-57345","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Mouser Electronics et Essentra Components signent un accord de ...<\/title>\n<meta name=\"description\" content=\"Mouser Electronics, Inc. annonce un accord de distribution mondial avec Essentra Components, un des principaux fabricants d&#039;articles en plastique moul\u00e9 par...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/57345\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mouser Electronics et Essentra Components signent un accord de distribution mondial\" \/>\n<meta property=\"og:description\" content=\"Mouser Electronics, Inc. annonce un accord de distribution mondial avec Essentra Components, un des principaux fabricants d&#039;articles en plastique moul\u00e9 par injection, en vinyle moul\u00e9 par immersion, et en m\u00e9tal. Gr\u00e2ce \u00e0 cet accord, Mouser compte d\u00e9sormais en stock une large s\u00e9lection de garnitures, de hardware, de composants \u00e9lectroniques et de fixations de Essentra, dont les principales cat\u00e9gories de produits de la firme: des clips et serre-c\u00e2bles, des colliers de serrage, des supports \u00e0 encliquetage et des rivets.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/57345\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-28T07:31:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8582_mouser.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"835\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/mouser-electronics-et-essentra-components-signent-un-accord-de-distribution-mondial\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/mouser-electronics-et-essentra-components-signent-un-accord-de-distribution-mondial\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Mouser Electronics et Essentra Components signent un accord de distribution mondial\",\"datePublished\":\"2020-04-28T07:31:44+00:00\",\"dateModified\":\"2020-04-28T07:31:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/mouser-electronics-et-essentra-components-signent-un-accord-de-distribution-mondial\/\"},\"wordCount\":347,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/mouser-electronics-et-essentra-components-signent-un-accord-de-distribution-mondial\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/mouser-electronics-et-essentra-components-signent-un-accord-de-distribution-mondial\/\",\"name\":\"Mouser Electronics et Essentra Components signent un accord de distribution mondial -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2020-04-28T07:31:44+00:00\",\"dateModified\":\"2020-04-28T07:31:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/mouser-electronics-et-essentra-components-signent-un-accord-de-distribution-mondial\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/mouser-electronics-et-essentra-components-signent-un-accord-de-distribution-mondial\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/mouser-electronics-et-essentra-components-signent-un-accord-de-distribution-mondial\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mouser Electronics et Essentra Components signent un accord de distribution mondial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Mouser Electronics et Essentra Components signent un accord de ...","description":"Mouser Electronics, Inc. annonce un accord de distribution mondial avec Essentra Components, un des principaux fabricants d'articles en plastique moul\u00e9 par...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/57345\/","og_locale":"fr_FR","og_type":"article","og_title":"Mouser Electronics et Essentra Components signent un accord de distribution mondial","og_description":"Mouser Electronics, Inc. annonce un accord de distribution mondial avec Essentra Components, un des principaux fabricants d'articles en plastique moul\u00e9 par injection, en vinyle moul\u00e9 par immersion, et en m\u00e9tal. Gr\u00e2ce \u00e0 cet accord, Mouser compte d\u00e9sormais en stock une large s\u00e9lection de garnitures, de hardware, de composants \u00e9lectroniques et de fixations de Essentra, dont les principales cat\u00e9gories de produits de la firme: des clips et serre-c\u00e2bles, des colliers de serrage, des supports \u00e0 encliquetage et des rivets.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/57345\/","og_site_name":"EENewsEurope","article_published_time":"2020-04-28T07:31:44+00:00","og_image":[{"width":1000,"height":835,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8582_mouser.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/mouser-electronics-et-essentra-components-signent-un-accord-de-distribution-mondial\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/mouser-electronics-et-essentra-components-signent-un-accord-de-distribution-mondial\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Mouser Electronics et Essentra Components signent un accord de distribution mondial","datePublished":"2020-04-28T07:31:44+00:00","dateModified":"2020-04-28T07:31:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/mouser-electronics-et-essentra-components-signent-un-accord-de-distribution-mondial\/"},"wordCount":347,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/mouser-electronics-et-essentra-components-signent-un-accord-de-distribution-mondial\/","url":"https:\/\/www.ecinews.fr\/fr\/mouser-electronics-et-essentra-components-signent-un-accord-de-distribution-mondial\/","name":"Mouser Electronics et Essentra Components signent un accord de distribution mondial -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2020-04-28T07:31:44+00:00","dateModified":"2020-04-28T07:31:44+00:00","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/mouser-electronics-et-essentra-components-signent-un-accord-de-distribution-mondial\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/mouser-electronics-et-essentra-components-signent-un-accord-de-distribution-mondial\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/mouser-electronics-et-essentra-components-signent-un-accord-de-distribution-mondial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Mouser Electronics et Essentra Components signent un accord de distribution mondial"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/57345"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=57345"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/57345\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/57346"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=57345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=57345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=57345"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=57345"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=57345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}