{"id":54215,"date":"2020-06-03T22:00:44","date_gmt":"2020-06-03T22:00:44","guid":{"rendered":"https:\/\/\/connecteur-a-receptacle-usb-type-c-pour-les-applications-dalimentation\/"},"modified":"2020-06-03T22:00:44","modified_gmt":"2020-06-03T22:00:44","slug":"connecteur-a-receptacle-usb-type-c-pour-les-applications-dalimentation","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/connecteur-a-receptacle-usb-type-c-pour-les-applications-dalimentation\/","title":{"rendered":"Connecteur \u00e0 r\u00e9ceptacle USB Type C pour les applications d&rsquo;alimentation"},"content":{"rendered":"<p>Conditionn\u00e9 sous la forme d&rsquo;un bo\u00eetier \u00e0 montage en surface, l&rsquo;UJC-HP-3-SMT-TR est \u00e9galement compatible avec&nbsp;n&rsquo;importe quelle prise USB Type C standard.&nbsp;Ainsi ce r\u00e9ceptacle b\u00e9n\u00e9ficie de tous les avantages en termes d\u2019accessibilit\u00e9 et de facilit\u00e9 d\u2019int\u00e9gration de la connectivit\u00e9 USB Type C, d\u00e9sormais universellement adopt\u00e9e,&nbsp;pour les offrir&nbsp;sp\u00e9cifiquement aux applications d&rsquo;alimentation. Il est en outre compatible avec la soudure par refusion, et garantit&nbsp;une plage de temp\u00e9ratures de fonctionnement de -40\u00b0C&nbsp;\u00e0 80\u00b0C ainsi qu&rsquo;une fiabilit\u00e9 \u00e9lev\u00e9e allant jusqu&rsquo;\u00e0 10 000 cycles de raccordement.<\/p>\n<p><a href=\"http:\/\/www.cuidevices.com \\h\">www.cuidevices.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uniquement con\u00e7u pour les applications d&rsquo;alimentation uniquement, l&rsquo;UJC-HP-3-SMT-TR propos\u00e9 par l&rsquo;Interconnect Group de CUI Devices s\u2019av\u00e8re \u00eatre un r\u00e9ceptacle USB Type C \u00e0 6 broches qui peut fournir jusqu&rsquo;\u00e0 60 W de puissance avec des caract\u00e9ristiques nominales de 3 A en courant et de 20 Vdc en tension. D\u00e9pourvu de broches d\u00e9di\u00e9es au transfert de donn\u00e9es, il offre une solution sp\u00e9cialement rentable pour les conceptions ayant comme seule fonction l&rsquo;alimentation ou la recharge.<\/p>\n","protected":false},"author":9,"featured_media":54216,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-54215","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Connecteur \u00e0 r\u00e9ceptacle USB Type C pour les applications d&#039;al...<\/title>\n<meta name=\"description\" content=\"Uniquement con\u00e7u pour les applications d&#039;alimentation uniquement, l&#039;UJC-HP-3-SMT-TR propos\u00e9 par l&#039;Interconnect Group de CUI Devices s\u2019av\u00e8re \u00eatre un...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/54215\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Connecteur \u00e0 r\u00e9ceptacle USB Type C pour les applications d&#039;alimentation\" \/>\n<meta property=\"og:description\" content=\"Uniquement con\u00e7u pour les applications d&#039;alimentation uniquement, l&#039;UJC-HP-3-SMT-TR propos\u00e9 par l&#039;Interconnect Group de CUI Devices s\u2019av\u00e8re \u00eatre un r\u00e9ceptacle USB Type C \u00e0 6 broches qui peut fournir jusqu&#039;\u00e0 60 W de puissance avec des caract\u00e9ristiques nominales de 3 A en courant et de 20 Vdc en tension. D\u00e9pourvu de broches d\u00e9di\u00e9es au transfert de donn\u00e9es, il offre une solution sp\u00e9cialement rentable pour les conceptions ayant comme seule fonction l&#039;alimentation ou la recharge.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/54215\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-03T22:00:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8647_cui.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2502\" \/>\n\t<meta property=\"og:image:height\" content=\"1744\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/test.ecinews.fr\/fr\/connecteur-a-receptacle-usb-type-c-pour-les-applications-dalimentation\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/test.ecinews.fr\/fr\/connecteur-a-receptacle-usb-type-c-pour-les-applications-dalimentation\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Connecteur \u00e0 r\u00e9ceptacle USB Type C pour les applications d&rsquo;alimentation\",\"datePublished\":\"2020-06-03T22:00:44+00:00\",\"dateModified\":\"2020-06-03T22:00:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/test.ecinews.fr\/fr\/connecteur-a-receptacle-usb-type-c-pour-les-applications-dalimentation\/\"},\"wordCount\":121,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/test.ecinews.fr\/fr\/connecteur-a-receptacle-usb-type-c-pour-les-applications-dalimentation\/\",\"url\":\"https:\/\/test.ecinews.fr\/fr\/connecteur-a-receptacle-usb-type-c-pour-les-applications-dalimentation\/\",\"name\":\"Connecteur \u00e0 r\u00e9ceptacle USB Type C pour les applications d'alimentation -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2020-06-03T22:00:44+00:00\",\"dateModified\":\"2020-06-03T22:00:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/test.ecinews.fr\/fr\/connecteur-a-receptacle-usb-type-c-pour-les-applications-dalimentation\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/test.ecinews.fr\/fr\/connecteur-a-receptacle-usb-type-c-pour-les-applications-dalimentation\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/test.ecinews.fr\/fr\/connecteur-a-receptacle-usb-type-c-pour-les-applications-dalimentation\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Connecteur \u00e0 r\u00e9ceptacle USB Type C pour les applications d&rsquo;alimentation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Connecteur \u00e0 r\u00e9ceptacle USB Type C pour les applications d'al...","description":"Uniquement con\u00e7u pour les applications d'alimentation uniquement, l'UJC-HP-3-SMT-TR propos\u00e9 par l'Interconnect Group de CUI Devices s\u2019av\u00e8re \u00eatre un...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/54215\/","og_locale":"fr_FR","og_type":"article","og_title":"Connecteur \u00e0 r\u00e9ceptacle USB Type C pour les applications d'alimentation","og_description":"Uniquement con\u00e7u pour les applications d'alimentation uniquement, l'UJC-HP-3-SMT-TR propos\u00e9 par l'Interconnect Group de CUI Devices s\u2019av\u00e8re \u00eatre un r\u00e9ceptacle USB Type C \u00e0 6 broches qui peut fournir jusqu'\u00e0 60 W de puissance avec des caract\u00e9ristiques nominales de 3 A en courant et de 20 Vdc en tension. D\u00e9pourvu de broches d\u00e9di\u00e9es au transfert de donn\u00e9es, il offre une solution sp\u00e9cialement rentable pour les conceptions ayant comme seule fonction l'alimentation ou la recharge.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/54215\/","og_site_name":"EENewsEurope","article_published_time":"2020-06-03T22:00:44+00:00","og_image":[{"width":2502,"height":1744,"url":"https:\/\/test.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8647_cui.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/test.ecinews.fr\/fr\/connecteur-a-receptacle-usb-type-c-pour-les-applications-dalimentation\/#article","isPartOf":{"@id":"https:\/\/test.ecinews.fr\/fr\/connecteur-a-receptacle-usb-type-c-pour-les-applications-dalimentation\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Connecteur \u00e0 r\u00e9ceptacle USB Type C pour les applications d&rsquo;alimentation","datePublished":"2020-06-03T22:00:44+00:00","dateModified":"2020-06-03T22:00:44+00:00","mainEntityOfPage":{"@id":"https:\/\/test.ecinews.fr\/fr\/connecteur-a-receptacle-usb-type-c-pour-les-applications-dalimentation\/"},"wordCount":121,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/test.ecinews.fr\/fr\/connecteur-a-receptacle-usb-type-c-pour-les-applications-dalimentation\/","url":"https:\/\/test.ecinews.fr\/fr\/connecteur-a-receptacle-usb-type-c-pour-les-applications-dalimentation\/","name":"Connecteur \u00e0 r\u00e9ceptacle USB Type C pour les applications d'alimentation -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2020-06-03T22:00:44+00:00","dateModified":"2020-06-03T22:00:44+00:00","breadcrumb":{"@id":"https:\/\/test.ecinews.fr\/fr\/connecteur-a-receptacle-usb-type-c-pour-les-applications-dalimentation\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test.ecinews.fr\/fr\/connecteur-a-receptacle-usb-type-c-pour-les-applications-dalimentation\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/test.ecinews.fr\/fr\/connecteur-a-receptacle-usb-type-c-pour-les-applications-dalimentation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Connecteur \u00e0 r\u00e9ceptacle USB Type C pour les applications d&rsquo;alimentation"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/54215"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=54215"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/54215\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/54216"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=54215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=54215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=54215"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=54215"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=54215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}