{"id":50963,"date":"2020-07-14T07:49:20","date_gmt":"2020-07-14T07:49:20","guid":{"rendered":"https:\/\/\/controleurs-automobiles-pour-surfaces-intelligentes-et-ecrans-multifonctions\/"},"modified":"2020-07-14T07:49:20","modified_gmt":"2020-07-14T07:49:20","slug":"controleurs-automobiles-pour-surfaces-intelligentes-et-ecrans-multifonctions","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/controleurs-automobiles-pour-surfaces-intelligentes-et-ecrans-multifonctions\/","title":{"rendered":"Contr\u00f4leurs automobiles pour surfaces intelligentes et \u00e9crans multifonctions"},"content":{"rendered":"<p>Soutenant le d\u00e9veloppement de ces \u00e9crans secondaires dot\u00e9s de fonctionnalit\u00e9s avanc\u00e9es, Microchip Technology Inc. propose le d\u00e9veloppement de son portefeuille de composants de pointe maXTouch, avec l\u2019introduction de la nouvelle famille de contr\u00f4leurs tactiles MXT288UD, les contr\u00f4leurs d\u2019\u00e9cran tactile les plus compacts du march\u00e9 destin\u00e9s \u00e0 l\u2019industrie automobile. Les composants MXT288UD-AM et MXT144UD-AM offrent un mode faible consommation, une bonne r\u00e9sistance aux intemp\u00e9ries et la d\u00e9tection \u00e0 travers de gants \u00e9pais sur les \u00e9crans multipoints, les pav\u00e9s tactiles et les surfaces tactiles intelligentes pour les automobiles, les motos, les v\u00e9los \u00e9lectriques et les services d\u2019auto-partage.Les \u00e9crans tactiles secondaires peuvent \u00eatre plac\u00e9s \u00e0 l\u2019int\u00e9rieur comme \u00e0 l\u2019ext\u00e9rieur des v\u00e9hicules \u00e0 moteur, sur le guidon, les porti\u00e8res, les r\u00e9troviseurs \u00e9lectriques, les boutons de commande, le volant, entre les si\u00e8ges ou sur un accoudoir. Gr\u00e2ce au bo\u00eetier compact VQFN56 de qualit\u00e9 automobile mesurant 7&nbsp;x&nbsp;7&nbsp;mm de la famille MXT288UD, les fournisseurs de rang 1 peuvent dor\u00e9navant r\u00e9duire l\u2019encombrement sur la carte d\u2019environ 75&nbsp;% et diminuer significativement la nomenclature de ces applications compactes, tout en pr\u00e9sentant d&rsquo;excellentes performances tactiles ultra fiables, sup\u00e9rieures aux normes du secteur. Le mode faible consommation \u00ab&nbsp;Wait for Touch&nbsp;\u00bb, qui permet l&rsquo;activation par effleurement, consomme moins de 50&nbsp;\u00b5A, tout en restant r\u00e9actif pour l\u2019utilisateur, y compris si l\u2019\u00e9cran s\u2019\u00e9teint pour \u00e9conomiser de l\u2019\u00e9nergie ou ne pas d\u00e9ranger le conducteur lorsqu\u2019il fait nuit. Un effleurement n\u2019importe o\u00f9 sur l\u2019\u00e9cran r\u00e9veille le syst\u00e8me.&nbsp;<\/p>\n<p>De plus, les composants MXT288UD-AM et MXT144UD-AM permettent la d\u00e9tection et le suivi de gestes multipoints \u00e0 travers des gants \u00e9pais, sur un large \u00e9ventail de surfaces quels qu\u2019en soient le rev\u00eatement ou l\u2019\u00e9paisseur (cuir, bois, etc.), y compris sur les surfaces irr\u00e9guli\u00e8res et en pr\u00e9sence d\u2019humidit\u00e9. En principe, la constante di\u00e9lectrique de ces rev\u00eatements de surface devrait limiter la d\u00e9tection tactile&nbsp;: cependant, ces composants constituent une solution unique qui permet de d\u00e9tecter et suivre les gestes multipoints avec un haut degr\u00e9 de fiabilit\u00e9 et un rapport signal-sur-bruit (SNR, pour&nbsp;Signal-to-Noise Ratio) \u00e9lev\u00e9, gr\u00e2ce \u00e0 un proc\u00e9d\u00e9 d\u2019acquisition mutuel diff\u00e9rentiel propri\u00e9taire. &nbsp;<\/p>\n<p>Par exemple, sur les applications d\u2019auto-partage, cette fonctionnalit\u00e9 tactile fiable permet aux utilisateurs d\u2019avoir acc\u00e8s au v\u00e9hicule depuis l\u2019ext\u00e9rieur gr\u00e2ce au suivi des coordonn\u00e9es tactiles sur un \u00e9cran externe, quelles que soient les conditions environnementales (pluie, neige, grosses chaleurs). Ce type de conception insensible aux intemp\u00e9ries est \u00e9galement id\u00e9al pour les motos et autres scooters. En tant que solution cl\u00e9 en main, la famille MXT288UD int\u00e8gre un firmware ayant fait ses preuves et d\u00e9velopp\u00e9 conform\u00e9ment aux processus SPICE sp\u00e9cifiques au secteur automobile, et sont \u00e9galement certifi\u00e9s AEC-Q100, simplifiant la t\u00e2che aux constructeurs automobiles pour les int\u00e9grer \u00e0 des syst\u00e8mes existants, en prenant peu de risque tout en acc\u00e9l\u00e9rant les d\u00e9lais de commercialisation.&nbsp;<\/p>\n<p><a href=\"http:\/\/www.microchip.com\/\">www.microchip.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour am\u00e9liorer l\u2019exp\u00e9rience de conduite et la rendre plus ais\u00e9e, les constructeurs automobiles mettent dor\u00e9navant en \u0153uvre des \u00e9crans tactiles suppl\u00e9mentaires en plus de la console centrale d\u00e9di\u00e9e aux info-loisirs. <\/p>\n","protected":false},"author":9,"featured_media":50964,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-50963","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Contr\u00f4leurs automobiles pour surfaces intelligentes et \u00e9crans...<\/title>\n<meta name=\"description\" content=\"Pour am\u00e9liorer l\u2019exp\u00e9rience de conduite et la rendre plus ais\u00e9e, les constructeurs automobiles mettent dor\u00e9navant en \u0153uvre des \u00e9crans tactiles...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/50963\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contr\u00f4leurs automobiles pour surfaces intelligentes et \u00e9crans multifonctions\" \/>\n<meta property=\"og:description\" content=\"Pour am\u00e9liorer l\u2019exp\u00e9rience de conduite et la rendre plus ais\u00e9e, les constructeurs automobiles mettent dor\u00e9navant en \u0153uvre des \u00e9crans tactiles suppl\u00e9mentaires en plus de la console centrale d\u00e9di\u00e9e aux info-loisirs.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/50963\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-14T07:49:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8702_microchip-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1422\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/test.ecinews.fr\/fr\/controleurs-automobiles-pour-surfaces-intelligentes-et-ecrans-multifonctions\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/test.ecinews.fr\/fr\/controleurs-automobiles-pour-surfaces-intelligentes-et-ecrans-multifonctions\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Contr\u00f4leurs automobiles pour surfaces intelligentes et \u00e9crans multifonctions\",\"datePublished\":\"2020-07-14T07:49:20+00:00\",\"dateModified\":\"2020-07-14T07:49:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/test.ecinews.fr\/fr\/controleurs-automobiles-pour-surfaces-intelligentes-et-ecrans-multifonctions\/\"},\"wordCount\":551,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/test.ecinews.fr\/fr\/controleurs-automobiles-pour-surfaces-intelligentes-et-ecrans-multifonctions\/\",\"url\":\"https:\/\/test.ecinews.fr\/fr\/controleurs-automobiles-pour-surfaces-intelligentes-et-ecrans-multifonctions\/\",\"name\":\"Contr\u00f4leurs automobiles pour surfaces intelligentes et \u00e9crans multifonctions -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2020-07-14T07:49:20+00:00\",\"dateModified\":\"2020-07-14T07:49:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/test.ecinews.fr\/fr\/controleurs-automobiles-pour-surfaces-intelligentes-et-ecrans-multifonctions\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/test.ecinews.fr\/fr\/controleurs-automobiles-pour-surfaces-intelligentes-et-ecrans-multifonctions\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/test.ecinews.fr\/fr\/controleurs-automobiles-pour-surfaces-intelligentes-et-ecrans-multifonctions\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contr\u00f4leurs automobiles pour surfaces intelligentes et \u00e9crans multifonctions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Contr\u00f4leurs automobiles pour surfaces intelligentes et \u00e9crans...","description":"Pour am\u00e9liorer l\u2019exp\u00e9rience de conduite et la rendre plus ais\u00e9e, les constructeurs automobiles mettent dor\u00e9navant en \u0153uvre des \u00e9crans tactiles...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/50963\/","og_locale":"fr_FR","og_type":"article","og_title":"Contr\u00f4leurs automobiles pour surfaces intelligentes et \u00e9crans multifonctions","og_description":"Pour am\u00e9liorer l\u2019exp\u00e9rience de conduite et la rendre plus ais\u00e9e, les constructeurs automobiles mettent dor\u00e9navant en \u0153uvre des \u00e9crans tactiles suppl\u00e9mentaires en plus de la console centrale d\u00e9di\u00e9e aux info-loisirs.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/50963\/","og_site_name":"EENewsEurope","article_published_time":"2020-07-14T07:49:20+00:00","og_image":[{"width":2560,"height":1422,"url":"https:\/\/test.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8702_microchip-scaled.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/test.ecinews.fr\/fr\/controleurs-automobiles-pour-surfaces-intelligentes-et-ecrans-multifonctions\/#article","isPartOf":{"@id":"https:\/\/test.ecinews.fr\/fr\/controleurs-automobiles-pour-surfaces-intelligentes-et-ecrans-multifonctions\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Contr\u00f4leurs automobiles pour surfaces intelligentes et \u00e9crans multifonctions","datePublished":"2020-07-14T07:49:20+00:00","dateModified":"2020-07-14T07:49:20+00:00","mainEntityOfPage":{"@id":"https:\/\/test.ecinews.fr\/fr\/controleurs-automobiles-pour-surfaces-intelligentes-et-ecrans-multifonctions\/"},"wordCount":551,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/test.ecinews.fr\/fr\/controleurs-automobiles-pour-surfaces-intelligentes-et-ecrans-multifonctions\/","url":"https:\/\/test.ecinews.fr\/fr\/controleurs-automobiles-pour-surfaces-intelligentes-et-ecrans-multifonctions\/","name":"Contr\u00f4leurs automobiles pour surfaces intelligentes et \u00e9crans multifonctions -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2020-07-14T07:49:20+00:00","dateModified":"2020-07-14T07:49:20+00:00","breadcrumb":{"@id":"https:\/\/test.ecinews.fr\/fr\/controleurs-automobiles-pour-surfaces-intelligentes-et-ecrans-multifonctions\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test.ecinews.fr\/fr\/controleurs-automobiles-pour-surfaces-intelligentes-et-ecrans-multifonctions\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/test.ecinews.fr\/fr\/controleurs-automobiles-pour-surfaces-intelligentes-et-ecrans-multifonctions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Contr\u00f4leurs automobiles pour surfaces intelligentes et \u00e9crans multifonctions"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/50963"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=50963"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/50963\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/50964"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=50963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=50963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=50963"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=50963"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=50963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}