{"id":488599,"date":"2025-11-27T13:59:31","date_gmt":"2025-11-27T12:59:31","guid":{"rendered":"https:\/\/www.ecinews.fr\/?p=488599"},"modified":"2025-12-01T14:36:41","modified_gmt":"2025-12-01T13:36:41","slug":"un-mosfet-compact-et-performant-pour-des-alimentations-plus-efficaces","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/un-mosfet-compact-et-performant-pour-des-alimentations-plus-efficaces\/","title":{"rendered":"Un MOSFET compact et performant pour des alimentations plus efficaces"},"content":{"rendered":"<h3>Toshiba Electronics Europe GmbH d\u00e9voile le MOSFET TK057V60Z, un composant de puissance 600 V \u00e0 canal N, bas\u00e9 sur la technologie DTMOSVI et dot\u00e9 d\u2019une structure super jonction. Ce dispositif est int\u00e9gr\u00e9 dans un bo\u00eetier compact DFN8\u00d78, id\u00e9al pour les conceptions \u00e0 haute densit\u00e9.<\/h3>\n<p>Avec une tension drain-source (VDSS) de 600 V et un courant de drain maximal de 40 A, ce MOSFET affiche une r\u00e9sistance RDS(ON) typique de seulement 0,047 \u03a9 (0,057 \u03a9 max.). Sa charge grille-drain (Qgd) peut descendre \u00e0 15 nC, garantissant des performances optimales pour les applications exigeantes.<\/p>\n<h4>Points cl\u00e9s :<\/h4>\n<ul>\n<li>Technologie DTMOSVI 600 V pour une efficacit\u00e9 accrue.<\/li>\n<li>Bo\u00eetier DFN8\u00d78 compact pour r\u00e9duire la taille des \u00e9quipements.<\/li>\n<li>RDS(ON) ultra-faible et Qgd optimis\u00e9 pour limiter les pertes.<\/li>\n<\/ul>\n<p>Ce composant r\u00e9pond aux besoins des alimentations \u00e0 d\u00e9coupage pour serveurs, des UPS et des conditionneurs de puissance photovolta\u00efques, en offrant une densit\u00e9 de puissance optimis\u00e9e et une fiabilit\u00e9 renforc\u00e9e.<\/p>\n<p><a href=\"http:\/\/toshiba.semicon-storage.com\/eu\/top.html\">Toshiba Electronics Europe GmbH<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Toshiba Electronics Europe GmbH d\u00e9voile le MOSFET TK057V60Z, un composant de puissance 600 V \u00e0 canal N, bas\u00e9 sur la technologie DTMOSVI et dot\u00e9 d\u2019une structure super jonction. Ce dispositif est int\u00e9gr\u00e9 dans un bo\u00eetier compact DFN8\u00d78, id\u00e9al pour les conceptions \u00e0 haute densit\u00e9. Avec une tension drain-source (VDSS) de 600 V et un courant [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":488602,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[2468],"domains":[47],"ppma_author":[6113],"class_list":["post-488599","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","tag-mosfet-fr","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Un MOSFET compact et performant pour des alimentations plus eff...<\/title>\n<meta name=\"description\" content=\"Toshiba Electronics Europe GmbH d\u00e9voile le MOSFET TK057V60Z, un composant de puissance 600 V \u00e0 canal N, bas\u00e9 sur la technologie DTMOSVI et dot\u00e9 d\u2019une...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/488599\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un MOSFET compact et performant pour des alimentations plus efficaces\" \/>\n<meta property=\"og:description\" content=\"Toshiba Electronics Europe GmbH d\u00e9voile le MOSFET TK057V60Z, un composant de puissance 600 V \u00e0 canal N, bas\u00e9 sur la technologie DTMOSVI et dot\u00e9 d\u2019une structure super jonction.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/488599\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-27T12:59:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-01T13:36:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2025\/12\/ECI5171-7649F-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"771\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"NicolasFeste\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"NicolasFeste\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/un-mosfet-compact-et-performant-pour-des-alimentations-plus-efficaces\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/un-mosfet-compact-et-performant-pour-des-alimentations-plus-efficaces\/\"},\"author\":{\"name\":\"NicolasFeste\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/c7104a72b466a801f257e51481de0c43\"},\"headline\":\"Un MOSFET compact et performant pour des alimentations plus efficaces\",\"datePublished\":\"2025-11-27T12:59:31+00:00\",\"dateModified\":\"2025-12-01T13:36:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/un-mosfet-compact-et-performant-pour-des-alimentations-plus-efficaces\/\"},\"wordCount\":169,\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"keywords\":[\"MOSFET\"],\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/un-mosfet-compact-et-performant-pour-des-alimentations-plus-efficaces\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/un-mosfet-compact-et-performant-pour-des-alimentations-plus-efficaces\/\",\"name\":\"Un MOSFET compact et performant pour des alimentations plus efficaces -\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\"},\"datePublished\":\"2025-11-27T12:59:31+00:00\",\"dateModified\":\"2025-12-01T13:36:41+00:00\",\"description\":\"Toshiba Electronics Europe GmbH d\u00e9voile le MOSFET TK057V60Z, un composant de puissance 600 V \u00e0 canal N, bas\u00e9 sur la technologie DTMOSVI et dot\u00e9 d\u2019une structure super jonction.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/un-mosfet-compact-et-performant-pour-des-alimentations-plus-efficaces\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/un-mosfet-compact-et-performant-pour-des-alimentations-plus-efficaces\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/un-mosfet-compact-et-performant-pour-des-alimentations-plus-efficaces\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un MOSFET compact et performant pour des alimentations plus efficaces\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/c7104a72b466a801f257e51481de0c43\",\"name\":\"NicolasFeste\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/1ea421e7d03c1e96a9ea2bcf2705734a\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2e187f4d96902933ba445ed6c760e11c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2e187f4d96902933ba445ed6c760e11c?s=96&d=mm&r=g\",\"caption\":\"NicolasFeste\"}}]}<\/script>","yoast_head_json":{"title":"Un MOSFET compact et performant pour des alimentations plus eff...","description":"Toshiba Electronics Europe GmbH d\u00e9voile le MOSFET TK057V60Z, un composant de puissance 600 V \u00e0 canal N, bas\u00e9 sur la technologie DTMOSVI et dot\u00e9 d\u2019une...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/488599\/","og_locale":"fr_FR","og_type":"article","og_title":"Un MOSFET compact et performant pour des alimentations plus efficaces","og_description":"Toshiba Electronics Europe GmbH d\u00e9voile le MOSFET TK057V60Z, un composant de puissance 600 V \u00e0 canal N, bas\u00e9 sur la technologie DTMOSVI et dot\u00e9 d\u2019une structure super jonction.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/488599\/","og_site_name":"EENewsEurope","article_published_time":"2025-11-27T12:59:31+00:00","article_modified_time":"2025-12-01T13:36:41+00:00","og_image":[{"width":1080,"height":771,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2025\/12\/ECI5171-7649F-scaled.jpg","type":"image\/jpeg"}],"author":"NicolasFeste","twitter_card":"summary_large_image","twitter_misc":{"Written by":"NicolasFeste","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/un-mosfet-compact-et-performant-pour-des-alimentations-plus-efficaces\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/un-mosfet-compact-et-performant-pour-des-alimentations-plus-efficaces\/"},"author":{"name":"NicolasFeste","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/c7104a72b466a801f257e51481de0c43"},"headline":"Un MOSFET compact et performant pour des alimentations plus efficaces","datePublished":"2025-11-27T12:59:31+00:00","dateModified":"2025-12-01T13:36:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/un-mosfet-compact-et-performant-pour-des-alimentations-plus-efficaces\/"},"wordCount":169,"publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"keywords":["MOSFET"],"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/un-mosfet-compact-et-performant-pour-des-alimentations-plus-efficaces\/","url":"https:\/\/www.ecinews.fr\/fr\/un-mosfet-compact-et-performant-pour-des-alimentations-plus-efficaces\/","name":"Un MOSFET compact et performant pour des alimentations plus efficaces -","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/#website"},"datePublished":"2025-11-27T12:59:31+00:00","dateModified":"2025-12-01T13:36:41+00:00","description":"Toshiba Electronics Europe GmbH d\u00e9voile le MOSFET TK057V60Z, un composant de puissance 600 V \u00e0 canal N, bas\u00e9 sur la technologie DTMOSVI et dot\u00e9 d\u2019une structure super jonction.","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/un-mosfet-compact-et-performant-pour-des-alimentations-plus-efficaces\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/un-mosfet-compact-et-performant-pour-des-alimentations-plus-efficaces\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/un-mosfet-compact-et-performant-pour-des-alimentations-plus-efficaces\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Un MOSFET compact et performant pour des alimentations plus efficaces"}]},{"@type":"WebSite","@id":"https:\/\/www.ecinews.fr\/fr\/#website","url":"https:\/\/www.ecinews.fr\/fr\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ecinews.fr\/fr\/#organization","name":"EENewsEurope","url":"https:\/\/www.ecinews.fr\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/c7104a72b466a801f257e51481de0c43","name":"NicolasFeste","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/1ea421e7d03c1e96a9ea2bcf2705734a","url":"https:\/\/secure.gravatar.com\/avatar\/2e187f4d96902933ba445ed6c760e11c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2e187f4d96902933ba445ed6c760e11c?s=96&d=mm&r=g","caption":"NicolasFeste"}}]}},"authors":[{"term_id":6113,"user_id":39,"is_guest":0,"slug":"nicolasfeste","display_name":"NicolasFeste","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/2e187f4d96902933ba445ed6c760e11c?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/488599"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=488599"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/488599\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/488602"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=488599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=488599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=488599"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=488599"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=488599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}