{"id":487107,"date":"2025-10-21T10:57:16","date_gmt":"2025-10-21T08:57:16","guid":{"rendered":"https:\/\/www.ecinews.fr\/?p=487107"},"modified":"2025-10-21T10:57:16","modified_gmt":"2025-10-21T08:57:16","slug":"sealsq-presente-la-premiere-puce-de-securite-post-quantique","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/sealsq-presente-la-premiere-puce-de-securite-post-quantique\/","title":{"rendered":"SEALSQ pr\u00e9sente la premi\u00e8re puce de s\u00e9curit\u00e9 post-quantique"},"content":{"rendered":"<p data-start=\"112\" data-end=\"482\">Bas\u00e9e \u00e0 Gen\u00e8ve, SEALSQ Corp a <a href=\"https:\/\/www.sealsq.com\/investors\/news-releases\/sealsq-unveils-qs7001-at-qai-2025-conference-in-new-york\">d\u00e9voil\u00e9<\/a> ce qu&rsquo;elle appelle la premi\u00e8re puce de s\u00e9curit\u00e9 <a href=\"https:\/\/www.eenewseurope.com\/en\/tags\/post-quantum-cryptography\/\">post-quantique<\/a> int\u00e9gr\u00e9e au hardware, le Quantum Shield QS7001, lors de la conf\u00e9rence Quantum+AI 2025 \u00e0 New York. Cette puce int\u00e8gre des algorithmes normalis\u00e9s par le NIST directement dans le silicium, ce qui constitue une \u00e9tape cl\u00e9 pour le cryptage <a href=\"https:\/\/www.eenewseurope.com\/en\/tags\/quantum\">\u00e0 s\u00e9curit\u00e9 quantique<\/a> dans les syst\u00e8mes connect\u00e9s de la prochaine g\u00e9n\u00e9ration.<\/p>\n<p data-start=\"484\" data-end=\"848\">Cette annonce marque le d\u00e9but d&rsquo;une voie de migration pratique vers du mat\u00e9riel \u00e0 s\u00e9curit\u00e9 quantique. Face \u00e0 la menace du d\u00e9cryptage quantique, la disponibilit\u00e9 de puces PQC natives pourrait red\u00e9finir la mani\u00e8re dont les syst\u00e8mes s\u00e9curis\u00e9s sont construits dans les secteurs europ\u00e9ens de la d\u00e9fense, de l&rsquo;industrie et de l&rsquo;\u00e9nergie.<\/p>\n<h2 data-start=\"484\" data-end=\"848\">La s\u00e9curit\u00e9 post-quantique s&rsquo;adapte au mat\u00e9riel<\/h2>\n<p data-start=\"909\" data-end=\"1330\">Le Quantum Shield QS7001 int\u00e8gre ML-KEM (CRYSTALS-Kyber) et ML-DSA (CRYSTALS-Dilithium) &#8211; les algorithmes PQC s\u00e9lectionn\u00e9s par le NIST &#8211; directement au niveau du silicium. Selon SEALSQ, cette approche permet des gains de performance allant jusqu&rsquo;\u00e0 10 fois, une meilleure r\u00e9sistance aux canaux lat\u00e9raux et une protection robuste contre le sabotage. La puce est \u00e9galement dot\u00e9e d&rsquo;une plate-forme mat\u00e9rielle ouverte qui prend en charge la cryptographie hybride et le d\u00e9veloppement de microprogrammes personnalis\u00e9s.<\/p>\n<p data-start=\"1332\" data-end=\"1647\">SEALSQ pr\u00e9voit de lancer officiellement le QS7001 \u00e0 la mi-novembre 2025, avec des kits de d\u00e9veloppement client disponibles peu de temps apr\u00e8s. La soci\u00e9t\u00e9 a \u00e9galement annonc\u00e9 que les variantes QVault TPM suivront au cours du premier semestre 2026, \u00e9largissant ainsi son portefeuille \u00e0 s\u00e9curit\u00e9 quantique pour les applications d&rsquo;authentification s\u00e9curis\u00e9e et de gestion des cl\u00e9s.<\/p>\n<p data-start=\"1649\" data-end=\"2192\">\u00ab\u00a0Avec plus de 1,75 milliard d&rsquo;appareils prot\u00e9g\u00e9s dans le monde, SEALSQ est fi\u00e8re d&rsquo;\u00eatre l&rsquo;une des rares entreprises au monde capable de fournir les plus hauts niveaux de s\u00e9curit\u00e9\u00a0\u00bb, a d\u00e9clar\u00e9 Carlos Moreira, PDG de SEALSQ. \u00ab\u00a0Cette fois, nous arrivons les premiers, en d\u00e9voilant une premi\u00e8re dans l&rsquo;industrie des solutions r\u00e9sistantes au quantum. En int\u00e9grant la cryptographie post-quantique directement dans le mat\u00e9riel, cette puce vise \u00e0 \u00e9tablir un nouveau paradigme de confiance et de protection, en s\u00e9curisant les infrastructures souveraines, les soins de sant\u00e9, les syst\u00e8mes \u00e9nerg\u00e9tiques et les appareils connect\u00e9s contre la menace quantique \u00e0 venir.\u00a0\u00bb<\/p>\n<h2 data-start=\"2199\" data-end=\"2246\">R\u00e9pondre aux mandats quantiques mondiaux<\/h2>\n<p data-start=\"2248\" data-end=\"2685\">Ce lancement intervient alors que l&rsquo;adoption de la PQC devient de plus en plus urgente. Apr\u00e8s la finalisation des normes PQC par le NIST en 2024, le cadre am\u00e9ricain CNSA 2.0 et les r\u00e9glementations europ\u00e9ennes \u00e0 venir pr\u00e9conisent la migration vers la PQC dans tous les secteurs critiques d&rsquo;ici \u00e0 2030. Le risque d&rsquo;attaques de type \u00ab\u00a0harvest now, decrypt later\u00a0\u00bb &#8211; o\u00f9 des donn\u00e9es crypt\u00e9es sont stock\u00e9es aujourd&rsquo;hui pour \u00eatre d\u00e9chiffr\u00e9es par de futurs ordinateurs quantiques &#8211; a acc\u00e9l\u00e9r\u00e9 le besoin de contre-mesures bas\u00e9es sur le mat\u00e9riel.<\/p>\n<p data-start=\"2687\" data-end=\"3131\">Les partenaires de l&rsquo;industrie ont salu\u00e9 cette annonce. Yann Vincent, responsable des produits de cybers\u00e9curit\u00e9 chez Eviden (groupe Atos), a d\u00e9clar\u00e9 : \u00ab\u00a0Avec l&rsquo;av\u00e8nement de l&rsquo;informatique quantique, les m\u00e9thodes de cryptage traditionnelles sont confront\u00e9es \u00e0 des risques sans pr\u00e9c\u00e9dent [&#8230;]. Gr\u00e2ce \u00e0 cette coop\u00e9ration avec SEALSQ, nous int\u00e9grons leur nouvelle puce cryptographique post-quantique dans nos mod\u00e8les de s\u00e9curit\u00e9 mat\u00e9rielle, construisant ainsi une solution de protection de bout en bout pour r\u00e9sister \u00e0 la menace quantique d&rsquo;aujourd&rsquo;hui.\u00a0\u00bb<\/p>\n<p data-start=\"3133\" data-end=\"3450\">Zake Huang, PDG d&rsquo;AuthenTrend, a ajout\u00e9 : \u00ab\u00a0AuthenTrend est fier d&rsquo;\u00eatre le premier \u00e0 int\u00e9grer le bouclier quantique QS7001 de SEALSQ dans sa solution de cl\u00e9 de s\u00e9curit\u00e9. Notre objectif est de fournir des cl\u00e9s d&rsquo;authentification quantiques qui prot\u00e8gent nos clients contre les menaces \u00e9mergentes tout en pr\u00e9servant leur confort d&rsquo;utilisation.\u00a0\u00bb<\/p>\n<h2 data-start=\"3457\" data-end=\"3505\">Cr\u00e9ation d&rsquo;un \u00e9cosyst\u00e8me europ\u00e9en et mondial<\/h2>\n<p data-start=\"3507\" data-end=\"3809\">Bas\u00e9e \u00e0 Gen\u00e8ve, SEALSQ exploite des centres de personnalisation s\u00e9curis\u00e9s en Suisse, en France et bient\u00f4t en Espagne, en Inde et aux \u00c9tats-Unis. L&rsquo;entreprise a obtenu des certifications de haut niveau &#8211; Common Criteria EAL5+ et FIPS 140-3 &#8211; et continue de d\u00e9velopper un \u00e9cosyst\u00e8me pour une infrastructure r\u00e9sistante au quantum.<\/p>\n<p data-start=\"3811\" data-end=\"4171\" data-is-last-node=\"\" data-is-only-node=\"\">Avec le QS7001, SEALSQ se positionne comme un pr\u00e9curseur dans l&rsquo;innovation des semi-conducteurs post-quantiques, m\u00ealant mat\u00e9riel certifi\u00e9, expertise cryptographique et port\u00e9e mondiale. Pour les fabricants de puces, les OEM et les d\u00e9veloppeurs IoT, ce jalon ne repr\u00e9sente pas seulement un nouveau produit, mais une base essentielle pour concevoir des syst\u00e8mes \u00e0 s\u00e9curit\u00e9 quantique pr\u00eats pour la prochaine d\u00e9cennie.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bas\u00e9e \u00e0 Gen\u00e8ve, SEALSQ Corp a d\u00e9voil\u00e9 ce qu&rsquo;elle appelle la premi\u00e8re puce de s\u00e9curit\u00e9 post-quantique int\u00e9gr\u00e9e au hardware, le Quantum Shield QS7001, lors de la conf\u00e9rence Quantum+AI 2025 \u00e0 New York. Cette puce int\u00e8gre des algorithmes normalis\u00e9s par le NIST directement dans le silicium, ce qui constitue une \u00e9tape cl\u00e9 pour le cryptage \u00e0 [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":487056,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3669],"tags":[7844,5559,10233],"domains":[47],"ppma_author":[10490,1153],"class_list":["post-487107","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles","tag-crypto-quantique","tag-nist-fr","tag-pqc-fr","domains-electronique-eci"],"acf":[],"yoast_head":"<title>SEALSQ pr\u00e9sente la premi\u00e8re puce de s\u00e9curit\u00e9 post-quantique ...<\/title>\n<meta name=\"description\" content=\"SEALSQ lance le Quantum Shield QS7001, une puce qui apporte aux appareils connect\u00e9s une s\u00e9curit\u00e9 post-quantique bas\u00e9e sur le mat\u00e9riel.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/487107\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SEALSQ pr\u00e9sente la premi\u00e8re puce de s\u00e9curit\u00e9 post-quantique\" \/>\n<meta property=\"og:description\" content=\"SEALSQ lance le Quantum Shield QS7001, une puce qui apporte aux appareils connect\u00e9s une s\u00e9curit\u00e9 post-quantique bas\u00e9e sur le mat\u00e9riel.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/487107\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-21T08:57:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2025\/10\/QS7001_QAI-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"864\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Asma Adhimi, A Delapalisse\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"A Delapalisse\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/sealsq-presente-la-premiere-puce-de-securite-post-quantique\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/sealsq-presente-la-premiere-puce-de-securite-post-quantique\/\"},\"author\":{\"name\":\"A Delapalisse\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/0aa2cfb0bd8949724a68cbac8d8321b4\"},\"headline\":\"SEALSQ pr\u00e9sente la premi\u00e8re puce de s\u00e9curit\u00e9 post-quantique\",\"datePublished\":\"2025-10-21T08:57:16+00:00\",\"dateModified\":\"2025-10-21T08:57:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/sealsq-presente-la-premiere-puce-de-securite-post-quantique\/\"},\"wordCount\":806,\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"keywords\":[\"Crypto Quantique\",\"NIST\",\"PQC\"],\"articleSection\":[\"Nouvelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/sealsq-presente-la-premiere-puce-de-securite-post-quantique\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/sealsq-presente-la-premiere-puce-de-securite-post-quantique\/\",\"name\":\"SEALSQ pr\u00e9sente la premi\u00e8re puce de s\u00e9curit\u00e9 post-quantique -\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\"},\"datePublished\":\"2025-10-21T08:57:16+00:00\",\"dateModified\":\"2025-10-21T08:57:16+00:00\",\"description\":\"SEALSQ lance le Quantum Shield QS7001, une puce qui apporte aux appareils connect\u00e9s une s\u00e9curit\u00e9 post-quantique bas\u00e9e sur le mat\u00e9riel.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/sealsq-presente-la-premiere-puce-de-securite-post-quantique\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/sealsq-presente-la-premiere-puce-de-securite-post-quantique\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/sealsq-presente-la-premiere-puce-de-securite-post-quantique\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SEALSQ pr\u00e9sente la premi\u00e8re puce de s\u00e9curit\u00e9 post-quantique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/0aa2cfb0bd8949724a68cbac8d8321b4\",\"name\":\"A Delapalisse\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/211ac42237c2e9683c0964086c393cb4\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ad45a8c5da24bc9c7c4940dd1c48a695?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ad45a8c5da24bc9c7c4940dd1c48a695?s=96&d=mm&r=g\",\"caption\":\"A Delapalisse\"},\"sameAs\":[\"http:\/\/ECI\"]}]}<\/script>","yoast_head_json":{"title":"SEALSQ pr\u00e9sente la premi\u00e8re puce de s\u00e9curit\u00e9 post-quantique ...","description":"SEALSQ lance le Quantum Shield QS7001, une puce qui apporte aux appareils connect\u00e9s une s\u00e9curit\u00e9 post-quantique bas\u00e9e sur le mat\u00e9riel.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/487107\/","og_locale":"fr_FR","og_type":"article","og_title":"SEALSQ pr\u00e9sente la premi\u00e8re puce de s\u00e9curit\u00e9 post-quantique","og_description":"SEALSQ lance le Quantum Shield QS7001, une puce qui apporte aux appareils connect\u00e9s une s\u00e9curit\u00e9 post-quantique bas\u00e9e sur le mat\u00e9riel.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/487107\/","og_site_name":"EENewsEurope","article_published_time":"2025-10-21T08:57:16+00:00","og_image":[{"width":1080,"height":864,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2025\/10\/QS7001_QAI-scaled.jpg","type":"image\/jpeg"}],"author":"Asma Adhimi, A Delapalisse","twitter_card":"summary_large_image","twitter_misc":{"Written by":"A Delapalisse","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/sealsq-presente-la-premiere-puce-de-securite-post-quantique\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/sealsq-presente-la-premiere-puce-de-securite-post-quantique\/"},"author":{"name":"A Delapalisse","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/0aa2cfb0bd8949724a68cbac8d8321b4"},"headline":"SEALSQ pr\u00e9sente la premi\u00e8re puce de s\u00e9curit\u00e9 post-quantique","datePublished":"2025-10-21T08:57:16+00:00","dateModified":"2025-10-21T08:57:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/sealsq-presente-la-premiere-puce-de-securite-post-quantique\/"},"wordCount":806,"publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"keywords":["Crypto Quantique","NIST","PQC"],"articleSection":["Nouvelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/sealsq-presente-la-premiere-puce-de-securite-post-quantique\/","url":"https:\/\/www.ecinews.fr\/fr\/sealsq-presente-la-premiere-puce-de-securite-post-quantique\/","name":"SEALSQ pr\u00e9sente la premi\u00e8re puce de s\u00e9curit\u00e9 post-quantique -","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/#website"},"datePublished":"2025-10-21T08:57:16+00:00","dateModified":"2025-10-21T08:57:16+00:00","description":"SEALSQ lance le Quantum Shield QS7001, une puce qui apporte aux appareils connect\u00e9s une s\u00e9curit\u00e9 post-quantique bas\u00e9e sur le mat\u00e9riel.","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/sealsq-presente-la-premiere-puce-de-securite-post-quantique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/sealsq-presente-la-premiere-puce-de-securite-post-quantique\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/sealsq-presente-la-premiere-puce-de-securite-post-quantique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"SEALSQ pr\u00e9sente la premi\u00e8re puce de s\u00e9curit\u00e9 post-quantique"}]},{"@type":"WebSite","@id":"https:\/\/www.ecinews.fr\/fr\/#website","url":"https:\/\/www.ecinews.fr\/fr\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ecinews.fr\/fr\/#organization","name":"EENewsEurope","url":"https:\/\/www.ecinews.fr\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/0aa2cfb0bd8949724a68cbac8d8321b4","name":"A Delapalisse","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/211ac42237c2e9683c0964086c393cb4","url":"https:\/\/secure.gravatar.com\/avatar\/ad45a8c5da24bc9c7c4940dd1c48a695?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad45a8c5da24bc9c7c4940dd1c48a695?s=96&d=mm&r=g","caption":"A Delapalisse"},"sameAs":["http:\/\/ECI"]}]}},"authors":[{"term_id":10490,"user_id":0,"is_guest":1,"slug":"asma-adhimi","display_name":"Asma Adhimi","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""},{"term_id":1153,"user_id":34,"is_guest":0,"slug":"adelapalisse","display_name":"A Delapalisse","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/ad45a8c5da24bc9c7c4940dd1c48a695?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/487107"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=487107"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/487107\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/487056"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=487107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=487107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=487107"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=487107"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=487107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}