{"id":48687,"date":"2020-08-04T00:31:44","date_gmt":"2020-08-04T00:31:44","guid":{"rendered":"https:\/\/\/ansys-accelere-le-developpement-des-systemes-de-securite-passive-des-vehicules\/"},"modified":"2020-08-04T00:31:44","modified_gmt":"2020-08-04T00:31:44","slug":"ansys-accelere-le-developpement-des-systemes-de-securite-passive-des-vehicules","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/ansys-accelere-le-developpement-des-systemes-de-securite-passive-des-vehicules\/","title":{"rendered":"Ansys acc\u00e9l\u00e8re le d\u00e9veloppement des syst\u00e8mes de s\u00e9curit\u00e9 passive des v\u00e9hicules"},"content":{"rendered":"<p>Pour \u00eatre consid\u00e9r\u00e9s comme s\u00fbrs, les v\u00e9hicules doivent \u00eatre soumis \u00e0 des sc\u00e9narios de crash test complets et rigoureux pendant les phases de conception et de d\u00e9veloppement. \u00c0 mesure que la complexit\u00e9 des v\u00e9hicules augmente, la r\u00e9glementation relative \u00e0 la r\u00e9ussite de ces tests devient de plus en plus stricte. C\u2019est pourquoi Ansys met \u00e0 disposition des constructeurs automobiles, des outils de simulation haute-fid\u00e9lit\u00e9 permettant de pr\u00e9dire les r\u00e9actions des v\u00e9hicules lors de ces tests et, ainsi, d\u2019acc\u00e9l\u00e9rer les cycles de d\u00e9veloppement et de production.<\/p>\n<p>Les solutions d&rsquo;Ansys prennent en charge les essais de collision virtuels. Elles permettent aux ing\u00e9nieurs d&rsquo;optimiser la conception structurelle pour l&rsquo;absorption d&rsquo;\u00e9nergie lors des collisions et d&rsquo;am\u00e9liorer l&rsquo;interaction entre les diff\u00e9rents syst\u00e8mes de retenue, tels que les tendeurs de ceinture de s\u00e9curit\u00e9 et les airbags frontaux et lat\u00e9raux. Les utilisateurs d\u2019Ansys LS-DYNA peuvent ainsi d\u00e9velopper un concept de s\u00e9curit\u00e9 passive coh\u00e9rent dans un d\u00e9lai tr\u00e8s court et avec une utilisation minimale de mat\u00e9riel.<\/p>\n<p>Ansys LS-DYNA est un solveur multiphysique hautement \u00e9volutif qui simule le comportement de la plupart des composants d&rsquo;un v\u00e9hicule ainsi que du v\u00e9hicule complet dans un cadre math\u00e9matique enti\u00e8rement coupl\u00e9. LS-DYNA est \u00e9volutif sur des architectures informatiques parall\u00e8les \u00e0 hautes performances, dispose d&rsquo;une gamme \u00e9tendue de mod\u00e8les de mat\u00e9riaux et facilite la mise en \u0153uvre rapide des demandes de d\u00e9veloppement.<\/p>\n<p>\u00ab&nbsp;L&rsquo;analyse approfondie et d\u00e9taill\u00e9e des m\u00e9thodes et des algorithmes de LS-DYNA, initi\u00e9e par le groupe BMW, a \u00e9t\u00e9 un projet tr\u00e8s exigeant pour nous&nbsp;\u00bb,&nbsp;d\u00e9clare Ulrich Franz, Directeur g\u00e9n\u00e9ral de DYNAmore. \u00ab&nbsp;Les exigences sp\u00e9cifiques du groupe BMW concernant les fonctionnalit\u00e9s techniques et l&rsquo;int\u00e9gration dans les processus et les flux de travail existants furent les principaux d\u00e9fis. Ils n\u2019ont pu \u00eatre relev\u00e9s qu&rsquo;au prix d\u2019importants efforts \u00e0 tous \u00e9gards. DYNAmore travaille en tant que partenaire permanent dans le d\u00e9veloppement de logiciels, le d\u00e9veloppement de m\u00e9thodes, l&rsquo;assistance aux utilisateurs et en tant qu&rsquo;expert en science des mat\u00e9riaux.&nbsp;\u00bb,&nbsp;ajoute-t-il.<\/p>\n<p>\u00ab&nbsp;Les syst\u00e8mes de s\u00e9curit\u00e9 active et passive am\u00e9liorent la s\u00e9curit\u00e9 routi\u00e8re et sauvent des vies en r\u00e9duisant consid\u00e9rablement le risque de blessure des occupants lors d&rsquo;accidents in\u00e9vitables. Suite \u00e0 l&rsquo;acquisition de LSTC et \u00e0 l&rsquo;int\u00e9gration de LS-DYNA dans nos suites de produits, les capacit\u00e9s d&rsquo;Ansys dans ce domaine sont in\u00e9gal\u00e9es&nbsp;\u00bb,&nbsp;d\u00e9clare Shane Emswiler,&nbsp;Vice-pr\u00e9sident senior d&rsquo;Ansys. \u00ab&nbsp;Nos nombreuses collaborations en cours, combin\u00e9es \u00e0 notre \u00e9cosyst\u00e8me ouvert et \u00e0 nos solutions de simulation de pointe, nous permettent d&rsquo;aller plus loin dans l&rsquo;int\u00e9gration des syst\u00e8mes de s\u00e9curit\u00e9 passive et active pour r\u00e9pondre aux exigences \u00e9lev\u00e9es de l\u2019industrie automobile.&nbsp;\u00bb,&nbsp;conclut-il.<\/p>\n<p><a href=\"http:\/\/www.ansys.com\/%20\/t%20_blank\">www.ansys.com<\/a><\/p>\n<h3 class=\"title\"><a href=\"https:\/\/www.electronique-eci.com\/news\/ansys-parraine-le-premier-tournoi-de-courses-davions-propulsion-electrique\">Ansys parraine le premier tournoi de courses d\u2019avions \u00e0 propulsion \u00e9lectrique<\/a><\/h3>\n<h3 class=\"title\"><a href=\"https:\/\/www.electronique-eci.com\/news\/aeye-collabore-avec-ansys-pour-optimiser-la-securite-des-vehicules-autonomes\">AEye collabore avec Ansys pour optimiser la s\u00e9curit\u00e9 des v\u00e9hicules autonomes<\/a><\/h3>\n<h3 class=\"title\"><a href=\"https:\/\/www.electronique-eci.com\/news\/ansys-et-edge-case-research-ameliorent-la-surete-des-vehicules-autonomes\">Ansys et Edge Case Research am\u00e9liorent la s\u00fbret\u00e9 des v\u00e9hicules autonomes<\/a><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>En collaboration avec son partenaire europ\u00e9en DYNAmore, Ansys fournit au groupe BMW la technologie Ansys LS-DYNA pour le d\u00e9veloppement de syst\u00e8mes de s\u00e9curit\u00e9 passive de la future g\u00e9n\u00e9ration de v\u00e9hicules s\u00fbrs et performants. Ansys LS-DYNA permet aux utilisateurs d&rsquo;optimiser la conception et l&rsquo;analyse des syst\u00e8mes de s\u00e9curit\u00e9 passive, en permettant des pr\u00e9visions plus pr\u00e9cises du comportement des v\u00e9hicules lors des collisions. <\/p>\n","protected":false},"author":9,"featured_media":48688,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-48687","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Ansys acc\u00e9l\u00e8re le d\u00e9veloppement des syst\u00e8mes de s\u00e9curit\u00e9 ...<\/title>\n<meta name=\"description\" content=\"En collaboration avec son partenaire europ\u00e9en DYNAmore, Ansys fournit au groupe BMW la technologie Ansys LS-DYNA pour le d\u00e9veloppement de syst\u00e8mes de...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/48687\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ansys acc\u00e9l\u00e8re le d\u00e9veloppement des syst\u00e8mes de s\u00e9curit\u00e9 passive des v\u00e9hicules\" \/>\n<meta property=\"og:description\" content=\"En collaboration avec son partenaire europ\u00e9en DYNAmore, Ansys fournit au groupe BMW la technologie Ansys LS-DYNA pour le d\u00e9veloppement de syst\u00e8mes de s\u00e9curit\u00e9 passive de la future g\u00e9n\u00e9ration de v\u00e9hicules s\u00fbrs et performants. Ansys LS-DYNA permet aux utilisateurs d&#039;optimiser la conception et l&#039;analyse des syst\u00e8mes de s\u00e9curit\u00e9 passive, en permettant des pr\u00e9visions plus pr\u00e9cises du comportement des v\u00e9hicules lors des collisions.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/48687\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-04T00:31:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8751_ansys.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/test.ecinews.fr\/fr\/ansys-accelere-le-developpement-des-systemes-de-securite-passive-des-vehicules\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/test.ecinews.fr\/fr\/ansys-accelere-le-developpement-des-systemes-de-securite-passive-des-vehicules\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Ansys acc\u00e9l\u00e8re le d\u00e9veloppement des syst\u00e8mes de s\u00e9curit\u00e9 passive des v\u00e9hicules\",\"datePublished\":\"2020-08-04T00:31:44+00:00\",\"dateModified\":\"2020-08-04T00:31:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/test.ecinews.fr\/fr\/ansys-accelere-le-developpement-des-systemes-de-securite-passive-des-vehicules\/\"},\"wordCount\":572,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/test.ecinews.fr\/fr\/ansys-accelere-le-developpement-des-systemes-de-securite-passive-des-vehicules\/\",\"url\":\"https:\/\/test.ecinews.fr\/fr\/ansys-accelere-le-developpement-des-systemes-de-securite-passive-des-vehicules\/\",\"name\":\"Ansys acc\u00e9l\u00e8re le d\u00e9veloppement des syst\u00e8mes de s\u00e9curit\u00e9 passive des v\u00e9hicules -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2020-08-04T00:31:44+00:00\",\"dateModified\":\"2020-08-04T00:31:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/test.ecinews.fr\/fr\/ansys-accelere-le-developpement-des-systemes-de-securite-passive-des-vehicules\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/test.ecinews.fr\/fr\/ansys-accelere-le-developpement-des-systemes-de-securite-passive-des-vehicules\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/test.ecinews.fr\/fr\/ansys-accelere-le-developpement-des-systemes-de-securite-passive-des-vehicules\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ansys acc\u00e9l\u00e8re le d\u00e9veloppement des syst\u00e8mes de s\u00e9curit\u00e9 passive des v\u00e9hicules\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Ansys acc\u00e9l\u00e8re le d\u00e9veloppement des syst\u00e8mes de s\u00e9curit\u00e9 ...","description":"En collaboration avec son partenaire europ\u00e9en DYNAmore, Ansys fournit au groupe BMW la technologie Ansys LS-DYNA pour le d\u00e9veloppement de syst\u00e8mes de...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/48687\/","og_locale":"fr_FR","og_type":"article","og_title":"Ansys acc\u00e9l\u00e8re le d\u00e9veloppement des syst\u00e8mes de s\u00e9curit\u00e9 passive des v\u00e9hicules","og_description":"En collaboration avec son partenaire europ\u00e9en DYNAmore, Ansys fournit au groupe BMW la technologie Ansys LS-DYNA pour le d\u00e9veloppement de syst\u00e8mes de s\u00e9curit\u00e9 passive de la future g\u00e9n\u00e9ration de v\u00e9hicules s\u00fbrs et performants. Ansys LS-DYNA permet aux utilisateurs d'optimiser la conception et l'analyse des syst\u00e8mes de s\u00e9curit\u00e9 passive, en permettant des pr\u00e9visions plus pr\u00e9cises du comportement des v\u00e9hicules lors des collisions.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/48687\/","og_site_name":"EENewsEurope","article_published_time":"2020-08-04T00:31:44+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/test.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8751_ansys.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/test.ecinews.fr\/fr\/ansys-accelere-le-developpement-des-systemes-de-securite-passive-des-vehicules\/#article","isPartOf":{"@id":"https:\/\/test.ecinews.fr\/fr\/ansys-accelere-le-developpement-des-systemes-de-securite-passive-des-vehicules\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Ansys acc\u00e9l\u00e8re le d\u00e9veloppement des syst\u00e8mes de s\u00e9curit\u00e9 passive des v\u00e9hicules","datePublished":"2020-08-04T00:31:44+00:00","dateModified":"2020-08-04T00:31:44+00:00","mainEntityOfPage":{"@id":"https:\/\/test.ecinews.fr\/fr\/ansys-accelere-le-developpement-des-systemes-de-securite-passive-des-vehicules\/"},"wordCount":572,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/test.ecinews.fr\/fr\/ansys-accelere-le-developpement-des-systemes-de-securite-passive-des-vehicules\/","url":"https:\/\/test.ecinews.fr\/fr\/ansys-accelere-le-developpement-des-systemes-de-securite-passive-des-vehicules\/","name":"Ansys acc\u00e9l\u00e8re le d\u00e9veloppement des syst\u00e8mes de s\u00e9curit\u00e9 passive des v\u00e9hicules -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2020-08-04T00:31:44+00:00","dateModified":"2020-08-04T00:31:44+00:00","breadcrumb":{"@id":"https:\/\/test.ecinews.fr\/fr\/ansys-accelere-le-developpement-des-systemes-de-securite-passive-des-vehicules\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test.ecinews.fr\/fr\/ansys-accelere-le-developpement-des-systemes-de-securite-passive-des-vehicules\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/test.ecinews.fr\/fr\/ansys-accelere-le-developpement-des-systemes-de-securite-passive-des-vehicules\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Ansys acc\u00e9l\u00e8re le d\u00e9veloppement des syst\u00e8mes de s\u00e9curit\u00e9 passive des v\u00e9hicules"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/48687"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=48687"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/48687\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/48688"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=48687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=48687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=48687"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=48687"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=48687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}