{"id":485045,"date":"2025-08-28T17:49:05","date_gmt":"2025-08-28T15:49:05","guid":{"rendered":"https:\/\/www.ecinews.fr\/?p=485045"},"modified":"2025-08-28T17:49:05","modified_gmt":"2025-08-28T15:49:05","slug":"yokogawa-sl2000-une-nouvelle-reference-pour-lacquisition-de-donnees-haute-performance","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/yokogawa-sl2000-une-nouvelle-reference-pour-lacquisition-de-donnees-haute-performance\/","title":{"rendered":"Yokogawa SL2000 \u2013 Une nouvelle r\u00e9f\u00e9rence pour l\u2019acquisition de donn\u00e9es haute performance"},"content":{"rendered":"<h3>Yokogawa Test &amp; Measurement franchit une nouvelle \u00e9tape dans le domaine de l\u2019acquisition de donn\u00e9es avec le lancement du SL2000, un syst\u00e8me rapide et modulaire qui vient compl\u00e9ter la famille des ScopeCorder. Con\u00e7u pour r\u00e9pondre aux exigences croissantes des secteurs de l\u2019automobile, de la m\u00e9catronique et de l\u2019\u00e9lectronique de puissance, le SL2000 allie la pr\u00e9cision d\u2019un oscilloscope \u00e0 la robustesse d\u2019un enregistreur de donn\u00e9es longue dur\u00e9e.<\/h3>\n<p>Ce syst\u00e8me se distingue par sa capacit\u00e9 \u00e0 capturer des signaux transitoires rapides tout en enregistrant des tendances sur de longues p\u00e9riodes. Gr\u00e2ce \u00e0 sa fonction double capture, il peut atteindre des vitesses d\u2019\u00e9chantillonnage allant jusqu\u2019\u00e0 200 M\u00e9chs\/s\/voie, tout en r\u00e9alisant des calculs math\u00e9matiques en temps r\u00e9el. Cette capacit\u00e9 permet de r\u00e9duire significativement les d\u00e9lais de validation et d\u2019acc\u00e9l\u00e9rer la mise sur le march\u00e9 des produits.<\/p>\n<p>Le SL2000 est \u00e9galement compatible avec la plateforme logicielle IS8000, qui facilite les tests d\u2019endurance et am\u00e9liore la productivit\u00e9. Son architecture isol\u00e9e garantit une immunit\u00e9 au bruit optimale, m\u00eame dans des environnements industriels exigeants.<\/p>\n<p>Avec huit emplacements modulaires et plus de 20 types de modules d\u2019entr\u00e9e, le SL2000 peut mesurer des signaux \u00e9lectriques, m\u00e9caniques et d\u00e9coder des bus s\u00e9rie automobiles comme le CAN et le CAN FD. Il est possible de synchroniser jusqu\u2019\u00e0 cinq unit\u00e9s SL2000 ou DL950, offrant une flexibilit\u00e9 in\u00e9gal\u00e9e pour les acquisitions multivoies.<\/p>\n<p>Le SL2000 s\u2019adresse \u00e0 des march\u00e9s vari\u00e9s : transport, \u00e9nergie, m\u00e9catronique, et trouve des applications dans les tests d\u2019endurance, l\u2019analyse de signaux m\u00e9caniques et \u00e9lectriques, ou encore la caract\u00e9risation de syst\u00e8mes de commande.<\/p>\n<p>Avec une interface PC rapide, une compatibilit\u00e9 avec les standards IEEE1588 pour la synchronisation, et des outils logiciels avanc\u00e9s (API, drivers LabVIEW, exemples Python, etc.), le SL2000 s\u2019impose comme une solution compl\u00e8te et \u00e9volutive pour les ing\u00e9nieurs et chercheurs en qu\u00eate de pr\u00e9cision et de fiabilit\u00e9.<\/p>\n<p><a href=\"https:\/\/tmi.yokogawa.com\/\">Yokogawa Test &amp; Measurement<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Yokogawa Test &amp; Measurement franchit une nouvelle \u00e9tape dans le domaine de l\u2019acquisition de donn\u00e9es avec le lancement du SL2000, un syst\u00e8me rapide et modulaire qui vient compl\u00e9ter la famille des ScopeCorder. Con\u00e7u pour r\u00e9pondre aux exigences croissantes des secteurs de l\u2019automobile, de la m\u00e9catronique et de l\u2019\u00e9lectronique de puissance, le SL2000 allie la pr\u00e9cision [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":485048,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[1128,4015,6157],"domains":[47],"ppma_author":[6113],"class_list":["post-485045","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","tag-acquisition-de-donnees","tag-test-mesure","tag-test-mesures","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Yokogawa SL2000 \u2013 Une nouvelle r\u00e9f\u00e9rence pour l\u2019acquisiti...<\/title>\n<meta name=\"description\" content=\"Yokogawa Test &amp; Measurement franchit une nouvelle \u00e9tape dans le domaine de l\u2019acquisition de donn\u00e9es avec le lancement du SL2000, un syst\u00e8me rapide et...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/485045\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Yokogawa SL2000 \u2013 Une nouvelle r\u00e9f\u00e9rence pour l\u2019acquisition de donn\u00e9es haute performance\" \/>\n<meta property=\"og:description\" content=\"Yokogawa Test &amp; Measurement franchit une nouvelle \u00e9tape dans le domaine de l\u2019acquisition de donn\u00e9es avec le lancement du SL2000, un syst\u00e8me rapide et modulaire qui vient compl\u00e9ter la famille des ScopeCorder.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/485045\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-28T15:49:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test.ecinews.fr\/wp-content\/uploads\/2025\/08\/ECI5119-Yokogawa-PR007-2025-SL2000-high-speed-data-acquisition-unit-product-press-release_FINAL_FR-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"696\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"NicolasFeste\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"NicolasFeste\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/test.ecinews.fr\/fr\/yokogawa-sl2000-une-nouvelle-reference-pour-lacquisition-de-donnees-haute-performance\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/test.ecinews.fr\/fr\/yokogawa-sl2000-une-nouvelle-reference-pour-lacquisition-de-donnees-haute-performance\/\"},\"author\":{\"name\":\"NicolasFeste\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/c7104a72b466a801f257e51481de0c43\"},\"headline\":\"Yokogawa SL2000 \u2013 Une nouvelle r\u00e9f\u00e9rence pour l\u2019acquisition de donn\u00e9es haute performance\",\"datePublished\":\"2025-08-28T15:49:05+00:00\",\"dateModified\":\"2025-08-28T15:49:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/test.ecinews.fr\/fr\/yokogawa-sl2000-une-nouvelle-reference-pour-lacquisition-de-donnees-haute-performance\/\"},\"wordCount\":365,\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"keywords\":[\"Acquisition de donn\u00e9es\",\"Test &amp; Mesure\",\"Test &amp; mesures\"],\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/test.ecinews.fr\/fr\/yokogawa-sl2000-une-nouvelle-reference-pour-lacquisition-de-donnees-haute-performance\/\",\"url\":\"https:\/\/test.ecinews.fr\/fr\/yokogawa-sl2000-une-nouvelle-reference-pour-lacquisition-de-donnees-haute-performance\/\",\"name\":\"Yokogawa SL2000 \u2013 Une nouvelle r\u00e9f\u00e9rence pour l\u2019acquisition de donn\u00e9es haute performance -\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\"},\"datePublished\":\"2025-08-28T15:49:05+00:00\",\"dateModified\":\"2025-08-28T15:49:05+00:00\",\"description\":\"Yokogawa Test & Measurement franchit une nouvelle \u00e9tape dans le domaine de l\u2019acquisition de donn\u00e9es avec le lancement du SL2000, un syst\u00e8me rapide et modulaire qui vient compl\u00e9ter la famille des ScopeCorder.\",\"breadcrumb\":{\"@id\":\"https:\/\/test.ecinews.fr\/fr\/yokogawa-sl2000-une-nouvelle-reference-pour-lacquisition-de-donnees-haute-performance\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/test.ecinews.fr\/fr\/yokogawa-sl2000-une-nouvelle-reference-pour-lacquisition-de-donnees-haute-performance\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/test.ecinews.fr\/fr\/yokogawa-sl2000-une-nouvelle-reference-pour-lacquisition-de-donnees-haute-performance\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Yokogawa SL2000 \u2013 Une nouvelle r\u00e9f\u00e9rence pour l\u2019acquisition de donn\u00e9es haute performance\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/c7104a72b466a801f257e51481de0c43\",\"name\":\"NicolasFeste\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/1ea421e7d03c1e96a9ea2bcf2705734a\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2e187f4d96902933ba445ed6c760e11c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2e187f4d96902933ba445ed6c760e11c?s=96&d=mm&r=g\",\"caption\":\"NicolasFeste\"}}]}<\/script>","yoast_head_json":{"title":"Yokogawa SL2000 \u2013 Une nouvelle r\u00e9f\u00e9rence pour l\u2019acquisiti...","description":"Yokogawa Test & Measurement franchit une nouvelle \u00e9tape dans le domaine de l\u2019acquisition de donn\u00e9es avec le lancement du SL2000, un syst\u00e8me rapide et...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/485045\/","og_locale":"fr_FR","og_type":"article","og_title":"Yokogawa SL2000 \u2013 Une nouvelle r\u00e9f\u00e9rence pour l\u2019acquisition de donn\u00e9es haute performance","og_description":"Yokogawa Test & Measurement franchit une nouvelle \u00e9tape dans le domaine de l\u2019acquisition de donn\u00e9es avec le lancement du SL2000, un syst\u00e8me rapide et modulaire qui vient compl\u00e9ter la famille des ScopeCorder.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/485045\/","og_site_name":"EENewsEurope","article_published_time":"2025-08-28T15:49:05+00:00","og_image":[{"width":1080,"height":696,"url":"https:\/\/test.ecinews.fr\/wp-content\/uploads\/2025\/08\/ECI5119-Yokogawa-PR007-2025-SL2000-high-speed-data-acquisition-unit-product-press-release_FINAL_FR-scaled.jpg","type":"image\/jpeg"}],"author":"NicolasFeste","twitter_card":"summary_large_image","twitter_misc":{"Written by":"NicolasFeste","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/test.ecinews.fr\/fr\/yokogawa-sl2000-une-nouvelle-reference-pour-lacquisition-de-donnees-haute-performance\/#article","isPartOf":{"@id":"https:\/\/test.ecinews.fr\/fr\/yokogawa-sl2000-une-nouvelle-reference-pour-lacquisition-de-donnees-haute-performance\/"},"author":{"name":"NicolasFeste","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/c7104a72b466a801f257e51481de0c43"},"headline":"Yokogawa SL2000 \u2013 Une nouvelle r\u00e9f\u00e9rence pour l\u2019acquisition de donn\u00e9es haute performance","datePublished":"2025-08-28T15:49:05+00:00","dateModified":"2025-08-28T15:49:05+00:00","mainEntityOfPage":{"@id":"https:\/\/test.ecinews.fr\/fr\/yokogawa-sl2000-une-nouvelle-reference-pour-lacquisition-de-donnees-haute-performance\/"},"wordCount":365,"publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"keywords":["Acquisition de donn\u00e9es","Test &amp; Mesure","Test &amp; mesures"],"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/test.ecinews.fr\/fr\/yokogawa-sl2000-une-nouvelle-reference-pour-lacquisition-de-donnees-haute-performance\/","url":"https:\/\/test.ecinews.fr\/fr\/yokogawa-sl2000-une-nouvelle-reference-pour-lacquisition-de-donnees-haute-performance\/","name":"Yokogawa SL2000 \u2013 Une nouvelle r\u00e9f\u00e9rence pour l\u2019acquisition de donn\u00e9es haute performance -","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/#website"},"datePublished":"2025-08-28T15:49:05+00:00","dateModified":"2025-08-28T15:49:05+00:00","description":"Yokogawa Test & Measurement franchit une nouvelle \u00e9tape dans le domaine de l\u2019acquisition de donn\u00e9es avec le lancement du SL2000, un syst\u00e8me rapide et modulaire qui vient compl\u00e9ter la famille des ScopeCorder.","breadcrumb":{"@id":"https:\/\/test.ecinews.fr\/fr\/yokogawa-sl2000-une-nouvelle-reference-pour-lacquisition-de-donnees-haute-performance\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test.ecinews.fr\/fr\/yokogawa-sl2000-une-nouvelle-reference-pour-lacquisition-de-donnees-haute-performance\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/test.ecinews.fr\/fr\/yokogawa-sl2000-une-nouvelle-reference-pour-lacquisition-de-donnees-haute-performance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Yokogawa SL2000 \u2013 Une nouvelle r\u00e9f\u00e9rence pour l\u2019acquisition de donn\u00e9es haute performance"}]},{"@type":"WebSite","@id":"https:\/\/www.ecinews.fr\/fr\/#website","url":"https:\/\/www.ecinews.fr\/fr\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ecinews.fr\/fr\/#organization","name":"EENewsEurope","url":"https:\/\/www.ecinews.fr\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/c7104a72b466a801f257e51481de0c43","name":"NicolasFeste","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/1ea421e7d03c1e96a9ea2bcf2705734a","url":"https:\/\/secure.gravatar.com\/avatar\/2e187f4d96902933ba445ed6c760e11c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2e187f4d96902933ba445ed6c760e11c?s=96&d=mm&r=g","caption":"NicolasFeste"}}]}},"authors":[{"term_id":6113,"user_id":39,"is_guest":0,"slug":"nicolasfeste","display_name":"NicolasFeste","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/2e187f4d96902933ba445ed6c760e11c?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/485045"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=485045"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/485045\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/485048"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=485045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=485045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=485045"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=485045"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=485045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}