{"id":483525,"date":"2025-07-23T09:00:03","date_gmt":"2025-07-23T07:00:03","guid":{"rendered":"https:\/\/www.ecinews.fr\/?p=483525"},"modified":"2025-07-23T01:05:56","modified_gmt":"2025-07-22T23:05:56","slug":"omron-renforce-la-detection-detat-et-de-defaut-avec-ses-nouveaux-commutateurs-ultra-subminiatures-d2ew-r","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/omron-renforce-la-detection-detat-et-de-defaut-avec-ses-nouveaux-commutateurs-ultra-subminiatures-d2ew-r\/","title":{"rendered":"OMRON renforce la d\u00e9tection d\u2019\u00e9tat et de d\u00e9faut avec ses nouveaux commutateurs ultra-subminiatures D2EW-R"},"content":{"rendered":"<h3>OMRON Electronic Components Europe \u00e9largit sa gamme de commutateurs \u00e9tanches avec la s\u00e9rie D2EW-R, con\u00e7ue pour offrir une d\u00e9tection avanc\u00e9e d\u2019\u00e9tat et de d\u00e9faut dans les syst\u00e8mes automatis\u00e9s. Gr\u00e2ce \u00e0 l\u2019int\u00e9gration de r\u00e9sistances internes, ces commutateurs permettent de distinguer les \u00e9tats ouverts\/ferm\u00e9s, les courts-circuits et les circuits ouverts, facilitant ainsi les diagnostics de pannes.<\/h3>\n<p>Avec un format ultra-compact (8,3 mm x 7,0 mm x 5,3 mm), les D2EW-R conservent la flexibilit\u00e9 d\u2019installation sans levier, tout en assurant une utilisation silencieuse gr\u00e2ce \u00e0 leur contact coulissant. Leur protection IP67 les rend r\u00e9sistants aux chocs et vibrations, id\u00e9als pour les environnements industriels exigeants.<\/p>\n<p>Disponibles avec plusieurs options de montage et de connexion, ces commutateurs sont parfaitement adapt\u00e9s aux syst\u00e8mes de s\u00e9curit\u00e9, robots industriels, v\u00e9hicules autonomes (AGV\/AMR) et compteurs connect\u00e9s. Ils compl\u00e8tent la large gamme de commutateurs miniatures d\u2019OMRON, offrant des solutions pour des charges faibles \u00e0 \u00e9lev\u00e9es.<\/p>\n<p><a href=\"https:\/\/www.omron.com\/\">OMRON Corporation<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>OMRON Electronic Components Europe \u00e9largit sa gamme de commutateurs \u00e9tanches avec la s\u00e9rie D2EW-R, con\u00e7ue pour offrir une d\u00e9tection avanc\u00e9e d\u2019\u00e9tat et de d\u00e9faut dans les syst\u00e8mes automatis\u00e9s. Gr\u00e2ce \u00e0 l\u2019int\u00e9gration de r\u00e9sistances internes, ces commutateurs permettent de distinguer les \u00e9tats ouverts\/ferm\u00e9s, les courts-circuits et les circuits ouverts, facilitant ainsi les diagnostics de pannes. Avec [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":483538,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[3792],"domains":[47],"ppma_author":[6113],"class_list":["post-483525","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","tag-commutateurs","domains-electronique-eci"],"acf":[],"yoast_head":"<title>OMRON renforce la d\u00e9tection d\u2019\u00e9tat et de d\u00e9faut avec ses n...<\/title>\n<meta name=\"description\" content=\"OMRON Electronic Components Europe \u00e9largit sa gamme de commutateurs \u00e9tanches avec la s\u00e9rie D2EW-R, con\u00e7ue pour offrir une d\u00e9tection avanc\u00e9e d\u2019\u00e9tat...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/483525\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OMRON renforce la d\u00e9tection d\u2019\u00e9tat et de d\u00e9faut avec ses nouveaux commutateurs ultra-subminiatures D2EW-R\" \/>\n<meta property=\"og:description\" content=\"OMRON Electronic Components Europe \u00e9largit sa gamme de commutateurs \u00e9tanches avec la s\u00e9rie D2EW-R, con\u00e7ue pour offrir une d\u00e9tection avanc\u00e9e d\u2019\u00e9tat et de d\u00e9faut dans les syst\u00e8mes automatis\u00e9s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/483525\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-23T07:00:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-22T23:05:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/2025\/07\/ECI5042-OM21fr-Omron-D2EW-R-press-release_final-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"694\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"NicolasFeste\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"NicolasFeste\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/omron-renforce-la-detection-detat-et-de-defaut-avec-ses-nouveaux-commutateurs-ultra-subminiatures-d2ew-r\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/omron-renforce-la-detection-detat-et-de-defaut-avec-ses-nouveaux-commutateurs-ultra-subminiatures-d2ew-r\/\"},\"author\":{\"name\":\"NicolasFeste\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/c7104a72b466a801f257e51481de0c43\"},\"headline\":\"OMRON renforce la d\u00e9tection d\u2019\u00e9tat et de d\u00e9faut avec ses nouveaux commutateurs ultra-subminiatures D2EW-R\",\"datePublished\":\"2025-07-23T07:00:03+00:00\",\"dateModified\":\"2025-07-22T23:05:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/omron-renforce-la-detection-detat-et-de-defaut-avec-ses-nouveaux-commutateurs-ultra-subminiatures-d2ew-r\/\"},\"wordCount\":188,\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"keywords\":[\"Commutateurs\"],\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/omron-renforce-la-detection-detat-et-de-defaut-avec-ses-nouveaux-commutateurs-ultra-subminiatures-d2ew-r\/\",\"url\":\"https:\/\/www.eenewseurope.com\/fr\/omron-renforce-la-detection-detat-et-de-defaut-avec-ses-nouveaux-commutateurs-ultra-subminiatures-d2ew-r\/\",\"name\":\"OMRON renforce la d\u00e9tection d\u2019\u00e9tat et de d\u00e9faut avec ses nouveaux commutateurs ultra-subminiatures D2EW-R -\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\"},\"datePublished\":\"2025-07-23T07:00:03+00:00\",\"dateModified\":\"2025-07-22T23:05:56+00:00\",\"description\":\"OMRON Electronic Components Europe \u00e9largit sa gamme de commutateurs \u00e9tanches avec la s\u00e9rie D2EW-R, con\u00e7ue pour offrir une d\u00e9tection avanc\u00e9e d\u2019\u00e9tat et de d\u00e9faut dans les syst\u00e8mes automatis\u00e9s\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/omron-renforce-la-detection-detat-et-de-defaut-avec-ses-nouveaux-commutateurs-ultra-subminiatures-d2ew-r\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eenewseurope.com\/fr\/omron-renforce-la-detection-detat-et-de-defaut-avec-ses-nouveaux-commutateurs-ultra-subminiatures-d2ew-r\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/omron-renforce-la-detection-detat-et-de-defaut-avec-ses-nouveaux-commutateurs-ultra-subminiatures-d2ew-r\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OMRON renforce la d\u00e9tection d\u2019\u00e9tat et de d\u00e9faut avec ses nouveaux commutateurs ultra-subminiatures D2EW-R\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/c7104a72b466a801f257e51481de0c43\",\"name\":\"NicolasFeste\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/1ea421e7d03c1e96a9ea2bcf2705734a\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2e187f4d96902933ba445ed6c760e11c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2e187f4d96902933ba445ed6c760e11c?s=96&d=mm&r=g\",\"caption\":\"NicolasFeste\"}}]}<\/script>","yoast_head_json":{"title":"OMRON renforce la d\u00e9tection d\u2019\u00e9tat et de d\u00e9faut avec ses n...","description":"OMRON Electronic Components Europe \u00e9largit sa gamme de commutateurs \u00e9tanches avec la s\u00e9rie D2EW-R, con\u00e7ue pour offrir une d\u00e9tection avanc\u00e9e d\u2019\u00e9tat...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/483525\/","og_locale":"fr_FR","og_type":"article","og_title":"OMRON renforce la d\u00e9tection d\u2019\u00e9tat et de d\u00e9faut avec ses nouveaux commutateurs ultra-subminiatures D2EW-R","og_description":"OMRON Electronic Components Europe \u00e9largit sa gamme de commutateurs \u00e9tanches avec la s\u00e9rie D2EW-R, con\u00e7ue pour offrir une d\u00e9tection avanc\u00e9e d\u2019\u00e9tat et de d\u00e9faut dans les syst\u00e8mes automatis\u00e9s","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/483525\/","og_site_name":"EENewsEurope","article_published_time":"2025-07-23T07:00:03+00:00","article_modified_time":"2025-07-22T23:05:56+00:00","og_image":[{"width":1080,"height":694,"url":"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/2025\/07\/ECI5042-OM21fr-Omron-D2EW-R-press-release_final-scaled.jpg","type":"image\/jpeg"}],"author":"NicolasFeste","twitter_card":"summary_large_image","twitter_misc":{"Written by":"NicolasFeste","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eenewseurope.com\/fr\/omron-renforce-la-detection-detat-et-de-defaut-avec-ses-nouveaux-commutateurs-ultra-subminiatures-d2ew-r\/#article","isPartOf":{"@id":"https:\/\/www.eenewseurope.com\/fr\/omron-renforce-la-detection-detat-et-de-defaut-avec-ses-nouveaux-commutateurs-ultra-subminiatures-d2ew-r\/"},"author":{"name":"NicolasFeste","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/c7104a72b466a801f257e51481de0c43"},"headline":"OMRON renforce la d\u00e9tection d\u2019\u00e9tat et de d\u00e9faut avec ses nouveaux commutateurs ultra-subminiatures D2EW-R","datePublished":"2025-07-23T07:00:03+00:00","dateModified":"2025-07-22T23:05:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eenewseurope.com\/fr\/omron-renforce-la-detection-detat-et-de-defaut-avec-ses-nouveaux-commutateurs-ultra-subminiatures-d2ew-r\/"},"wordCount":188,"publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"keywords":["Commutateurs"],"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.eenewseurope.com\/fr\/omron-renforce-la-detection-detat-et-de-defaut-avec-ses-nouveaux-commutateurs-ultra-subminiatures-d2ew-r\/","url":"https:\/\/www.eenewseurope.com\/fr\/omron-renforce-la-detection-detat-et-de-defaut-avec-ses-nouveaux-commutateurs-ultra-subminiatures-d2ew-r\/","name":"OMRON renforce la d\u00e9tection d\u2019\u00e9tat et de d\u00e9faut avec ses nouveaux commutateurs ultra-subminiatures D2EW-R -","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/#website"},"datePublished":"2025-07-23T07:00:03+00:00","dateModified":"2025-07-22T23:05:56+00:00","description":"OMRON Electronic Components Europe \u00e9largit sa gamme de commutateurs \u00e9tanches avec la s\u00e9rie D2EW-R, con\u00e7ue pour offrir une d\u00e9tection avanc\u00e9e d\u2019\u00e9tat et de d\u00e9faut dans les syst\u00e8mes automatis\u00e9s","breadcrumb":{"@id":"https:\/\/www.eenewseurope.com\/fr\/omron-renforce-la-detection-detat-et-de-defaut-avec-ses-nouveaux-commutateurs-ultra-subminiatures-d2ew-r\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eenewseurope.com\/fr\/omron-renforce-la-detection-detat-et-de-defaut-avec-ses-nouveaux-commutateurs-ultra-subminiatures-d2ew-r\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eenewseurope.com\/fr\/omron-renforce-la-detection-detat-et-de-defaut-avec-ses-nouveaux-commutateurs-ultra-subminiatures-d2ew-r\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"OMRON renforce la d\u00e9tection d\u2019\u00e9tat et de d\u00e9faut avec ses nouveaux commutateurs ultra-subminiatures D2EW-R"}]},{"@type":"WebSite","@id":"https:\/\/www.ecinews.fr\/fr\/#website","url":"https:\/\/www.ecinews.fr\/fr\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ecinews.fr\/fr\/#organization","name":"EENewsEurope","url":"https:\/\/www.ecinews.fr\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/c7104a72b466a801f257e51481de0c43","name":"NicolasFeste","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/1ea421e7d03c1e96a9ea2bcf2705734a","url":"https:\/\/secure.gravatar.com\/avatar\/2e187f4d96902933ba445ed6c760e11c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2e187f4d96902933ba445ed6c760e11c?s=96&d=mm&r=g","caption":"NicolasFeste"}}]}},"authors":[{"term_id":6113,"user_id":39,"is_guest":0,"slug":"nicolasfeste","display_name":"NicolasFeste","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/2e187f4d96902933ba445ed6c760e11c?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/483525"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=483525"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/483525\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/483538"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=483525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=483525"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=483525"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=483525"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=483525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}