{"id":482790,"date":"2025-07-08T09:32:56","date_gmt":"2025-07-08T07:32:56","guid":{"rendered":"https:\/\/www.ecinews.fr\/?p=482790"},"modified":"2025-07-08T09:32:56","modified_gmt":"2025-07-08T07:32:56","slug":"cout-de-la-fermeture-de-belgan-1-million-deuros","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/cout-de-la-fermeture-de-belgan-1-million-deuros\/","title":{"rendered":"Co\u00fbt de la fermeture de BelGaN : 1 million d&rsquo;euros"},"content":{"rendered":"<p>La fermeture de l&rsquo;usine de nitrure de gallium BelGaN en Belgique l&rsquo;ann\u00e9e derni\u00e8re co\u00fbtera aux autorit\u00e9s plus de 1,1 million d&rsquo;euros.<\/p>\n<p>Une proposition du Fonds europ\u00e9en d&rsquo;ajustement \u00e0 la mondialisation pour les travailleurs d\u00e9plac\u00e9s soutiendra 417 employ\u00e9s qui ont perdu leur emploi en juillet 2024. Cette situation a entra\u00een\u00e9 une hausse de 9 % du ch\u00f4mage dans la municipalit\u00e9 d&rsquo;Audenarde, en Flandre orientale. La Belgique a demand\u00e9 l&rsquo;aide du FEM en f\u00e9vrier 2025 et la proposition du FEM doit \u00eatre approuv\u00e9e par le Parlement europ\u00e9en et le Conseil.<\/p>\n<p>Le financement aidera les travailleurs licenci\u00e9s gr\u00e2ce \u00e0 des mesures telles que le conseil, l&rsquo;orientation professionnelle, l&rsquo;aide \u00e0 la recherche d&#8217;emploi et la formation professionnelle. Le FEM couvre 85 % des co\u00fbts (930 000 euros) et le Service flamand de l&#8217;emploi et de la formation professionnelle (VDAB) finance les 15 % restants (170 000 euros). Les autorit\u00e9s belges ont commenc\u00e9 \u00e0 fournir une aide imm\u00e9diatement apr\u00e8s les licenciements, en ao\u00fbt 2024, et le FEM peut couvrir ces co\u00fbts r\u00e9troactivement.<\/p>\n<p>L&rsquo;usine, qui a d\u00e9but\u00e9 avec Mietec et appartenait \u00e0 onsemi avant d&rsquo;\u00eatre vendue \u00e0 BelGaN en f\u00e9vrier 2022, s&rsquo;est concentr\u00e9e sur les dispositifs d&rsquo;alimentation automobile.<\/p>\n<p><a href=\"https:\/\/www.eenewseurope.com\/en\/bidders-line-up-for-belgian-chip-production-site\/\">Trois consortiums seraient int\u00e9ress\u00e9s par l&rsquo;usine<\/a>, principalement pour la photonique. Deux des soumissionnaires sont asiatiques et un est europ\u00e9en. L&rsquo;un des soumissionnaires serait la soci\u00e9t\u00e9 chinoise Silex Microsystems de J\u00e4rf\u00e4lla, en Su\u00e8de, la plus grande fonderie au monde pour les composants MEMS. Les entreprises chinoises ont <a href=\"https:\/\/www.eenewseurope.com\/en\/chinese-buyers-swoop-on-belgan-equipment-assets\/\">achet\u00e9 l&rsquo;\u00e9quipement de fabrication de puces de l&rsquo;usine \u00e0 l&rsquo;<\/a> administrateur.<\/p>\n<p>Un consortium europ\u00e9en aurait vers\u00e9 un acompte de 2 millions d&rsquo;euros pour l&rsquo;usine en avril 2025 dans le cadre d&rsquo;un accord de 20 millions d&rsquo;euros visant \u00e0 utiliser l&rsquo;usine pour fabriquer des <a href=\"https:\/\/www.eenewseurope.com\/en\/bankrupt-belgian-fab-pivots-toward-photonic-ic-production\/\">puces photoniques<\/a>.<\/p>\n<p>\u00ab\u00a0Je soup\u00e7onne que des n\u00e9gociations sont encore en cours sur les modalit\u00e9s et l&rsquo;ampleur de l&rsquo;investissement. Mais il est confirm\u00e9 qu&rsquo;il s&rsquo;agit de la production de puces. Il existe un plan d&rsquo;entreprise pour la production de puces photoniques\u00a0\u00bb, a d\u00e9clar\u00e9 l&rsquo;administrateur Ali Heerman.<\/p>\n<p><a href=\"http:\/\/www.belgan.com\">www.belgan.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La fermeture de l&rsquo;usine de nitrure de gallium BelGaN en Belgique l&rsquo;ann\u00e9e derni\u00e8re co\u00fbtera aux autorit\u00e9s plus de 1,1 million d&rsquo;euros. Une proposition du Fonds europ\u00e9en d&rsquo;ajustement \u00e0 la mondialisation pour les travailleurs d\u00e9plac\u00e9s soutiendra 417 employ\u00e9s qui ont perdu leur emploi en juillet 2024. Cette situation a entra\u00een\u00e9 une hausse de 9 % du [&hellip;]<\/p>\n","protected":false},"author":40,"featured_media":482755,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[880],"tags":[6837,3897],"domains":[47],"ppma_author":[3640,6199],"class_list":["post-482790","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-economiques","tag-belgique","tag-gan-fr-2","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Co\u00fbt de la fermeture de BelGaN : 1 million d&#039;euros ...<\/title>\n<meta name=\"description\" content=\"La fermeture de l&#039;usine de BelGaN en Belgique l&#039;ann\u00e9e derni\u00e8re co\u00fbtera aux autorit\u00e9s plus de 1,1 million d&#039;euros pour soutenir 417 employ\u00e9s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/482790\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Co\u00fbt de la fermeture de BelGaN : 1 million d&#039;euros\" \/>\n<meta property=\"og:description\" content=\"La fermeture de l&#039;usine de BelGaN en Belgique l&#039;ann\u00e9e derni\u00e8re co\u00fbtera aux autorit\u00e9s plus de 1,1 million d&#039;euros pour soutenir 417 employ\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/482790\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-08T07:32:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2025\/07\/BelgaN1-2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nick Flaherty, A Delapalisse\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"A Delapalisse\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/cout-de-la-fermeture-de-belgan-1-million-deuros\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/cout-de-la-fermeture-de-belgan-1-million-deuros\/\"},\"author\":{\"name\":\"A Delapalisse\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/4b3db5ba5c953c5fddeb226df86d8635\"},\"headline\":\"Co\u00fbt de la fermeture de BelGaN : 1 million d&rsquo;euros\",\"datePublished\":\"2025-07-08T07:32:56+00:00\",\"dateModified\":\"2025-07-08T07:32:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/cout-de-la-fermeture-de-belgan-1-million-deuros\/\"},\"wordCount\":378,\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"keywords\":[\"Belgique\",\"GaN\"],\"articleSection\":[\"Actualit\u00e9s \u00e9conomiques\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/cout-de-la-fermeture-de-belgan-1-million-deuros\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/cout-de-la-fermeture-de-belgan-1-million-deuros\/\",\"name\":\"Co\u00fbt de la fermeture de BelGaN : 1 million d'euros -\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\"},\"datePublished\":\"2025-07-08T07:32:56+00:00\",\"dateModified\":\"2025-07-08T07:32:56+00:00\",\"description\":\"La fermeture de l'usine de BelGaN en Belgique l'ann\u00e9e derni\u00e8re co\u00fbtera aux autorit\u00e9s plus de 1,1 million d'euros pour soutenir 417 employ\u00e9s.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/cout-de-la-fermeture-de-belgan-1-million-deuros\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/cout-de-la-fermeture-de-belgan-1-million-deuros\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/cout-de-la-fermeture-de-belgan-1-million-deuros\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Co\u00fbt de la fermeture de BelGaN : 1 million d&rsquo;euros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/4b3db5ba5c953c5fddeb226df86d8635\",\"name\":\"A Delapalisse\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/09af0e1236b95ff53924b8dfe5af278e\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/010f811c0933b47aea7e9204117b17c6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/010f811c0933b47aea7e9204117b17c6?s=96&d=mm&r=g\",\"caption\":\"A Delapalisse\"}}]}<\/script>","yoast_head_json":{"title":"Co\u00fbt de la fermeture de BelGaN : 1 million d'euros ...","description":"La fermeture de l'usine de BelGaN en Belgique l'ann\u00e9e derni\u00e8re co\u00fbtera aux autorit\u00e9s plus de 1,1 million d'euros pour soutenir 417 employ\u00e9s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/482790\/","og_locale":"fr_FR","og_type":"article","og_title":"Co\u00fbt de la fermeture de BelGaN : 1 million d'euros","og_description":"La fermeture de l'usine de BelGaN en Belgique l'ann\u00e9e derni\u00e8re co\u00fbtera aux autorit\u00e9s plus de 1,1 million d'euros pour soutenir 417 employ\u00e9s.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/482790\/","og_site_name":"EENewsEurope","article_published_time":"2025-07-08T07:32:56+00:00","og_image":[{"width":1080,"height":480,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2025\/07\/BelgaN1-2-scaled.jpg","type":"image\/jpeg"}],"author":"Nick Flaherty, A Delapalisse","twitter_card":"summary_large_image","twitter_misc":{"Written by":"A Delapalisse","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/cout-de-la-fermeture-de-belgan-1-million-deuros\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/cout-de-la-fermeture-de-belgan-1-million-deuros\/"},"author":{"name":"A Delapalisse","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/4b3db5ba5c953c5fddeb226df86d8635"},"headline":"Co\u00fbt de la fermeture de BelGaN : 1 million d&rsquo;euros","datePublished":"2025-07-08T07:32:56+00:00","dateModified":"2025-07-08T07:32:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/cout-de-la-fermeture-de-belgan-1-million-deuros\/"},"wordCount":378,"publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"keywords":["Belgique","GaN"],"articleSection":["Actualit\u00e9s \u00e9conomiques"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/cout-de-la-fermeture-de-belgan-1-million-deuros\/","url":"https:\/\/www.ecinews.fr\/fr\/cout-de-la-fermeture-de-belgan-1-million-deuros\/","name":"Co\u00fbt de la fermeture de BelGaN : 1 million d'euros -","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/#website"},"datePublished":"2025-07-08T07:32:56+00:00","dateModified":"2025-07-08T07:32:56+00:00","description":"La fermeture de l'usine de BelGaN en Belgique l'ann\u00e9e derni\u00e8re co\u00fbtera aux autorit\u00e9s plus de 1,1 million d'euros pour soutenir 417 employ\u00e9s.","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/cout-de-la-fermeture-de-belgan-1-million-deuros\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/cout-de-la-fermeture-de-belgan-1-million-deuros\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/cout-de-la-fermeture-de-belgan-1-million-deuros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Co\u00fbt de la fermeture de BelGaN : 1 million d&rsquo;euros"}]},{"@type":"WebSite","@id":"https:\/\/www.ecinews.fr\/fr\/#website","url":"https:\/\/www.ecinews.fr\/fr\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ecinews.fr\/fr\/#organization","name":"EENewsEurope","url":"https:\/\/www.ecinews.fr\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/4b3db5ba5c953c5fddeb226df86d8635","name":"A Delapalisse","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/09af0e1236b95ff53924b8dfe5af278e","url":"https:\/\/secure.gravatar.com\/avatar\/010f811c0933b47aea7e9204117b17c6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/010f811c0933b47aea7e9204117b17c6?s=96&d=mm&r=g","caption":"A Delapalisse"}}]}},"authors":[{"term_id":3640,"user_id":0,"is_guest":1,"slug":"nick-flaherty","display_name":"Nick Flaherty","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""},{"term_id":6199,"user_id":40,"is_guest":0,"slug":"andre-rousselotemisys-com","display_name":"A Delapalisse","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/010f811c0933b47aea7e9204117b17c6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/482790"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=482790"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/482790\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/482755"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=482790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=482790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=482790"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=482790"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=482790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}