{"id":481532,"date":"2025-06-13T08:11:55","date_gmt":"2025-06-13T06:11:55","guid":{"rendered":"https:\/\/www.ecinews.fr\/?p=481532"},"modified":"2025-06-12T18:18:20","modified_gmt":"2025-06-12T16:18:20","slug":"ericsson-et-google-sassocient-pour-un-service-5g-saas","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/ericsson-et-google-sassocient-pour-un-service-5g-saas\/","title":{"rendered":"Ericsson et Google s&rsquo;associent pour un service 5G SaaS"},"content":{"rendered":"<h2>Ericsson a lanc\u00e9 la plateforme Ericsson On-Demand, qui fournit des services de r\u00e9seau central 5G sous la forme d&rsquo;une v\u00e9ritable plateforme SaaS (Software-as-a-Service) aux fournisseurs de services de communications (CSP).<\/h2>\n<p>La plateforme est con\u00e7ue avec Google Cloud, en s&rsquo;appuyant sur l&rsquo;infrastructure AI et Google Kubernetes Engine (GKE), et est g\u00e9r\u00e9e de bout en bout par Ericsson. Elle aidera les CSP \u00e0 \u00e9tablir et \u00e0 \u00e9tendre rapidement les services de r\u00e9seau central 5G, \u00e0 r\u00e9duire les co\u00fbts d&rsquo;exploitation et \u00e0 gagner en flexibilit\u00e9 commerciale gr\u00e2ce \u00e0 une plateforme cloud-native enti\u00e8rement g\u00e9r\u00e9e.<\/p>\n<p>\u00c0 une \u00e9poque o\u00f9 les FSC sont soumis \u00e0 une pression croissante pour innover \u00e0 la vitesse et \u00e0 l&rsquo;\u00e9chelle tout en g\u00e9rant une complexit\u00e9 op\u00e9rationnelle de plus en plus grande, Ericsson On-Demand offre un changement radical en termes d&rsquo;agilit\u00e9 et d&rsquo;efficacit\u00e9. La plateforme d\u00e9ploie l&rsquo;ensemble du noyau en quelques minutes, s&rsquo;adapte en fonction des besoins et permet aux FSC de ne payer que pour ce qu&rsquo;ils utilisent. Les clients n&rsquo;ont pas non plus \u00e0 se pr\u00e9occuper de la gestion de l&rsquo;infrastructure sous-jacente.<\/p>\n<p>Ericsson On-Demand peut \u00eatre provisionn\u00e9 en quelques minutes, en lan\u00e7ant rapidement des services de r\u00e9seau de base sans cycles de d\u00e9ploiement longs et en augmentant instantan\u00e9ment la capacit\u00e9 pour r\u00e9pondre aux demandes de pointe, sans d\u00e9penses d&rsquo;investissement initiales ni sur-provisionnement. La plateforme permet aux FSC d&rsquo;innover dans le domaine de la 5G \u00e0 la m\u00eame vitesse que le cloud et de se d\u00e9velopper \u00e0 l&rsquo;\u00e9chelle mondiale. Une autre caract\u00e9ristique cl\u00e9 est la tarification rentable et transparente gr\u00e2ce \u00e0 la facturation bas\u00e9e sur la consommation, sans frais d&rsquo;infrastructure ou de licence. La s\u00e9curit\u00e9 et le contr\u00f4le int\u00e9gr\u00e9s comprennent des d\u00e9ploiements g\u00e9o-restreints, des politiques de gestion de l&rsquo;identit\u00e9 et de l&rsquo;acc\u00e8s (IAM) et des pare-feux natifs du cloud.<\/p>\n<p>En outre, Ericsson fournit une exploitation enti\u00e8rement g\u00e9r\u00e9e avec ses \u00e9quipes d&rsquo;ing\u00e9nierie de fiabilit\u00e9 des sites (SRE) 24\/7, le d\u00e9pannage assist\u00e9 par l&rsquo;IA et l&rsquo;automatisation du cycle de vie, ce qui r\u00e9duit encore le temps de r\u00e9solution et les frais g\u00e9n\u00e9raux d&rsquo;exploitation.<\/p>\n<p>Ericsson On-Demand combine une fiabilit\u00e9 de niveau t\u00e9l\u00e9com avec la flexibilit\u00e9 du cloud public. La plateforme s&rsquo;appuie sur GKE pour simplifier et am\u00e9liorer la disponibilit\u00e9 du r\u00e9seau, en plus de l&rsquo;infrastructure AI compl\u00e8te de Google Cloud, qui est disponible \u00e0 l&rsquo;\u00e9chelle mondiale dans 42 r\u00e9gions de cloud et sur plus de deux millions de kilom\u00e8tres de fibres terrestres et sous-marines.<\/p>\n<p>La plateforme 5G aide \u00e9galement les FSC \u00e0 ajouter progressivement de nouvelles fonctionnalit\u00e9s \u00e0 leurs syst\u00e8mes existants, petit \u00e0 petit, sans causer de temps d&rsquo;arr\u00eat. Son architecture s\u00e9curis\u00e9e d\u00e8s la conception est conforme \u00e0 l \u00ab \u00e9volution des r\u00e9glementations et aux exigences de souverainet\u00e9, ce qui offre des options de d\u00e9ploiement \u00e0 l \u00bb \u00e9chelle mondiale.<\/p>\n<p>Qu&rsquo;il s&rsquo;agisse de mettre en place des r\u00e9seaux d&rsquo;entreprise \u00e0 grande \u00e9chelle, d&rsquo;acc\u00e9l\u00e9rer les d\u00e9ploiements d&rsquo;acc\u00e8s sans fil fixe (FWA) ou d&rsquo;explorer de nouveaux march\u00e9s, la plateforme 5G permet aux FSC de passer de l&rsquo;id\u00e9e \u00e0 l&rsquo;ex\u00e9cution avec une rapidit\u00e9 in\u00e9gal\u00e9e.<\/p>\n<p><a href=\"http:\/\/www.ericsson.com\">www.ericsson.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fournit des services de base 5G en quelques minutes, ce qui permet aux FSC d&rsquo;\u00e9voluer sans effort et de ne payer que pour ce qui est utilis\u00e9.<\/p>\n","protected":false},"author":40,"featured_media":481518,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[880,883],"tags":[2122,8307,9985,9983,6357,9984],"domains":[47],"ppma_author":[3682,6199],"class_list":["post-481532","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-economiques","category-technologies","tag-5g-fr-2","tag-communications-service-providers","tag-ericsson-fr","tag-fsc","tag-google-cloud-fr","tag-saas-fr","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Ericsson et Google s&#039;associent pour un service 5G SaaS ...<\/title>\n<meta name=\"description\" content=\"Fournit des services de base 5G en quelques minutes, ce qui permet aux FSC d&#039;\u00e9voluer sans effort et de ne payer que pour ce qui est utilis\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/481532\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ericsson et Google s&#039;associent pour un service 5G SaaS\" \/>\n<meta property=\"og:description\" content=\"Fournit des services de base 5G en quelques minutes, ce qui permet aux FSC d&#039;\u00e9voluer sans effort et de ne payer que pour ce qui est utilis\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/481532\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-13T06:11:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-12T16:18:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2025\/06\/5G-City-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"771\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jean-Pierre Joosting, A Delapalisse\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"A Delapalisse\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/ericsson-et-google-sassocient-pour-un-service-5g-saas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/ericsson-et-google-sassocient-pour-un-service-5g-saas\/\"},\"author\":{\"name\":\"A Delapalisse\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/4b3db5ba5c953c5fddeb226df86d8635\"},\"headline\":\"Ericsson et Google s&rsquo;associent pour un service 5G SaaS\",\"datePublished\":\"2025-06-13T06:11:55+00:00\",\"dateModified\":\"2025-06-12T16:18:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/ericsson-et-google-sassocient-pour-un-service-5g-saas\/\"},\"wordCount\":578,\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"keywords\":[\"5G\",\"Communications Service Providers\",\"Ericsson\",\"FSC\",\"Google Cloud\",\"SAAS\"],\"articleSection\":[\"Actualit\u00e9s \u00e9conomiques\",\"Technologies\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/ericsson-et-google-sassocient-pour-un-service-5g-saas\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/ericsson-et-google-sassocient-pour-un-service-5g-saas\/\",\"name\":\"Ericsson et Google s'associent pour un service 5G SaaS -\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\"},\"datePublished\":\"2025-06-13T06:11:55+00:00\",\"dateModified\":\"2025-06-12T16:18:20+00:00\",\"description\":\"Fournit des services de base 5G en quelques minutes, ce qui permet aux FSC d'\u00e9voluer sans effort et de ne payer que pour ce qui est utilis\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/ericsson-et-google-sassocient-pour-un-service-5g-saas\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/ericsson-et-google-sassocient-pour-un-service-5g-saas\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/ericsson-et-google-sassocient-pour-un-service-5g-saas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ericsson et Google s&rsquo;associent pour un service 5G SaaS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/4b3db5ba5c953c5fddeb226df86d8635\",\"name\":\"A Delapalisse\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/09af0e1236b95ff53924b8dfe5af278e\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/010f811c0933b47aea7e9204117b17c6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/010f811c0933b47aea7e9204117b17c6?s=96&d=mm&r=g\",\"caption\":\"A Delapalisse\"}}]}<\/script>","yoast_head_json":{"title":"Ericsson et Google s'associent pour un service 5G SaaS ...","description":"Fournit des services de base 5G en quelques minutes, ce qui permet aux FSC d'\u00e9voluer sans effort et de ne payer que pour ce qui est utilis\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/481532\/","og_locale":"fr_FR","og_type":"article","og_title":"Ericsson et Google s'associent pour un service 5G SaaS","og_description":"Fournit des services de base 5G en quelques minutes, ce qui permet aux FSC d'\u00e9voluer sans effort et de ne payer que pour ce qui est utilis\u00e9.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/481532\/","og_site_name":"EENewsEurope","article_published_time":"2025-06-13T06:11:55+00:00","article_modified_time":"2025-06-12T16:18:20+00:00","og_image":[{"width":1080,"height":771,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2025\/06\/5G-City-scaled.jpg","type":"image\/jpeg"}],"author":"Jean-Pierre Joosting, A Delapalisse","twitter_card":"summary_large_image","twitter_misc":{"Written by":"A Delapalisse","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/ericsson-et-google-sassocient-pour-un-service-5g-saas\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/ericsson-et-google-sassocient-pour-un-service-5g-saas\/"},"author":{"name":"A Delapalisse","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/4b3db5ba5c953c5fddeb226df86d8635"},"headline":"Ericsson et Google s&rsquo;associent pour un service 5G SaaS","datePublished":"2025-06-13T06:11:55+00:00","dateModified":"2025-06-12T16:18:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/ericsson-et-google-sassocient-pour-un-service-5g-saas\/"},"wordCount":578,"publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"keywords":["5G","Communications Service Providers","Ericsson","FSC","Google Cloud","SAAS"],"articleSection":["Actualit\u00e9s \u00e9conomiques","Technologies"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/ericsson-et-google-sassocient-pour-un-service-5g-saas\/","url":"https:\/\/www.ecinews.fr\/fr\/ericsson-et-google-sassocient-pour-un-service-5g-saas\/","name":"Ericsson et Google s'associent pour un service 5G SaaS -","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/#website"},"datePublished":"2025-06-13T06:11:55+00:00","dateModified":"2025-06-12T16:18:20+00:00","description":"Fournit des services de base 5G en quelques minutes, ce qui permet aux FSC d'\u00e9voluer sans effort et de ne payer que pour ce qui est utilis\u00e9.","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/ericsson-et-google-sassocient-pour-un-service-5g-saas\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/ericsson-et-google-sassocient-pour-un-service-5g-saas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/ericsson-et-google-sassocient-pour-un-service-5g-saas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Ericsson et Google s&rsquo;associent pour un service 5G SaaS"}]},{"@type":"WebSite","@id":"https:\/\/www.ecinews.fr\/fr\/#website","url":"https:\/\/www.ecinews.fr\/fr\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ecinews.fr\/fr\/#organization","name":"EENewsEurope","url":"https:\/\/www.ecinews.fr\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/4b3db5ba5c953c5fddeb226df86d8635","name":"A Delapalisse","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/09af0e1236b95ff53924b8dfe5af278e","url":"https:\/\/secure.gravatar.com\/avatar\/010f811c0933b47aea7e9204117b17c6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/010f811c0933b47aea7e9204117b17c6?s=96&d=mm&r=g","caption":"A Delapalisse"}}]}},"authors":[{"term_id":3682,"user_id":0,"is_guest":1,"slug":"jean-pierre-joosting","display_name":"Jean-Pierre Joosting","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""},{"term_id":6199,"user_id":40,"is_guest":0,"slug":"andre-rousselotemisys-com","display_name":"A Delapalisse","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/010f811c0933b47aea7e9204117b17c6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/481532"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=481532"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/481532\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/481518"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=481532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=481532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=481532"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=481532"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=481532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}