{"id":481427,"date":"2025-06-11T14:22:48","date_gmt":"2025-06-11T12:22:48","guid":{"rendered":"https:\/\/www.ecinews.fr\/?p=481427"},"modified":"2025-06-11T14:22:48","modified_gmt":"2025-06-11T12:22:48","slug":"renault-soutient-un-developpeur-francais-dexosquelette","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/renault-soutient-un-developpeur-francais-dexosquelette\/","title":{"rendered":"Renault soutient un d\u00e9veloppeur fran\u00e7ais d&rsquo;exosquelette"},"content":{"rendered":"<p>Plut\u00f4t que d&rsquo;utiliser des robots humano\u00efdes, le constructeur automobile fran\u00e7ais Renault soutient une start-up qui d\u00e9veloppe une technologie d&rsquo;exosquelette.<\/p>\n<p>Wandercraft, \u00e0 Paris, est une entreprise d&rsquo;\u00e9lectronique m\u00e9dicale qui d\u00e9veloppe, fabrique et commercialise des exosquelettes auto-\u00e9quilibr\u00e9s, initialement pour aider les personnes handicap\u00e9es \u00e0 marcher. Elle a d\u00e9j\u00e0 lev\u00e9 plus de 67 millions d&rsquo;euros, dont un pr\u00eat de 25 millions d&rsquo;euros de la Banque europ\u00e9enne d&rsquo;investissement (BEI). La valeur de l&rsquo;op\u00e9ration n&rsquo;a pas \u00e9t\u00e9 divulgu\u00e9e.<\/p>\n<p>Dans le cadre d&rsquo;un accord de partenariat commercial, Renault soutiendra le d\u00e9veloppement de la prochaine g\u00e9n\u00e9ration de robots, baptis\u00e9e Calvin-40, initialement destin\u00e9e \u00e0 des usages industriels. Les ouvriers de Renault utiliseront le syst\u00e8me Calvin pour effectuer des t\u00e2ches visant \u00e0 acc\u00e9l\u00e9rer la production.<\/p>\n<p>Il dispose d&rsquo;une gamme d&rsquo;effecteurs adaptables qui peuvent \u00eatre personnalis\u00e9s pour diverses t\u00e2ches telles que le transport d&rsquo;objets lourds ou le rivetage de panneaux. Il utilise le m\u00eame logiciel de qualit\u00e9 m\u00e9dicale que celui qui a \u00e9t\u00e9 d\u00e9velopp\u00e9 pour la premi\u00e8re g\u00e9n\u00e9ration du syst\u00e8me Atalente-X, utilis\u00e9 dans six h\u00f4pitaux \u00e0 travers l&rsquo;Europe.<\/p>\n<ul>\n<li><a href=\"https:\/\/www.eenewseurope.com\/en\/the-march-of-the-humanoid-robots\/\">La marche des robots humano\u00efdes<\/a><\/li>\n<li><a href=\"https:\/\/www.eenewseurope.com\/en\/swiss-drive-maker-teams-on-exoskeleton\/\">Le fabricant suisse d&rsquo;entra\u00eenement fait \u00e9quipe pour l&rsquo;exosquelette chinois<\/a><\/li>\n<li><a href=\"https:\/\/www.eenewseurope.com\/en\/german-bionic-partnership-sees-kulr-move-into-robotics\/\">Un partenariat bionique permet \u00e0 Kulr de se lancer dans la robotique<\/a><\/li>\n<\/ul>\n<p>La capacit\u00e9 d&rsquo;auto-\u00e9quilibrage provient de capteurs de force dans les pieds combin\u00e9s \u00e0 des algorithmes d \u00ab \u00e9quilibre IA pour un contr\u00f4le pr\u00e9cis du centre de masse et des ajustements r\u00e9actifs de l \u00bb \u00e9quilibre, tandis qu&rsquo;une cam\u00e9ra optique et infrarouge permet la manipulation, la navigation et l \u00ab \u00e9vitement des obstacles. Des bandes lumineuses LED communiquent l \u00bb \u00e9tat du syst\u00e8me aux op\u00e9rateurs \u00e0 proximit\u00e9 pour plus de s\u00e9curit\u00e9.<\/p>\n<p>\u00c0 un stade ult\u00e9rieur, le partenariat comprendra \u00e9galement l&rsquo;industrialisation de robots et d&rsquo;exosquelettes par le Groupe Renault afin d&rsquo;augmenter la production et de r\u00e9duire les co\u00fbts. Cela aidera Wandercraft \u00e0 mettre son nouvel exosquelette Eve sur le march\u00e9 et \u00e0 ouvrir de nouvelles perspectives commerciales dans le domaine de la robotique.<\/p>\n<p>German Bionics fabrique \u00e9galement un exosquelette utilis\u00e9 dans les h\u00f4pitaux, \u00e0 l&rsquo;a\u00e9roport local de Nuremberg et chez le d\u00e9taillant Currys au Royaume-Uni. Elle travaille avec le d\u00e9veloppeur am\u00e9ricain de mat\u00e9riaux pour batteries Kulr sur l&rsquo;exosquelette Apogee ULTRA afin d&rsquo;en augmenter la puissance et les capacit\u00e9s d&rsquo;intelligence artificielle.<\/p>\n<p>Renault consid\u00e8re l&rsquo;exosquelette comme un \u00e9l\u00e9ment cl\u00e9 de ses processus futurs d&rsquo;assemblage de v\u00e9hicules.<\/p>\n<p>\u00ab\u00a0Cela nous permettra d&rsquo;acc\u00e9l\u00e9rer l&rsquo;automatisation et de d\u00e9velopper des robots pour notre utilisation industrielle automobile sp\u00e9cifique, nous donnant la possibilit\u00e9 de concentrer notre personnel sur des t\u00e2ches \u00e0 plus forte valeur ajout\u00e9e et de soulager les op\u00e9rateurs de t\u00e2ches p\u00e9nibles et non ergonomiques\u00a0\u00bb, a d\u00e9clar\u00e9 Thierry Charvet, directeur g\u00e9n\u00e9ral de l&rsquo;industrie et de la qualit\u00e9 du groupe Renault. \u00ab\u00a0La productivit\u00e9 sera am\u00e9lior\u00e9e gr\u00e2ce \u00e0 l&rsquo;acc\u00e9l\u00e9ration du temps de production et \u00e0 la r\u00e9duction des co\u00fbts. En fin de compte, il est tout \u00e0 fait logique de combiner l&rsquo;expertise et la technologie uniques de Wandercraft en mati\u00e8re d&rsquo;exosquelettes et de robots, avec la forte capacit\u00e9 industrielle du Groupe Renault et son savoir-faire en mati\u00e8re de conception \u00e0 co\u00fbts r\u00e9duits, afin d&rsquo;assurer la production de robots \u00e0 grande \u00e9chelle.<\/p>\n<p>\u00ab\u00a0L&rsquo;investissement du Groupe Renault marque un moment d\u00e9cisif pour Wandercraft. Ce partenariat va renforcer notre capacit\u00e9 \u00e0 construire et \u00e0 mettre \u00e0 l&rsquo;\u00e9chelle des robots \u00e0 fort impact et \u00e0 faible co\u00fbt qui am\u00e9liorent la vie quotidienne de personnes r\u00e9elles, qu&rsquo;il s&rsquo;agisse d&rsquo;aider les personnes handicap\u00e9es \u00e0 marcher ou de soutenir les travailleurs industriels gr\u00e2ce \u00e0 l&rsquo;automatisation &#8211; dans les usines, les cliniques et \u00e0 la maison. Nous sommes fiers d&rsquo;associer notre technologie \u00e0 l&rsquo;excellence industrielle du Groupe Renault pour proposer la prochaine g\u00e9n\u00e9ration de robotique mobile\u00a0\u00bb, a d\u00e9clar\u00e9 Matthieu Masselin, PDG et cofondateur de Wandercraft.<\/p>\n<p><a title=\"www.renaultgroup.com\" href=\"http:\/\/www.renaultgroup.com\" target=\"_blank\" rel=\"noopener\">www.renaultgroup.com<\/a> <a href=\"http:\/\/www.renaultgroup.com\">;<\/a> <a href=\"http:\/\/www.wandercraft.com\">www.wandercraft.com<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Plut\u00f4t que d&rsquo;utiliser des robots humano\u00efdes, le constructeur automobile fran\u00e7ais Renault soutient une start-up qui d\u00e9veloppe une technologie d&rsquo;exosquelette. Wandercraft, \u00e0 Paris, est une entreprise d&rsquo;\u00e9lectronique m\u00e9dicale qui d\u00e9veloppe, fabrique et commercialise des exosquelettes auto-\u00e9quilibr\u00e9s, initialement pour aider les personnes handicap\u00e9es \u00e0 marcher. Elle a d\u00e9j\u00e0 lev\u00e9 plus de 67 millions d&rsquo;euros, dont un pr\u00eat [&hellip;]<\/p>\n","protected":false},"author":40,"featured_media":481406,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[880],"tags":[891],"domains":[47],"ppma_author":[3640,6199],"class_list":["post-481427","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-economiques","tag-automotive-fr","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Renault soutient un d\u00e9veloppeur fran\u00e7ais d&#039;exosquelette ...<\/title>\n<meta name=\"description\" content=\"Plut\u00f4t que d&#039;utiliser des robots humano\u00efdes, le constructeur automobile Renault soutient Wadercraft pour sa technologie d&#039;exosquelette.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/481427\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Renault soutient un d\u00e9veloppeur fran\u00e7ais d&#039;exosquelette\" \/>\n<meta property=\"og:description\" content=\"Plut\u00f4t que d&#039;utiliser des robots humano\u00efdes, le constructeur automobile Renault soutient Wadercraft pour sa technologie d&#039;exosquelette.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/481427\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-11T12:22:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2025\/06\/wandercraft-calvin-40-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"862\" \/>\n\t<meta property=\"og:image:height\" content=\"862\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nick Flaherty, A Delapalisse\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"A Delapalisse\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/renault-soutient-un-developpeur-francais-dexosquelette\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/renault-soutient-un-developpeur-francais-dexosquelette\/\"},\"author\":{\"name\":\"A Delapalisse\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/4b3db5ba5c953c5fddeb226df86d8635\"},\"headline\":\"Renault soutient un d\u00e9veloppeur fran\u00e7ais d&rsquo;exosquelette\",\"datePublished\":\"2025-06-11T12:22:48+00:00\",\"dateModified\":\"2025-06-11T12:22:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/renault-soutient-un-developpeur-francais-dexosquelette\/\"},\"wordCount\":712,\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"keywords\":[\"Automotive\"],\"articleSection\":[\"Actualit\u00e9s \u00e9conomiques\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/renault-soutient-un-developpeur-francais-dexosquelette\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/renault-soutient-un-developpeur-francais-dexosquelette\/\",\"name\":\"Renault soutient un d\u00e9veloppeur fran\u00e7ais d'exosquelette -\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\"},\"datePublished\":\"2025-06-11T12:22:48+00:00\",\"dateModified\":\"2025-06-11T12:22:48+00:00\",\"description\":\"Plut\u00f4t que d'utiliser des robots humano\u00efdes, le constructeur automobile Renault soutient Wadercraft pour sa technologie d'exosquelette.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/renault-soutient-un-developpeur-francais-dexosquelette\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/renault-soutient-un-developpeur-francais-dexosquelette\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/renault-soutient-un-developpeur-francais-dexosquelette\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Renault soutient un d\u00e9veloppeur fran\u00e7ais d&rsquo;exosquelette\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/4b3db5ba5c953c5fddeb226df86d8635\",\"name\":\"A Delapalisse\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/09af0e1236b95ff53924b8dfe5af278e\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/010f811c0933b47aea7e9204117b17c6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/010f811c0933b47aea7e9204117b17c6?s=96&d=mm&r=g\",\"caption\":\"A Delapalisse\"}}]}<\/script>","yoast_head_json":{"title":"Renault soutient un d\u00e9veloppeur fran\u00e7ais d'exosquelette ...","description":"Plut\u00f4t que d'utiliser des robots humano\u00efdes, le constructeur automobile Renault soutient Wadercraft pour sa technologie d'exosquelette.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/481427\/","og_locale":"fr_FR","og_type":"article","og_title":"Renault soutient un d\u00e9veloppeur fran\u00e7ais d'exosquelette","og_description":"Plut\u00f4t que d'utiliser des robots humano\u00efdes, le constructeur automobile Renault soutient Wadercraft pour sa technologie d'exosquelette.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/481427\/","og_site_name":"EENewsEurope","article_published_time":"2025-06-11T12:22:48+00:00","og_image":[{"width":862,"height":862,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2025\/06\/wandercraft-calvin-40-1.jpg","type":"image\/jpeg"}],"author":"Nick Flaherty, A Delapalisse","twitter_card":"summary_large_image","twitter_misc":{"Written by":"A Delapalisse","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/renault-soutient-un-developpeur-francais-dexosquelette\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/renault-soutient-un-developpeur-francais-dexosquelette\/"},"author":{"name":"A Delapalisse","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/4b3db5ba5c953c5fddeb226df86d8635"},"headline":"Renault soutient un d\u00e9veloppeur fran\u00e7ais d&rsquo;exosquelette","datePublished":"2025-06-11T12:22:48+00:00","dateModified":"2025-06-11T12:22:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/renault-soutient-un-developpeur-francais-dexosquelette\/"},"wordCount":712,"publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"keywords":["Automotive"],"articleSection":["Actualit\u00e9s \u00e9conomiques"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/renault-soutient-un-developpeur-francais-dexosquelette\/","url":"https:\/\/www.ecinews.fr\/fr\/renault-soutient-un-developpeur-francais-dexosquelette\/","name":"Renault soutient un d\u00e9veloppeur fran\u00e7ais d'exosquelette -","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/#website"},"datePublished":"2025-06-11T12:22:48+00:00","dateModified":"2025-06-11T12:22:48+00:00","description":"Plut\u00f4t que d'utiliser des robots humano\u00efdes, le constructeur automobile Renault soutient Wadercraft pour sa technologie d'exosquelette.","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/renault-soutient-un-developpeur-francais-dexosquelette\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/renault-soutient-un-developpeur-francais-dexosquelette\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/renault-soutient-un-developpeur-francais-dexosquelette\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Renault soutient un d\u00e9veloppeur fran\u00e7ais d&rsquo;exosquelette"}]},{"@type":"WebSite","@id":"https:\/\/www.ecinews.fr\/fr\/#website","url":"https:\/\/www.ecinews.fr\/fr\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ecinews.fr\/fr\/#organization","name":"EENewsEurope","url":"https:\/\/www.ecinews.fr\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/4b3db5ba5c953c5fddeb226df86d8635","name":"A Delapalisse","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/09af0e1236b95ff53924b8dfe5af278e","url":"https:\/\/secure.gravatar.com\/avatar\/010f811c0933b47aea7e9204117b17c6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/010f811c0933b47aea7e9204117b17c6?s=96&d=mm&r=g","caption":"A Delapalisse"}}]}},"authors":[{"term_id":3640,"user_id":0,"is_guest":1,"slug":"nick-flaherty","display_name":"Nick Flaherty","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""},{"term_id":6199,"user_id":40,"is_guest":0,"slug":"andre-rousselotemisys-com","display_name":"A Delapalisse","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/010f811c0933b47aea7e9204117b17c6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/481427"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=481427"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/481427\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/481406"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=481427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=481427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=481427"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=481427"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=481427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}