{"id":479415,"date":"2025-05-12T01:00:19","date_gmt":"2025-05-11T23:00:19","guid":{"rendered":"https:\/\/www.ecinews.fr\/?p=479415"},"modified":"2025-05-11T13:48:34","modified_gmt":"2025-05-11T11:48:34","slug":"impression-3d-de-capteurs-rf-haute-performance","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/impression-3d-de-capteurs-rf-haute-performance\/","title":{"rendered":"Impression 3D de capteurs RF haute performance"},"content":{"rendered":"<h3><span style=\"font-size: 16px;\">Des chercheurs chinois ont mis au point une m\u00e9thode r\u00e9volutionnaire pour produire des microstructures 3D \u00e0 haut facteur de forme avec une r\u00e9solution inf\u00e9rieure \u00e0 10 microns pour les capteurs RF.<\/span><\/h3>\n<p>Cette technique permet d&rsquo;obtenir des sillons profonds avec un rapport largeur\/hauteur de 1:4, tout en assurant un contr\u00f4le pr\u00e9cis des propri\u00e9t\u00e9s de r\u00e9sonance et en am\u00e9liorant consid\u00e9rablement les performances. Cette technique hybride permet non seulement d&rsquo;am\u00e9liorer le facteur de qualit\u00e9 (facteur Q) et le r\u00e9glage des fr\u00e9quences des m\u00e9tastructures RF, mais aussi de r\u00e9duire l&rsquo;encombrement des dispositifs jusqu&rsquo;\u00e0 45 %.\u00a0Ce qui ouvre la voie \u00e0 des applications de nouvelle g\u00e9n\u00e9ration dans les domaines de la d\u00e9tection, des MEMS et des m\u00e9tamat\u00e9riaux RF.<\/p>\n<p>Les techniques traditionnelles de lithographie, telles que la lithographie par faisceau d&rsquo;\u00e9lectrons et la nanoimpression, ont eu du mal \u00e0 r\u00e9pondre \u00e0 la demande de structures ultrafines \u00e0 rapport d&rsquo;aspect \u00e9lev\u00e9. Un mauvais contr\u00f4le de l&rsquo;\u00e9paisseur, des parois lat\u00e9rales irr\u00e9guli\u00e8res et des limitations mat\u00e9rielles ont entrav\u00e9 les performances et l&rsquo;\u00e9volutivit\u00e9.<\/p>\n<p>Cette technique combine la polym\u00e9risation \u00e0 deux photons (2PP), l&rsquo;\u00e9lectrod\u00e9position et la gravure \u00e0 sec. Cependant, l&rsquo;int\u00e9gration de la polym\u00e9risation \u00e0 deux photons avec une m\u00e9tallisation robuste pour les composants RF fonctionnels est rest\u00e9e difficile \u00e0 r\u00e9aliser en raison des incompatibilit\u00e9s de processus.<\/p>\n<p>Les chercheurs de l&rsquo;universit\u00e9 de Bilkent et de l&rsquo;universit\u00e9 technologique de Nanyang ont pr\u00e9sent\u00e9 un nouveau processus de fabrication qui utilise le 2PP pour cr\u00e9er des sillons profonds et complexes, qui sont ensuite remplies de cuivre par \u00e9lectrod\u00e9position et affin\u00e9es par gravure \u00e0 sec. Il en r\u00e9sulte des r\u00e9sonateurs RF ultracompacts avec des fr\u00e9quences accordables entre 4 et 6 GHz, un rapport d&rsquo;aspect de 1:4 et des facteurs Q \u00e9lev\u00e9s dans un cadre de r\u00e9solution inf\u00e9rieur \u00e0 10 \u00b5m.<\/p>\n<p><strong>Des structures m\u00e9talliques autonomes<\/strong><\/p>\n<p>Le processus commence par l&rsquo;utilisation de 2PP pour d\u00e9finir des sillons \u00e0 haut rapport d&rsquo;aspect dans une couche de r\u00e9sine photosensible. Ces vides sont ensuite remplis de cuivre \u00e9pais &#8211; jusqu&rsquo;\u00e0 8 \u00b5m &#8211; par galvanoplastie. La gravure s\u00e8che qui s&rsquo;ensuit \u00e9limine les couches d&rsquo;ensemencement, ce qui permet d&rsquo;obtenir des structures m\u00e9talliques autonomes aux parois lat\u00e9rales plates et verticales, d&rsquo;une pr\u00e9cision dimensionnelle remarquable. L&rsquo;\u00e9quipe a d\u00e9montr\u00e9 l&rsquo;existence de microstructures d&rsquo;une largeur de 2-3 \u00b5m et d&rsquo;une hauteur de plus de 10 \u00b5m.<\/p>\n<p>Un recuit rapide est utilis\u00e9 pour renforcer les liaisons en cuivre, ce qui permet de relever les d\u00e9fis thermiques et m\u00e9caniques. La microscopie \u00e9lectronique \u00e0 balayage (MEB) a permis de v\u00e9rifier la grande fid\u00e9lit\u00e9 des structures, confirmant leur robustesse et leur fabricabilit\u00e9.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-479392 lazyload\" data-src=\"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/2025\/05\/China-3D-RF-print.jpg\" alt=\"\" width=\"700\" height=\"399\" data-srcset=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2025\/05\/China-3D-RF-print.jpg 700w, https:\/\/www.ecinews.fr\/wp-content\/uploads\/2025\/05\/China-3D-RF-print-300x171.jpg 300w\" data-sizes=\"(max-width: 700px) 100vw, 700px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 700px; --smush-placeholder-aspect-ratio: 700\/399;\" \/><\/p>\n<p><em>La m\u00e9thode de fabrication commence par <strong>a l&rsquo;<\/strong> application d&rsquo;<strong>une<\/strong> r\u00e9sine photosensible positive AZ-4562 sur un verre recouvert d&rsquo;ITO, <strong>b<\/strong> le placement du substrat pr\u00e9par\u00e9 sur le porte-\u00e9chantillon du syst\u00e8me d&rsquo;impression 3D et l&rsquo;exposition \u00e0 la lumi\u00e8re pour obtenir le motif souhait\u00e9, <strong>c le<\/strong> d\u00e9veloppement de la partie expos\u00e9e de la r\u00e9sine photosensible, <strong>d<\/strong> d\u00e9p\u00f4t d&rsquo;un film \u00e9pais de cuivre m\u00e9tallique sur la couche d&rsquo;amor\u00e7age ITO le long de la ligne du motif donn\u00e9, <strong>e<\/strong> spin-coating de la couche de protection, <strong>f<\/strong> d\u00e9coupage du substrat en plus petits morceaux \u00e0 l&rsquo;aide d&rsquo;une scie \u00e0 d\u00e9couper, <strong>g<\/strong> retrait de la r\u00e9sine photosensible, <strong>h<\/strong> gravure \u00e0 sec de la couche d&rsquo;amor\u00e7age ITO \u00e0 l&rsquo;aide de l&rsquo;ICP, et <strong>i<\/strong> recuit thermique pour renforcer la structure du cuivre.<\/em><\/p>\n<p><strong>Adaptation pr\u00e9cise \u00e0 des applications RF sp\u00e9cifiques.<\/strong><\/p>\n<p>L&rsquo;augmentation de l&rsquo;\u00e9paisseur du m\u00e9tal peut multiplier le facteur Q par six ou sept, et les fr\u00e9quences de r\u00e9sonance peuvent \u00eatre d\u00e9cal\u00e9es jusqu&rsquo;\u00e0 200 MHz, ce qui permet une adaptation pr\u00e9cise \u00e0 des applications RF sp\u00e9cifiques. Par rapport aux r\u00e9sonateurs conventionnels fabriqu\u00e9s \u00e0 partir de circuits imprim\u00e9s, les versions imprim\u00e9es en 3D ont conserv\u00e9 leurs performances tout en r\u00e9duisant l&rsquo;encombrement de 45 %.<\/p>\n<p>\u00ab\u00a0Ce travail comble un foss\u00e9 critique entre l&rsquo;impression 3D et les dispositifs RF fonctionnels\u00a0\u00bb, a d\u00e9clar\u00e9 le professeur Hilmi Volkan Demir de Bilkent. \u00ab\u00a0En obtenant une r\u00e9solution inf\u00e9rieure \u00e0 10 microns dans des structures m\u00e9talliques \u00e0 rapport d&rsquo;aspect \u00e9lev\u00e9, nous avons lib\u00e9r\u00e9 de nouvelles libert\u00e9s de conception pour des composants miniaturis\u00e9s \u00e0 hautes performances. La possibilit\u00e9 d&rsquo;ajuster les fr\u00e9quences de r\u00e9sonance et les facteurs Q gr\u00e2ce au contr\u00f4le g\u00e9om\u00e9trique offre des opportunit\u00e9s int\u00e9ressantes pour les capteurs et les syst\u00e8mes de communication de la prochaine g\u00e9n\u00e9ration.\u00a0\u00bb<\/p>\n<p>Cette technique peut \u00eatre utilis\u00e9e pour des capteurs RF plus petits et plus performants, ou des microdispositifs implantables ou portables pour le diagnostic et la th\u00e9rapie. Int\u00e9gr\u00e9e aux MEMS, elle pourrait \u00eatre utilis\u00e9e pour cr\u00e9er des antennes sur puce et des processeurs de signaux pour les r\u00e9seaux IdO.<\/p>\n<p>Les d\u00e9veloppements futurs incluent l&rsquo;int\u00e9gration d&rsquo;autres mat\u00e9riaux fonctionnels ou la construction de structures multicouches pour \u00e9tendre les capacit\u00e9s des capteurs RF.<\/p>\n<p><a href=\"http:\/\/www.aircas.ac.cn\">www.aircas.ac.cn<\/a><\/p>\n<p>Article : <a href=\"https:\/\/www.eenewseurope.com\/en\/infineon-merges-sensor-and-rf-businesses\/\">Infineon merges sensor and RF divisions<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Des chercheurs chinois ont mis au point une m\u00e9thode r\u00e9volutionnaire pour produire des microstructures 3D \u00e0 haut facteur de forme avec une r\u00e9solution inf\u00e9rieure \u00e0 10 microns pour les capteurs RF. Cette technique permet d&rsquo;obtenir des sillons profonds avec un rapport largeur\/hauteur de 1:4, tout en assurant un contr\u00f4le pr\u00e9cis des propri\u00e9t\u00e9s de r\u00e9sonance et [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":479395,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[883],"tags":[937,1315,910],"domains":[47],"ppma_author":[3640,1143],"class_list":["post-479415","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-technologies","tag-capteur","tag-rf-fr","tag-sensing-conditioning-fr","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Impression 3D de capteurs RF haute performance ...<\/title>\n<meta name=\"description\" content=\"M\u00e9thode pour construire des capteurs RF 3D \u00e0 rapport d&#039;aspect \u00e9lev\u00e9 avec une r\u00e9solution inf\u00e9rieure \u00e0 10 microns.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/479415\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Impression 3D de capteurs RF haute performance\" \/>\n<meta property=\"og:description\" content=\"M\u00e9thode pour construire des capteurs RF 3D \u00e0 rapport d&#039;aspect \u00e9lev\u00e9 avec une r\u00e9solution inf\u00e9rieure \u00e0 10 microns.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/479415\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-11T23:00:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-11T11:48:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/2025\/05\/China-3D-RF.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"332\" \/>\n\t<meta property=\"og:image:height\" content=\"284\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nick Flaherty, Daniel Cardon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel Cardon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/impression-3d-de-capteurs-rf-haute-performance\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/impression-3d-de-capteurs-rf-haute-performance\/\"},\"author\":{\"name\":\"Daniel Cardon\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/93c44cde463762f40a8236eaa44c1c17\"},\"headline\":\"Impression 3D de capteurs RF haute performance\",\"datePublished\":\"2025-05-11T23:00:19+00:00\",\"dateModified\":\"2025-05-11T11:48:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/impression-3d-de-capteurs-rf-haute-performance\/\"},\"wordCount\":901,\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"keywords\":[\"Capteur\",\"RF\",\"Sensing \/ Conditioning\"],\"articleSection\":[\"Technologies\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/impression-3d-de-capteurs-rf-haute-performance\/\",\"url\":\"https:\/\/www.eenewseurope.com\/fr\/impression-3d-de-capteurs-rf-haute-performance\/\",\"name\":\"Impression 3D de capteurs RF haute performance -\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\"},\"datePublished\":\"2025-05-11T23:00:19+00:00\",\"dateModified\":\"2025-05-11T11:48:34+00:00\",\"description\":\"M\u00e9thode pour construire des capteurs RF 3D \u00e0 rapport d'aspect \u00e9lev\u00e9 avec une r\u00e9solution inf\u00e9rieure \u00e0 10 microns.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/impression-3d-de-capteurs-rf-haute-performance\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eenewseurope.com\/fr\/impression-3d-de-capteurs-rf-haute-performance\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/impression-3d-de-capteurs-rf-haute-performance\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Impression 3D de capteurs RF haute performance\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/93c44cde463762f40a8236eaa44c1c17\",\"name\":\"Daniel Cardon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/2b243f6bcc1cff7d86aadfb2cd0bd870\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/de9edc136dfc061ad4778e04635baefa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/de9edc136dfc061ad4778e04635baefa?s=96&d=mm&r=g\",\"caption\":\"Daniel Cardon\"}}]}<\/script>","yoast_head_json":{"title":"Impression 3D de capteurs RF haute performance ...","description":"M\u00e9thode pour construire des capteurs RF 3D \u00e0 rapport d'aspect \u00e9lev\u00e9 avec une r\u00e9solution inf\u00e9rieure \u00e0 10 microns.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/479415\/","og_locale":"fr_FR","og_type":"article","og_title":"Impression 3D de capteurs RF haute performance","og_description":"M\u00e9thode pour construire des capteurs RF 3D \u00e0 rapport d'aspect \u00e9lev\u00e9 avec une r\u00e9solution inf\u00e9rieure \u00e0 10 microns.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/479415\/","og_site_name":"EENewsEurope","article_published_time":"2025-05-11T23:00:19+00:00","article_modified_time":"2025-05-11T11:48:34+00:00","og_image":[{"width":332,"height":284,"url":"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/2025\/05\/China-3D-RF.jpg","type":"image\/jpeg"}],"author":"Nick Flaherty, Daniel Cardon","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Daniel Cardon","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eenewseurope.com\/fr\/impression-3d-de-capteurs-rf-haute-performance\/#article","isPartOf":{"@id":"https:\/\/www.eenewseurope.com\/fr\/impression-3d-de-capteurs-rf-haute-performance\/"},"author":{"name":"Daniel Cardon","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/93c44cde463762f40a8236eaa44c1c17"},"headline":"Impression 3D de capteurs RF haute performance","datePublished":"2025-05-11T23:00:19+00:00","dateModified":"2025-05-11T11:48:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eenewseurope.com\/fr\/impression-3d-de-capteurs-rf-haute-performance\/"},"wordCount":901,"publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"keywords":["Capteur","RF","Sensing \/ Conditioning"],"articleSection":["Technologies"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.eenewseurope.com\/fr\/impression-3d-de-capteurs-rf-haute-performance\/","url":"https:\/\/www.eenewseurope.com\/fr\/impression-3d-de-capteurs-rf-haute-performance\/","name":"Impression 3D de capteurs RF haute performance -","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/#website"},"datePublished":"2025-05-11T23:00:19+00:00","dateModified":"2025-05-11T11:48:34+00:00","description":"M\u00e9thode pour construire des capteurs RF 3D \u00e0 rapport d'aspect \u00e9lev\u00e9 avec une r\u00e9solution inf\u00e9rieure \u00e0 10 microns.","breadcrumb":{"@id":"https:\/\/www.eenewseurope.com\/fr\/impression-3d-de-capteurs-rf-haute-performance\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eenewseurope.com\/fr\/impression-3d-de-capteurs-rf-haute-performance\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eenewseurope.com\/fr\/impression-3d-de-capteurs-rf-haute-performance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Impression 3D de capteurs RF haute performance"}]},{"@type":"WebSite","@id":"https:\/\/www.ecinews.fr\/fr\/#website","url":"https:\/\/www.ecinews.fr\/fr\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ecinews.fr\/fr\/#organization","name":"EENewsEurope","url":"https:\/\/www.ecinews.fr\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/93c44cde463762f40a8236eaa44c1c17","name":"Daniel Cardon","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/2b243f6bcc1cff7d86aadfb2cd0bd870","url":"https:\/\/secure.gravatar.com\/avatar\/de9edc136dfc061ad4778e04635baefa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/de9edc136dfc061ad4778e04635baefa?s=96&d=mm&r=g","caption":"Daniel Cardon"}}]}},"authors":[{"term_id":3640,"user_id":0,"is_guest":1,"slug":"nick-flaherty","display_name":"Nick Flaherty","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""},{"term_id":1143,"user_id":11,"is_guest":0,"slug":"danielcardon","display_name":"Daniel Cardon","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/de9edc136dfc061ad4778e04635baefa?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/479415"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=479415"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/479415\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/479395"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=479415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=479415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=479415"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=479415"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=479415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}