{"id":477200,"date":"2025-04-08T17:50:53","date_gmt":"2025-04-08T15:50:53","guid":{"rendered":"https:\/\/www.ecinews.fr\/?p=477200"},"modified":"2025-04-08T21:47:19","modified_gmt":"2025-04-08T19:47:19","slug":"les-llm-utilises-pour-coder-peuvent-introduire-de-graves-erreurs","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/les-llm-utilises-pour-coder-peuvent-introduire-de-graves-erreurs\/","title":{"rendered":"Les LLM utilis\u00e9s pour coder peuvent introduire de graves erreurs"},"content":{"rendered":"<h2>Dans l&rsquo;une des \u00e9tudes les plus compl\u00e8tes, les chercheurs de l&rsquo;UTSA ont d\u00e9montr\u00e9 comment une erreur particuli\u00e8re pouvait causer de graves probl\u00e8mes aux programmeurs qui utilisent l&rsquo;IA, en particulier les LLM, pour les aider \u00e0 \u00e9crire leur code.<\/h2>\n<p>Les hallucinations dans les LLM se produisent lorsque le mod\u00e8le produit un contenu qui est factuellement incorrect, absurde ou compl\u00e8tement sans rapport avec la t\u00e2che d&rsquo;entr\u00e9e. La plupart des recherches actuelles se sont principalement concentr\u00e9es sur les hallucinations dans les t\u00e2ches classiques de g\u00e9n\u00e9ration et de pr\u00e9diction du langage naturel, telles que la traduction automatique, le r\u00e9sum\u00e9 et l&rsquo;intelligence artificielle conversationnelle. Cependant, l&rsquo;\u00e9quipe de recherche s&rsquo;est concentr\u00e9e sur les hallucinations de paquets, qui se produisent lorsqu&rsquo;un LLM g\u00e9n\u00e8re ou recommande l&rsquo;utilisation d&rsquo;une biblioth\u00e8que logicielle tierce qui n&rsquo;existe pas. Ce qui fait des hallucinations de paquets un domaine de recherche fascinant, c&rsquo;est la fa\u00e7on dont quelque chose d&rsquo;aussi simple &#8211; une simple commande de tous les jours &#8211; peut entra\u00eener de graves risques de s\u00e9curit\u00e9.<\/p>\n<p>Joe Spracklen, doctorant en informatique \u00e0 l&rsquo;UTSA, a dirig\u00e9 l&rsquo;\u00e9tude sur la mani\u00e8re dont les grands mod\u00e8les de langage (LLM) g\u00e9n\u00e8rent fr\u00e9quemment des codes non s\u00e9curis\u00e9s. \u00ab\u00a0Il n&rsquo;y a pas besoin d&rsquo;un ensemble de circonstances alambiqu\u00e9es ou d&rsquo;une chose obscure pour que cela se produise\u00a0\u00bb, a d\u00e9clar\u00e9 M. Spracklen. \u00ab\u00a0Il suffit de taper une commande que la plupart des personnes travaillant dans ces langages de programmation tapent quotidiennement. C&rsquo;est tout ce qu&rsquo;il faut. C&rsquo;est tr\u00e8s direct et tr\u00e8s simple\u00a0\u00bb.<\/p>\n<p>\u00ab\u00a0Il est \u00e9galement omnipr\u00e9sent\u00a0\u00bb, a-t-il ajout\u00e9. \u00ab\u00a0Vous pouvez faire tr\u00e8s peu de choses avec votre langage de codage Python de base. Il vous faudrait beaucoup de temps pour \u00e9crire le code vous-m\u00eame, il est donc universel de s&rsquo;appuyer sur des logiciels libres pour \u00e9tendre les capacit\u00e9s de votre langage de programmation afin d&rsquo;accomplir des t\u00e2ches sp\u00e9cifiques\u00a0\u00bb.<\/p>\n<p>Les LLM sont de plus en plus populaires aupr\u00e8s des d\u00e9veloppeurs pour les aider \u00e0 assembler des programmes. Selon l&rsquo;\u00e9tude, jusqu&rsquo;\u00e0 97 % des d\u00e9veloppeurs de logiciels int\u00e8grent l&rsquo;IA g\u00e9n\u00e9rative dans leur flux de travail, et 30 % du code \u00e9crit aujourd&rsquo;hui est g\u00e9n\u00e9r\u00e9 par l&rsquo;IA. En outre, de nombreux langages de programmation populaires, comme PyPI pour Python et npm pour JavaScript, s&rsquo;appuient sur un d\u00e9p\u00f4t de paquets centralis\u00e9. Ces r\u00e9f\u00e9rentiels \u00e9tant souvent ouverts, des acteurs malveillants peuvent t\u00e9l\u00e9charger des codes malveillants d\u00e9guis\u00e9s en paquets l\u00e9gitimes.<\/p>\n<p>Depuis des ann\u00e9es, les pirates utilisent diverses astuces pour inciter les utilisateurs \u00e0 installer leurs logiciels malveillants. Les hallucinations de colis sont la derni\u00e8re tactique en date.<\/p>\n<p>Selon l&rsquo;un des chercheurs, le professeur associ\u00e9 Murtuza Jadliwala, directeur du SPriTELab (Security, Privacy, Trust, and Ethics in Computing Research Lab) : \u00ab\u00a0Supposons que je demande \u00e0 ChatGPT de m&rsquo;aider \u00e0 \u00e9crire un code et qu&rsquo;il le fasse. Maintenant, disons que le code g\u00e9n\u00e9r\u00e9 inclut un lien vers un paquetage, que je lui fais confiance et que j&rsquo;ex\u00e9cute le code, mais que le paquetage n&rsquo;existe pas, qu&rsquo;il s&rsquo;agit d&rsquo;un paquetage hallucin\u00e9. Un adversaire\/hacker astucieux pourrait voir ce comportement (du LLM) et r\u00e9aliser que le LLM dit aux gens d&rsquo;utiliser ce paquet inexistant, ce paquet hallucin\u00e9. L&rsquo;adversaire peut alors cr\u00e9er trivialement un nouveau paquet avec le m\u00eame nom que le paquet hallucin\u00e9 (recommand\u00e9 par le LLM) et y injecter du mauvais code. La prochaine fois que le LLM recommande le m\u00eame paquet dans le code g\u00e9n\u00e9r\u00e9 et qu&rsquo;un utilisateur peu m\u00e9fiant ex\u00e9cute le code, ce paquet malveillant est t\u00e9l\u00e9charg\u00e9 et ex\u00e9cut\u00e9 sur la machine de l&rsquo;utilisateur\u00a0\u00bb, a expliqu\u00e9 M. Jadliwala.<\/p>\n<p>Les chercheurs de l&rsquo;UTSA ont \u00e9valu\u00e9 l&rsquo;occurrence des hallucinations de paquets dans diff\u00e9rents langages de programmation, r\u00e9glages et param\u00e8tres, en explorant la probabilit\u00e9 de recommandations erron\u00e9es de paquets et en identifiant les causes profondes.<\/p>\n<p>Les chercheurs de l&rsquo;UTSA ont effectu\u00e9 30 tests diff\u00e9rents et ont d\u00e9couvert que 440 445 des 2,23 millions d&rsquo;\u00e9chantillons de code g\u00e9n\u00e9r\u00e9s en Python et en JavaScript \u00e0 l&rsquo;aide de mod\u00e8les LLM faisaient r\u00e9f\u00e9rence \u00e0 des paquets hallucin\u00e9s. Parmi les LLM test\u00e9s, l&rsquo;\u00e9tude note que \u00ab\u00a0les mod\u00e8les de la s\u00e9rie GPT sont quatre fois moins susceptibles de g\u00e9n\u00e9rer des paquets hallucin\u00e9s que les mod\u00e8les open-source, avec un taux d&rsquo;hallucination de 5,2 % contre 21,7 %\u00a0\u00bb. Les chercheurs ont \u00e9galement constat\u00e9 que le code Python \u00e9tait moins sujet aux hallucinations que le code JavaScript.<\/p>\n<p>Bien que le recoupement des paquets g\u00e9n\u00e9r\u00e9s avec une liste ma\u00eetresse puisse contribuer \u00e0 att\u00e9nuer les hallucinations, les chercheurs de l&rsquo;UTSA affirment que la meilleure solution consiste \u00e0 s&rsquo;attaquer aux fondements des LLM au cours de leur propre d\u00e9veloppement. L&rsquo;\u00e9quipe a partag\u00e9 ses conclusions avec des fournisseurs de mod\u00e8les, notamment OpenAI, Meta, DeepSeek et Mistral AI.<\/p>\n<p>Trois autres chercheurs de l&rsquo;UTSA ont particip\u00e9 \u00e0 cette collaboration multi-institutionnelle : le doctorant A.H.M. Nazmus Sakib, le chercheur postdoctoral Raveen Wijewickrama et le professeur associ\u00e9 Murtuza Jadliwala, directeur du SPriTELab (laboratoire de recherche sur la s\u00e9curit\u00e9, la vie priv\u00e9e, la confiance et l&rsquo;\u00e9thique en informatique). Les autres collaborateurs \u00e9taient Anindya Maita de l&rsquo;universit\u00e9 d&rsquo;Oklahoma (ancien chercheur postdoctoral de l&rsquo;UTSA) et Bimal Viswanath de Virginia Tech.<\/p>\n<p>DOI:<a href=\"https:\/\/doi.org\/10.48550\/arXiv.2406.10279\"> https:\/\/doi.org\/10.48550\/arXiv.2406.10279<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les chercheurs de l&rsquo;UTSA ont montr\u00e9 comment les hallucinations des LLM peuvent \u00eatre utilis\u00e9es pour installer des logiciels malveillants et cr\u00e9er des risques de s\u00e9curit\u00e9 dans le code.<\/p>\n","protected":false},"author":40,"featured_media":477171,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[883],"tags":[9431,9428,9429,4603,4302,9430],"domains":[47],"ppma_author":[3682,6199],"class_list":["post-477200","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-technologies","tag-ai-hallucinations-fr","tag-generation-de-codes","tag-javascript-fr","tag-llm-fr","tag-python-fr","tag-utsa-fr","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Les LLM utilis\u00e9s pour coder peuvent introduire de graves erreurs ...<\/title>\n<meta name=\"description\" content=\"Les chercheurs de l&#039;UTSA ont montr\u00e9 comment les hallucinations des LLM peuvent \u00eatre utilis\u00e9es pour installer des logiciels malveillants.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/477200\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les LLM utilis\u00e9s pour coder peuvent introduire de graves erreurs\" \/>\n<meta property=\"og:description\" content=\"Les chercheurs de l&#039;UTSA ont montr\u00e9 comment les hallucinations des LLM peuvent \u00eatre utilis\u00e9es pour installer des logiciels malveillants.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/477200\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-08T15:50:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-08T19:47:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2025\/04\/Security-Cyber-Hacker.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"847\" \/>\n\t<meta property=\"og:image:height\" content=\"565\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jean-Pierre Joosting, A Delapalisse\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"A Delapalisse\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/les-llm-utilises-pour-coder-peuvent-introduire-de-graves-erreurs\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/les-llm-utilises-pour-coder-peuvent-introduire-de-graves-erreurs\/\"},\"author\":{\"name\":\"A Delapalisse\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/4b3db5ba5c953c5fddeb226df86d8635\"},\"headline\":\"Les LLM utilis\u00e9s pour coder peuvent introduire de graves erreurs\",\"datePublished\":\"2025-04-08T15:50:53+00:00\",\"dateModified\":\"2025-04-08T19:47:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/les-llm-utilises-pour-coder-peuvent-introduire-de-graves-erreurs\/\"},\"wordCount\":967,\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"keywords\":[\"AI Hallucinations\",\"G\u00e9n\u00e9ration de codes\",\"JavaScript\",\"LLM\",\"Python\",\"UTSA\"],\"articleSection\":[\"Technologies\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/les-llm-utilises-pour-coder-peuvent-introduire-de-graves-erreurs\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/les-llm-utilises-pour-coder-peuvent-introduire-de-graves-erreurs\/\",\"name\":\"Les LLM utilis\u00e9s pour coder peuvent introduire de graves erreurs -\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\"},\"datePublished\":\"2025-04-08T15:50:53+00:00\",\"dateModified\":\"2025-04-08T19:47:19+00:00\",\"description\":\"Les chercheurs de l'UTSA ont montr\u00e9 comment les hallucinations des LLM peuvent \u00eatre utilis\u00e9es pour installer des logiciels malveillants.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/les-llm-utilises-pour-coder-peuvent-introduire-de-graves-erreurs\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/les-llm-utilises-pour-coder-peuvent-introduire-de-graves-erreurs\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/les-llm-utilises-pour-coder-peuvent-introduire-de-graves-erreurs\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les LLM utilis\u00e9s pour coder peuvent introduire de graves erreurs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/4b3db5ba5c953c5fddeb226df86d8635\",\"name\":\"A Delapalisse\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/09af0e1236b95ff53924b8dfe5af278e\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/010f811c0933b47aea7e9204117b17c6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/010f811c0933b47aea7e9204117b17c6?s=96&d=mm&r=g\",\"caption\":\"A Delapalisse\"}}]}<\/script>","yoast_head_json":{"title":"Les LLM utilis\u00e9s pour coder peuvent introduire de graves erreurs ...","description":"Les chercheurs de l'UTSA ont montr\u00e9 comment les hallucinations des LLM peuvent \u00eatre utilis\u00e9es pour installer des logiciels malveillants.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/477200\/","og_locale":"fr_FR","og_type":"article","og_title":"Les LLM utilis\u00e9s pour coder peuvent introduire de graves erreurs","og_description":"Les chercheurs de l'UTSA ont montr\u00e9 comment les hallucinations des LLM peuvent \u00eatre utilis\u00e9es pour installer des logiciels malveillants.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/477200\/","og_site_name":"EENewsEurope","article_published_time":"2025-04-08T15:50:53+00:00","article_modified_time":"2025-04-08T19:47:19+00:00","og_image":[{"width":847,"height":565,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2025\/04\/Security-Cyber-Hacker.jpg","type":"image\/jpeg"}],"author":"Jean-Pierre Joosting, A Delapalisse","twitter_card":"summary_large_image","twitter_misc":{"Written by":"A Delapalisse","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/les-llm-utilises-pour-coder-peuvent-introduire-de-graves-erreurs\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/les-llm-utilises-pour-coder-peuvent-introduire-de-graves-erreurs\/"},"author":{"name":"A Delapalisse","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/4b3db5ba5c953c5fddeb226df86d8635"},"headline":"Les LLM utilis\u00e9s pour coder peuvent introduire de graves erreurs","datePublished":"2025-04-08T15:50:53+00:00","dateModified":"2025-04-08T19:47:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/les-llm-utilises-pour-coder-peuvent-introduire-de-graves-erreurs\/"},"wordCount":967,"publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"keywords":["AI Hallucinations","G\u00e9n\u00e9ration de codes","JavaScript","LLM","Python","UTSA"],"articleSection":["Technologies"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/les-llm-utilises-pour-coder-peuvent-introduire-de-graves-erreurs\/","url":"https:\/\/www.ecinews.fr\/fr\/les-llm-utilises-pour-coder-peuvent-introduire-de-graves-erreurs\/","name":"Les LLM utilis\u00e9s pour coder peuvent introduire de graves erreurs -","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/#website"},"datePublished":"2025-04-08T15:50:53+00:00","dateModified":"2025-04-08T19:47:19+00:00","description":"Les chercheurs de l'UTSA ont montr\u00e9 comment les hallucinations des LLM peuvent \u00eatre utilis\u00e9es pour installer des logiciels malveillants.","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/les-llm-utilises-pour-coder-peuvent-introduire-de-graves-erreurs\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/les-llm-utilises-pour-coder-peuvent-introduire-de-graves-erreurs\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/les-llm-utilises-pour-coder-peuvent-introduire-de-graves-erreurs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Les LLM utilis\u00e9s pour coder peuvent introduire de graves erreurs"}]},{"@type":"WebSite","@id":"https:\/\/www.ecinews.fr\/fr\/#website","url":"https:\/\/www.ecinews.fr\/fr\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ecinews.fr\/fr\/#organization","name":"EENewsEurope","url":"https:\/\/www.ecinews.fr\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/4b3db5ba5c953c5fddeb226df86d8635","name":"A Delapalisse","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/09af0e1236b95ff53924b8dfe5af278e","url":"https:\/\/secure.gravatar.com\/avatar\/010f811c0933b47aea7e9204117b17c6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/010f811c0933b47aea7e9204117b17c6?s=96&d=mm&r=g","caption":"A Delapalisse"}}]}},"authors":[{"term_id":3682,"user_id":0,"is_guest":1,"slug":"jean-pierre-joosting","display_name":"Jean-Pierre Joosting","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""},{"term_id":6199,"user_id":40,"is_guest":0,"slug":"andre-rousselotemisys-com","display_name":"A Delapalisse","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/010f811c0933b47aea7e9204117b17c6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/477200"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=477200"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/477200\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/477171"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=477200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=477200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=477200"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=477200"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=477200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}