{"id":473453,"date":"2025-02-24T09:19:48","date_gmt":"2025-02-24T08:19:48","guid":{"rendered":"https:\/\/www.ecinews.fr\/?p=473453"},"modified":"2025-02-24T09:19:48","modified_gmt":"2025-02-24T08:19:48","slug":"bosch-arrete-son-activite-de-piles-a-combustible-a-oxyde-solide","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/bosch-arrete-son-activite-de-piles-a-combustible-a-oxyde-solide\/","title":{"rendered":"Bosch arr\u00eate son activit\u00e9 de piles \u00e0 combustible \u00e0 oxyde solide"},"content":{"rendered":"<p>Robert Bosch va cesser l&rsquo;industrialisation de syst\u00e8mes d&rsquo;alimentation \u00e9lectrique d\u00e9centralis\u00e9s bas\u00e9s sur la technologie des piles \u00e0 combustible \u00e0 oxyde solide (SOFC) et se concentrer sur les \u00e9lectrolyseurs pour la production d&rsquo;hydrog\u00e8ne.<\/p>\n<p>Cette d\u00e9cision risque de toucher Ceres Power au Royaume-Uni, qui \u00e9tait l&rsquo;un des fournisseurs de technologie et avait une entreprise commune <a href=\"https:\/\/www.eenewseurope.com\/en\/ceres-delays-chinese-fuel-cell-joint-venture\/\">avec Bosch et Weichai Power en Chine<\/a>. Bosch travaillait \u00e9galement avec <a href=\"https:\/\/www.eenewseurope.com\/en\/bosch-powercell-make-fuel-cell-technology-ready-for-mass-production\/\">Powercell, une entreprise d\u00e9riv\u00e9e de Volvo, en Su\u00e8de, sur la technologie des piles \u00e0 combustible.<\/a><\/p>\n<p>Bosch avait pr\u00e9vu d&rsquo;acc\u00e9l\u00e9rer la production de sa technologie de piles \u00e0 combustible \u00e0 oxyde solide l&rsquo;ann\u00e9e derni\u00e8re et emploie 550 personnes dans le secteur des SOFC, mais le march\u00e9 ne s&rsquo;est pas concr\u00e9tis\u00e9, selon l&rsquo;entreprise.<\/p>\n<p>\u00ab\u00a0Pour nous, en tant qu&rsquo;entreprise, l&rsquo;\u00e9volution volatile du march\u00e9 signifie que nous devons consolider nos efforts et concentrer notre portefeuille. Nous consid\u00e9rons l&rsquo;hydrog\u00e8ne comme une source d&rsquo;\u00e9nergie importante pour d\u00e9carboniser le syst\u00e8me \u00e9nerg\u00e9tique. Pour produire de l&rsquo;hydrog\u00e8ne de mani\u00e8re \u00e9cologique, un grand nombre d&rsquo;usines d&rsquo;\u00e9lectrolyse dot\u00e9es de piles \u00e0 haute performance devront \u00eatre mises en place dans le monde entier. Gr\u00e2ce \u00e0 son expertise, Bosch dispose d&rsquo;\u00e9normes opportunit\u00e9s commerciales dans ce domaine. Et c&rsquo;est sur ces opportunit\u00e9s que nous allons nous concentrer\u00a0\u00bb, a d\u00e9clar\u00e9 Thomas Pauer, pr\u00e9sident de Bosch Power Solutions.<\/p>\n<p>D&rsquo;importantes subventions sont \u00e9galement disponibles dans l&rsquo;UE pour le d\u00e9veloppement d&rsquo;\u00e9lectrolyseurs utilisant la technologie des membranes d&rsquo;\u00e9change de protons (PEM) et Bosch fournira les composants de l&rsquo;ensemble de piles \u00e0 combustible, qui sera lanc\u00e9 dans le courant de l&rsquo;ann\u00e9e.<\/p>\n<p>\u00c0 l&rsquo;\u00e9chelle mondiale, l&rsquo;\u00e9lectrolyse de l&rsquo;hydrog\u00e8ne atteindra une capacit\u00e9 install\u00e9e comprise entre 100 et 170 gigawatts d&rsquo;ici \u00e0 2030. D&rsquo;ici la fin de la d\u00e9cennie, le march\u00e9 mondial de l&rsquo;\u00e9lectrolyse devrait repr\u00e9senter un volume de 37 milliards d&rsquo;euros.<\/p>\n<p>La SOFC a \u00e9t\u00e9 consid\u00e9r\u00e9e comme une technologie stationnaire adapt\u00e9e \u00e0 l&rsquo;alimentation des centres de donn\u00e9es, car les granul\u00e9s solides sont plus faciles \u00e0 transporter que l&rsquo;hydrog\u00e8ne liquide. L&rsquo;utilisation d&rsquo;un \u00e9lectrolyseur local avec de l&rsquo;\u00e9nergie renouvelable peut potentiellement fournir l&rsquo;hydrog\u00e8ne localement en utilisant l&rsquo;eau des syst\u00e8mes de refroidissement du centre de donn\u00e9es.<\/p>\n<p>Les travaux visant \u00e0 explorer les possibilit\u00e9s de la technologie de l&rsquo;oxyde solide se poursuivront au sein de l&rsquo;unit\u00e9 de recherche de l&rsquo;entreprise, qui reste par ailleurs tr\u00e8s attach\u00e9e aux applications mobiles de l&rsquo;<sub>H2<\/sub> dans les piles \u00e0 combustible et les moteurs \u00e0 hydrog\u00e8ne.<\/p>\n<p>\u00ab\u00a0Au cours des dix derni\u00e8res ann\u00e9es, Bosch a travaill\u00e9 avec des partenaires pour d\u00e9velopper la technologie des piles \u00e0 combustible \u00e0 oxyde solide pour les syst\u00e8mes d&rsquo;alimentation \u00e9lectrique d\u00e9centralis\u00e9s. Ces syst\u00e8mes ont atteint un niveau \u00e9lev\u00e9 de maturit\u00e9 technique, qui a \u00e9t\u00e9 d\u00e9montr\u00e9 dans plus de 100 syst\u00e8mes pilotes. R\u00e9cemment, cependant, le march\u00e9 ne s&rsquo;est pas d\u00e9velopp\u00e9 comme pr\u00e9vu. D&rsquo;une part, le march\u00e9 est particuli\u00e8rement demandeur de syst\u00e8mes \u00e0 haut rendement avec capture du carbone, ce qui rend les conditions d&rsquo;une exploitation \u00e9conomique beaucoup plus difficiles. D&rsquo;autre part, la conversion de l&rsquo;hydrog\u00e8ne en \u00e9lectricit\u00e9 ne b\u00e9n\u00e9ficie pas encore de la priorit\u00e9 n\u00e9cessaire en Europe, et en particulier en Allemagne. Cela signifie que des efforts d&rsquo;ing\u00e9nierie suppl\u00e9mentaires seront n\u00e9cessaires dans les ann\u00e9es \u00e0 venir, ce qui r\u00e9duira consid\u00e9rablement la viabilit\u00e9 commerciale\u00a0\u00bb.<\/p>\n<p>Bosch a inform\u00e9 Ceres qu&rsquo;elle cherchera \u00e0 mettre fin \u00e0 son partenariat avec Ceres de mani\u00e8re ordonn\u00e9e, tout en continuant \u00e0 respecter ses obligations contractuelles, et qu&rsquo;elle vendra sa <a href=\"https:\/\/www.eenewseurope.com\/en\/bosch-boosts-stake-in-uk-hydrogen-solid-oxide-fuel-cell-maker\/\">participation minoritaire de 17,44 %<\/a>. Uwe Glock, le repr\u00e9sentant de Bosch au conseil d&rsquo;administration de Ceres, se retire avec effet imm\u00e9diat.<\/p>\n<p>\u00ab\u00a0Ceres est d\u00e9\u00e7ue que Bosch mette fin \u00e0 ses activit\u00e9s li\u00e9es \u00e0 l&rsquo;industrialisation et \u00e0 la pr\u00e9paration \u00e0 la production de syst\u00e8mes d&rsquo;alimentation \u00e9lectrique d\u00e9centralis\u00e9s utilisant la technologie \u00e0 oxyde solide de Ceres, mais nous reconnaissons que cette d\u00e9cision s&rsquo;inscrit dans le cadre d&rsquo;une r\u00e9vision plus large de l&rsquo;orientation strat\u00e9gique de Bosch et ne refl\u00e8te pas sa confiance en Ceres ou en notre technologie\u00a0\u00bb, a d\u00e9clar\u00e9 Phil Caldwell, directeur g\u00e9n\u00e9ral de Ceres Power.<\/p>\n<p>\u00ab\u00a0Au cours des 12 derniers mois, Ceres a \u00e9largi son \u00e9cosyst\u00e8me de partenaires de fabrication mondiaux, tandis que l&rsquo;entreprise continue de conc\u00e9der des licences pour sa technologie de pointe. Cette \u00e9volution est \u00e9tay\u00e9e par nos solides performances financi\u00e8res et nous restons bien positionn\u00e9s pour l&rsquo;avenir\u00a0\u00bb, a-t-il d\u00e9clar\u00e9.<\/p>\n<p>Il s&rsquo;agit notamment d&rsquo;accords avec <a href=\"https:\/\/www.eenewseurope.com\/en\/major-55m-deal-for-solid-oxide-hydrogen-power\/\">Delta \u00e0 Ta\u00efwan<\/a> et <a href=\"https:\/\/www.eenewseurope.com\/en\/ceres-confirms-denso-as-fuel-cell-partner\/\">Denso au Japon<\/a>.<\/p>\n<p>www.cerespower.com <a href=\"http:\/\/www.cerespower.com\">;<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Robert Bosch va cesser l&rsquo;industrialisation de syst\u00e8mes d&rsquo;alimentation \u00e9lectrique d\u00e9centralis\u00e9s bas\u00e9s sur la technologie des piles \u00e0 combustible \u00e0 oxyde solide (SOFC) et se concentrer sur les \u00e9lectrolyseurs pour la production d&rsquo;hydrog\u00e8ne. Cette d\u00e9cision risque de toucher Ceres Power au Royaume-Uni, qui \u00e9tait l&rsquo;un des fournisseurs de technologie et avait une entreprise commune avec Bosch [&hellip;]<\/p>\n","protected":false},"author":40,"featured_media":473248,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[880],"tags":[890],"domains":[47],"ppma_author":[3640,6199],"class_list":["post-473453","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-economiques","tag-powermanagement-fr","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Bosch arr\u00eate son activit\u00e9 de piles \u00e0 combustible \u00e0 oxyde so...<\/title>\n<meta name=\"description\" content=\"Robert Bosch abandonne l&#039;industrialisation des syst\u00e8mes d&#039;alimentation en \u00e9nergie par piles \u00e0 combustible \u00e0 oxyde solide (SOFC).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/473453\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bosch arr\u00eate son activit\u00e9 de piles \u00e0 combustible \u00e0 oxyde solide\" \/>\n<meta property=\"og:description\" content=\"Robert Bosch abandonne l&#039;industrialisation des syst\u00e8mes d&#039;alimentation en \u00e9nergie par piles \u00e0 combustible \u00e0 oxyde solide (SOFC).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/473453\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-24T08:19:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/2025\/02\/sofc-bosch-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"608\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nick Flaherty, A Delapalisse\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"A Delapalisse\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/bosch-arrete-son-activite-de-piles-a-combustible-a-oxyde-solide\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/bosch-arrete-son-activite-de-piles-a-combustible-a-oxyde-solide\/\"},\"author\":{\"name\":\"A Delapalisse\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/4b3db5ba5c953c5fddeb226df86d8635\"},\"headline\":\"Bosch arr\u00eate son activit\u00e9 de piles \u00e0 combustible \u00e0 oxyde solide\",\"datePublished\":\"2025-02-24T08:19:48+00:00\",\"dateModified\":\"2025-02-24T08:19:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/bosch-arrete-son-activite-de-piles-a-combustible-a-oxyde-solide\/\"},\"wordCount\":826,\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"keywords\":[\"PowerManagement\"],\"articleSection\":[\"Actualit\u00e9s \u00e9conomiques\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/bosch-arrete-son-activite-de-piles-a-combustible-a-oxyde-solide\/\",\"url\":\"https:\/\/www.eenewseurope.com\/fr\/bosch-arrete-son-activite-de-piles-a-combustible-a-oxyde-solide\/\",\"name\":\"Bosch arr\u00eate son activit\u00e9 de piles \u00e0 combustible \u00e0 oxyde solide -\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\"},\"datePublished\":\"2025-02-24T08:19:48+00:00\",\"dateModified\":\"2025-02-24T08:19:48+00:00\",\"description\":\"Robert Bosch abandonne l'industrialisation des syst\u00e8mes d'alimentation en \u00e9nergie par piles \u00e0 combustible \u00e0 oxyde solide (SOFC).\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/bosch-arrete-son-activite-de-piles-a-combustible-a-oxyde-solide\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eenewseurope.com\/fr\/bosch-arrete-son-activite-de-piles-a-combustible-a-oxyde-solide\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/bosch-arrete-son-activite-de-piles-a-combustible-a-oxyde-solide\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bosch arr\u00eate son activit\u00e9 de piles \u00e0 combustible \u00e0 oxyde solide\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/4b3db5ba5c953c5fddeb226df86d8635\",\"name\":\"A Delapalisse\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/09af0e1236b95ff53924b8dfe5af278e\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/010f811c0933b47aea7e9204117b17c6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/010f811c0933b47aea7e9204117b17c6?s=96&d=mm&r=g\",\"caption\":\"A Delapalisse\"}}]}<\/script>","yoast_head_json":{"title":"Bosch arr\u00eate son activit\u00e9 de piles \u00e0 combustible \u00e0 oxyde so...","description":"Robert Bosch abandonne l'industrialisation des syst\u00e8mes d'alimentation en \u00e9nergie par piles \u00e0 combustible \u00e0 oxyde solide (SOFC).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/473453\/","og_locale":"fr_FR","og_type":"article","og_title":"Bosch arr\u00eate son activit\u00e9 de piles \u00e0 combustible \u00e0 oxyde solide","og_description":"Robert Bosch abandonne l'industrialisation des syst\u00e8mes d'alimentation en \u00e9nergie par piles \u00e0 combustible \u00e0 oxyde solide (SOFC).","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/473453\/","og_site_name":"EENewsEurope","article_published_time":"2025-02-24T08:19:48+00:00","og_image":[{"width":1080,"height":608,"url":"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/2025\/02\/sofc-bosch-scaled.jpg","type":"image\/jpeg"}],"author":"Nick Flaherty, A Delapalisse","twitter_card":"summary_large_image","twitter_misc":{"Written by":"A Delapalisse","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eenewseurope.com\/fr\/bosch-arrete-son-activite-de-piles-a-combustible-a-oxyde-solide\/#article","isPartOf":{"@id":"https:\/\/www.eenewseurope.com\/fr\/bosch-arrete-son-activite-de-piles-a-combustible-a-oxyde-solide\/"},"author":{"name":"A Delapalisse","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/4b3db5ba5c953c5fddeb226df86d8635"},"headline":"Bosch arr\u00eate son activit\u00e9 de piles \u00e0 combustible \u00e0 oxyde solide","datePublished":"2025-02-24T08:19:48+00:00","dateModified":"2025-02-24T08:19:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eenewseurope.com\/fr\/bosch-arrete-son-activite-de-piles-a-combustible-a-oxyde-solide\/"},"wordCount":826,"publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"keywords":["PowerManagement"],"articleSection":["Actualit\u00e9s \u00e9conomiques"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.eenewseurope.com\/fr\/bosch-arrete-son-activite-de-piles-a-combustible-a-oxyde-solide\/","url":"https:\/\/www.eenewseurope.com\/fr\/bosch-arrete-son-activite-de-piles-a-combustible-a-oxyde-solide\/","name":"Bosch arr\u00eate son activit\u00e9 de piles \u00e0 combustible \u00e0 oxyde solide -","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/#website"},"datePublished":"2025-02-24T08:19:48+00:00","dateModified":"2025-02-24T08:19:48+00:00","description":"Robert Bosch abandonne l'industrialisation des syst\u00e8mes d'alimentation en \u00e9nergie par piles \u00e0 combustible \u00e0 oxyde solide (SOFC).","breadcrumb":{"@id":"https:\/\/www.eenewseurope.com\/fr\/bosch-arrete-son-activite-de-piles-a-combustible-a-oxyde-solide\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eenewseurope.com\/fr\/bosch-arrete-son-activite-de-piles-a-combustible-a-oxyde-solide\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eenewseurope.com\/fr\/bosch-arrete-son-activite-de-piles-a-combustible-a-oxyde-solide\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Bosch arr\u00eate son activit\u00e9 de piles \u00e0 combustible \u00e0 oxyde solide"}]},{"@type":"WebSite","@id":"https:\/\/www.ecinews.fr\/fr\/#website","url":"https:\/\/www.ecinews.fr\/fr\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ecinews.fr\/fr\/#organization","name":"EENewsEurope","url":"https:\/\/www.ecinews.fr\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/4b3db5ba5c953c5fddeb226df86d8635","name":"A Delapalisse","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/09af0e1236b95ff53924b8dfe5af278e","url":"https:\/\/secure.gravatar.com\/avatar\/010f811c0933b47aea7e9204117b17c6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/010f811c0933b47aea7e9204117b17c6?s=96&d=mm&r=g","caption":"A Delapalisse"}}]}},"authors":[{"term_id":3640,"user_id":0,"is_guest":1,"slug":"nick-flaherty","display_name":"Nick Flaherty","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""},{"term_id":6199,"user_id":40,"is_guest":0,"slug":"andre-rousselotemisys-com","display_name":"A Delapalisse","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/010f811c0933b47aea7e9204117b17c6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/473453"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=473453"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/473453\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/473248"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=473453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=473453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=473453"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=473453"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=473453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}