{"id":469721,"date":"2025-01-17T09:00:50","date_gmt":"2025-01-17T08:00:50","guid":{"rendered":"https:\/\/www.ecinews.fr\/?p=469721"},"modified":"2025-01-08T18:51:58","modified_gmt":"2025-01-08T17:51:58","slug":"pilote-de-courant-lineaire-flexibilite-et-efficacite-pour-leclairage-automobile","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/pilote-de-courant-lineaire-flexibilite-et-efficacite-pour-leclairage-automobile\/","title":{"rendered":"Pilote de courant lin\u00e9aire : Flexibilit\u00e9 et efficacit\u00e9 pour l&rsquo;\u00e9clairage automobile"},"content":{"rendered":"<h3 class=\"western\" lang=\"fr-FR\"><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\">Avec sa capacit\u00e9 \u00e0 piloter des configurations RGB ainsi que des LED individuelles, le pilote de courant lin\u00e9aire LED automobile \u00e0 36 canaux, AL5887Q, de Diodes Incorporated (Diodes) r\u00e9pond au besoin des OEM de diff\u00e9rencier leurs marques en permettant aux concepteurs de cr\u00e9er diff\u00e9rents motifs d&rsquo;\u00e9clairage anim\u00e9s et profondeurs de couleur pour les lampes int\u00e9rieures et ext\u00e9rieures. <\/span><\/span><\/h3>\n<p class=\"western\" lang=\"fr-FR\"><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\">Cette capacit\u00e9 de contr\u00f4le \u00e0 double r\u00f4le simplifie la conception de ces modules \u00e0 LED autrefois complexes et, associ\u00e9e \u00e0 son efficacit\u00e9 \u00e9lev\u00e9e, permet d&rsquo;\u00e9conomiser de l&rsquo;\u00e9nergie pr\u00e9cieuse. Les applications incluent l&rsquo;\u00e9clairage ambiant int\u00e9rieur, l&rsquo;\u00e9clairage arri\u00e8re, les indicateurs de statut de charge des v\u00e9hicules \u00e9lectriques ext\u00e9rieurs, les syst\u00e8mes d&rsquo;infodivertissement, et plus encore.<\/span><\/span><\/p>\n<p class=\"western\" lang=\"fr-FR\"><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\">L&rsquo;AL5887Q prend en charge jusqu&rsquo;\u00e0 12 modules LED RGB avec trois banques programmables (A, B, C) pour le contr\u00f4le logiciel de chaque couleur. Une r\u00e9sistance externe d\u00e9finit le courant de sortie de tous les 36 canaux. En utilisant l&rsquo;interface num\u00e9rique s\u00e9lectionnable par mat\u00e9riel (broche INT_SEL), les concepteurs d&rsquo;\u00e9clairage ont la possibilit\u00e9 de choisir entre I\u00b2C ou SPI pour une flexibilit\u00e9 de programmation compl\u00e8te du syst\u00e8me. <\/span><\/span><\/p>\n<p class=\"western\" lang=\"fr-FR\"><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\">Le courant de chaque canal est configurable jusqu&rsquo;\u00e0 70mA, permettant une optimisation compl\u00e8te de la clart\u00e9 visuelle des LED, \u00e9vitant ainsi le besoin de parall\u00e9lisme. Les concepteurs b\u00e9n\u00e9ficient \u00e9galement du mode d&rsquo;\u00e9conomie d&rsquo;\u00e9nergie automatique de l&rsquo;appareil de 15\u00b5A et de l&rsquo;arr\u00eat en mode de veille ultra-faible de 1\u00b5A lorsque toutes les LED sont \u00e9teintes pendant plus de 30ms, aidant \u00e0 minimiser la consommation d&rsquo;\u00e9nergie inutile de la batterie de la voiture.<\/span><\/span><\/p>\n<p class=\"western\" lang=\"fr-FR\"><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\">L&rsquo;appareil dispose de plusieurs fonctionnalit\u00e9s de protection, y compris une broche FAULT \u00e0 drain ouvert pour le rapport de d\u00e9faut et une protection contre la surchauffe (OTP) avec avertissement pr\u00e9-OTP. Les registres de masque de d\u00e9faut adressables individuellement et les registres ouverts\/courts permettent aux concepteurs d&rsquo;activer et de d\u00e9sactiver le rapport de d\u00e9faut pour chacun des 36 canaux du syst\u00e8me d&rsquo;\u00e9clairage. Tous les canaux RGB inutilis\u00e9s peuvent \u00eatre d\u00e9sactiv\u00e9s par les registres configurables des LED.<\/span><\/span><\/p>\n<p class=\"western\" lang=\"fr-FR\"><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\">L&rsquo;AL5887Q dispose d&rsquo;un oscillateur int\u00e9gr\u00e9 de 16MHz pour le gradation PWM, \u00e9liminant le besoin d&rsquo;une horloge externe, ce qui r\u00e9duit l&#8217;empreinte PCB des modules d&rsquo;\u00e9clairage, facilite la conception et la disposition, et r\u00e9duit les co\u00fbts de la nomenclature (BOM). <\/span><\/span><\/p>\n<p class=\"western\" lang=\"fr-FR\"><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\">Pour optimiser le m\u00e9lange des couleurs et minimiser le bruit audible, il utilise un registre adressable PWM 12 bits ainsi qu&rsquo;un g\u00e9n\u00e9rateur PWM interne de 30kHz. L&rsquo;appareil prend en charge la gradation PWM profonde en modulant le cycle de service du courant constant de 100% \u00e0 3%. Une fois que le cycle de service est inf\u00e9rieur \u00e0 3%, le circuit interne passe le signal PWM \u00e0 la gradation analogique pour maintenir la lin\u00e9arit\u00e9 globale. <\/span><\/span><\/p>\n<p class=\"western\" lang=\"fr-FR\"><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\">L&rsquo;AL5887Q a une pr\u00e9cision de courant de 3% d&rsquo;appareil \u00e0 appareil et de canal \u00e0 canal, ce qui permet aux concepteurs de cr\u00e9er un m\u00e9lange de couleurs pr\u00e9cis et une distribution uniforme des couleurs sur leurs modules d&rsquo;\u00e9clairage et affichages.<\/span><\/span><\/p>\n<p class=\"western\" lang=\"fr-FR\"><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\">L&rsquo;AL5887Q est sp\u00e9cifi\u00e9 pour une plage de temp\u00e9rature de fonctionnement de -40\u00b0C \u00e0 +125\u00b0C et est disponible dans le bo\u00eetier compact W-QFN6060-52\/SWP (Type A1) \u00e0 empreinte mouillable, occupant seulement 6mm x 6mm.<\/span><\/span><\/p>\n<p class=\"western\"><span style=\"font-size: medium;\"><a href=\"https:\/\/www.diodes.com\/\"><span style=\"color: #0000ff;\"><span style=\"font-family: Open Sans, sans-serif;\"><span lang=\"fr-FR\"><u>Diodes Incorporated<\/u><\/span><\/span><\/span><\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avec sa capacit\u00e9 \u00e0 piloter des configurations RGB ainsi que des LED individuelles, le pilote de courant lin\u00e9aire LED automobile \u00e0 36 canaux, AL5887Q, de Diodes Incorporated (Diodes) r\u00e9pond au besoin des OEM de diff\u00e9rencier leurs marques en permettant aux concepteurs de cr\u00e9er diff\u00e9rents motifs d&rsquo;\u00e9clairage anim\u00e9s et profondeurs de couleur pour les lampes int\u00e9rieures [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":469742,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[7485],"domains":[47],"ppma_author":[6113],"class_list":["post-469721","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","tag-pilote-de-led","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Pilote de courant lin\u00e9aire : Flexibilit\u00e9 et efficacit\u00e9 pour ...<\/title>\n<meta name=\"description\" content=\"Avec sa capacit\u00e9 \u00e0 piloter des configurations RGB ainsi que des LED individuelles, le pilote de courant lin\u00e9aire LED automobile \u00e0 36 canaux, AL5887Q, de...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/469721\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pilote de courant lin\u00e9aire : Flexibilit\u00e9 et efficacit\u00e9 pour l&#039;\u00e9clairage automobile\" \/>\n<meta property=\"og:description\" content=\"Avec sa capacit\u00e9 \u00e0 piloter des configurations RGB ainsi que des LED individuelles, le pilote de courant lin\u00e9aire LED automobile \u00e0 36 canaux, AL5887Q, de Diodes Incorporated (Diodes) r\u00e9pond au besoin des OEM de diff\u00e9rencier leurs marques en permettant aux concepteurs de cr\u00e9er diff\u00e9rents motifs d&#039;\u00e9clairage anim\u00e9s et profondeurs de couleur pour les lampes int\u00e9rieures et ext\u00e9rieures.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/469721\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-17T08:00:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-08T17:51:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2025\/01\/ECI4725-DIO1099A_ENG_AL5887Q.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"690\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"NicolasFeste\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"NicolasFeste\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/pilote-de-courant-lineaire-flexibilite-et-efficacite-pour-leclairage-automobile\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/pilote-de-courant-lineaire-flexibilite-et-efficacite-pour-leclairage-automobile\/\"},\"author\":{\"name\":\"NicolasFeste\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/c7104a72b466a801f257e51481de0c43\"},\"headline\":\"Pilote de courant lin\u00e9aire : Flexibilit\u00e9 et efficacit\u00e9 pour l&rsquo;\u00e9clairage automobile\",\"datePublished\":\"2025-01-17T08:00:50+00:00\",\"dateModified\":\"2025-01-08T17:51:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/pilote-de-courant-lineaire-flexibilite-et-efficacite-pour-leclairage-automobile\/\"},\"wordCount\":592,\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"keywords\":[\"Pilote de LED\"],\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/pilote-de-courant-lineaire-flexibilite-et-efficacite-pour-leclairage-automobile\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/pilote-de-courant-lineaire-flexibilite-et-efficacite-pour-leclairage-automobile\/\",\"name\":\"Pilote de courant lin\u00e9aire : Flexibilit\u00e9 et efficacit\u00e9 pour l'\u00e9clairage automobile -\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\"},\"datePublished\":\"2025-01-17T08:00:50+00:00\",\"dateModified\":\"2025-01-08T17:51:58+00:00\",\"description\":\"Avec sa capacit\u00e9 \u00e0 piloter des configurations RGB ainsi que des LED individuelles, le pilote de courant lin\u00e9aire LED automobile \u00e0 36 canaux, AL5887Q, de Diodes Incorporated (Diodes) r\u00e9pond au besoin des OEM de diff\u00e9rencier leurs marques en permettant aux concepteurs de cr\u00e9er diff\u00e9rents motifs d'\u00e9clairage anim\u00e9s et profondeurs de couleur pour les lampes int\u00e9rieures et ext\u00e9rieures.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/pilote-de-courant-lineaire-flexibilite-et-efficacite-pour-leclairage-automobile\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/pilote-de-courant-lineaire-flexibilite-et-efficacite-pour-leclairage-automobile\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/pilote-de-courant-lineaire-flexibilite-et-efficacite-pour-leclairage-automobile\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pilote de courant lin\u00e9aire : Flexibilit\u00e9 et efficacit\u00e9 pour l&rsquo;\u00e9clairage automobile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/c7104a72b466a801f257e51481de0c43\",\"name\":\"NicolasFeste\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/1ea421e7d03c1e96a9ea2bcf2705734a\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2e187f4d96902933ba445ed6c760e11c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2e187f4d96902933ba445ed6c760e11c?s=96&d=mm&r=g\",\"caption\":\"NicolasFeste\"}}]}<\/script>","yoast_head_json":{"title":"Pilote de courant lin\u00e9aire : Flexibilit\u00e9 et efficacit\u00e9 pour ...","description":"Avec sa capacit\u00e9 \u00e0 piloter des configurations RGB ainsi que des LED individuelles, le pilote de courant lin\u00e9aire LED automobile \u00e0 36 canaux, AL5887Q, de...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/469721\/","og_locale":"fr_FR","og_type":"article","og_title":"Pilote de courant lin\u00e9aire : Flexibilit\u00e9 et efficacit\u00e9 pour l'\u00e9clairage automobile","og_description":"Avec sa capacit\u00e9 \u00e0 piloter des configurations RGB ainsi que des LED individuelles, le pilote de courant lin\u00e9aire LED automobile \u00e0 36 canaux, AL5887Q, de Diodes Incorporated (Diodes) r\u00e9pond au besoin des OEM de diff\u00e9rencier leurs marques en permettant aux concepteurs de cr\u00e9er diff\u00e9rents motifs d'\u00e9clairage anim\u00e9s et profondeurs de couleur pour les lampes int\u00e9rieures et ext\u00e9rieures.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/469721\/","og_site_name":"EENewsEurope","article_published_time":"2025-01-17T08:00:50+00:00","article_modified_time":"2025-01-08T17:51:58+00:00","og_image":[{"width":900,"height":690,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2025\/01\/ECI4725-DIO1099A_ENG_AL5887Q.jpg","type":"image\/jpeg"}],"author":"NicolasFeste","twitter_card":"summary_large_image","twitter_misc":{"Written by":"NicolasFeste","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/pilote-de-courant-lineaire-flexibilite-et-efficacite-pour-leclairage-automobile\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/pilote-de-courant-lineaire-flexibilite-et-efficacite-pour-leclairage-automobile\/"},"author":{"name":"NicolasFeste","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/c7104a72b466a801f257e51481de0c43"},"headline":"Pilote de courant lin\u00e9aire : Flexibilit\u00e9 et efficacit\u00e9 pour l&rsquo;\u00e9clairage automobile","datePublished":"2025-01-17T08:00:50+00:00","dateModified":"2025-01-08T17:51:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/pilote-de-courant-lineaire-flexibilite-et-efficacite-pour-leclairage-automobile\/"},"wordCount":592,"publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"keywords":["Pilote de LED"],"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/pilote-de-courant-lineaire-flexibilite-et-efficacite-pour-leclairage-automobile\/","url":"https:\/\/www.ecinews.fr\/fr\/pilote-de-courant-lineaire-flexibilite-et-efficacite-pour-leclairage-automobile\/","name":"Pilote de courant lin\u00e9aire : Flexibilit\u00e9 et efficacit\u00e9 pour l'\u00e9clairage automobile -","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/#website"},"datePublished":"2025-01-17T08:00:50+00:00","dateModified":"2025-01-08T17:51:58+00:00","description":"Avec sa capacit\u00e9 \u00e0 piloter des configurations RGB ainsi que des LED individuelles, le pilote de courant lin\u00e9aire LED automobile \u00e0 36 canaux, AL5887Q, de Diodes Incorporated (Diodes) r\u00e9pond au besoin des OEM de diff\u00e9rencier leurs marques en permettant aux concepteurs de cr\u00e9er diff\u00e9rents motifs d'\u00e9clairage anim\u00e9s et profondeurs de couleur pour les lampes int\u00e9rieures et ext\u00e9rieures.","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/pilote-de-courant-lineaire-flexibilite-et-efficacite-pour-leclairage-automobile\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/pilote-de-courant-lineaire-flexibilite-et-efficacite-pour-leclairage-automobile\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/pilote-de-courant-lineaire-flexibilite-et-efficacite-pour-leclairage-automobile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Pilote de courant lin\u00e9aire : Flexibilit\u00e9 et efficacit\u00e9 pour l&rsquo;\u00e9clairage automobile"}]},{"@type":"WebSite","@id":"https:\/\/www.ecinews.fr\/fr\/#website","url":"https:\/\/www.ecinews.fr\/fr\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ecinews.fr\/fr\/#organization","name":"EENewsEurope","url":"https:\/\/www.ecinews.fr\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/c7104a72b466a801f257e51481de0c43","name":"NicolasFeste","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/1ea421e7d03c1e96a9ea2bcf2705734a","url":"https:\/\/secure.gravatar.com\/avatar\/2e187f4d96902933ba445ed6c760e11c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2e187f4d96902933ba445ed6c760e11c?s=96&d=mm&r=g","caption":"NicolasFeste"}}]}},"authors":[{"term_id":6113,"user_id":39,"is_guest":0,"slug":"nicolasfeste","display_name":"NicolasFeste","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/2e187f4d96902933ba445ed6c760e11c?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/469721"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=469721"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/469721\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/469742"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=469721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=469721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=469721"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=469721"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=469721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}