{"id":468958,"date":"2025-01-02T09:00:13","date_gmt":"2025-01-02T08:00:13","guid":{"rendered":"https:\/\/www.ecinews.fr\/?p=468958"},"modified":"2024-12-31T16:17:24","modified_gmt":"2024-12-31T15:17:24","slug":"supercondensateurs-fiables-et-performants","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/supercondensateurs-fiables-et-performants\/","title":{"rendered":"Supercondensateurs fiables et performants"},"content":{"rendered":"<h3 class=\"western\"><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\">La combinaison de mat\u00e9riaux et de proc\u00e9d\u00e9s propri\u00e9taires, respectueux de l&rsquo;environnement, avec la conception d\u2019un condensateur \u00e0 double couche \u00e9lectrique rend les supercondensateurs XLR-LV d&rsquo;EATON extr\u00eamement fiables. <\/span><\/span><\/h3>\n<p class=\"western\"><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\">Ces puissants dispositifs de stockage d\u2019\u00e9nergie sont disponibles en diff\u00e9rentes variations pour une vari\u00e9t\u00e9 de solutions de condensateurs. Les modules, d&rsquo;une capacit\u00e9 de 500\u00a0F, sont sans entretien \u00e0 des temp\u00e9ratures de fonctionnement de -40 \u00b0C \u00e0 +65\u00a0\u00b0C et ont une dur\u00e9e de vie allant jusqu\u2019\u00e0 20\u00a0ans. Ils se caract\u00e9risent par une ESR extr\u00eamement faible de 1,7\u00a0mOhm, une r\u00e9sistance aux surtensions particuli\u00e8rement \u00e9lev\u00e9e et un courant de veille minimal. <\/span><\/span><\/p>\n<p class=\"western\"><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\">Ils sont certifi\u00e9s UL810a, conformes RoHS et atteignent la plus haute cote de protection IP65. Cela les rend id\u00e9aux pour une utilisation dans des applications avanc\u00e9es telles que l&rsquo;alimentation de secours, l&rsquo;alimentation par impulsions et les syst\u00e8mes \u00e9nerg\u00e9tiques hybrides.<\/span><\/span><\/p>\n<p class=\"western\"><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\">Les dispositifs de stockage d\u2019\u00e9nergie sont install\u00e9s dans des bo\u00eetiers en aluminium pour une meilleure int\u00e9grit\u00e9 m\u00e9canique et un meilleur refroidissement et poss\u00e8dent une structure interne soud\u00e9e au laser qui assure leur haute fiabilit\u00e9. Afin d\u2019atteindre 18\u00a0V \/ 500\u00a0F dans la m\u00eame taille de bo\u00eetier que les produits comparables, les supercondensateurs XLR-LV sont d\u00e9sormais disponibles avec une technologie de cellule de 3\u00a0V.<\/span><\/span><\/p>\n<p class=\"western\"><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\">Ils peuvent \u00eatre utilis\u00e9s comme seul stockage d\u2019\u00e9nergie, mais aussi en combinaison avec des batteries pour r\u00e9duire les co\u00fbts et optimiser la dur\u00e9e de vie et le temps de fonctionnement. Les condensateurs peuvent supporter des surtensions allant jusqu\u2019\u00e0 105\u00a0% de la tension de fonctionnement maximale, ont une tol\u00e9rance de capacit\u00e9 de -5\u00a0% \u00e0 +20\u00a0% et affichent quatre valeurs de pointe dans l\u2019industrie\u00a0:<\/span><\/span><\/p>\n<ul>\n<li>\n<p class=\"western\"><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\">ESR minimale (1,7 mOhm)<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"western\"><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\">Courant de veille extr\u00eamement faible (max. 8 mA)<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"western\"><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\">Classe de protection IP65<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"western\"><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\">R\u00e9sistance maximale aux chocs et aux vibrations (SAE J2464 &amp; J2380)<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<p class=\"western\"><strong><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\">Avantages\u00a0:<\/span><\/span><\/strong><\/p>\n<ul>\n<li>\n<p class=\"western\"><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\">Longue dur\u00e9e de vie allant jusqu&rsquo;\u00e0 20 ans<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"western\"><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\">Large plage de temp\u00e9ratures de -40\u00b0C \u00e0 +65\u00b0C<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"western\"><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\">Haute fiabilit\u00e9<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"western\"><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\">Faibles co\u00fbts de fonctionnement<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"western\"><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\">Sans entretien<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"western\"><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\">Conforme RoHS<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"western\"><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\">Certifi\u00e9 UL810a<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<p class=\"western\"><strong><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\">Exemples d&rsquo;applications\u00a0:<\/span><\/span><\/strong><\/p>\n<ul>\n<li>\n<p class=\"western\"><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\">Entrep\u00f4t automatis\u00e9<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"western\"><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\">Alimentation principale pour les v\u00e9hicules AGV (rechargeable en 20 secondes)<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"western\"><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\">Piles \u00e0 hydrog\u00e8ne pour la gestion des rampes de puissance<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"western\"><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\">Alimentation de secours pour les machines industrielles<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<p class=\"western\" align=\"left\"><span style=\"color: #000080;\"><u><a href=\"https:\/\/www.rutronik.com\/\"><span style=\"color: #0000ff;\"><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\">Rutronik<\/span><\/span><\/span><\/a><\/u><\/span> <span style=\"color: #000000;\"><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\">| <a href=\"https:\/\/www.eaton.com\/\">EATON<\/a><\/span><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La combinaison de mat\u00e9riaux et de proc\u00e9d\u00e9s propri\u00e9taires, respectueux de l&rsquo;environnement, avec la conception d\u2019un condensateur \u00e0 double couche \u00e9lectrique rend les supercondensateurs XLR-LV d&rsquo;EATON extr\u00eamement fiables. Ces puissants dispositifs de stockage d\u2019\u00e9nergie sont disponibles en diff\u00e9rentes variations pour une vari\u00e9t\u00e9 de solutions de condensateurs. Les modules, d&rsquo;une capacit\u00e9 de 500\u00a0F, sont sans entretien \u00e0 [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":468974,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[1588],"domains":[47],"ppma_author":[6113],"class_list":["post-468958","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","tag-condensateurs","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Supercondensateurs fiables et performants ...<\/title>\n<meta name=\"description\" content=\"La combinaison de mat\u00e9riaux et de proc\u00e9d\u00e9s propri\u00e9taires, respectueux de l&#039;environnement, avec la conception d\u2019un condensateur \u00e0 double couche...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/468958\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Supercondensateurs fiables et performants\" \/>\n<meta property=\"og:description\" content=\"La combinaison de mat\u00e9riaux et de proc\u00e9d\u00e9s propri\u00e9taires, respectueux de l&#039;environnement, avec la conception d\u2019un condensateur \u00e0 double couche \u00e9lectrique rend les supercondensateurs XLR-LV d&#039;EATON extr\u00eamement fiables.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/468958\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-02T08:00:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-31T15:17:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/2024\/12\/ECI4680-Nov24-RUT-EATON-XLRLV_EN-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"NicolasFeste\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"NicolasFeste\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/supercondensateurs-fiables-et-performants\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/supercondensateurs-fiables-et-performants\/\"},\"author\":{\"name\":\"NicolasFeste\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/c7104a72b466a801f257e51481de0c43\"},\"headline\":\"Supercondensateurs fiables et performants\",\"datePublished\":\"2025-01-02T08:00:13+00:00\",\"dateModified\":\"2024-12-31T15:17:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/supercondensateurs-fiables-et-performants\/\"},\"wordCount\":394,\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"keywords\":[\"Condensateurs\"],\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/supercondensateurs-fiables-et-performants\/\",\"url\":\"https:\/\/www.eenewseurope.com\/fr\/supercondensateurs-fiables-et-performants\/\",\"name\":\"Supercondensateurs fiables et performants -\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\"},\"datePublished\":\"2025-01-02T08:00:13+00:00\",\"dateModified\":\"2024-12-31T15:17:24+00:00\",\"description\":\"La combinaison de mat\u00e9riaux et de proc\u00e9d\u00e9s propri\u00e9taires, respectueux de l'environnement, avec la conception d\u2019un condensateur \u00e0 double couche \u00e9lectrique rend les supercondensateurs XLR-LV d'EATON extr\u00eamement fiables.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/supercondensateurs-fiables-et-performants\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eenewseurope.com\/fr\/supercondensateurs-fiables-et-performants\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/supercondensateurs-fiables-et-performants\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Supercondensateurs fiables et performants\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/c7104a72b466a801f257e51481de0c43\",\"name\":\"NicolasFeste\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/1ea421e7d03c1e96a9ea2bcf2705734a\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2e187f4d96902933ba445ed6c760e11c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2e187f4d96902933ba445ed6c760e11c?s=96&d=mm&r=g\",\"caption\":\"NicolasFeste\"}}]}<\/script>","yoast_head_json":{"title":"Supercondensateurs fiables et performants ...","description":"La combinaison de mat\u00e9riaux et de proc\u00e9d\u00e9s propri\u00e9taires, respectueux de l'environnement, avec la conception d\u2019un condensateur \u00e0 double couche...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/468958\/","og_locale":"fr_FR","og_type":"article","og_title":"Supercondensateurs fiables et performants","og_description":"La combinaison de mat\u00e9riaux et de proc\u00e9d\u00e9s propri\u00e9taires, respectueux de l'environnement, avec la conception d\u2019un condensateur \u00e0 double couche \u00e9lectrique rend les supercondensateurs XLR-LV d'EATON extr\u00eamement fiables.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/468958\/","og_site_name":"EENewsEurope","article_published_time":"2025-01-02T08:00:13+00:00","article_modified_time":"2024-12-31T15:17:24+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/2024\/12\/ECI4680-Nov24-RUT-EATON-XLRLV_EN-scaled.jpg","type":"image\/jpeg"}],"author":"NicolasFeste","twitter_card":"summary_large_image","twitter_misc":{"Written by":"NicolasFeste","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eenewseurope.com\/fr\/supercondensateurs-fiables-et-performants\/#article","isPartOf":{"@id":"https:\/\/www.eenewseurope.com\/fr\/supercondensateurs-fiables-et-performants\/"},"author":{"name":"NicolasFeste","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/c7104a72b466a801f257e51481de0c43"},"headline":"Supercondensateurs fiables et performants","datePublished":"2025-01-02T08:00:13+00:00","dateModified":"2024-12-31T15:17:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eenewseurope.com\/fr\/supercondensateurs-fiables-et-performants\/"},"wordCount":394,"publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"keywords":["Condensateurs"],"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.eenewseurope.com\/fr\/supercondensateurs-fiables-et-performants\/","url":"https:\/\/www.eenewseurope.com\/fr\/supercondensateurs-fiables-et-performants\/","name":"Supercondensateurs fiables et performants -","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/#website"},"datePublished":"2025-01-02T08:00:13+00:00","dateModified":"2024-12-31T15:17:24+00:00","description":"La combinaison de mat\u00e9riaux et de proc\u00e9d\u00e9s propri\u00e9taires, respectueux de l'environnement, avec la conception d\u2019un condensateur \u00e0 double couche \u00e9lectrique rend les supercondensateurs XLR-LV d'EATON extr\u00eamement fiables.","breadcrumb":{"@id":"https:\/\/www.eenewseurope.com\/fr\/supercondensateurs-fiables-et-performants\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eenewseurope.com\/fr\/supercondensateurs-fiables-et-performants\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eenewseurope.com\/fr\/supercondensateurs-fiables-et-performants\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Supercondensateurs fiables et performants"}]},{"@type":"WebSite","@id":"https:\/\/www.ecinews.fr\/fr\/#website","url":"https:\/\/www.ecinews.fr\/fr\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ecinews.fr\/fr\/#organization","name":"EENewsEurope","url":"https:\/\/www.ecinews.fr\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/c7104a72b466a801f257e51481de0c43","name":"NicolasFeste","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/1ea421e7d03c1e96a9ea2bcf2705734a","url":"https:\/\/secure.gravatar.com\/avatar\/2e187f4d96902933ba445ed6c760e11c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2e187f4d96902933ba445ed6c760e11c?s=96&d=mm&r=g","caption":"NicolasFeste"}}]}},"authors":[{"term_id":6113,"user_id":39,"is_guest":0,"slug":"nicolasfeste","display_name":"NicolasFeste","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/2e187f4d96902933ba445ed6c760e11c?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/468958"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=468958"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/468958\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/468974"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=468958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=468958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=468958"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=468958"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=468958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}