{"id":468609,"date":"2024-12-23T16:44:51","date_gmt":"2024-12-23T15:44:51","guid":{"rendered":"https:\/\/www.ecinews.fr\/?p=468609"},"modified":"2024-12-24T17:29:47","modified_gmt":"2024-12-24T16:29:47","slug":"sonde-de-courant-avec-isolation-radiofrequence-rf-pour-plus-de-precision-et-de-securite","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/sonde-de-courant-avec-isolation-radiofrequence-rf-pour-plus-de-precision-et-de-securite\/","title":{"rendered":"Sonde de courant avec isolation radiofr\u00e9quence (RF) pour plus de pr\u00e9cision et de s\u00e9curit\u00e9"},"content":{"rendered":"<h3 class=\"western\"><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\"><span lang=\"fr-FR\">Faisant partie d\u2019une g<\/span><\/span><\/span><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\"><span lang=\"fr-FR\">amme<\/span><\/span><\/span><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\"><span lang=\"fr-FR\"> d\u2019instruments de test puissance destin\u00e9e \u00e0 acc\u00e9l\u00e9rer le processus d\u2019innovation dans les secteurs industriels exigeant davantage d\u2019efficacit\u00e9 et de capacit\u00e9 de puissance, <\/span><\/span><\/span><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\"><span lang=\"fr-FR\">l<\/span><\/span><\/span><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\"><span lang=\"fr-FR\">es <\/span><\/span><\/span><span style=\"color: #0563c1;\"><u><a href=\"https:\/\/www.tek.com\/fr\/products\/oscilloscopes\/oscilloscope-probes\/isovu-isolated-current-probes?utm_source=pr&amp;utm_medium=press&amp;utm_campaign=software|ticp-psb20k-npi|fr\"><span style=\"color: #0000ff;\"><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\"><span lang=\"fr-FR\">sondes de courant isol\u00e9es de la gamme TICP Series IsoVu<\/span><\/span><\/span><\/span><\/a><\/u><\/span><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\"><span lang=\"fr-FR\"> sont les premi\u00e8res au monde \u00e0 mettre en \u0153uvre une technologie d\u2019isolation radiofr\u00e9quence (RF), permet<\/span><\/span><\/span><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\"><span lang=\"fr-FR\">tant<\/span><\/span><\/span><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\"><span lang=\"fr-FR\"> d\u2019offrir un exceptionnel niveau de pr\u00e9cision et de s\u00e9curit\u00e9 pour mesurer des courants \u00e9voluant rapidement au sein des syst\u00e8mes basse et haute tension. <\/span><\/span><\/span><\/h3>\n<p><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\"><span lang=\"fr-FR\"><b>Les sondes de courant isol\u00e9es TICP Series IsoVu \u00e9tablissent une nouvelle r\u00e9f\u00e9rence sur le march\u00e9<br \/>\n<\/b><\/span><span lang=\"fr-FR\">Les sondes TICP IsoVu sont les premi\u00e8res sondes de courant \u00e0 shunt du march\u00e9 \u00e0 utiliser une technologie d&rsquo;isolation RF qui permet d\u2019assurer une totale isolation galvanique entre les syst\u00e8mes de mesure et les dispositifs sous test. Ce qui permet de r\u00e9aliser des mesures de courant sur une large bande de fr\u00e9quences et avec un faible bruit dans le cadre d\u2019applications haute tension. Ce qui les d\u00e9marque des sondes existantes sur le march\u00e9 ou des techniques de mesure \u00e0 shunt alternatives. Offrant une bande passante allant jusqu&rsquo;\u00e0 1 GHz, ces sondes permettent aux ing\u00e9nieurs d\u2019effectuer de pr\u00e9cises mesures de courant \u00e9voluant rapidement \u00e0 partir de leurs oscilloscopes dans une large gamme de tension &#8211; des microamp\u00e8res aux kiloamp\u00e8res &#8211; en quelques nanosecondes. <\/span><\/span><\/span><\/p>\n<p><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\"><span lang=\"fr-FR\">\u00ab La gamme de mesures \u00e9tendue permet d\u2019adresser des environnements haute tension auparavant inaccessibles, depuis les convertisseurs de puissance \u00e0 commutation rapide \u00e0 base de semi-conducteurs SiC et GaN jusqu&rsquo;aux applications de faible puissance telles que les tests de performance des batteries des appareils mobiles &#8211; le tout avec une seule et unique sonde \u00bb, a d\u00e9clar\u00e9 Daryl Ellis, directeur g\u00e9n\u00e9ral de l\u2019offre Entry et Mainstream de Tektronix. \u00ab Alors que le processus d&rsquo;innovation en mati\u00e8re d&rsquo;alimentation s&rsquo;acc\u00e9l\u00e8re au niveau mondial, nous \u00e9tablissons de nouvelles r\u00e9f\u00e9rences en mati\u00e8re de pr\u00e9cision, de s\u00e9curit\u00e9 et d&rsquo;\u00e9volutivit\u00e9. Ce qui permet aux clients de repousser les limites du possible dans des secteurs industriels allant de l&rsquo;automobile aux \u00e9nergies renouvelables. \u00bb<\/span><\/span><\/span><\/p>\n<p><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\"><span lang=\"fr-FR\"><b>Principales caract\u00e9ristiques :<\/b><\/span> <\/span><\/span><\/p>\n<ul>\n<li>\n<p><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\"><span lang=\"fr-FR\">Totale isolation galvanique RF qui \u00e9limine les boucles de masse.<\/span><\/span><\/span><\/p>\n<\/li>\n<li>\n<p><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\"><span lang=\"fr-FR\">R\u00e9jection en mode commun (CMRR) plus de 30 fois sup\u00e9rieure \u00e0 celle des sondes de tension diff\u00e9rentielles traditionnelles : 140 dB CMRR en courant continu, jusqu&rsquo;\u00e0 90 dB \u00e0 1 MHz.<\/span><\/span><\/span><\/p>\n<\/li>\n<li>\n<p><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\"><span lang=\"fr-FR\">Ultra-faible contribution au bruit &#8211; dans une configuration 1X, l&rsquo;entr\u00e9e 50 \u03a9 pr\u00e9sente un bruit extr\u00eamement faible\u00a0: &lt;4,7 nV \/ \u221aHz (&lt;150 \u03bcV \u00e0 1 GHz).<\/span><\/span><\/span><\/p>\n<\/li>\n<li>\n<p><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\"><span lang=\"fr-FR\">Disponible en 3 mod\u00e8les \u00e0 des largeurs de bande de 1 GHz (TICP100), 500 MHz (TICP050) et 250 MHz (TICP025).<\/span><\/span><\/span><\/p>\n<\/li>\n<li>\n<p><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\"><span lang=\"fr-FR\">Utilise l&rsquo;interface de sonde TekVPI pour se connecter aux oscilloscopes des s\u00e9ries MSO 4, 5 et 6 de Tektronix.<\/span><\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.tek.com\/\"><span style=\"color: #0000ff;\"><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: medium;\"><span lang=\"fr-FR\"><u>Tektronix<\/u><\/span><\/span><\/span><\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Faisant partie d\u2019une gamme d\u2019instruments de test puissance destin\u00e9e \u00e0 acc\u00e9l\u00e9rer le processus d\u2019innovation dans les secteurs industriels exigeant davantage d\u2019efficacit\u00e9 et de capacit\u00e9 de puissance, les sondes de courant isol\u00e9es de la gamme TICP Series IsoVu sont les premi\u00e8res au monde \u00e0 mettre en \u0153uvre une technologie d\u2019isolation radiofr\u00e9quence (RF), permettant d\u2019offrir un exceptionnel [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":468612,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[7273,8543,4015,6157],"domains":[47],"ppma_author":[6113],"class_list":["post-468609","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","tag-sonde","tag-sonde-de-courant","tag-test-mesure","tag-test-mesures","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Sonde de courant avec isolation radiofr\u00e9quence (RF) pour plus ...<\/title>\n<meta name=\"description\" content=\"Gamme d\u2019instruments de test puissance destin\u00e9e \u00e0 acc\u00e9l\u00e9rer le processus d\u2019innovation dans les secteurs industriels exigeant davantage d\u2019efficacit\u00e9...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/468609\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sonde de courant avec isolation radiofr\u00e9quence (RF) pour plus de pr\u00e9cision et de s\u00e9curit\u00e9\" \/>\n<meta property=\"og:description\" content=\"Gamme d\u2019instruments de test puissance destin\u00e9e \u00e0 acc\u00e9l\u00e9rer le processus d\u2019innovation dans les secteurs industriels exigeant davantage d\u2019efficacit\u00e9 et de capacit\u00e9 de puissance, les sondes de courant isol\u00e9es de la gamme TICP Series IsoVu sont les premi\u00e8res au monde \u00e0 mettre en \u0153uvre une technologie d\u2019isolation radiofr\u00e9quence (RF), permettant d\u2019offrir un exceptionnel niveau de pr\u00e9cision et de s\u00e9curit\u00e9 pour mesurer des courants \u00e9voluant rapidement au sein des syst\u00e8mes basse et haute tension.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/468609\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-23T15:44:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-24T16:29:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2024\/12\/ECI4654a-TEK075fr-Tektronix-unveils-breakthrough-power-instrumentation-to-fast-track-customer-innovation-in-an-increasingly-electrified-world-final-approved-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"NicolasFeste\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"NicolasFeste\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/sonde-de-courant-avec-isolation-radiofrequence-rf-pour-plus-de-precision-et-de-securite\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/sonde-de-courant-avec-isolation-radiofrequence-rf-pour-plus-de-precision-et-de-securite\/\"},\"author\":{\"name\":\"NicolasFeste\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/c7104a72b466a801f257e51481de0c43\"},\"headline\":\"Sonde de courant avec isolation radiofr\u00e9quence (RF) pour plus de pr\u00e9cision et de s\u00e9curit\u00e9\",\"datePublished\":\"2024-12-23T15:44:51+00:00\",\"dateModified\":\"2024-12-24T16:29:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/sonde-de-courant-avec-isolation-radiofrequence-rf-pour-plus-de-precision-et-de-securite\/\"},\"wordCount\":485,\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"keywords\":[\"Sonde\",\"Sonde de courant\",\"Test &amp; Mesure\",\"Test &amp; mesures\"],\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/sonde-de-courant-avec-isolation-radiofrequence-rf-pour-plus-de-precision-et-de-securite\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/sonde-de-courant-avec-isolation-radiofrequence-rf-pour-plus-de-precision-et-de-securite\/\",\"name\":\"Sonde de courant avec isolation radiofr\u00e9quence (RF) pour plus de pr\u00e9cision et de s\u00e9curit\u00e9 -\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\"},\"datePublished\":\"2024-12-23T15:44:51+00:00\",\"dateModified\":\"2024-12-24T16:29:47+00:00\",\"description\":\"Gamme d\u2019instruments de test puissance destin\u00e9e \u00e0 acc\u00e9l\u00e9rer le processus d\u2019innovation dans les secteurs industriels exigeant davantage d\u2019efficacit\u00e9 et de capacit\u00e9 de puissance, les sondes de courant isol\u00e9es de la gamme TICP Series IsoVu sont les premi\u00e8res au monde \u00e0 mettre en \u0153uvre une technologie d\u2019isolation radiofr\u00e9quence (RF), permettant d\u2019offrir un exceptionnel niveau de pr\u00e9cision et de s\u00e9curit\u00e9 pour mesurer des courants \u00e9voluant rapidement au sein des syst\u00e8mes basse et haute tension.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/sonde-de-courant-avec-isolation-radiofrequence-rf-pour-plus-de-precision-et-de-securite\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/sonde-de-courant-avec-isolation-radiofrequence-rf-pour-plus-de-precision-et-de-securite\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/sonde-de-courant-avec-isolation-radiofrequence-rf-pour-plus-de-precision-et-de-securite\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sonde de courant avec isolation radiofr\u00e9quence (RF) pour plus de pr\u00e9cision et de s\u00e9curit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/c7104a72b466a801f257e51481de0c43\",\"name\":\"NicolasFeste\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/1ea421e7d03c1e96a9ea2bcf2705734a\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2e187f4d96902933ba445ed6c760e11c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2e187f4d96902933ba445ed6c760e11c?s=96&d=mm&r=g\",\"caption\":\"NicolasFeste\"}}]}<\/script>","yoast_head_json":{"title":"Sonde de courant avec isolation radiofr\u00e9quence (RF) pour plus ...","description":"Gamme d\u2019instruments de test puissance destin\u00e9e \u00e0 acc\u00e9l\u00e9rer le processus d\u2019innovation dans les secteurs industriels exigeant davantage d\u2019efficacit\u00e9...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/468609\/","og_locale":"fr_FR","og_type":"article","og_title":"Sonde de courant avec isolation radiofr\u00e9quence (RF) pour plus de pr\u00e9cision et de s\u00e9curit\u00e9","og_description":"Gamme d\u2019instruments de test puissance destin\u00e9e \u00e0 acc\u00e9l\u00e9rer le processus d\u2019innovation dans les secteurs industriels exigeant davantage d\u2019efficacit\u00e9 et de capacit\u00e9 de puissance, les sondes de courant isol\u00e9es de la gamme TICP Series IsoVu sont les premi\u00e8res au monde \u00e0 mettre en \u0153uvre une technologie d\u2019isolation radiofr\u00e9quence (RF), permettant d\u2019offrir un exceptionnel niveau de pr\u00e9cision et de s\u00e9curit\u00e9 pour mesurer des courants \u00e9voluant rapidement au sein des syst\u00e8mes basse et haute tension.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/468609\/","og_site_name":"EENewsEurope","article_published_time":"2024-12-23T15:44:51+00:00","article_modified_time":"2024-12-24T16:29:47+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2024\/12\/ECI4654a-TEK075fr-Tektronix-unveils-breakthrough-power-instrumentation-to-fast-track-customer-innovation-in-an-increasingly-electrified-world-final-approved-scaled.jpg","type":"image\/jpeg"}],"author":"NicolasFeste","twitter_card":"summary_large_image","twitter_misc":{"Written by":"NicolasFeste","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/sonde-de-courant-avec-isolation-radiofrequence-rf-pour-plus-de-precision-et-de-securite\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/sonde-de-courant-avec-isolation-radiofrequence-rf-pour-plus-de-precision-et-de-securite\/"},"author":{"name":"NicolasFeste","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/c7104a72b466a801f257e51481de0c43"},"headline":"Sonde de courant avec isolation radiofr\u00e9quence (RF) pour plus de pr\u00e9cision et de s\u00e9curit\u00e9","datePublished":"2024-12-23T15:44:51+00:00","dateModified":"2024-12-24T16:29:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/sonde-de-courant-avec-isolation-radiofrequence-rf-pour-plus-de-precision-et-de-securite\/"},"wordCount":485,"publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"keywords":["Sonde","Sonde de courant","Test &amp; Mesure","Test &amp; mesures"],"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/sonde-de-courant-avec-isolation-radiofrequence-rf-pour-plus-de-precision-et-de-securite\/","url":"https:\/\/www.ecinews.fr\/fr\/sonde-de-courant-avec-isolation-radiofrequence-rf-pour-plus-de-precision-et-de-securite\/","name":"Sonde de courant avec isolation radiofr\u00e9quence (RF) pour plus de pr\u00e9cision et de s\u00e9curit\u00e9 -","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/#website"},"datePublished":"2024-12-23T15:44:51+00:00","dateModified":"2024-12-24T16:29:47+00:00","description":"Gamme d\u2019instruments de test puissance destin\u00e9e \u00e0 acc\u00e9l\u00e9rer le processus d\u2019innovation dans les secteurs industriels exigeant davantage d\u2019efficacit\u00e9 et de capacit\u00e9 de puissance, les sondes de courant isol\u00e9es de la gamme TICP Series IsoVu sont les premi\u00e8res au monde \u00e0 mettre en \u0153uvre une technologie d\u2019isolation radiofr\u00e9quence (RF), permettant d\u2019offrir un exceptionnel niveau de pr\u00e9cision et de s\u00e9curit\u00e9 pour mesurer des courants \u00e9voluant rapidement au sein des syst\u00e8mes basse et haute tension.","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/sonde-de-courant-avec-isolation-radiofrequence-rf-pour-plus-de-precision-et-de-securite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/sonde-de-courant-avec-isolation-radiofrequence-rf-pour-plus-de-precision-et-de-securite\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/sonde-de-courant-avec-isolation-radiofrequence-rf-pour-plus-de-precision-et-de-securite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Sonde de courant avec isolation radiofr\u00e9quence (RF) pour plus de pr\u00e9cision et de s\u00e9curit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.ecinews.fr\/fr\/#website","url":"https:\/\/www.ecinews.fr\/fr\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ecinews.fr\/fr\/#organization","name":"EENewsEurope","url":"https:\/\/www.ecinews.fr\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/c7104a72b466a801f257e51481de0c43","name":"NicolasFeste","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/1ea421e7d03c1e96a9ea2bcf2705734a","url":"https:\/\/secure.gravatar.com\/avatar\/2e187f4d96902933ba445ed6c760e11c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2e187f4d96902933ba445ed6c760e11c?s=96&d=mm&r=g","caption":"NicolasFeste"}}]}},"authors":[{"term_id":6113,"user_id":39,"is_guest":0,"slug":"nicolasfeste","display_name":"NicolasFeste","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/2e187f4d96902933ba445ed6c760e11c?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/468609"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=468609"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/468609\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/468612"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=468609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=468609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=468609"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=468609"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=468609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}