{"id":465737,"date":"2024-11-19T01:07:02","date_gmt":"2024-11-19T00:07:02","guid":{"rendered":"https:\/\/www.ecinews.fr\/?p=465737"},"modified":"2024-11-19T01:07:02","modified_gmt":"2024-11-19T00:07:02","slug":"circuits-integres-pour-le-marche-io-link-en-pleine-croissance","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/circuits-integres-pour-le-marche-io-link-en-pleine-croissance\/","title":{"rendered":"Circuits Int\u00e9gr\u00e9s pour le March\u00e9 IO-Link en Pleine Croissance"},"content":{"rendered":"<h3>Pour r\u00e9pondre \u00e0 la forte croissance du march\u00e9 de l\u2019IO-Link, <a href=\"http:\/\/www.renesas.com\/\">Renesas Electronics Corporation<\/a> a lanc\u00e9 le circuit int\u00e9gr\u00e9 ma\u00eetre IO-Link \u00e0 quatre canaux CCE4511 et le circuit int\u00e9gr\u00e9 conditionneur de signaux de capteurs r\u00e9sistifs \u00e0 deux canaux ZSSC3286.<\/h3>\n<p>IO-Link est un protocole de communication num\u00e9rique tr\u00e8s largement utilis\u00e9 dans les applications d&rsquo;automatisation industrielle. En tant que technologie normalis\u00e9e, il permet une communication transparente entre les capteurs, les actionneurs et les autres dispositifs d&rsquo;un syst\u00e8me d&rsquo;automatisation. IO-Link est devenu de plus en plus populaire ces derni\u00e8res ann\u00e9es en raison de sa capacit\u00e9 \u00e0 fournir des donn\u00e9es et des diagnostics en temps r\u00e9el, de sa facilit\u00e9 d&rsquo;utilisation et de sa compatibilit\u00e9 avec les syst\u00e8mes existants. Il permet \u00e9galement de r\u00e9guler et de r\u00e9duire le c\u00e2blage, d&rsquo;am\u00e9liorer la disponibilit\u00e9 des donn\u00e9es et d&rsquo;offrir une configuration et une surveillance \u00e0 distance. Le cabinet d&rsquo;\u00e9tudes de march\u00e9 Infogence Global Research estime que le march\u00e9 de l&rsquo;IO-Link va cro\u00eetre de plus de 20 % par an, pour atteindre plus de 34 milliards de dollars en 2028. En tant que leader des solutions d&rsquo;automatisation industrielle, Renesas s&rsquo;engage \u00e0 fournir \u00e0 ses clients des solutions IO-Link innovantes.<\/p>\n<p><strong>Circuit Int\u00e9gr\u00e9 Ma\u00eetre IO-Link \u00e0 Quatre Canaux CCE4511<\/strong><\/p>\n<p>Le nouveau\u00a0<a href=\"https:\/\/www.renesas.com\/products\/interface\/io-link-line-drivers\/cce4511-4-channel-io-link-master-transceiver-integrated-frame-handler?utm_campaign=f-up-csd_iolink_cce4511-epsg-imsd-iag-null&amp;utm_source=null&amp;utm_medium=pr&amp;utm_content=pp\">CCE4511<\/a>\u00a0de Renesas est le premier circuit int\u00e9gr\u00e9 ma\u00eetre \u00e0 quatre canaux pour le protocole IO-Link, avec un courant d&rsquo;attaque de 500 mA pour chaque canal, et offre de nombreux avantages par rapport aux circuits ma\u00eetres \u00e0 deux canaux. Il \u00e9conomise de l&rsquo;\u00e9nergie, r\u00e9duit la taille du circuit imprim\u00e9 et n\u00e9cessite moins de composants externes que les produits concurrents.\u00a0<\/p>\n<p>Le CCE4511 offre une interface haute tension ainsi qu&rsquo;une d\u00e9tection de surtension et une protection contre les surintensit\u00e9s. Pour am\u00e9liorer les performances des applications, un gestionnaire de trames IO-Link int\u00e9gr\u00e9 est fourni, qui automatise la plupart des t\u00e2ches de communication de la couche inf\u00e9rieure. Cela r\u00e9duit consid\u00e9rablement la charge du microcontr\u00f4leur (MCU), ce qui permet de gagner en performance pour d&rsquo;autres t\u00e2ches, et\/ou permet aux concepteurs d&rsquo;utiliser un MCU moins co\u00fbteux. Le CCE4511 a une temp\u00e9rature ambiante de fonctionnement allant jusqu&rsquo;\u00e0 125\u00ba C pour les environnements industriels difficiles. Il prend \u00e9galement en charge la d\u00e9tection des impulsions de disponibilit\u00e9 des dispositifs IO-Link, ce qui est n\u00e9cessaire pour r\u00e9pondre \u00e0 la nouvelle d\u00e9finition de l&rsquo;extension du syst\u00e8me de s\u00e9curit\u00e9 IO-Link.<\/p>\n<p><strong>Circuit Int\u00e9gr\u00e9 de Conditionnement de Signaux de Capteurs R\u00e9sistifs \u00e0 Deux Canaux, Pr\u00eat pour IO-Link, ZSSC3286<\/strong><\/p>\n<p>Le\u00a0<a href=\"https:\/\/www.renesas.com\/products\/sensor-products\/sensor-signal-conditioners-ssc-afe\/zssc3286-io-link-ready-dual-channel-resistive-sensor-signal-conditioner-ic?utm_campaign=f-up-csd_iolink_zssc3286-epsg-snsd-senst-null&amp;utm_source=null&amp;utm_medium=pr&amp;utm_content=pp\">ZSSC3286<\/a>\u00a0est un circuit int\u00e9gr\u00e9 de conditionnement de signaux de capteurs (SSC) \u00e0 double voie pour une amplification, une num\u00e9risation et une correction tr\u00e8s pr\u00e9cises des signaux de capteurs. Il prend en charge la connectivit\u00e9 IO-Link avec une pile IO-Link int\u00e9gr\u00e9e ex\u00e9cutant le profil IO-Link Smart Sensor pour les capteurs num\u00e9riques de mesure et de commutation. Le composant convient aux capteurs \u00e0 pont et \u00e0 demi-pont, ainsi qu&rsquo;aux \u00e9l\u00e9ments \u00e0 source de tension externe. La compensation num\u00e9rique du d\u00e9calage, de la sensibilit\u00e9, de la d\u00e9rive en temp\u00e9rature et de la non-lin\u00e9arit\u00e9 du capteur s&rsquo;effectue par l&rsquo;interm\u00e9diaire d&rsquo;un c\u0153ur math\u00e9matique 32 bits bas\u00e9 sur le processeur Arm, qui ex\u00e9cute un algorithme de correction avec des coefficients d&rsquo;\u00e9talonnage stock\u00e9s dans une m\u00e9moire non volatile et reprogrammable. Le SSC int\u00e9gr\u00e9 et programmable permet d&rsquo;appliquer de mani\u00e8re optimale diff\u00e9rents capteurs pour une large gamme d&rsquo;applications.\u00a0<\/p>\n<p>Le ZSSC3286 est le premier conditionneur de signaux de capteurs avec une pile int\u00e9gr\u00e9e compatible IO-Link. Traditionnellement, un microcontr\u00f4leur suppl\u00e9mentaire \u00e9tait utilis\u00e9 pour faire fonctionner la pile. Le ZSSC3286 supprime le MCU, ce qui permet d&rsquo;\u00e9conomiser de l&rsquo;espace sur la carte et de r\u00e9duire les co\u00fbts. Il offre \u00e9galement deux CAN parall\u00e8les avec une r\u00e9solution allant jusqu&rsquo;\u00e0 24 bits, un planificateur de mesures pour optimiser les performances et des fonctions de diagnostic syst\u00e8me avanc\u00e9es.<\/p>\n<p>\u00ab\u00a0Notre large base de clients industriels nous a demand\u00e9 de nouvelles solutions pour tirer parti du protocole IO-Link \u00bb,\u00a0<strong>a d\u00e9clar\u00e9 Leopold Beer, vice-pr\u00e9sident de la division Connectivity Sensor de Renesas<\/strong>. \u00ab Ces deux nouveaux produits offrent des performances et des fonctionnalit\u00e9s de pointe pour les applications IO-Link, et nous pr\u00e9voyons d&rsquo;autres offres pour ce march\u00e9 important. \u00bb<\/p>\n<p><strong>Combinaisons Gagnantes<\/strong><\/p>\n<p>Renesas a combin\u00e9 le CCE4511 et le ZSSC3286 avec d&rsquo;autres offres de la large gamme de solutions de traitement embarqu\u00e9, analogiques, d&rsquo;alimentation et de connectivit\u00e9 de Renesas pour cr\u00e9er la combinaison gagnante\u00a0<a href=\"https:\/\/www.renesas.com\/applications\/industrial\/industrial-automation\/io-link-sensor?utm_campaign=f-up-csd_iolink_zssc3286-epsg-snsd-senst-null&amp;utm_source=null&amp;utm_medium=pr&amp;utm_content=wc\">IO-Link Sensor<\/a>. Les combinaisons gagnantes sont des architectures de syst\u00e8me techniquement valid\u00e9es \u00e0 partir de composants mutuellement compatibles qui fonctionnent ensemble de mani\u00e8re transparente pour apporter une conception optimis\u00e9e \u00e0 faible risque pour un temps de mise sur le march\u00e9 plus rapide. Renesas propose plus de 400 combinaisons gagnantes avec une large gamme de produits du portefeuille Renesas pour permettre aux clients d&rsquo;acc\u00e9l\u00e9rer le processus de conception et de mettre leurs produits sur le march\u00e9 plus rapidement.<\/p>\n<p><a href=\"http:\/\/www.renesas.com\/\">Renesas Electronics Corporation<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour r\u00e9pondre \u00e0 la forte croissance du march\u00e9 de l\u2019IO-Link, Renesas Electronics Corporation a lanc\u00e9 le circuit int\u00e9gr\u00e9 ma\u00eetre IO-Link \u00e0 quatre canaux CCE4511 et le circuit int\u00e9gr\u00e9 conditionneur de signaux de capteurs r\u00e9sistifs \u00e0 deux canaux ZSSC3286. IO-Link est un protocole de communication num\u00e9rique tr\u00e8s largement utilis\u00e9 dans les applications d&rsquo;automatisation industrielle. En tant [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":465749,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[7961,8191],"domains":[47],"ppma_author":[6113],"class_list":["post-465737","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","tag-circuits-integre","tag-io-link-fr","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Circuits Int\u00e9gr\u00e9s pour le March\u00e9 IO-Link en Pleine Croissance ...<\/title>\n<meta name=\"description\" content=\"Pour r\u00e9pondre \u00e0 la forte croissance du march\u00e9 de l\u2019IO-Link, Renesas Electronics Corporation a lanc\u00e9 le circuit int\u00e9gr\u00e9 ma\u00eetre IO-Link \u00e0 quatre...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/465737\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Circuits Int\u00e9gr\u00e9s pour le March\u00e9 IO-Link en Pleine Croissance\" \/>\n<meta property=\"og:description\" content=\"Pour r\u00e9pondre \u00e0 la forte croissance du march\u00e9 de l\u2019IO-Link, Renesas Electronics Corporation a lanc\u00e9 le circuit int\u00e9gr\u00e9 ma\u00eetre IO-Link \u00e0 quatre canaux CCE4511 et le circuit int\u00e9gr\u00e9 conditionneur de signaux de capteurs r\u00e9sistifs \u00e0 deux canaux ZSSC3286.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/465737\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-19T00:07:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/2024\/11\/ECI4572-Renesas-Presente-un-Circuit-Integre-Maitre-a-Quatre-Canaux-et-un-Conditionneur-de-Signaux-de-Capteurs-pour-le-Marche-IO-Link-en-Pleine-Croissance-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"608\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"NicolasFeste\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"NicolasFeste\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/circuits-integres-pour-le-marche-io-link-en-pleine-croissance\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/circuits-integres-pour-le-marche-io-link-en-pleine-croissance\/\"},\"author\":{\"name\":\"NicolasFeste\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/c7104a72b466a801f257e51481de0c43\"},\"headline\":\"Circuits Int\u00e9gr\u00e9s pour le March\u00e9 IO-Link en Pleine Croissance\",\"datePublished\":\"2024-11-19T00:07:02+00:00\",\"dateModified\":\"2024-11-19T00:07:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/circuits-integres-pour-le-marche-io-link-en-pleine-croissance\/\"},\"wordCount\":886,\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"keywords\":[\"Circuits int\u00e9gr\u00e9\",\"IO-Link\"],\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/circuits-integres-pour-le-marche-io-link-en-pleine-croissance\/\",\"url\":\"https:\/\/www.eenewseurope.com\/fr\/circuits-integres-pour-le-marche-io-link-en-pleine-croissance\/\",\"name\":\"Circuits Int\u00e9gr\u00e9s pour le March\u00e9 IO-Link en Pleine Croissance -\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\"},\"datePublished\":\"2024-11-19T00:07:02+00:00\",\"dateModified\":\"2024-11-19T00:07:02+00:00\",\"description\":\"Pour r\u00e9pondre \u00e0 la forte croissance du march\u00e9 de l\u2019IO-Link, Renesas Electronics Corporation a lanc\u00e9 le circuit int\u00e9gr\u00e9 ma\u00eetre IO-Link \u00e0 quatre canaux CCE4511 et le circuit int\u00e9gr\u00e9 conditionneur de signaux de capteurs r\u00e9sistifs \u00e0 deux canaux ZSSC3286.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/circuits-integres-pour-le-marche-io-link-en-pleine-croissance\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eenewseurope.com\/fr\/circuits-integres-pour-le-marche-io-link-en-pleine-croissance\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/circuits-integres-pour-le-marche-io-link-en-pleine-croissance\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Circuits Int\u00e9gr\u00e9s pour le March\u00e9 IO-Link en Pleine Croissance\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/c7104a72b466a801f257e51481de0c43\",\"name\":\"NicolasFeste\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/1ea421e7d03c1e96a9ea2bcf2705734a\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2e187f4d96902933ba445ed6c760e11c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2e187f4d96902933ba445ed6c760e11c?s=96&d=mm&r=g\",\"caption\":\"NicolasFeste\"}}]}<\/script>","yoast_head_json":{"title":"Circuits Int\u00e9gr\u00e9s pour le March\u00e9 IO-Link en Pleine Croissance ...","description":"Pour r\u00e9pondre \u00e0 la forte croissance du march\u00e9 de l\u2019IO-Link, Renesas Electronics Corporation a lanc\u00e9 le circuit int\u00e9gr\u00e9 ma\u00eetre IO-Link \u00e0 quatre...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/465737\/","og_locale":"fr_FR","og_type":"article","og_title":"Circuits Int\u00e9gr\u00e9s pour le March\u00e9 IO-Link en Pleine Croissance","og_description":"Pour r\u00e9pondre \u00e0 la forte croissance du march\u00e9 de l\u2019IO-Link, Renesas Electronics Corporation a lanc\u00e9 le circuit int\u00e9gr\u00e9 ma\u00eetre IO-Link \u00e0 quatre canaux CCE4511 et le circuit int\u00e9gr\u00e9 conditionneur de signaux de capteurs r\u00e9sistifs \u00e0 deux canaux ZSSC3286.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/465737\/","og_site_name":"EENewsEurope","article_published_time":"2024-11-19T00:07:02+00:00","og_image":[{"width":1080,"height":608,"url":"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/2024\/11\/ECI4572-Renesas-Presente-un-Circuit-Integre-Maitre-a-Quatre-Canaux-et-un-Conditionneur-de-Signaux-de-Capteurs-pour-le-Marche-IO-Link-en-Pleine-Croissance-scaled.jpg","type":"image\/jpeg"}],"author":"NicolasFeste","twitter_card":"summary_large_image","twitter_misc":{"Written by":"NicolasFeste","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eenewseurope.com\/fr\/circuits-integres-pour-le-marche-io-link-en-pleine-croissance\/#article","isPartOf":{"@id":"https:\/\/www.eenewseurope.com\/fr\/circuits-integres-pour-le-marche-io-link-en-pleine-croissance\/"},"author":{"name":"NicolasFeste","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/c7104a72b466a801f257e51481de0c43"},"headline":"Circuits Int\u00e9gr\u00e9s pour le March\u00e9 IO-Link en Pleine Croissance","datePublished":"2024-11-19T00:07:02+00:00","dateModified":"2024-11-19T00:07:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eenewseurope.com\/fr\/circuits-integres-pour-le-marche-io-link-en-pleine-croissance\/"},"wordCount":886,"publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"keywords":["Circuits int\u00e9gr\u00e9","IO-Link"],"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.eenewseurope.com\/fr\/circuits-integres-pour-le-marche-io-link-en-pleine-croissance\/","url":"https:\/\/www.eenewseurope.com\/fr\/circuits-integres-pour-le-marche-io-link-en-pleine-croissance\/","name":"Circuits Int\u00e9gr\u00e9s pour le March\u00e9 IO-Link en Pleine Croissance -","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/#website"},"datePublished":"2024-11-19T00:07:02+00:00","dateModified":"2024-11-19T00:07:02+00:00","description":"Pour r\u00e9pondre \u00e0 la forte croissance du march\u00e9 de l\u2019IO-Link, Renesas Electronics Corporation a lanc\u00e9 le circuit int\u00e9gr\u00e9 ma\u00eetre IO-Link \u00e0 quatre canaux CCE4511 et le circuit int\u00e9gr\u00e9 conditionneur de signaux de capteurs r\u00e9sistifs \u00e0 deux canaux ZSSC3286.","breadcrumb":{"@id":"https:\/\/www.eenewseurope.com\/fr\/circuits-integres-pour-le-marche-io-link-en-pleine-croissance\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eenewseurope.com\/fr\/circuits-integres-pour-le-marche-io-link-en-pleine-croissance\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eenewseurope.com\/fr\/circuits-integres-pour-le-marche-io-link-en-pleine-croissance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Circuits Int\u00e9gr\u00e9s pour le March\u00e9 IO-Link en Pleine Croissance"}]},{"@type":"WebSite","@id":"https:\/\/www.ecinews.fr\/fr\/#website","url":"https:\/\/www.ecinews.fr\/fr\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ecinews.fr\/fr\/#organization","name":"EENewsEurope","url":"https:\/\/www.ecinews.fr\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/c7104a72b466a801f257e51481de0c43","name":"NicolasFeste","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/1ea421e7d03c1e96a9ea2bcf2705734a","url":"https:\/\/secure.gravatar.com\/avatar\/2e187f4d96902933ba445ed6c760e11c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2e187f4d96902933ba445ed6c760e11c?s=96&d=mm&r=g","caption":"NicolasFeste"}}]}},"authors":[{"term_id":6113,"user_id":39,"is_guest":0,"slug":"nicolasfeste","display_name":"NicolasFeste","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/2e187f4d96902933ba445ed6c760e11c?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/465737"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=465737"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/465737\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/465749"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=465737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=465737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=465737"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=465737"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=465737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}