{"id":46358,"date":"2020-09-02T16:31:44","date_gmt":"2020-09-02T16:31:44","guid":{"rendered":"https:\/\/\/terminal-medical-a-hautes-performances\/"},"modified":"2020-09-02T16:31:44","modified_gmt":"2020-09-02T16:31:44","slug":"terminal-medical-a-hautes-performances","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/terminal-medical-a-hautes-performances\/","title":{"rendered":"Terminal m\u00e9dical \u00e0 hautes performances"},"content":{"rendered":"<p>Conforme aux normes de s\u00e9curit\u00e9 CEI 60601 pour les dispositifs m\u00e9dicaux, le terminal POC-624&nbsp;est convivial et offre un d\u00e9lai de commercialisation r\u00e9duit gr\u00e2ce \u00e0 sa conformit\u00e9 aux r\u00e9glementations de sant\u00e9 applicables.&nbsp;Gr\u00e2ce \u00e0 l\u2019int\u00e9gration de la solution Intel Wireless-AC 2&#215;2, le POC-624 transmet les donn\u00e9es de mani\u00e8re plus fiable et 12&nbsp;fois plus rapide que les solutions BGN 1&#215;1 traditionnelles.<\/p>\n<p><u>Am\u00e9lioration de la lutte contre les infections gr\u00e2ce \u00e0 l\u2019indice de protection IP54&nbsp;<\/u><br \/>\nLe POC-624 est con\u00e7u sans ventilateur et est scell\u00e9 dans un bo\u00eetier en plastique sp\u00e9cialement con\u00e7u qui permet une d\u00e9sinfection r\u00e9guli\u00e8re \u00e0 l\u2019aide d\u2019une vari\u00e9t\u00e9 de d\u00e9sinfectants et d\u2019agents assainissants afin d\u2019assurer un contr\u00f4le strict de l\u2019hygi\u00e8ne. En outre, l\u2019ensemble du syst\u00e8me est class\u00e9 IP54 pour la protection contre la p\u00e9n\u00e9tration d\u2019eau et de poussi\u00e8re (panneau avant IP65), ce qui augmente encore la s\u00e9curit\u00e9 des utilisateurs et la gestion de la contagion.&nbsp;<\/p>\n<p>Conforme \u00e0 la norme de s\u00e9curit\u00e9 m\u00e9dicale CEI 60601-1 pour les dispositifs \u00e9lectriques, le POC-624 est con\u00e7u pour un fonctionnement fiable dans un large \u00e9ventail d\u2019environnements de soins de sant\u00e9. En outre, le syst\u00e8me comporte des ports COM et LAN (1,5&nbsp;kV) \u00e9quip\u00e9s d\u2019une protection d\u2019isolation contre les interf\u00e9rences \u00e9lectromagn\u00e9tiques (EMI) ou les fuites, assurant une int\u00e9gration s\u00fbre avec les infrastructures et les \u00e9quipements existants.<\/p>\n<p><u>Une conception extensible pour une personnalisation flexible&nbsp;<\/u><\/p>\n<p>Pour prendre en charge diverses applications, le terminal POC POC-624 peut \u00eatre \u00e9quip\u00e9 de modules \u00e0 valeur ajout\u00e9e en option, tels qu\u2019un lecteur RFID ou un lecteur de carte \u00e0 puce pour l\u2019identification des patients et un module de cam\u00e9ra HD et de barre de son pour les applications de t\u00e9l\u00e9m\u00e9decine. La mise \u00e0 disposition d\u2019un emplacement d\u2019extension permet d\u2019int\u00e9grer des cartes suppl\u00e9mentaires et des E\/S personnalis\u00e9es en vue de l\u2019extension des fonctionnalit\u00e9s du syst\u00e8me. Enfin, gr\u00e2ce \u00e0 l\u2019inclusion d\u2019un syst\u00e8me d\u2019alimentation \u00e9lectrique optionnel rempla\u00e7able \u00e0 chaud, le POC-624 peut \u00eatre utilis\u00e9 pour fournir des soins de sant\u00e9 mobiles dans un large \u00e9ventail de contextes de traitement.&nbsp;<\/p>\n<p><a href=\"http:\/\/www.advantech.com\/\">www.advantech.com<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Advantech annonce son terminal m\u00e9dical point d\u2019intervention POC-624 de 24 pouces, con\u00e7u pour diverses applications dans le domaine des soins de sant\u00e9. Dot\u00e9 d\u2019un processeur Intel Core i5\/i7-8665UE de 8e g\u00e9n\u00e9ration, le POC-624 est un terminal \u00e0 hautes performances et ultra-mince qui permet d\u2019am\u00e9liorer l\u2019efficacit\u00e9 op\u00e9rationnelle des h\u00f4pitaux, des cliniques et des \u00e9tablissements de soins<\/p>\n","protected":false},"author":9,"featured_media":46359,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-46358","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Terminal m\u00e9dical \u00e0 hautes performances ...<\/title>\n<meta name=\"description\" content=\"Advantech annonce son terminal m\u00e9dical point d\u2019intervention POC-624 de 24 pouces, con\u00e7u pour diverses applications dans le domaine des soins de sant\u00e9....\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/46358\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Terminal m\u00e9dical \u00e0 hautes performances\" \/>\n<meta property=\"og:description\" content=\"Advantech annonce son terminal m\u00e9dical point d\u2019intervention POC-624 de 24 pouces, con\u00e7u pour diverses applications dans le domaine des soins de sant\u00e9. Dot\u00e9 d\u2019un processeur Intel Core i5\/i7-8665UE de 8e g\u00e9n\u00e9ration, le POC-624 est un terminal \u00e0 hautes performances et ultra-mince qui permet d\u2019am\u00e9liorer l\u2019efficacit\u00e9 op\u00e9rationnelle des h\u00f4pitaux, des cliniques et des \u00e9tablissements de soins\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/46358\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-02T16:31:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8789_advantech.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"638\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/terminal-medical-a-hautes-performances\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/terminal-medical-a-hautes-performances\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Terminal m\u00e9dical \u00e0 hautes performances\",\"datePublished\":\"2020-09-02T16:31:44+00:00\",\"dateModified\":\"2020-09-02T16:31:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/terminal-medical-a-hautes-performances\/\"},\"wordCount\":401,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/terminal-medical-a-hautes-performances\/\",\"url\":\"https:\/\/www.eenewseurope.com\/fr\/terminal-medical-a-hautes-performances\/\",\"name\":\"Terminal m\u00e9dical \u00e0 hautes performances -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2020-09-02T16:31:44+00:00\",\"dateModified\":\"2020-09-02T16:31:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/terminal-medical-a-hautes-performances\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eenewseurope.com\/fr\/terminal-medical-a-hautes-performances\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/terminal-medical-a-hautes-performances\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Terminal m\u00e9dical \u00e0 hautes performances\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Terminal m\u00e9dical \u00e0 hautes performances ...","description":"Advantech annonce son terminal m\u00e9dical point d\u2019intervention POC-624 de 24 pouces, con\u00e7u pour diverses applications dans le domaine des soins de sant\u00e9....","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/46358\/","og_locale":"fr_FR","og_type":"article","og_title":"Terminal m\u00e9dical \u00e0 hautes performances","og_description":"Advantech annonce son terminal m\u00e9dical point d\u2019intervention POC-624 de 24 pouces, con\u00e7u pour diverses applications dans le domaine des soins de sant\u00e9. Dot\u00e9 d\u2019un processeur Intel Core i5\/i7-8665UE de 8e g\u00e9n\u00e9ration, le POC-624 est un terminal \u00e0 hautes performances et ultra-mince qui permet d\u2019am\u00e9liorer l\u2019efficacit\u00e9 op\u00e9rationnelle des h\u00f4pitaux, des cliniques et des \u00e9tablissements de soins","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/46358\/","og_site_name":"EENewsEurope","article_published_time":"2020-09-02T16:31:44+00:00","og_image":[{"width":638,"height":600,"url":"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8789_advantech.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eenewseurope.com\/fr\/terminal-medical-a-hautes-performances\/#article","isPartOf":{"@id":"https:\/\/www.eenewseurope.com\/fr\/terminal-medical-a-hautes-performances\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Terminal m\u00e9dical \u00e0 hautes performances","datePublished":"2020-09-02T16:31:44+00:00","dateModified":"2020-09-02T16:31:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eenewseurope.com\/fr\/terminal-medical-a-hautes-performances\/"},"wordCount":401,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.eenewseurope.com\/fr\/terminal-medical-a-hautes-performances\/","url":"https:\/\/www.eenewseurope.com\/fr\/terminal-medical-a-hautes-performances\/","name":"Terminal m\u00e9dical \u00e0 hautes performances -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2020-09-02T16:31:44+00:00","dateModified":"2020-09-02T16:31:44+00:00","breadcrumb":{"@id":"https:\/\/www.eenewseurope.com\/fr\/terminal-medical-a-hautes-performances\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eenewseurope.com\/fr\/terminal-medical-a-hautes-performances\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eenewseurope.com\/fr\/terminal-medical-a-hautes-performances\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Terminal m\u00e9dical \u00e0 hautes performances"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/46358"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=46358"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/46358\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/46359"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=46358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=46358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=46358"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=46358"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=46358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}