{"id":457711,"date":"2024-08-07T00:15:49","date_gmt":"2024-08-06T22:15:49","guid":{"rendered":"https:\/\/www.eenewseurope.com\/?p=457711"},"modified":"2024-08-07T00:15:49","modified_gmt":"2024-08-06T22:15:49","slug":"module-de-controle-du-spectre-des-micro-ondes-pour-tout-systeme","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/module-de-controle-du-spectre-des-micro-ondes-pour-tout-systeme\/","title":{"rendered":"Module de contr\u00f4le du spectre des micro-ondes pour tout syst\u00e8me"},"content":{"rendered":"<h3><span style=\"font-size: 16px;\">Anritsu Company propose le module de contr\u00f4le du spectre des micro-ondes MS27200A qui permet d&rsquo;int\u00e9grer la technologie d&rsquo;analyse du spectre dans n&rsquo;importe quelle plate-forme ou syst\u00e8me.<\/span><\/h3>\n<p>Le MS27200A est un module autonome de contr\u00f4le du spectre des micro-ondes qui va de 9 kHz \u00e0 54 GHz avec un processus de traitement int\u00e9gr\u00e9 Le module dispose d&rsquo;une largeur de bande de 110 MHz pour l&rsquo;analyse du spectre en temps r\u00e9el (RTSA) avec un DANL de -164 dBm (avec pr\u00e9ampli), ce qui signifie que le module est capable de recevoir les signaux les plus faibles et les plus intermittents.<\/p>\n<p>Le MS27200A peut \u00eatre utilis\u00e9 dans des syst\u00e8mes militaires, a\u00e9rospatiaux, satellitaires et par des int\u00e9grateurs de syst\u00e8mes pour divers march\u00e9s. Le module de contr\u00f4le du spectre des micro-ondes est con\u00e7u pour \u00eatre int\u00e9gr\u00e9 dans un syst\u00e8me \u00e0 partir de la base. Le module permet \u00e0 l&rsquo;utilisateur d&rsquo;int\u00e9grer les meilleures performances d&rsquo;analyse de spectre dans son propre syst\u00e8me.<\/p>\n<p>Unit\u00e9 autonome con\u00e7ue pour faire partie d&rsquo;un syst\u00e8me plus vaste, le module MS27200A peut effectuer des mesures de type VSA, telles que des mesures 5G et LTE. C&rsquo;est le bon outil pour ajouter la connaissance du spectre \u00e0 toute plateforme cherchant \u00e0 cartographier les interf\u00e9rences ou la couverture. Gr\u00e2ce aux capacit\u00e9s RTSA, les utilisateurs peuvent surveiller l&rsquo;environnement RF sans manquer aucun signal intermittent. En outre, le module a la capacit\u00e9 de capturer et de diffuser les composantes de signaux IQ de signaux inconnus pour une analyse ult\u00e9rieure. Le MS27200A peut transmettre et capturer l&rsquo;IQ en 32 bits et \u00e0 une largeur de bande de 110 MHz. Cela signifie que le module peut capturer de mani\u00e8re tr\u00e8s d\u00e9taill\u00e9e une large bande de signaux int\u00e9ressantes en une seule fois, sans qu&rsquo;il soit n\u00e9cessaire de combiner ou d&rsquo;assembler les donn\u00e9es IQ.<\/p>\n<p>Dans les environnements dynamiques, un ensemble de capteurs fiables pour surveiller le spectre RF peut \u00eatre critique pour les op\u00e9rations, et le MS27200A combine l&rsquo;exp\u00e9rience d&rsquo;Anritsu en un seul module. Le module est dot\u00e9 de nombreuses fonctions accessibles par des commandes SCPI.<\/p>\n<p><strong>Caract\u00e9ristiques et principaux avantages :<\/strong><\/p>\n<ul>\n<li><strong>Polyvalent et facile \u00e0 int\u00e9grer<\/strong>: Le module est autonome et il n&rsquo;est pas n\u00e9cessaire d&rsquo;int\u00e9grer un PC suppl\u00e9mentaire dans le syst\u00e8me. Il utilise des commandes SCPI standard pour contr\u00f4ler l&rsquo;unit\u00e9, de sorte qu&rsquo;il n&rsquo;est pas n\u00e9cessaire d&rsquo;utiliser un logiciel suppl\u00e9mentaire. Le module dispose \u00e9galement d&rsquo;une m\u00e9moire embarqu\u00e9e, ce qui facilite l&rsquo;int\u00e9gration et permet aux utilisateurs de commencer rapidement \u00e0 collecter des donn\u00e9es.<\/li>\n<li><strong>Des performances \u00e9lev\u00e9es d\u00e8s la sortie de la bo\u00eete<\/strong>: La gamme de fr\u00e9quences s&rsquo;\u00e9tend de 9 kHz \u00e0 54 GHz avec une largeur de bande d&rsquo;analyse allant jusqu&rsquo;\u00e0 110 MHz. En outre, l&rsquo;appareil dispose de capacit\u00e9s RTSA ainsi que la possibilit\u00e9 de stocker et de diffuser des donn\u00e9es IQ \u00e0 32 bits et 110 MHz de bande passante. En outre, il int\u00e8gre des mesures VSA telles que WCDMA, LTE, 5G, AM\/FM, ainsi que d&rsquo;autres mesures de qualit\u00e9.<\/li>\n<li><strong>Fiabilit\u00e9 \u00e9prouv\u00e9e<\/strong>: Anritsu fabrique des analyseurs de spectre depuis des d\u00e9cennies et met cette exp\u00e9rience au service des int\u00e9grateurs avec le MS27200A. Avec le MS27200A, les utilisateurs ne seront pas \u00e0 la poursuite d&rsquo;un fant\u00f4me tel que les spurs li\u00e9s \u00e0 l&rsquo;entr\u00e9e et n&rsquo;auront pas besoin de passer beaucoup de temps \u00e0 se demander si le module fonctionne correctement.<\/li>\n<\/ul>\n<p>Le module de contr\u00f4le du spectre des micro-ondes MS27200A est unique car sa conception s&rsquo;int\u00e8gre dans d&rsquo;autres syst\u00e8mes et plates-formes. Il offre un \u00e9quilibre parfait entre performance, facilit\u00e9 d&rsquo;utilisation et fiabilit\u00e9.<\/p>\n<p><a href=\"http:\/\/www.anritsu.com\">www.anritsu.com<\/a><\/p>\n<p><a href=\"https:\/\/news.google.com\/publications\/CAAqBwgKMJbcwQswuPfYAw?hl=fr&amp;gl=BE&amp;ceid=BE:fr\" target=\"news.google.com\" rel=\"noopener\">Suivre ECInews sur Google news<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Facile \u00e0 int\u00e9grer, le module de contr\u00f4le du spectre des micro-ondes couvre une plage de 9 kHz \u00e0 54 GHz avec des capacit\u00e9s RTSA et des mesures VSA.<\/p>\n","protected":false},"author":11,"featured_media":457631,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[2122,7214,7213,7206,7205,2939,4322,7209,1315,7207,7210,7212],"domains":[47],"ppma_author":[3682,1143],"class_list":["post-457711","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","tag-5g-fr-2","tag-am-fm-fr","tag-amrc","tag-donnees-du-qi","tag-en-temps-reel","tag-lte-fr","tag-micro-ondes","tag-moniteur-de-spectre","tag-rf-fr","tag-scpi-fr","tag-signaux-intermittents","tag-vsa-fr","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Module de contr\u00f4le du spectre des micro-ondes pour tout syst\u00e8me ...<\/title>\n<meta name=\"description\" content=\"Le module de contr\u00f4le du spectre des micro-ondes couvre une plage de 9 kHz \u00e0 54 GHz avec des capacit\u00e9s RTSA et des mesures VSA.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/457711\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Module de contr\u00f4le du spectre des micro-ondes pour tout syst\u00e8me\" \/>\n<meta property=\"og:description\" content=\"Le module de contr\u00f4le du spectre des micro-ondes couvre une plage de 9 kHz \u00e0 54 GHz avec des capacit\u00e9s RTSA et des mesures VSA.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/457711\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-06T22:15:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2024\/08\/2024-08-06-Anritsu-MS27200A-Microwave-Spectrum-Monitor-Module-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"771\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jean-Pierre Joosting, Daniel Cardon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel Cardon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/module-de-controle-du-spectre-des-micro-ondes-pour-tout-systeme\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/module-de-controle-du-spectre-des-micro-ondes-pour-tout-systeme\/\"},\"author\":{\"name\":\"Daniel Cardon\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/93c44cde463762f40a8236eaa44c1c17\"},\"headline\":\"Module de contr\u00f4le du spectre des micro-ondes pour tout syst\u00e8me\",\"datePublished\":\"2024-08-06T22:15:49+00:00\",\"dateModified\":\"2024-08-06T22:15:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/module-de-controle-du-spectre-des-micro-ondes-pour-tout-systeme\/\"},\"wordCount\":671,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"keywords\":[\"5G\",\"AM\/FM\",\"AMRC\",\"Donn\u00e9es du QI\",\"En temps r\u00e9el\",\"LTE\",\"Micro-ondes\",\"Moniteur de spectre\",\"RF\",\"SCPI\",\"Signaux intermittents\",\"VSA\"],\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/module-de-controle-du-spectre-des-micro-ondes-pour-tout-systeme\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/module-de-controle-du-spectre-des-micro-ondes-pour-tout-systeme\/\",\"name\":\"Module de contr\u00f4le du spectre des micro-ondes pour tout syst\u00e8me -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2024-08-06T22:15:49+00:00\",\"dateModified\":\"2024-08-06T22:15:49+00:00\",\"description\":\"Le module de contr\u00f4le du spectre des micro-ondes couvre une plage de 9 kHz \u00e0 54 GHz avec des capacit\u00e9s RTSA et des mesures VSA.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/module-de-controle-du-spectre-des-micro-ondes-pour-tout-systeme\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/module-de-controle-du-spectre-des-micro-ondes-pour-tout-systeme\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/module-de-controle-du-spectre-des-micro-ondes-pour-tout-systeme\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Module de contr\u00f4le du spectre des micro-ondes pour tout syst\u00e8me\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/93c44cde463762f40a8236eaa44c1c17\",\"name\":\"Daniel Cardon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/2b243f6bcc1cff7d86aadfb2cd0bd870\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/de9edc136dfc061ad4778e04635baefa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/de9edc136dfc061ad4778e04635baefa?s=96&d=mm&r=g\",\"caption\":\"Daniel Cardon\"}}]}<\/script>","yoast_head_json":{"title":"Module de contr\u00f4le du spectre des micro-ondes pour tout syst\u00e8me ...","description":"Le module de contr\u00f4le du spectre des micro-ondes couvre une plage de 9 kHz \u00e0 54 GHz avec des capacit\u00e9s RTSA et des mesures VSA.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/457711\/","og_locale":"fr_FR","og_type":"article","og_title":"Module de contr\u00f4le du spectre des micro-ondes pour tout syst\u00e8me","og_description":"Le module de contr\u00f4le du spectre des micro-ondes couvre une plage de 9 kHz \u00e0 54 GHz avec des capacit\u00e9s RTSA et des mesures VSA.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/457711\/","og_site_name":"EENewsEurope","article_published_time":"2024-08-06T22:15:49+00:00","og_image":[{"width":1080,"height":771,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2024\/08\/2024-08-06-Anritsu-MS27200A-Microwave-Spectrum-Monitor-Module-scaled.jpg","type":"image\/jpeg"}],"author":"Jean-Pierre Joosting, Daniel Cardon","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Daniel Cardon","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/module-de-controle-du-spectre-des-micro-ondes-pour-tout-systeme\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/module-de-controle-du-spectre-des-micro-ondes-pour-tout-systeme\/"},"author":{"name":"Daniel Cardon","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/93c44cde463762f40a8236eaa44c1c17"},"headline":"Module de contr\u00f4le du spectre des micro-ondes pour tout syst\u00e8me","datePublished":"2024-08-06T22:15:49+00:00","dateModified":"2024-08-06T22:15:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/module-de-controle-du-spectre-des-micro-ondes-pour-tout-systeme\/"},"wordCount":671,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"keywords":["5G","AM\/FM","AMRC","Donn\u00e9es du QI","En temps r\u00e9el","LTE","Micro-ondes","Moniteur de spectre","RF","SCPI","Signaux intermittents","VSA"],"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/module-de-controle-du-spectre-des-micro-ondes-pour-tout-systeme\/","url":"https:\/\/www.ecinews.fr\/fr\/module-de-controle-du-spectre-des-micro-ondes-pour-tout-systeme\/","name":"Module de contr\u00f4le du spectre des micro-ondes pour tout syst\u00e8me -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2024-08-06T22:15:49+00:00","dateModified":"2024-08-06T22:15:49+00:00","description":"Le module de contr\u00f4le du spectre des micro-ondes couvre une plage de 9 kHz \u00e0 54 GHz avec des capacit\u00e9s RTSA et des mesures VSA.","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/module-de-controle-du-spectre-des-micro-ondes-pour-tout-systeme\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/module-de-controle-du-spectre-des-micro-ondes-pour-tout-systeme\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/module-de-controle-du-spectre-des-micro-ondes-pour-tout-systeme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Module de contr\u00f4le du spectre des micro-ondes pour tout syst\u00e8me"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/93c44cde463762f40a8236eaa44c1c17","name":"Daniel Cardon","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/2b243f6bcc1cff7d86aadfb2cd0bd870","url":"https:\/\/secure.gravatar.com\/avatar\/de9edc136dfc061ad4778e04635baefa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/de9edc136dfc061ad4778e04635baefa?s=96&d=mm&r=g","caption":"Daniel Cardon"}}]}},"authors":[{"term_id":3682,"user_id":0,"is_guest":1,"slug":"jean-pierre-joosting","display_name":"Jean-Pierre Joosting","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""},{"term_id":1143,"user_id":11,"is_guest":0,"slug":"danielcardon","display_name":"Daniel Cardon","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/de9edc136dfc061ad4778e04635baefa?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/457711"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=457711"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/457711\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/457631"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=457711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=457711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=457711"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=457711"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=457711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}