{"id":4565,"date":"2021-09-10T06:59:42","date_gmt":"2021-09-10T06:59:42","guid":{"rendered":"https:\/\/\/efirack-et-rittal-fusionnent-leurs-forces\/"},"modified":"2021-09-10T06:59:42","modified_gmt":"2021-09-10T06:59:42","slug":"efirack-et-rittal-fusionnent-leurs-forces","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/efirack-et-rittal-fusionnent-leurs-forces\/","title":{"rendered":"Efirack et Rittal fusionnent leurs forces"},"content":{"rendered":"<p>D\u00e9sormais \u00e9tablie, la compl\u00e9mentarit\u00e9 des deux gammes permet d\u2019adresser les besoins applicatifs du Cloud et du Edge Computing avec des produits et services innovants. Aujourd\u2019hui, l\u2019\u00e9quipe commerciale Efirack et Rittal conseillent les Clients en proposant des solutions packag\u00e9es, personnalis\u00e9es selon les besoins exprim\u00e9s.<\/p>\n<p>Efirack, est un fabricant fran\u00e7ais de coffrets, baies r\u00e9seau, baies serveur et couloirs thermiques \u00e9quip\u00e9s. La soci\u00e9t\u00e9 est n\u00e9e en 1991 dans l\u2019Yonne. Son si\u00e8ge social et son usine de fabrication sont situ\u00e9s \u00e0 Migennes. Elle d\u00e9veloppe un savoir-faire unique d\u2019assemblage de solutions 19\u2033 et 21\u2033 standards et\/ou sur mesure.<br \/>\nReconnue sur le march\u00e9 fran\u00e7ais des coffrets, baies r\u00e9seau, baies serveur et couloirs thermiques \u00e9quip\u00e9s, Efirack propose des solutions compl\u00e8tes avec installation sur site. Ses solutions sont adaptables dans tous les environnements et sont personnalisables en cod\u00e9veloppement gr\u00e2ce au savoir-faire de son Bureau d\u2019\u00c9tudes int\u00e9gr\u00e9.<br \/>\n<a href=\"http:\/\/www.efirack.com\/\">www.efirack.com<\/a><\/p>\n<p>Rittal, n\u00e9e en 1961 et soci\u00e9t\u00e9 leader du groupe FLG, est \u00e0 l\u2019origine des premiers coffrets fabriqu\u00e9s en s\u00e9rie pour les syst\u00e8mes de commande \u00e9lectrique. Aujourd\u2019hui, Rittal fournit toujours des bo\u00eetiers et des armoires \u00e9lectriques et a \u00e9tendu ses activit\u00e9s pour proposer des technologies de climatisation, des \u00e9quipements de distribution \u00e9lectrique, des infrastructures informatiques et des machines d\u2019automatisation.<br \/>\nLa soci\u00e9t\u00e9 est pr\u00e9sente dans le monde entier \u00e0 travers plus de 64 filiales. Elle poss\u00e8de 11 sites de production dans le monde et d\u00e9pose continuellement des brevets d\u2019innovation produit.<br \/>\nRittal produit en s\u00e9rie des solutions adapt\u00e9es \u00e0 des environnements exigeants.<br \/>\n<a href=\"http:\/\/www.rittal.com\/fr\">www.rittal.com\/fr<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Efirack, cr\u00e9ateur de solution de la baie au data center et Rittal, inventeur des coffrets \u00e9lectriques et leadeur mondial sur le march\u00e9 des infrastructures IT fusionnent leurs forces. Les deux soci\u00e9t\u00e9s font partie du m\u00eame groupe depuis 2001. Elles avaient annonc\u00e9 une premi\u00e8re phase de rapprochement en 2015. Aujourd\u2019hui, une seconde phase est amorc\u00e9e : Efirack porte l\u2019offre IT de Rittal ainsi que ses produits et solutions aupr\u00e8s de tous les Bureaux d\u2019Etudes, exploitants de salles, h\u00e9bergeurs, installateurs et distributeurs.<\/p>\n","protected":false},"author":9,"featured_media":4566,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-4565","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Efirack et Rittal fusionnent leurs forces ...<\/title>\n<meta name=\"description\" content=\"Efirack, cr\u00e9ateur de solution de la baie au data center et Rittal, inventeur des coffrets \u00e9lectriques et leadeur mondial sur le march\u00e9 des infrastructures...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/4565\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Efirack et Rittal fusionnent leurs forces\" \/>\n<meta property=\"og:description\" content=\"Efirack, cr\u00e9ateur de solution de la baie au data center et Rittal, inventeur des coffrets \u00e9lectriques et leadeur mondial sur le march\u00e9 des infrastructures IT fusionnent leurs forces. Les deux soci\u00e9t\u00e9s font partie du m\u00eame groupe depuis 2001. Elles avaient annonc\u00e9 une premi\u00e8re phase de rapprochement en 2015. Aujourd\u2019hui, une seconde phase est amorc\u00e9e : Efirack porte l\u2019offre IT de Rittal ainsi que ses produits et solutions aupr\u00e8s de tous les Bureaux d\u2019Etudes, exploitants de salles, h\u00e9bergeurs, installateurs et distributeurs.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/4565\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-10T06:59:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9731_efirack_rittal-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2015\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/efirack-et-rittal-fusionnent-leurs-forces\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/efirack-et-rittal-fusionnent-leurs-forces\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Efirack et Rittal fusionnent leurs forces\",\"datePublished\":\"2021-09-10T06:59:42+00:00\",\"dateModified\":\"2021-09-10T06:59:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/efirack-et-rittal-fusionnent-leurs-forces\/\"},\"wordCount\":284,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/efirack-et-rittal-fusionnent-leurs-forces\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/efirack-et-rittal-fusionnent-leurs-forces\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/efirack-et-rittal-fusionnent-leurs-forces\/\",\"name\":\"Efirack et Rittal fusionnent leurs forces -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2021-09-10T06:59:42+00:00\",\"dateModified\":\"2021-09-10T06:59:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/efirack-et-rittal-fusionnent-leurs-forces\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/efirack-et-rittal-fusionnent-leurs-forces\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/efirack-et-rittal-fusionnent-leurs-forces\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Efirack et Rittal fusionnent leurs forces\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Efirack et Rittal fusionnent leurs forces ...","description":"Efirack, cr\u00e9ateur de solution de la baie au data center et Rittal, inventeur des coffrets \u00e9lectriques et leadeur mondial sur le march\u00e9 des infrastructures...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/4565\/","og_locale":"fr_FR","og_type":"article","og_title":"Efirack et Rittal fusionnent leurs forces","og_description":"Efirack, cr\u00e9ateur de solution de la baie au data center et Rittal, inventeur des coffrets \u00e9lectriques et leadeur mondial sur le march\u00e9 des infrastructures IT fusionnent leurs forces. Les deux soci\u00e9t\u00e9s font partie du m\u00eame groupe depuis 2001. Elles avaient annonc\u00e9 une premi\u00e8re phase de rapprochement en 2015. Aujourd\u2019hui, une seconde phase est amorc\u00e9e : Efirack porte l\u2019offre IT de Rittal ainsi que ses produits et solutions aupr\u00e8s de tous les Bureaux d\u2019Etudes, exploitants de salles, h\u00e9bergeurs, installateurs et distributeurs.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/4565\/","og_site_name":"EENewsEurope","article_published_time":"2021-09-10T06:59:42+00:00","og_image":[{"width":2560,"height":2015,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9731_efirack_rittal-scaled.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/efirack-et-rittal-fusionnent-leurs-forces\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/efirack-et-rittal-fusionnent-leurs-forces\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Efirack et Rittal fusionnent leurs forces","datePublished":"2021-09-10T06:59:42+00:00","dateModified":"2021-09-10T06:59:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/efirack-et-rittal-fusionnent-leurs-forces\/"},"wordCount":284,"commentCount":0,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ecinews.fr\/fr\/efirack-et-rittal-fusionnent-leurs-forces\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/efirack-et-rittal-fusionnent-leurs-forces\/","url":"https:\/\/www.ecinews.fr\/fr\/efirack-et-rittal-fusionnent-leurs-forces\/","name":"Efirack et Rittal fusionnent leurs forces -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2021-09-10T06:59:42+00:00","dateModified":"2021-09-10T06:59:42+00:00","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/efirack-et-rittal-fusionnent-leurs-forces\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/efirack-et-rittal-fusionnent-leurs-forces\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/efirack-et-rittal-fusionnent-leurs-forces\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Efirack et Rittal fusionnent leurs forces"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/4565"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=4565"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/4565\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/4566"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=4565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=4565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=4565"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=4565"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=4565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}