{"id":448494,"date":"2024-04-12T09:52:08","date_gmt":"2024-04-12T07:52:08","guid":{"rendered":"https:\/\/www.eenewseurope.com\/?p=448494"},"modified":"2024-04-12T09:53:09","modified_gmt":"2024-04-12T07:53:09","slug":"les-fournisseurs-alertent-sur-une-penurie-de-composants-passifs","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/les-fournisseurs-alertent-sur-une-penurie-de-composants-passifs\/","title":{"rendered":"Les fournisseurs alertent sur une p\u00e9nurie de composants passifs"},"content":{"rendered":"<h3>Le distributeur Farnell a consid\u00e9rablement \u00e9largi sa gamme de composants passifs alors que les fournisseurs mettent en garde contre les difficult\u00e9s rencontr\u00e9es en Europe au cours du premier semestre de l&rsquo;ann\u00e9e.<\/h3>\n<p>Farnell a ajout\u00e9 des gammes de composants passifs de Yageo, Kemet, Murata, Wurth Electronik et Panasonic pour r\u00e9pondre \u00e0 la demande, les fournisseurs ayant mis en garde contre des p\u00e9nuries potentielles.<\/p>\n<p>Le march\u00e9 des composants passifs devrait continuer \u00e0 se d\u00e9velopper dans les ann\u00e9es \u00e0 venir, gr\u00e2ce \u00e0 la croissance de l&rsquo;\u00e9lectronique grand public, de l&rsquo;\u00e9lectronique automobile et de l&rsquo;automatisation industrielle.<\/p>\n<p>\u00ab\u00a0\u00c0 l&rsquo;heure actuelle, les cha\u00eenes d&rsquo;approvisionnement mondiales sont confront\u00e9es \u00e0 plusieurs probl\u00e8mes persistants : certains sont inh\u00e9rents, comme l&rsquo;augmentation des capacit\u00e9s et la complexit\u00e9 des composants modernes, et d&rsquo;autres sont externes, comme les perturbations de la cha\u00eene d&rsquo;approvisionnement et de la fabrication caus\u00e9es par les ph\u00e9nom\u00e8nes m\u00e9t\u00e9orologiques, les restrictions commerciales et l&rsquo;instabilit\u00e9 mondiale\u00a0\u00bb, a d\u00e9clar\u00e9 M. Murata.<\/p>\n<ul>\n<li><a href=\"https:\/\/www.eenewseurope.com\/en\/learning-to-live-with-supply-chain-stress\/\">Apprendre \u00e0 vivre avec le stress de la cha\u00eene d&rsquo;approvisionnement<\/a><\/li>\n<li><a href=\"https:\/\/www.eenewseurope.com\/en\/european-component-distribution-warns-of-general-slowdown\/\">La distribution europ\u00e9enne de composants met en garde contre une <\/a><\/li>\n<li><a href=\"https:\/\/www.eenewseurope.com\/en\/tackling-the-test-bottleneck-in-the-supply-chain\/\">S&rsquo;attaquer au goulot d&rsquo;\u00e9tranglement des tests dans la cha\u00eene d&rsquo;approvisionnement <\/a><\/li>\n<\/ul>\n<p>\u00ab\u00a0Les clients et les fournisseurs de services ont encore des stocks importants dans leurs entrep\u00f4ts. N\u00e9anmoins, W\u00fcrth Elektronik a investi dans sa cha\u00eene d&rsquo;approvisionnement et son stock pour permettre sa croissance\u00a0\u00bb, a d\u00e9clar\u00e9 Simon Leuz, Team Lead Distribution EMEA, Wurth Elektronik. \u00ab\u00a0Une cha\u00eene d&rsquo;approvisionnement solide, une bonne disponibilit\u00e9 et d&rsquo;excellents partenariats seront essentiels pour servir les clients lorsque le march\u00e9 reprendra. Nous consid\u00e9rons cela comme un d\u00e9fi mais aussi comme une opportunit\u00e9. Nous nous attendons \u00e0 ce que le second semestre 2024 soit meilleur.\u00a0\u00bb<\/p>\n<p>\u00ab\u00a0Farnell est bien conscient de l&rsquo;\u00e9volution constante des demandes du march\u00e9 et de la n\u00e9cessit\u00e9 de rester \u00e0 l&rsquo;avant-garde\u00a0\u00bb, a d\u00e9clar\u00e9 Juergen Ruben, directeur des ventes pour les pays germanophones et l&rsquo;Europe de l&rsquo;Est chez Farnell. \u00ab\u00a0Avec le nombre croissant d&rsquo;applications n\u00e9cessitant des composants passifs, telles que l&rsquo;IIOT, la robotique, les VE et la recharge, les wearables, et au-del\u00e0, notre gamme de produits \u00e9largie et notre solide gamme de produits nous placent en bonne position pour r\u00e9pondre \u00e0 la demande future de composants plus petits et plus puissants. Nous sommes conscients que le march\u00e9 peut \u00e9voluer rapidement et nous sommes pr\u00eats \u00e0 relever le d\u00e9fi gr\u00e2ce \u00e0 notre expertise et \u00e0 notre engagement en faveur d&rsquo;un excellent service.\u00a0\u00bb<\/p>\n<p>\u00ab\u00a0En ce qui concerne la disponibilit\u00e9 des stocks et les prix, l&rsquo;entreprise pr\u00e9voit de produire g\u00e9n\u00e9ralement en fonction des ventes ou de constituer des stocks. Les prix sont en baisse, en particulier pour les composants pour produits grand-public, pour les smartphones et les PC\u00a0\u00bb, a d\u00e9clar\u00e9 M. Murata. \u00ab\u00a0Murata s&rsquo;attend donc \u00e0 ce que les prix continuent de baisser dans ce secteur \u00e9galement, en particulier sur le march\u00e9 des v\u00e9hicules \u00e9lectriques. Cependant, la vitesse des r\u00e9ductions de prix dans les VE devrait s&rsquo;att\u00e9nuer d&rsquo;ici la fin de l&rsquo;ann\u00e9e 2024.\u00a0\u00bb<\/p>\n<p><a href=\"http:\/\/www.farnell.com\/\">www.farnell.com\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le distributeur Farnell a consid\u00e9rablement \u00e9largi sa gamme de composants passifs alors que les fournisseurs mettent en garde contre les difficult\u00e9s rencontr\u00e9es en Europe au cours du premier semestre de l&rsquo;ann\u00e9e. Farnell a ajout\u00e9 des gammes de composants passifs de Yageo, Kemet, Murata, Wurth Electronik et Panasonic pour r\u00e9pondre \u00e0 la demande, les fournisseurs ayant [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":447941,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3669],"tags":[6154,1713],"domains":[47],"ppma_author":[1153,3640],"class_list":["post-448494","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles","tag-composants-passifs-fr","tag-distributeurs","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Les fournisseurs alertent sur une p\u00e9nurie de composants passifs ...<\/title>\n<meta name=\"description\" content=\"Farnell a ajout\u00e9 des composants passifs de Yageo, Kemet, Murata, Wurth Electronik et Panasonic, en pr\u00e9vision de p\u00e9nuries potentielles.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/448494\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les fournisseurs alertent sur une p\u00e9nurie de composants passifs\" \/>\n<meta property=\"og:description\" content=\"Farnell a ajout\u00e9 des composants passifs de Yageo, Kemet, Murata, Wurth Electronik et Panasonic, en pr\u00e9vision de p\u00e9nuries potentielles.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/448494\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-12T07:52:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-12T07:53:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2024\/04\/Farnell-high-quality-passives-image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"A Delapalisse, Nick Flaherty\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"A Delapalisse\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/les-fournisseurs-alertent-sur-une-penurie-de-composants-passifs\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/les-fournisseurs-alertent-sur-une-penurie-de-composants-passifs\/\"},\"author\":{\"name\":\"A Delapalisse\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/0aa2cfb0bd8949724a68cbac8d8321b4\"},\"headline\":\"Les fournisseurs alertent sur une p\u00e9nurie de composants passifs\",\"datePublished\":\"2024-04-12T07:52:08+00:00\",\"dateModified\":\"2024-04-12T07:53:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/les-fournisseurs-alertent-sur-une-penurie-de-composants-passifs\/\"},\"wordCount\":542,\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"keywords\":[\"Composants passifs\",\"Distributeurs\"],\"articleSection\":[\"Nouvelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/les-fournisseurs-alertent-sur-une-penurie-de-composants-passifs\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/les-fournisseurs-alertent-sur-une-penurie-de-composants-passifs\/\",\"name\":\"Les fournisseurs alertent sur une p\u00e9nurie de composants passifs -\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\"},\"datePublished\":\"2024-04-12T07:52:08+00:00\",\"dateModified\":\"2024-04-12T07:53:09+00:00\",\"description\":\"Farnell a ajout\u00e9 des composants passifs de Yageo, Kemet, Murata, Wurth Electronik et Panasonic, en pr\u00e9vision de p\u00e9nuries potentielles.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/les-fournisseurs-alertent-sur-une-penurie-de-composants-passifs\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/les-fournisseurs-alertent-sur-une-penurie-de-composants-passifs\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/les-fournisseurs-alertent-sur-une-penurie-de-composants-passifs\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les fournisseurs alertent sur une p\u00e9nurie de composants passifs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/0aa2cfb0bd8949724a68cbac8d8321b4\",\"name\":\"A Delapalisse\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/211ac42237c2e9683c0964086c393cb4\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ad45a8c5da24bc9c7c4940dd1c48a695?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ad45a8c5da24bc9c7c4940dd1c48a695?s=96&d=mm&r=g\",\"caption\":\"A Delapalisse\"},\"sameAs\":[\"http:\/\/ECI\"]}]}<\/script>","yoast_head_json":{"title":"Les fournisseurs alertent sur une p\u00e9nurie de composants passifs ...","description":"Farnell a ajout\u00e9 des composants passifs de Yageo, Kemet, Murata, Wurth Electronik et Panasonic, en pr\u00e9vision de p\u00e9nuries potentielles.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/448494\/","og_locale":"fr_FR","og_type":"article","og_title":"Les fournisseurs alertent sur une p\u00e9nurie de composants passifs","og_description":"Farnell a ajout\u00e9 des composants passifs de Yageo, Kemet, Murata, Wurth Electronik et Panasonic, en pr\u00e9vision de p\u00e9nuries potentielles.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/448494\/","og_site_name":"EENewsEurope","article_published_time":"2024-04-12T07:52:08+00:00","article_modified_time":"2024-04-12T07:53:09+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2024\/04\/Farnell-high-quality-passives-image.jpg","type":"image\/jpeg"}],"author":"A Delapalisse, Nick Flaherty","twitter_card":"summary_large_image","twitter_misc":{"Written by":"A Delapalisse","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/les-fournisseurs-alertent-sur-une-penurie-de-composants-passifs\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/les-fournisseurs-alertent-sur-une-penurie-de-composants-passifs\/"},"author":{"name":"A Delapalisse","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/0aa2cfb0bd8949724a68cbac8d8321b4"},"headline":"Les fournisseurs alertent sur une p\u00e9nurie de composants passifs","datePublished":"2024-04-12T07:52:08+00:00","dateModified":"2024-04-12T07:53:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/les-fournisseurs-alertent-sur-une-penurie-de-composants-passifs\/"},"wordCount":542,"publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"keywords":["Composants passifs","Distributeurs"],"articleSection":["Nouvelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/les-fournisseurs-alertent-sur-une-penurie-de-composants-passifs\/","url":"https:\/\/www.ecinews.fr\/fr\/les-fournisseurs-alertent-sur-une-penurie-de-composants-passifs\/","name":"Les fournisseurs alertent sur une p\u00e9nurie de composants passifs -","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/#website"},"datePublished":"2024-04-12T07:52:08+00:00","dateModified":"2024-04-12T07:53:09+00:00","description":"Farnell a ajout\u00e9 des composants passifs de Yageo, Kemet, Murata, Wurth Electronik et Panasonic, en pr\u00e9vision de p\u00e9nuries potentielles.","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/les-fournisseurs-alertent-sur-une-penurie-de-composants-passifs\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/les-fournisseurs-alertent-sur-une-penurie-de-composants-passifs\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/les-fournisseurs-alertent-sur-une-penurie-de-composants-passifs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Les fournisseurs alertent sur une p\u00e9nurie de composants passifs"}]},{"@type":"WebSite","@id":"https:\/\/www.ecinews.fr\/fr\/#website","url":"https:\/\/www.ecinews.fr\/fr\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ecinews.fr\/fr\/#organization","name":"EENewsEurope","url":"https:\/\/www.ecinews.fr\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/0aa2cfb0bd8949724a68cbac8d8321b4","name":"A Delapalisse","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/211ac42237c2e9683c0964086c393cb4","url":"https:\/\/secure.gravatar.com\/avatar\/ad45a8c5da24bc9c7c4940dd1c48a695?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad45a8c5da24bc9c7c4940dd1c48a695?s=96&d=mm&r=g","caption":"A Delapalisse"},"sameAs":["http:\/\/ECI"]}]}},"authors":[{"term_id":1153,"user_id":34,"is_guest":0,"slug":"adelapalisse","display_name":"A Delapalisse","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/ad45a8c5da24bc9c7c4940dd1c48a695?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""},{"term_id":3640,"user_id":0,"is_guest":1,"slug":"nick-flaherty","display_name":"Nick Flaherty","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/448494"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=448494"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/448494\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/447941"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=448494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=448494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=448494"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=448494"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=448494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}