{"id":446800,"date":"2024-03-21T18:19:34","date_gmt":"2024-03-21T17:19:34","guid":{"rendered":"https:\/\/www.ecinews.fr\/?p=446800"},"modified":"2024-03-21T18:19:34","modified_gmt":"2024-03-21T17:19:34","slug":"connecteurs-traversants-monobloc-pour-les-circuits-imprimes-double-face","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/connecteurs-traversants-monobloc-pour-les-circuits-imprimes-double-face\/","title":{"rendered":"Connecteurs traversants monobloc pour les circuits imprim\u00e9s double face"},"content":{"rendered":"<h3>D\u00e9velopp\u00e9e comme une extension des\u00a0connecteurs traversants invers\u00e9s \u00e0 une rang\u00e9e de la\u00a0<a href=\"https:\/\/u7061146.ct.sendgrid.net\/ls\/click?upn=u001.gqh-2BaxUzlo7XKIuSly0rC0eAa-2BodwTJAeRAIpMUT-2FLH-2F46tCTdAG0TFplBan3c13Ips-2BlTAhvY3KEcTieZqgwxswzewJt2Er3LA8pfpv-2FsLR36SL5D9JXZkThDkBuyp6aDU-2BeZFqxjdeC-2BfsnKsSFw-3D-3DBYw4_jlxnHLW6ndH-2B7rTpwPMgT5gL9r-2FxnmMC-2F9-2BYOx8gbIhdgZM1BOHzJSIiYaff6Q1XVLoFat3-2FHtOlPJzBKBfN3o8eWQ7OQ5L7Noivlb4KVyBrECUSjTRlilLl6xjjVvIqT-2BcubiWeQ6Ma275akMBMjha8C-2BTh5dd2OMIS3oxNUYUbsgyLlzw9hYIkMbppNj8j7STirvAtZSCC5fwA9aK3sTTc97c-2FYpjcAJ2DfOuYVhzljK2pItjbUWlcQIi0YqJLVs7oQOtxtfYh95SbxiIjI0KuaD2WBRSMDiGXJ7AZqKEkQfYbQ47-2FeWBhGw2CIFB1HPx7I7bUBfmqUHZ2ZDzT-2FNPBYflogYTTJLYNZnflEP4-3D\">s\u00e9rie 9159-500,\u00a0<\/a><a href=\"https:\/\/u7061146.ct.sendgrid.net\/ls\/click?upn=u001.gqh-2BaxUzlo7XKIuSly0rC0eAa-2BodwTJAeRAIpMUT-2FLH-2F46tCTdAG0TFplBan3c13Ips-2BlTAhvY3KEcTieZqgw3zDrwP5a-2FFD0ftGRvWNsYpWMX-2B9rCdnJC8O0MMU-2BVNpVUD4jeFw3rP8mX2Pbq6w8KeqCaDYz8IxgrUsagcQusc-3DDePm_jlxnHLW6ndH-2B7rTpwPMgT5gL9r-2FxnmMC-2F9-2BYOx8gbIhdgZM1BOHzJSIiYaff6Q1XVLoFat3-2FHtOlPJzBKBfN3o8eWQ7OQ5L7Noivlb4KVyBrECUSjTRlilLl6xjjVvIqT-2BcubiWeQ6Ma275akMBMjha8C-2BTh5dd2OMIS3oxNUYUbsgyLlzw9hYIkMbppNj8j7STirvAtZSCC5fwA9aK3sQTlLcAR3iP-2BbCeD0cwo9h3up3M9PyJpX4vxhFw5nL-2BIOPeDlpO7JOJEeDQk6G8a2M4KS-2BcD03-2F8Vqi5pKbuua3SS56MO8cOpqIbVAkswhFrj-2FZkzfsxsFembZp75m-2BxzQs2QLn9HBWA-2FfSKglLJIQI-3D\">la nouvelle s\u00e9rie 9159-600<\/a>\u00a0de Kyocera r\u00e9pond \u00e0 la demande des utilisateurs pour une solution de carte traversante invers\u00e9e monobloc pour les circuits imprim\u00e9s double face et est actuellement unique sur le march\u00e9.<\/h3>\n<p>Ces nouveaux connecteurs de bord de carte traversante invers\u00e9s \u00e0 double rang\u00e9e sont dot\u00e9s de contacts d\u00e9cal\u00e9s qui permettent de doubler le nombre de positions (4 \u00e0 12 contre 2 \u00e0 6) dans un format de taille similaire et offrent de pr\u00e9cieuses \u00e9conomies d&rsquo;espace, des \u00e9conomies de co\u00fbts et des performances de haute fiabilit\u00e9.<\/p>\n<p>La s\u00e9rie 9159-600 offre \u00e9galement plusieurs autres caract\u00e9ristiques avec des avantages significatifs dans les applications avec des exigences d&rsquo;accouplement perpendiculaires des circuits imprim\u00e9s, notamment l&rsquo;automobile, les transports et l&rsquo;\u00e9clairage LED, ainsi que les applications industrielles et m\u00e9dicales, telles que les \u00e9quipements de diagnostic et de test et les appareils portables. Par exemple, son syst\u00e8me de contact \u00e9prouv\u00e9 \u00e0 haute r\u00e9sistance, plaqu\u00e9 or sur cuivre b\u00e9ryllium nickel\u00e9, fournit un courant nominal complet de 2,5 A par contact pour une fiabilit\u00e9 accrue dans les environnements difficiles. Sa conception traversante \u00e0 profil bas (2,85 mm au-dessus du panneau) prend en charge les applications avec des contraintes de hauteur minimales du c\u00f4t\u00e9 accouplement du circuit imprim\u00e9 et n&rsquo;interf\u00e8re pas avec les LED. De plus, sa configuration de contact d\u00e9cal\u00e9e emp\u00eache les courts-circuits et les dommages de contact lors de l&rsquo;insertion et du retrait des circuits imprim\u00e9s d&rsquo;accouplement, et il est approuv\u00e9 selon les normes de s\u00e9curit\u00e9 UL1977.<\/p>\n<p>Les nouveaux connecteurs traversants invers\u00e9s de la s\u00e9rie 9159-600 sont con\u00e7us pour les circuits imprim\u00e9s d&rsquo;accouplement de 1,6 mm d&rsquo;\u00e9paisseur avec des pastilles plaqu\u00e9es or et \u00e9valu\u00e9s \u00e0 2,5 A par contact, 300 VCA, 10 cycles d&rsquo;accouplement et des temp\u00e9ratures de fonctionnement allant de -40 \u00b0C \u00e0 +125 \u00b0C. Il est dot\u00e9 d&rsquo;isolateurs en nylon UL94 V-0 blancs, remplis de verre et haute temp\u00e9rature, \u00e9quip\u00e9s de 4, 6, 8, 10 ou 12 contacts, d&rsquo;un placage d&rsquo;or sur le nez et d&rsquo;un placage d&rsquo;\u00e9tain mat sans plomb sur les queues, et il est emball\u00e9 sur du ruban adh\u00e9sif et une bobine en quantit\u00e9s de 700.<\/p>\n<p>&nbsp;<\/p>\n<p><a title=\"www.kyocera-avx.com\" href=\"http:\/\/www.kyocera-avx.com\">www.kyocera-avx.com<\/a><\/p>\n<p><a href=\"https:\/\/news.google.com\/publications\/CAAqBwgKMJbcwQswuPfYAw?hl=fr&amp;gl=BE&amp;ceid=BE:fr\">Suivre ECInews sur Google news<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9velopp\u00e9e comme une extension des\u00a0connecteurs traversants invers\u00e9s \u00e0 une rang\u00e9e de la\u00a0s\u00e9rie 9159-500,\u00a0la nouvelle s\u00e9rie 9159-600\u00a0de Kyocera r\u00e9pond \u00e0 la demande des utilisateurs pour une solution de carte traversante invers\u00e9e monobloc pour les circuits imprim\u00e9s double face et est actuellement unique sur le march\u00e9. Ces nouveaux connecteurs de bord de carte traversante invers\u00e9s \u00e0 double [&hellip;]<\/p>\n","protected":false},"author":36,"featured_media":446801,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[938],"domains":[47],"ppma_author":[1154],"class_list":["post-446800","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","tag-connectique","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Connecteurs traversants monobloc pour les circuits imprim\u00e9s do...<\/title>\n<meta name=\"description\" content=\"D\u00e9velopp\u00e9e comme une extension des\u00a0connecteurs traversants invers\u00e9s \u00e0 une rang\u00e9e de la\u00a0s\u00e9rie 9159-500,\u00a0la nouvelle s\u00e9rie 9159-600\u00a0de Kyocera...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/446800\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Connecteurs traversants monobloc pour les circuits imprim\u00e9s double face\" \/>\n<meta property=\"og:description\" content=\"D\u00e9velopp\u00e9e comme une extension des\u00a0connecteurs traversants invers\u00e9s \u00e0 une rang\u00e9e de la\u00a0s\u00e9rie 9159-500,\u00a0la nouvelle s\u00e9rie 9159-600\u00a0de Kyocera r\u00e9pond \u00e0 la demande des utilisateurs pour une solution de carte traversante invers\u00e9e monobloc pour les circuits imprim\u00e9s double face et est actuellement unique sur le march\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/446800\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-21T17:19:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2024\/03\/ECI3960_Kyocera-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"567\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/connecteurs-traversants-monobloc-pour-les-circuits-imprimes-double-face\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/connecteurs-traversants-monobloc-pour-les-circuits-imprimes-double-face\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/e4387676ad67ce722325c7832f3c3762\"},\"headline\":\"Connecteurs traversants monobloc pour les circuits imprim\u00e9s double face\",\"datePublished\":\"2024-03-21T17:19:34+00:00\",\"dateModified\":\"2024-03-21T17:19:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/connecteurs-traversants-monobloc-pour-les-circuits-imprimes-double-face\/\"},\"wordCount\":408,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"keywords\":[\"Connectique\"],\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/connecteurs-traversants-monobloc-pour-les-circuits-imprimes-double-face\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/connecteurs-traversants-monobloc-pour-les-circuits-imprimes-double-face\/\",\"name\":\"Connecteurs traversants monobloc pour les circuits imprim\u00e9s double face -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2024-03-21T17:19:34+00:00\",\"dateModified\":\"2024-03-21T17:19:34+00:00\",\"description\":\"D\u00e9velopp\u00e9e comme une extension des\u00a0connecteurs traversants invers\u00e9s \u00e0 une rang\u00e9e de la\u00a0s\u00e9rie 9159-500,\u00a0la nouvelle s\u00e9rie 9159-600\u00a0de Kyocera r\u00e9pond \u00e0 la demande des utilisateurs pour une solution de carte traversante invers\u00e9e monobloc pour les circuits imprim\u00e9s double face et est actuellement unique sur le march\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/connecteurs-traversants-monobloc-pour-les-circuits-imprimes-double-face\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/connecteurs-traversants-monobloc-pour-les-circuits-imprimes-double-face\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/connecteurs-traversants-monobloc-pour-les-circuits-imprimes-double-face\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Connecteurs traversants monobloc pour les circuits imprim\u00e9s double face\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/e4387676ad67ce722325c7832f3c3762\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/736120675699dbbf0f0f282b9a9cfb75\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bc93b056d07515be5b8eecd4acf49c5c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bc93b056d07515be5b8eecd4acf49c5c?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"},\"sameAs\":[\"http:\/\/ECINews\"]}]}<\/script>","yoast_head_json":{"title":"Connecteurs traversants monobloc pour les circuits imprim\u00e9s do...","description":"D\u00e9velopp\u00e9e comme une extension des\u00a0connecteurs traversants invers\u00e9s \u00e0 une rang\u00e9e de la\u00a0s\u00e9rie 9159-500,\u00a0la nouvelle s\u00e9rie 9159-600\u00a0de Kyocera...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/446800\/","og_locale":"fr_FR","og_type":"article","og_title":"Connecteurs traversants monobloc pour les circuits imprim\u00e9s double face","og_description":"D\u00e9velopp\u00e9e comme une extension des\u00a0connecteurs traversants invers\u00e9s \u00e0 une rang\u00e9e de la\u00a0s\u00e9rie 9159-500,\u00a0la nouvelle s\u00e9rie 9159-600\u00a0de Kyocera r\u00e9pond \u00e0 la demande des utilisateurs pour une solution de carte traversante invers\u00e9e monobloc pour les circuits imprim\u00e9s double face et est actuellement unique sur le march\u00e9.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/446800\/","og_site_name":"EENewsEurope","article_published_time":"2024-03-21T17:19:34+00:00","og_image":[{"width":1080,"height":567,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2024\/03\/ECI3960_Kyocera-scaled.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/connecteurs-traversants-monobloc-pour-les-circuits-imprimes-double-face\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/connecteurs-traversants-monobloc-pour-les-circuits-imprimes-double-face\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/e4387676ad67ce722325c7832f3c3762"},"headline":"Connecteurs traversants monobloc pour les circuits imprim\u00e9s double face","datePublished":"2024-03-21T17:19:34+00:00","dateModified":"2024-03-21T17:19:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/connecteurs-traversants-monobloc-pour-les-circuits-imprimes-double-face\/"},"wordCount":408,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"keywords":["Connectique"],"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/connecteurs-traversants-monobloc-pour-les-circuits-imprimes-double-face\/","url":"https:\/\/www.ecinews.fr\/fr\/connecteurs-traversants-monobloc-pour-les-circuits-imprimes-double-face\/","name":"Connecteurs traversants monobloc pour les circuits imprim\u00e9s double face -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2024-03-21T17:19:34+00:00","dateModified":"2024-03-21T17:19:34+00:00","description":"D\u00e9velopp\u00e9e comme une extension des\u00a0connecteurs traversants invers\u00e9s \u00e0 une rang\u00e9e de la\u00a0s\u00e9rie 9159-500,\u00a0la nouvelle s\u00e9rie 9159-600\u00a0de Kyocera r\u00e9pond \u00e0 la demande des utilisateurs pour une solution de carte traversante invers\u00e9e monobloc pour les circuits imprim\u00e9s double face et est actuellement unique sur le march\u00e9.","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/connecteurs-traversants-monobloc-pour-les-circuits-imprimes-double-face\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/connecteurs-traversants-monobloc-pour-les-circuits-imprimes-double-face\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/connecteurs-traversants-monobloc-pour-les-circuits-imprimes-double-face\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Connecteurs traversants monobloc pour les circuits imprim\u00e9s double face"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/e4387676ad67ce722325c7832f3c3762","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/736120675699dbbf0f0f282b9a9cfb75","url":"https:\/\/secure.gravatar.com\/avatar\/bc93b056d07515be5b8eecd4acf49c5c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bc93b056d07515be5b8eecd4acf49c5c?s=96&d=mm&r=g","caption":"Alain Dieul"},"sameAs":["http:\/\/ECINews"]}]}},"authors":[{"term_id":1154,"user_id":36,"is_guest":0,"slug":"alain-dieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/bc93b056d07515be5b8eecd4acf49c5c?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/446800"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=446800"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/446800\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/446801"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=446800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=446800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=446800"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=446800"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=446800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}