{"id":446652,"date":"2024-03-20T20:27:42","date_gmt":"2024-03-20T19:27:42","guid":{"rendered":"https:\/\/www.eenewseurope.com\/?p=446652"},"modified":"2024-03-20T20:28:11","modified_gmt":"2024-03-20T19:28:11","slug":"spectrum-ajoute-la-synthese-directe-de-20-signaux-sinusoidaux-aux-cartes-awg","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/spectrum-ajoute-la-synthese-directe-de-20-signaux-sinusoidaux-aux-cartes-awg\/","title":{"rendered":"Spectrum ajoute la synth\u00e8se directe de 20 signaux sinuso\u00efdaux aux cartes AWG"},"content":{"rendered":"<h3><span style=\"font-size: 16px;\">Spectrum Instrumentation a d\u00e9velopp\u00e9 une option de micrologiciel pour ses cartes de g\u00e9n\u00e9rateur de formes d&rsquo;ondes arbitraires (AWG) de 16 bits afin de contr\u00f4ler 20 ondes sinuso\u00efdales ind\u00e9pendantes jusqu&rsquo;\u00e0 400 MHz \u00e0 partir d&rsquo;un seul canal de g\u00e9n\u00e9rateur.<\/span><\/h3>\n<p>La nouvelle option de synth\u00e8se num\u00e9rique directe (DDS) permet aux utilisateurs de d\u00e9finir 23 c\u0153urs DDS par carte AWG, prenant en charge des taux d&rsquo;\u00e9chantillonnage allant jusqu&rsquo;\u00e0 1,25 G\u00e9ch\/s et des largeurs de bande allant jusqu&rsquo;\u00e0 400 MHz.<\/p>\n<p><strong>Noyaux DDS programmables<\/strong><\/p>\n<p>Chaque noyau DDS (onde sinuso\u00efdale) peut \u00eatre programm\u00e9 pour la fr\u00e9quence, l&rsquo;amplitude, la phase, la pente de fr\u00e9quence et la pente d&rsquo;amplitude. Cela permet, par exemple, de contr\u00f4ler des lasers par l&rsquo;interm\u00e9diaire d&rsquo;AOD et d&rsquo;AOM, comme c&rsquo;est souvent le cas dans les exp\u00e9riences quantiques, \u00e0 l&rsquo;aide de quelques commandes simples &#8211; au lieu d&rsquo;effectuer des calculs sur des tableaux de donn\u00e9es volumineux. La sortie DDS peut \u00eatre synchronis\u00e9e avec des \u00e9v\u00e9nements de d\u00e9clenchement externes ou par un temporisateur programmable avec une r\u00e9solution de 6,4 ns.<\/p>\n<p>Le DDS g\u00e9n\u00e8re des ondes sinuso\u00efdales p\u00e9riodiques arbitraires \u00e0 partir d&rsquo;une horloge de r\u00e9f\u00e9rence unique \u00e0 fr\u00e9quence fixe. Il repose sur le principe de l&rsquo;ajout de plusieurs \u00ab\u00a0noyaux DDS\u00a0\u00bb pour g\u00e9n\u00e9rer un signal multiporteuse (multitonalit\u00e9), chaque porteuse ayant sa propre fr\u00e9quence, son amplitude et sa phase bien d\u00e9finies.<\/p>\n<p>La possibilit\u00e9 de passer du mode AWG normal (qui g\u00e9n\u00e8re des formes d&rsquo;onde \u00e0 partir de donn\u00e9es pr\u00e9programm\u00e9es) au mode DDS (qui ne n\u00e9cessite que quelques commandes pour g\u00e9n\u00e9rer des porteuses sinuso\u00efdales) permet d&rsquo;adapter les cartes AWG \u00e0 de nombreuses applications.<\/p>\n<p>En mode DDS, l&rsquo;AWG sert de base au DDS multi-tons. La m\u00e9moire int\u00e9gr\u00e9e de 4 GByte et le mode de transfert DMA rapide de l&rsquo;unit\u00e9 permettent de transmettre des commandes DDS \u00e0 un taux pouvant atteindre 10 millions de commandes par seconde. Cette capacit\u00e9 unique permet de r\u00e9aliser des pentes d\u00e9finies par l&rsquo;utilisateur (par exemple en forme de S) ainsi que divers types de modulation (par exemple FM et AM) \u00e0 l&rsquo;aide de commandes DDS simples et faciles \u00e0 utiliser.<\/p>\n<p><strong>L&rsquo;option DDS adapt\u00e9e \u00e0 de multiples applications<\/strong><\/p>\n<p>L&rsquo;option DDS permet aux utilisateurs de produire facilement et de mani\u00e8re programmable des trains de formes d&rsquo;ondes, des balayages de fr\u00e9quence ou des r\u00e9f\u00e9rences finement r\u00e9glables de diff\u00e9rentes fr\u00e9quences et profils. Les applications qui requi\u00e8rent la commutation de fr\u00e9quence rapide et le r\u00e9glage fin de la fr\u00e9quence qu&rsquo;offre le DDS sont tr\u00e8s r\u00e9pandues. On les trouve dans les syst\u00e8mes industriels, m\u00e9dicaux et d&rsquo;imagerie, dans l&rsquo;analyse des r\u00e9seaux ou encore dans les technologies de communication, o\u00f9 les donn\u00e9es sont cod\u00e9es par modulation de phase et de fr\u00e9quence sur une porteuse.<\/p>\n<p>L&rsquo;option DDS est disponible d\u00e8s maintenant pour la gamme compl\u00e8te des cartes PCIe M4i.66xx, des modules PXIe M4x.66xx, des unit\u00e9s portables LXI\/Ethernet DN2.66x et des produits LXI\/Ethernet multicanaux de bureau DN6.66xx. En effectuant simplement une mise \u00e0 jour du micrologiciel, tous les produits de la s\u00e9rie 66xx achet\u00e9s pr\u00e9c\u00e9demment peuvent \u00eatre \u00e9quip\u00e9s de la nouvelle option du micrologiciel. La programmation peut \u00eatre effectu\u00e9e \u00e0 l&rsquo;aide des kits de d\u00e9veloppement de pilotes existants qui sont inclus dans la livraison. Des exemples sont disponibles pour Python, C++, MATLAB, LabVIEW et bien d&rsquo;autres. L&rsquo;option est disponible d\u00e8s maintenant.<\/p>\n<p><a href=\"https:\/\/r20.rs6.net\/tn.jsp?f=001iYb6bZ_IxZF_M_MBW2J0tNVuF8csQO7eSAYgLDNVX4bdFbrbNdQ0MFCDH7LIgybYQgoWCjta_TgrzAom9i5fy99p2x23TjN_JBd-aK4EkVL47m5YRuCCrhOj8wAv_JUCRUDfzN285LbNiQxzRwDHvhr7YpSAEu-M&amp;c=nmwjwqzfs0cLoo8njiGg05PMdri20Vh7Ioap4BrMngLNeoi-KvCgjA==&amp;ch=gP6FHeKNJEbcjY9Uj4kQU9jzl2fMZckpCXcXS_NB1yA-9vurC_jb2g==\">spectrum-instrumentation.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Spectrum Instrumentation a d\u00e9velopp\u00e9 une option de micrologiciel pour ses cartes de g\u00e9n\u00e9rateur de formes d&rsquo;ondes arbitraires (AWG) de 16 bits afin de contr\u00f4ler 20 ondes sinuso\u00efdales ind\u00e9pendantes jusqu&rsquo;\u00e0 400 MHz \u00e0 partir d&rsquo;un seul canal de g\u00e9n\u00e9rateur. La nouvelle option de synth\u00e8se num\u00e9rique directe (DDS) permet aux utilisateurs de d\u00e9finir 23 c\u0153urs DDS par [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":446601,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[2199],"domains":[47],"ppma_author":[1143,3640],"class_list":["post-446652","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","tag-test-et-mesure","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Spectrum ajoute la synth\u00e8se directe de 20 signaux sinuso\u00efdaux...<\/title>\n<meta name=\"description\" content=\"micrologiciel pour ses cartes AWG 16 bits afin de g\u00e9n\u00e9rer 20 ondes sinuso\u00efdales ind\u00e9pendantes jusqu&#039;\u00e0 400 MHz.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/446652\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spectrum ajoute la synth\u00e8se directe de 20 signaux sinuso\u00efdaux aux cartes AWG\" \/>\n<meta property=\"og:description\" content=\"micrologiciel pour ses cartes AWG 16 bits afin de g\u00e9n\u00e9rer 20 ondes sinuso\u00efdales ind\u00e9pendantes jusqu&#039;\u00e0 400 MHz.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/446652\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-20T19:27:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-20T19:28:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2024\/03\/unnamed-31-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"607\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Daniel Cardon, Nick Flaherty\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel Cardon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/spectrum-ajoute-la-synthese-directe-de-20-signaux-sinusoidaux-aux-cartes-awg\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/spectrum-ajoute-la-synthese-directe-de-20-signaux-sinusoidaux-aux-cartes-awg\/\"},\"author\":{\"name\":\"Daniel Cardon\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/93c44cde463762f40a8236eaa44c1c17\"},\"headline\":\"Spectrum ajoute la synth\u00e8se directe de 20 signaux sinuso\u00efdaux aux cartes AWG\",\"datePublished\":\"2024-03-20T19:27:42+00:00\",\"dateModified\":\"2024-03-20T19:28:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/spectrum-ajoute-la-synthese-directe-de-20-signaux-sinusoidaux-aux-cartes-awg\/\"},\"wordCount\":636,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"keywords\":[\"Test et mesure\"],\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/spectrum-ajoute-la-synthese-directe-de-20-signaux-sinusoidaux-aux-cartes-awg\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/spectrum-ajoute-la-synthese-directe-de-20-signaux-sinusoidaux-aux-cartes-awg\/\",\"name\":\"Spectrum ajoute la synth\u00e8se directe de 20 signaux sinuso\u00efdaux aux cartes AWG -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2024-03-20T19:27:42+00:00\",\"dateModified\":\"2024-03-20T19:28:11+00:00\",\"description\":\"micrologiciel pour ses cartes AWG 16 bits afin de g\u00e9n\u00e9rer 20 ondes sinuso\u00efdales ind\u00e9pendantes jusqu'\u00e0 400 MHz.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/spectrum-ajoute-la-synthese-directe-de-20-signaux-sinusoidaux-aux-cartes-awg\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/spectrum-ajoute-la-synthese-directe-de-20-signaux-sinusoidaux-aux-cartes-awg\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/spectrum-ajoute-la-synthese-directe-de-20-signaux-sinusoidaux-aux-cartes-awg\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spectrum ajoute la synth\u00e8se directe de 20 signaux sinuso\u00efdaux aux cartes AWG\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/93c44cde463762f40a8236eaa44c1c17\",\"name\":\"Daniel Cardon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/2b243f6bcc1cff7d86aadfb2cd0bd870\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/de9edc136dfc061ad4778e04635baefa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/de9edc136dfc061ad4778e04635baefa?s=96&d=mm&r=g\",\"caption\":\"Daniel Cardon\"}}]}<\/script>","yoast_head_json":{"title":"Spectrum ajoute la synth\u00e8se directe de 20 signaux sinuso\u00efdaux...","description":"micrologiciel pour ses cartes AWG 16 bits afin de g\u00e9n\u00e9rer 20 ondes sinuso\u00efdales ind\u00e9pendantes jusqu'\u00e0 400 MHz.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/446652\/","og_locale":"fr_FR","og_type":"article","og_title":"Spectrum ajoute la synth\u00e8se directe de 20 signaux sinuso\u00efdaux aux cartes AWG","og_description":"micrologiciel pour ses cartes AWG 16 bits afin de g\u00e9n\u00e9rer 20 ondes sinuso\u00efdales ind\u00e9pendantes jusqu'\u00e0 400 MHz.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/446652\/","og_site_name":"EENewsEurope","article_published_time":"2024-03-20T19:27:42+00:00","article_modified_time":"2024-03-20T19:28:11+00:00","og_image":[{"width":1080,"height":607,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2024\/03\/unnamed-31-scaled.jpg","type":"image\/jpeg"}],"author":"Daniel Cardon, Nick Flaherty","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Daniel Cardon","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/spectrum-ajoute-la-synthese-directe-de-20-signaux-sinusoidaux-aux-cartes-awg\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/spectrum-ajoute-la-synthese-directe-de-20-signaux-sinusoidaux-aux-cartes-awg\/"},"author":{"name":"Daniel Cardon","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/93c44cde463762f40a8236eaa44c1c17"},"headline":"Spectrum ajoute la synth\u00e8se directe de 20 signaux sinuso\u00efdaux aux cartes AWG","datePublished":"2024-03-20T19:27:42+00:00","dateModified":"2024-03-20T19:28:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/spectrum-ajoute-la-synthese-directe-de-20-signaux-sinusoidaux-aux-cartes-awg\/"},"wordCount":636,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"keywords":["Test et mesure"],"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/spectrum-ajoute-la-synthese-directe-de-20-signaux-sinusoidaux-aux-cartes-awg\/","url":"https:\/\/www.ecinews.fr\/fr\/spectrum-ajoute-la-synthese-directe-de-20-signaux-sinusoidaux-aux-cartes-awg\/","name":"Spectrum ajoute la synth\u00e8se directe de 20 signaux sinuso\u00efdaux aux cartes AWG -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2024-03-20T19:27:42+00:00","dateModified":"2024-03-20T19:28:11+00:00","description":"micrologiciel pour ses cartes AWG 16 bits afin de g\u00e9n\u00e9rer 20 ondes sinuso\u00efdales ind\u00e9pendantes jusqu'\u00e0 400 MHz.","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/spectrum-ajoute-la-synthese-directe-de-20-signaux-sinusoidaux-aux-cartes-awg\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/spectrum-ajoute-la-synthese-directe-de-20-signaux-sinusoidaux-aux-cartes-awg\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/spectrum-ajoute-la-synthese-directe-de-20-signaux-sinusoidaux-aux-cartes-awg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Spectrum ajoute la synth\u00e8se directe de 20 signaux sinuso\u00efdaux aux cartes AWG"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/93c44cde463762f40a8236eaa44c1c17","name":"Daniel Cardon","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/2b243f6bcc1cff7d86aadfb2cd0bd870","url":"https:\/\/secure.gravatar.com\/avatar\/de9edc136dfc061ad4778e04635baefa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/de9edc136dfc061ad4778e04635baefa?s=96&d=mm&r=g","caption":"Daniel Cardon"}}]}},"authors":[{"term_id":1143,"user_id":11,"is_guest":0,"slug":"danielcardon","display_name":"Daniel Cardon","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/de9edc136dfc061ad4778e04635baefa?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""},{"term_id":3640,"user_id":0,"is_guest":1,"slug":"nick-flaherty","display_name":"Nick Flaherty","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/446652"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=446652"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/446652\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/446601"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=446652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=446652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=446652"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=446652"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=446652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}