{"id":445259,"date":"2024-03-04T15:18:30","date_gmt":"2024-03-04T14:18:30","guid":{"rendered":"https:\/\/www.ecinews.fr\/?p=445259"},"modified":"2024-03-04T15:18:30","modified_gmt":"2024-03-04T14:18:30","slug":"alimentation-pour-leclairage-led-des-vehicules","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/alimentation-pour-leclairage-led-des-vehicules\/","title":{"rendered":"Alimentation pour l\u2019\u00e9clairage LED des v\u00e9hicules"},"content":{"rendered":"<h3>L\u2019utilisation de LED Dlawik Eaton propos\u00e9es par TME a permis de concevoir des \u00e9clairages aux formes fantaisistes.<\/h3>\n<p>Les LED ont modifi\u00e9 de mani\u00e8re irr\u00e9versible le domaine de l\u2019\u00e9clairage, notamment dans les habitations et les bureaux. Cependant, du fait de leurs caract\u00e9ristiques, ils se sont r\u00e9v\u00e9l\u00e9s difficiles \u00e0 mettre en \u0153uvre dans l\u2019industrie automobile. L\u2019obstacle \u00e9tait l\u2019efficacit\u00e9 car les convertisseurs LDO (Low Drop Out) typiques ne sont pas en mesure de fournir une puissance suffisante pour alimenter les feux de croisement, les feux de route ou les feux stop, qui doit \u00eatre de forte intensit\u00e9 pour assurer la visibilit\u00e9 m\u00eame par une journ\u00e9e ensoleill\u00e9e.<\/p>\n<p>Les co\u00fbts des circuits d\u2019alimentation qui se caract\u00e9riseraient non seulement par une efficacit\u00e9 de courant appropri\u00e9e, mais \u00e9galement par une r\u00e9sistance aux vibrations, aux chocs et aux temp\u00e9ratures \u00e9lev\u00e9es (souvent sup\u00e9rieures \u00e0 120\u00b0C) signifiaient que les LED \u00e9taient principalement utilis\u00e9es dans les int\u00e9rieurs ou dans des voitures plus ch\u00e8res. Dans le segment grand public, on a principalement utilis\u00e9 des lampes halog\u00e8nes ou x\u00e9non, dont le principal inconv\u00e9nient est la pr\u00e9sence d\u2019\u00e9l\u00e9ments mobiles, tels que des filaments ou des \u00e9lectrodes, avec une dur\u00e9e de vie faible par rapport aux structures semi-conductrices. <\/p>\n<p><a href=\"http:\/\/www.tme.eu\/\">www.tme.eu\/<\/a><\/p>\n<p><a href=\"https:\/\/news.google.com\/publications\/CAAqBwgKMJbcwQswuPfYAw?hl=fr&amp;gl=BE&amp;ceid=BE:fr\">Suivre ECInews sur Google news<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019utilisation de LED Dlawik Eaton propos\u00e9es par TME a permis de concevoir des \u00e9clairages aux formes fantaisistes. Les LED ont modifi\u00e9 de mani\u00e8re irr\u00e9versible le domaine de l\u2019\u00e9clairage, notamment dans les habitations et les bureaux. Cependant, du fait de leurs caract\u00e9ristiques, ils se sont r\u00e9v\u00e9l\u00e9s difficiles \u00e0 mettre en \u0153uvre dans l\u2019industrie automobile. L\u2019obstacle \u00e9tait [&hellip;]<\/p>\n","protected":false},"author":36,"featured_media":445264,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[1640,4324],"domains":[47],"ppma_author":[1154],"class_list":["post-445259","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","tag-automobile","tag-eclairage-led","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Alimentation pour l\u2019\u00e9clairage LED des v\u00e9hicules ...<\/title>\n<meta name=\"description\" content=\"L\u2019utilisation de LED Dlawik Eaton propos\u00e9es par TME a permis de concevoir des \u00e9clairages aux formes fantaisistes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/445259\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alimentation pour l\u2019\u00e9clairage LED des v\u00e9hicules\" \/>\n<meta property=\"og:description\" content=\"L\u2019utilisation de LED Dlawik Eaton propos\u00e9es par TME a permis de concevoir des \u00e9clairages aux formes fantaisistes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/445259\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-04T14:18:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2024\/03\/ECI3919_TME-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"810\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/alimentation-pour-leclairage-led-des-vehicules\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/alimentation-pour-leclairage-led-des-vehicules\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/e4387676ad67ce722325c7832f3c3762\"},\"headline\":\"Alimentation pour l\u2019\u00e9clairage LED des v\u00e9hicules\",\"datePublished\":\"2024-03-04T14:18:30+00:00\",\"dateModified\":\"2024-03-04T14:18:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/alimentation-pour-leclairage-led-des-vehicules\/\"},\"wordCount\":240,\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"keywords\":[\"Automobile\",\"Eclairage LED\"],\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/alimentation-pour-leclairage-led-des-vehicules\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/alimentation-pour-leclairage-led-des-vehicules\/\",\"name\":\"Alimentation pour l\u2019\u00e9clairage LED des v\u00e9hicules -\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\"},\"datePublished\":\"2024-03-04T14:18:30+00:00\",\"dateModified\":\"2024-03-04T14:18:30+00:00\",\"description\":\"L\u2019utilisation de LED Dlawik Eaton propos\u00e9es par TME a permis de concevoir des \u00e9clairages aux formes fantaisistes.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/alimentation-pour-leclairage-led-des-vehicules\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/alimentation-pour-leclairage-led-des-vehicules\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/alimentation-pour-leclairage-led-des-vehicules\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alimentation pour l\u2019\u00e9clairage LED des v\u00e9hicules\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/e4387676ad67ce722325c7832f3c3762\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/736120675699dbbf0f0f282b9a9cfb75\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bc93b056d07515be5b8eecd4acf49c5c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bc93b056d07515be5b8eecd4acf49c5c?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"},\"sameAs\":[\"http:\/\/ECINews\"]}]}<\/script>","yoast_head_json":{"title":"Alimentation pour l\u2019\u00e9clairage LED des v\u00e9hicules ...","description":"L\u2019utilisation de LED Dlawik Eaton propos\u00e9es par TME a permis de concevoir des \u00e9clairages aux formes fantaisistes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/445259\/","og_locale":"fr_FR","og_type":"article","og_title":"Alimentation pour l\u2019\u00e9clairage LED des v\u00e9hicules","og_description":"L\u2019utilisation de LED Dlawik Eaton propos\u00e9es par TME a permis de concevoir des \u00e9clairages aux formes fantaisistes.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/445259\/","og_site_name":"EENewsEurope","article_published_time":"2024-03-04T14:18:30+00:00","og_image":[{"width":1080,"height":810,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2024\/03\/ECI3919_TME-scaled.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/alimentation-pour-leclairage-led-des-vehicules\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/alimentation-pour-leclairage-led-des-vehicules\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/e4387676ad67ce722325c7832f3c3762"},"headline":"Alimentation pour l\u2019\u00e9clairage LED des v\u00e9hicules","datePublished":"2024-03-04T14:18:30+00:00","dateModified":"2024-03-04T14:18:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/alimentation-pour-leclairage-led-des-vehicules\/"},"wordCount":240,"publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"keywords":["Automobile","Eclairage LED"],"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/alimentation-pour-leclairage-led-des-vehicules\/","url":"https:\/\/www.ecinews.fr\/fr\/alimentation-pour-leclairage-led-des-vehicules\/","name":"Alimentation pour l\u2019\u00e9clairage LED des v\u00e9hicules -","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/#website"},"datePublished":"2024-03-04T14:18:30+00:00","dateModified":"2024-03-04T14:18:30+00:00","description":"L\u2019utilisation de LED Dlawik Eaton propos\u00e9es par TME a permis de concevoir des \u00e9clairages aux formes fantaisistes.","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/alimentation-pour-leclairage-led-des-vehicules\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/alimentation-pour-leclairage-led-des-vehicules\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/alimentation-pour-leclairage-led-des-vehicules\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Alimentation pour l\u2019\u00e9clairage LED des v\u00e9hicules"}]},{"@type":"WebSite","@id":"https:\/\/www.ecinews.fr\/fr\/#website","url":"https:\/\/www.ecinews.fr\/fr\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ecinews.fr\/fr\/#organization","name":"EENewsEurope","url":"https:\/\/www.ecinews.fr\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/e4387676ad67ce722325c7832f3c3762","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/736120675699dbbf0f0f282b9a9cfb75","url":"https:\/\/secure.gravatar.com\/avatar\/bc93b056d07515be5b8eecd4acf49c5c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bc93b056d07515be5b8eecd4acf49c5c?s=96&d=mm&r=g","caption":"Alain Dieul"},"sameAs":["http:\/\/ECINews"]}]}},"authors":[{"term_id":1154,"user_id":36,"is_guest":0,"slug":"alain-dieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/bc93b056d07515be5b8eecd4acf49c5c?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/445259"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=445259"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/445259\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/445264"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=445259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=445259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=445259"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=445259"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=445259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}