{"id":441556,"date":"2024-01-17T21:15:41","date_gmt":"2024-01-17T20:15:41","guid":{"rendered":"https:\/\/www.ecinews.fr\/?p=441556"},"modified":"2024-01-17T21:15:41","modified_gmt":"2024-01-17T20:15:41","slug":"domotique-appareils-smart-home-avec-des-elements-de-la-marque-panasonic-composants","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/domotique-appareils-smart-home-avec-des-elements-de-la-marque-panasonic-composants\/","title":{"rendered":"Domotique : appareils Smart Home avec des \u00e9l\u00e9ments de la marque Panasonic  Composants"},"content":{"rendered":"<h3>Smart Home est une notion qui d\u00e9finit un large groupe de produits, principalement des appareils grand public pour l\u2019automatisation dans la construction r\u00e9sidentielle \u2013 mais aussi dans les bureaux. De telles solutions permettent le fonctionnement pratique de l\u2019\u00e9clairage, de la climatisation, des rideaux, des portails, des \u00e9l\u00e9ments de protection des biens, ainsi que des dispositifs d\u2019approvisionnement en eau ou m\u00eame des syst\u00e8mes complets d\u2019\u00e9nergie renouvelable. Parall\u00e8lement au d\u00e9veloppement de la technologie IoT (Internet of Things) on rencontre de plus en plus d&rsquo;appareils \u00e9lectrom\u00e9nagers dans lesquels des modules de t\u00e9l\u00e9commande ont \u00e9t\u00e9 impl\u00e9ment\u00e9s.<\/h3>\n<p>\nLes fournisseurs de composants \u00e9lectrom\u00e9caniques et de composants \u00e9lectroniques suivent la popularit\u00e9 croissante des solutionsSmart Home. La production de tels appareils n\u00e9cessite l\u2019utilisation de pi\u00e8ces caract\u00e9ris\u00e9es par une tr\u00e8s grande durabilit\u00e9 car ils sont soumis \u00e0 une utilisation constante et doivent assurer la satisfaction des utilisateurs dans les plus brefs d\u00e9lais, alors que (contrairement aux \u00e9l\u00e9ments utilis\u00e9s dans l\u2019industrie) ils ne feront pas faire l\u2019objet d\u2019une inspection et d\u2019un entretien p\u00e9riodiques. De tels composants sont propos\u00e9s par de nombreuses marques dans le catalogue TME \u2013 mais seuls quelques-uns sont reconnu comme les produits <a href=\"https:\/\/www.tme.eu\/fr\/linecard\/p,panasonic_131\/\">Panasonic<\/a>.\u00a0 <br \/>\nDans la suite nous pr\u00e9sentons une liste des composants Panasonic qui ont \u00e9t\u00e9 d\u00e9velopp\u00e9s pour la production de masse d\u2019appareils grand public, y compris ceux dans le domaine de la domotique. Les articles sont disponibles dans une large gamme de versions et sont adapt\u00e9s aux exigences typiques des composants utilis\u00e9s dans les \u00e9quipements grand public. \u00c0 la recherche de solutions appropri\u00e9es avec des param\u00e8tres sp\u00e9cifiques, veuillez visiter notre catalogue \u2013 et en m\u00eame temps, nous vous encourageons \u00e0 lire la liste suivante et \u00e0 vous familiariser avec la vaste gamme de Panasonic.<\/p>\n<p><strong>Interrupteurs<\/strong><\/p>\n<p>Panasonic est fournisseur d\u2019une tr\u00e8s large gamme de composants \u00e9lectrom\u00e9caniques. Ce groupe comprend de nombreux interrupteurs \u2013 \u00e0 la fois standard, TACT et de capteur. Puisqu\u2019ils se caract\u00e9risent par la durabilit\u00e9 et par la pr\u00e9cision dignes de la marque du fabricant, ils constituent un excellent choix pour la construction de panneaux de contr\u00f4le d\u2019appareils grand public (ainsi qu\u2019industriels). Ils ont \u00e9t\u00e9 adapt\u00e9s pour une installation dans des conditions de production de masse. De plus, la plupart des produits d\u00e9crits ci-dessous, propos\u00e9s par TME, sont disponibles directement depuis les entrep\u00f4ts, donc les retards dans la cha\u00eene d\u2019approvisionnement ne seront pas un probl\u00e8me.<\/p>\n<h3>Microinterrupteurs TACT<\/h3>\n<p>Bien que les \u00e9crans tactiles et les \u00e9crans soient de plus en plus pr\u00e9sents dans les appareils grand public, les commutateurs TACT restent l\u2019une des solutions les plus choisies. Ils permettent la construction d\u2019une interface intuitive \u2013 de nombreux utilisateurs appr\u00e9cient le clic perceptible, qui assure que la connexion est \u00e9tablie. Les boutons physiques sont \u00e9galement une solution durable et \u00e9conomique qui peut \u00eatre utilis\u00e9e dans des syst\u00e8mes \u00e0 microprocesseur avec une puissance de calcul inf\u00e9rieure et une tr\u00e8s faible consommation d\u2019\u00e9nergie.<\/p>\n<p>&nbsp;<\/p>\n<h3>Interrupteur s\u00e9rie EVQP de seulement 0,35 mm de haut<\/h3>\n<p>\nPanasonic propose des commutateurs TACT en versions pour montage SMD et THT orient\u00e9s parall\u00e8lement et perpendiculairement au plan du PCB. L\u2019assortiment de TME comprend au total plusieurs dizaines de s\u00e9ries constructeur, principalement diversifi\u00e9es en termes de tailles et de formes. Parmi ces articles, il y a des interrupteurs avec un profil allant jusqu\u2019\u00e0 0,35 mm qui fonctionneront dans tous les appareils mobiles (tels que les t\u00e9l\u00e9commandes ou les panneaux de commande muraux sans fil). La grande majorit\u00e9 des commutateurs TACT de Panasonic ont \u00e9t\u00e9 adapt\u00e9s \u00e0 des tensions ne d\u00e9passant pas 15V DC et \u00e9quip\u00e9s de contacts avec une r\u00e9sistance maximale de 100m\u03a9 et une configuration SPST, qui r\u00e9pond aux exigences de la plupart des circuits Smart Home typiques. Les boutons des boutons peuvent avoir des formes rondes ou rectangulaires, et les corps ont une zone de base avec des dimensions de 2,0&#215;3,9 mm \u00e0 10&#215;10 mm.<br \/>\nLes interrupteurs TACT de Panasonic sont une solution facile \u00e0 adapter et \u00e0 utiliser pour cr\u00e9er diverses interfaces utilisateur. Les produits sont disponibles dans de nombreux formats, tailles, configurations de bornes, ainsi que diverses caract\u00e9ristiques m\u00e9caniques (force de pression), gr\u00e2ce auxquelles le client peut facilement choisir les interrupteurs les mieux adapt\u00e9s \u00e0 l\u2019application cible.<\/p>\n<h3>Interrupteurs standard<\/h3>\n<p>Les interrupteurs standard existent dans de nombreuses variantes de tailles et de caract\u00e9ristiques m\u00e9caniques \u2013 ils sont utilis\u00e9s avec des boutons plus gros lors de la fabrication de panneaux de commande d\u2019appareils audio\/vid\u00e9o et d\u2019appareils \u00e9lectrom\u00e9nagers, ainsi que dans les consoles de voiture et applications similaires. Ces produits Panasonic sont disponibles dans des versions pour le montage sur un circuit imprim\u00e9, en technologie de surface ou traversante \u2013 ils appartiennent aux s\u00e9ries ESB30, ESB33, ESE20. Ce sont des \u00e9l\u00e9ments \u00e0 commande indirecte \u2013 leur capacit\u00e9 de charge \u00e9lectrique est maximale de 0,2A et 14V DC. Selon le mod\u00e8le, ils peuvent avoir une paire ou deux ensembles de contacts (SPST, DPDT), avec une ou deux positions stables. Les concepteurs ont le choix entre trois tailles de produits, avec des surfaces de base allant de 7,8&#215;7,9 mm do 10,9&#215;10 mm.<\/p>\n<h3>Interrupteurs de capteur<\/h3>\n<p>Interrupteurs de capteur peuvent \u00eatre mont\u00e9s directement dans le circuit PCB. La t\u00e2che des interrupteurs \u00e0 capteur consiste \u00e0 collecter des informations sur la position des \u00e9l\u00e9ments m\u00e9caniques des appareils (par exemple sur la fermeture du couvercle). Gr\u00e2ce \u00e0 cette fonction, ils ont une faible force de commutation (m\u00eame 0,29 N). Comme ils sont g\u00e9n\u00e9ralement utilis\u00e9s en conjonction avec des syst\u00e8mes de contr\u00f4le num\u00e9rique, ils ne supportent que des courants et des tensions faibles, dans le cas de l\u2019offre de Panasonic ne d\u00e9passant pas 0,2A \u00e0 14V DC (pour la plupart des articles : 0,01A \/ 5V DC). Ils se caract\u00e9risent par une petite taille et une large tol\u00e9rance thermique (m\u00eame -40&#8230;85\u00b0C). Ils sont disponibles en variantes \u00e0 levier ou \u00e0 bouton poussoir, pour un montage sur un circuit imprim\u00e9 ou dans un trou d\u00e9di\u00e9. La plupart des produits de ce groupe ont 2 \u00e9tats stables, cependant, des interrupteurs \u00e0 3 positions sont \u00e9galement disponibles.<\/p>\n<h2>Condensateurs polym\u00e8res OS-CON<\/h2>\n<p>Les appareils domotiques doivent \u00eatre r\u00e9sistants \u00e0 des interf\u00e9rences du secteur comme source d\u2019alimentation principale, tout en \u00e9tant compacts. C\u2019est l\u00e0 que les condensateurs polym\u00e8res haut de gamme de Panasonic, appartenant \u00e0 la famille OS-CON viennent \u00e0 l\u2019aide. Les produits compacts de ce groupe sont con\u00e7us pour \u00eatre utilis\u00e9s dans les stabilisateurs et les syst\u00e8mes de filtration. Les mod\u00e8les s\u00e9lectionn\u00e9s se caract\u00e9risent par une r\u00e9sistance aux courants d\u2019ondulation \u00e9lev\u00e9s, une faible imp\u00e9dance (Low ESR) et une tension nominale jusqu\u2019\u00e0 100 V. Ils ont d\u2019excellentes caract\u00e9ristiques haute fr\u00e9quence, ce qui en fait un \u00e9l\u00e9ment de d\u00e9couplage dans les convertisseurs de tension et les syst\u00e8mes \u00e0 microprocesseur o\u00f9 des protocoles de communication \u00e0 haut d\u00e9bit et des modules sans fil sont utilis\u00e9s pour contr\u00f4ler les composants. Parmi les avantages suppl\u00e9mentaires des condensateurs OS-CON il y a leur large tol\u00e9rance thermique dans la plage de -55&#8230;105\u00b0C ou -55\u00b0C&#8230;125\u00b0C et la disponibilit\u00e9 en versions pour le montage des deux SMD et THT. Parmi les plus grands avantages des condensateurs OS-CON il y a leurs dimensions compactes.<\/p>\n<h2>Module Bluetooth PAN1780<\/h2>\n<p>La petite taille permet au module d\u2019\u00eatre utilis\u00e9 dans les appareils mobiles. Une fonctionnalit\u00e9 inh\u00e9rente aux syst\u00e8mesSmart Home modernes est la capacit\u00e9 de contr\u00f4ler \u00e0 distance les appareils et de modifier les valeurs d\u00e9finies, g\u00e9n\u00e9ralement \u00e0 l\u2019aide d\u2019une application d\u00e9di\u00e9e dans un t\u00e9l\u00e9phone mobile et de la technologie sans fil. Pour activer la connectivit\u00e9 sans fil, des modules de communication sont utilis\u00e9s, tels que celui construit par Panasonic PAN1780. Il permet d\u2019obtenir une connexion stable avec un d\u00e9bit allant de 125kb\/s \u00e0 2Mbps \u2013 avec une plage relativement large en cas de transfert plus lent (norme Bluetooth 5.0). Gr\u00e2ce \u00e0 l\u2019utilisation d\u2019un algorithme de s\u00e9lection de canal avanc\u00e9, le PAN1780 peut fonctionner m\u00eame dans des conditions de forte intensit\u00e9 de signaux parasites (par exemple, \u00e0 partir de stations WiFi ou de t\u00e9l\u00e9phones portables). L\u2019avantage du module est le fait qu\u2019il est bas\u00e9 sur le SoC (System-on-Chip) nRF52840 de Nordic, compatible avec le standard de communication Matter (utilis\u00e9 pour la communication avec les appareils Smart Home), avec une \u00e2me Cortex M4F et 1 Mo de m\u00e9moire Flash. En rendant certaines ressources du microcontr\u00f4leur disponibles pour l\u2019application, le PAN1780 peut agir comme un pilote pour l\u2019ensemble de l\u2019appareil, en utilisant 48 lignes GPIO qui peuvent \u00e9galement fonctionner comme interfaces SPI, I<sup>2<\/sup>C, UART, USB. NRF52840. Le NRF52840 a \u00e9galement des g\u00e9n\u00e9rateurs PWM int\u00e9gr\u00e9s et des convertisseurs A\/C et assure une transmission s\u00e9curis\u00e9e des donn\u00e9es \u00e0 l\u2019aide d\u2019algorithmes de cryptage. De plus, le module est \u00e9quip\u00e9 d\u2019une antenne en c\u00e9ramique et d\u2019un capot de protection. Le tout tient sur une plaque d\u2019une surface de 15,6 x 8,7 mm, destin\u00e9e au montage en surface. Il convient de noter que le produit est certifi\u00e9 radio pour une utilisation dans l\u2019UE, aux \u00c9tats-Unis, au Canada, au Japon, en Cor\u00e9e, en Chine, en Australie et en Nouvelle-Z\u00e9lande.<br \/>\n<a href=\"https:\/\/www.youtube.com\/watch?v=fcU1eVoi2NI\">https:\/\/www.youtube.com\/watch?v=fcU1eVoi2NI<\/a>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/p>\n<h2>Relais miniatures SF-M<\/h2>\n<p>Les relais SF-M \u00e0 profil bas combinent deux caract\u00e9ristiques souhaitables dans la construction de circuits domotiques : taille miniaturis\u00e9e et tol\u00e9rance de courant relativement \u00e9lev\u00e9e. Les \u00e9l\u00e9ments peuvent \u00eatre utilis\u00e9s pour commuter des tensions jusqu\u2019\u00e0 250V AC \u00e0 un courant de 4A \u2013 ils feront donc leurs preuves dans des appareils contr\u00f4lant l\u2019alimentation de diverses charges : moteurs, actionneurs, ventilateurs, \u00e9lectrovannes, sources lumineuses et m\u00eame radiateurs. Les composants sont \u00e9quip\u00e9s de contacts fix\u00e9s par l\u2019utilisation d\u2019alliages d\u2019argent plaqu\u00e9s or. La s\u00e9rie SF-M comprend des relais avec des bobines pour des tensions de 3V \u00e0 24V DC, c\u2019est-\u00e0-dire compatibles avec les param\u00e8tres typiques des appareils grand public (y compris les appareils aliment\u00e9s par batterie). Le profil bas permet au module d\u2019\u00eatre utilis\u00e9 dans les appareils mobiles.<\/p>\n<h2>Relais temporis\u00e9s<\/h2>\n<p>Les relais sont mont\u00e9s sur panneau et disposent de grands \u00e9crans LCD clairs. L\u2019offre de Panasonic pour la domotique ne se limite pas aux composants. L\u2019assortiment du fournisseur comprend \u00e9galement des produits qui peuvent fonctionner de mani\u00e8re autonome et remplir diverses fonctions dans les installations \u00e9lectriques domestiques. Ces articles incluent les relais temporis\u00e9s des s\u00e9ries LT4H et LT4H-W. Ils fonctionnent avec des tensions de 12\u202624V DC, 24V AC ou une alimentation secteur typique de l\u2019ordre de 100\u2026 240V AC \u2013 le raccordement s\u2019effectue avec une douille ronde ou des bornes \u00e0 vis (selon le mod\u00e8le). Ce sont des appareils mont\u00e9s sur panneau avec un haut degr\u00e9 de protection (IP66). Ils peuvent fonctionner en mode compteur cumulatif, g\u00e9n\u00e9rateur d\u2019impulsions, activation ou d\u00e9sactivation retard\u00e9e du circuit, ainsi que cycliquement (avec deux minuteries ind\u00e9pendantes). La plage de comptage se r\u00e8gle facilement \u00e0 l\u2019aide des interrupteurs \u00e0 l\u2019avant ; Le r\u00e9glage est dans la plage de 0,01 s \u00e0 9999h ou de 0,001 s \u00e0 999,9h. Dans le domaine de la domotique, ces produits sont utilis\u00e9s principalement dans l\u2019habitat collectif, ils peuvent \u00eatre utilis\u00e9s pour contr\u00f4ler l\u2019\u00e9clairage, contr\u00f4ler les serrures \u00e9lectromagn\u00e9tiques, les portails, les barri\u00e8res, ainsi que les appareils de climatisation.<\/p>\n<p><a href=\"https:\/\/www.tme.eu\/fr\/news\/library-articles\/page\/46789\/production-dappareils-smart-home-avec-des-elements-de-la-marque-panasonic\/\">https:\/\/www.tme.eu\/fr\/news\/library-articles\/page\/46789\/production-dappareils-smart-home-avec-des-elements-de-la-marque-panasonic\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Smart Home est une notion qui d\u00e9finit un large groupe de produits, principalement des appareils grand public pour l\u2019automatisation dans la construction r\u00e9sidentielle \u2013 mais aussi dans les bureaux. De telles solutions permettent le fonctionnement pratique de l\u2019\u00e9clairage, de la climatisation, des rideaux, des portails, des \u00e9l\u00e9ments de protection des biens, ainsi que des dispositifs [&hellip;]<\/p>\n","protected":false},"author":36,"featured_media":441557,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[],"domains":[47],"ppma_author":[1154],"class_list":["post-441556","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Domotique : appareils Smart Home avec des \u00e9l\u00e9ments de la marq...<\/title>\n<meta name=\"description\" content=\"Smart Home est une notion qui d\u00e9finit un large groupe de produits, principalement des appareils grand public pour l\u2019automatisation dans la construction...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/441556\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Domotique : appareils Smart Home avec des \u00e9l\u00e9ments de la marque Panasonic Composants\" \/>\n<meta property=\"og:description\" content=\"Smart Home est une notion qui d\u00e9finit un large groupe de produits, principalement des appareils grand public pour l\u2019automatisation dans la construction r\u00e9sidentielle \u2013 mais aussi dans les bureaux. De telles solutions permettent le fonctionnement pratique de l\u2019\u00e9clairage, de la climatisation, des rideaux, des portails, des \u00e9l\u00e9ments de protection des biens, ainsi que des dispositifs [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/441556\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-17T20:15:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2024\/01\/ECI3275_Panasonic_web-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"676\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/domotique-appareils-smart-home-avec-des-elements-de-la-marque-panasonic-composants\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/domotique-appareils-smart-home-avec-des-elements-de-la-marque-panasonic-composants\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#\/schema\/person\/e4387676ad67ce722325c7832f3c3762\"},\"headline\":\"Domotique : appareils Smart Home avec des \u00e9l\u00e9ments de la marque Panasonic Composants\",\"datePublished\":\"2024-01-17T20:15:41+00:00\",\"dateModified\":\"2024-01-17T20:15:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/domotique-appareils-smart-home-avec-des-elements-de-la-marque-panasonic-composants\/\"},\"wordCount\":1992,\"publisher\":{\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#organization\"},\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/domotique-appareils-smart-home-avec-des-elements-de-la-marque-panasonic-composants\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/domotique-appareils-smart-home-avec-des-elements-de-la-marque-panasonic-composants\/\",\"name\":\"Domotique : appareils Smart Home avec des \u00e9l\u00e9ments de la marque Panasonic Composants -\",\"isPartOf\":{\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2024-01-17T20:15:41+00:00\",\"dateModified\":\"2024-01-17T20:15:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/domotique-appareils-smart-home-avec-des-elements-de-la-marque-panasonic-composants\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/domotique-appareils-smart-home-avec-des-elements-de-la-marque-panasonic-composants\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/domotique-appareils-smart-home-avec-des-elements-de-la-marque-panasonic-composants\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Domotique : appareils Smart Home avec des \u00e9l\u00e9ments de la marque Panasonic Composants\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/www.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/www.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#\/schema\/person\/e4387676ad67ce722325c7832f3c3762\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#\/schema\/person\/image\/736120675699dbbf0f0f282b9a9cfb75\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bc93b056d07515be5b8eecd4acf49c5c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bc93b056d07515be5b8eecd4acf49c5c?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"},\"sameAs\":[\"http:\/\/ECINews\"]}]}<\/script>","yoast_head_json":{"title":"Domotique : appareils Smart Home avec des \u00e9l\u00e9ments de la marq...","description":"Smart Home est une notion qui d\u00e9finit un large groupe de produits, principalement des appareils grand public pour l\u2019automatisation dans la construction...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/441556\/","og_locale":"fr_FR","og_type":"article","og_title":"Domotique : appareils Smart Home avec des \u00e9l\u00e9ments de la marque Panasonic Composants","og_description":"Smart Home est une notion qui d\u00e9finit un large groupe de produits, principalement des appareils grand public pour l\u2019automatisation dans la construction r\u00e9sidentielle \u2013 mais aussi dans les bureaux. De telles solutions permettent le fonctionnement pratique de l\u2019\u00e9clairage, de la climatisation, des rideaux, des portails, des \u00e9l\u00e9ments de protection des biens, ainsi que des dispositifs [&hellip;]","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/441556\/","og_site_name":"EENewsEurope","article_published_time":"2024-01-17T20:15:41+00:00","og_image":[{"width":1080,"height":676,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2024\/01\/ECI3275_Panasonic_web-scaled.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/domotique-appareils-smart-home-avec-des-elements-de-la-marque-panasonic-composants\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/domotique-appareils-smart-home-avec-des-elements-de-la-marque-panasonic-composants\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/www.eenewseurope.com\/en\/#\/schema\/person\/e4387676ad67ce722325c7832f3c3762"},"headline":"Domotique : appareils Smart Home avec des \u00e9l\u00e9ments de la marque Panasonic Composants","datePublished":"2024-01-17T20:15:41+00:00","dateModified":"2024-01-17T20:15:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/domotique-appareils-smart-home-avec-des-elements-de-la-marque-panasonic-composants\/"},"wordCount":1992,"publisher":{"@id":"https:\/\/www.eenewseurope.com\/en\/#organization"},"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/domotique-appareils-smart-home-avec-des-elements-de-la-marque-panasonic-composants\/","url":"https:\/\/www.ecinews.fr\/fr\/domotique-appareils-smart-home-avec-des-elements-de-la-marque-panasonic-composants\/","name":"Domotique : appareils Smart Home avec des \u00e9l\u00e9ments de la marque Panasonic Composants -","isPartOf":{"@id":"https:\/\/www.eenewseurope.com\/en\/#website"},"datePublished":"2024-01-17T20:15:41+00:00","dateModified":"2024-01-17T20:15:41+00:00","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/domotique-appareils-smart-home-avec-des-elements-de-la-marque-panasonic-composants\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/domotique-appareils-smart-home-avec-des-elements-de-la-marque-panasonic-composants\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/domotique-appareils-smart-home-avec-des-elements-de-la-marque-panasonic-composants\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Domotique : appareils Smart Home avec des \u00e9l\u00e9ments de la marque Panasonic Composants"}]},{"@type":"WebSite","@id":"https:\/\/www.eenewseurope.com\/en\/#website","url":"https:\/\/www.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/www.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/www.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/www.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.eenewseurope.com\/en\/#\/schema\/person\/e4387676ad67ce722325c7832f3c3762","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.eenewseurope.com\/en\/#\/schema\/person\/image\/736120675699dbbf0f0f282b9a9cfb75","url":"https:\/\/secure.gravatar.com\/avatar\/bc93b056d07515be5b8eecd4acf49c5c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bc93b056d07515be5b8eecd4acf49c5c?s=96&d=mm&r=g","caption":"Alain Dieul"},"sameAs":["http:\/\/ECINews"]}]}},"authors":[{"term_id":1154,"user_id":36,"is_guest":0,"slug":"alain-dieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/bc93b056d07515be5b8eecd4acf49c5c?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/441556"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=441556"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/441556\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/441557"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=441556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=441556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=441556"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=441556"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=441556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}