{"id":43690,"date":"2020-10-05T07:31:44","date_gmt":"2020-10-05T07:31:44","guid":{"rendered":"https:\/\/\/simulateur-de-radar-a-cibles-multiples-et-des-solutions-ethernet-avancees-pour-vehicules-autonomes\/"},"modified":"2020-10-05T07:31:44","modified_gmt":"2020-10-05T07:31:44","slug":"simulateur-de-radar-a-cibles-multiples-et-des-solutions-ethernet-avancees-pour-vehicules-autonomes","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/simulateur-de-radar-a-cibles-multiples-et-des-solutions-ethernet-avancees-pour-vehicules-autonomes\/","title":{"rendered":"Simulateur de radar \u00e0 cibles multiples et des solutions Ethernet avanc\u00e9es pour v\u00e9hicules autonomes"},"content":{"rendered":"<p>L&rsquo;\u00e9volution rapide des v\u00e9hicules autonomes et la demande de dispositifs de s\u00e9curit\u00e9 plus importants alimentent le besoin d&rsquo;une technologie radar automobile sensible et pr\u00e9cise. Expert en mati\u00e8re de technologie de test de radar, Keysight propose d\u00e9sormais un nouveau simulateur de cible radar (RTS) pour aider les fabricants d&rsquo;\u00e9lectronique automobile \u00e0 simuler en toute confiance des cibles radar dans divers sc\u00e9narios r\u00e9alistes.<\/p>\n<p>Ce nouveau RTS effectue des tests multi-cibles et multi-angles pour les modules radar dans un environnement de laboratoire. Il fournit des r\u00e9sultats rapides, pr\u00e9cis et fiables qui \u00e9quilibrent le d\u00e9bit et la qualit\u00e9. Les ing\u00e9nieurs conception et v\u00e9rification peuvent rapidement valider les performances des produits radar, tandis que les ing\u00e9nieurs de fabrication et de validation sont capables de simuler plusieurs objets \u00e0 des distances variables. En permettant aux utilisateurs d&rsquo;introduire un environnement de test r\u00e9el dans leur laboratoire, le RTS de Keysight permet de r\u00e9aliser d\u2019importantes \u00e9conomies en termes de temps et de co\u00fbts.<\/p>\n<p>\u00ab\u00a0Dans le domaine de la conduite autonome, la conception de modules de radar n&rsquo;est pas seulement un luxe, c&rsquo;est une exigence.&nbsp; La pr\u00e9cision de ces dispositifs ne peut \u00eatre al\u00e9atoire\u00a0\u00bb, d\u00e9clare Thomas Goetzl, Vice-Pr\u00e9sident et Directeur G\u00e9n\u00e9ral de l&rsquo;unit\u00e9 commerciale \u00ab\u00a0Automotive and Energy Solutions\u00a0\u00bb de Keysight.&nbsp;\u00ab\u00a0Keysight met \u00e0 profit une technologie issue de notre longue exp\u00e9rience en mati\u00e8re de conception RF pour fournir une t\u00eate d\u00e9port\u00e9e multi-cibles qui permet aux d\u00e9veloppeurs de modules radar de surmonter les difficult\u00e9s de conception et de v\u00e9rification des performances\u00a0\u00bb.<\/p>\n<p><u>Les normes qui r\u00e9gissent l&rsquo;Ethernet automobile<\/u><\/p>\n<p>Les syst\u00e8mes ADAS (Advanced Driver Assistance Systems) de nouvelle g\u00e9n\u00e9ration n\u00e9cessitent des syst\u00e8mes de cam\u00e9ras et de radars \u00e0 haute r\u00e9solution, qui demandent une vitesse et une largeur de bande accrues. L&rsquo;Ethernet automobile permet une communication de donn\u00e9es plus rapide pour r\u00e9pondre aux exigences des v\u00e9hicules d&rsquo;aujourd&rsquo;hui et des v\u00e9hicules connect\u00e9s de demain. Cependant, le canal ou le lien d&rsquo;un syst\u00e8me peut cr\u00e9er un point de d\u00e9faillance et doit donc \u00eatre enti\u00e8rement test\u00e9.<\/p>\n<p>Pour relever ce d\u00e9fi, Keysight a d\u00e9velopp\u00e9 une nouvelle solution logicielle de test de canal Ethernet automobile pour v\u00e9rifier que les informations sont transport\u00e9es, sans perte ni diaphonie, vers leur destination pr\u00e9vue.<\/p>\n<p>Les principales caract\u00e9ristiques de la nouvelle solution logicielle de test de canal Ethernet pour l&rsquo;automobile de Keysight sont les suivantes<\/p>\n<p>\u2022&nbsp;Cr\u00e9ation d&rsquo;un plan de test qui comprend tous les tests requis selon la sp\u00e9cification.<\/p>\n<p>\u2022&nbsp;Mise en place automatique de l&rsquo;analyseur de r\u00e9seau pour chaque mesure et application des limites de test d\u00e9finies.<\/p>\n<p>\u2022&nbsp;Rapport d\u00e9taill\u00e9 pour chaque test effectu\u00e9.<\/p>\n<p>La suite Automotive Ethernet de Keysight fournit le mat\u00e9riel, les logiciels, les c\u00e2bles et les accessoires n\u00e9cessaires pour permettre les tests de conformit\u00e9. Ces offres sont compl\u00e9t\u00e9es par un nouveau logiciel de test des r\u00e9cepteurs et une application de conformit\u00e9 de transmission mise \u00e0 jour qui offre 4 d\u00e9bits de donn\u00e9es diff\u00e9rents, y compris la version pr\u00e9liminaire de Multi-Gig IEEE 802.3ch, dans une seule application &#8211; faisant de Keysight le premier \u00e0 proposer des tests de conformit\u00e9 pour IEEE 802.3ch.<\/p>\n<p><a href=\"http:\/\/www.keysight.com\/find\/automotive-backgrounder\">www.keysight.com\/find\/automotive-backgrounder<\/a>.<\/p>\n<p><a href=\"http:\/\/www.keysight.com\/%20\/t%20_blank\">www.keysight.com<\/a><\/p>\n<h3 class=\"title\"><a href=\"https:\/\/www.electronique-eci.com\/news\/keysight-technologies-accelere-les-flux-de-conception-de-simulation-et-de-verification-5g\">Keysight Technologies acc\u00e9l\u00e8re les flux de conception, de simulation et de v\u00e9rification 5G<\/a><\/h3>\n<h3 class=\"title\"><a href=\"https:\/\/www.electronique-eci.com\/news\/keysight-technologies-renforce-ses-services-dassistance-technique\">Keysight Technologies renforce ses services d&rsquo;assistance technique<\/a><\/h3>\n<h3 class=\"title\"><a href=\"https:\/\/www.electronique-eci.com\/news\/keysight-technologies-lance-un-nouvel-oscilloscope-signaux-mixtes-de-la-gamme-infiniium-mxr\">Keysight Technologies lance un nouvel oscilloscope \u00e0 signaux mixtes de la gamme Infiniium MXR<\/a><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Keysight Technologies, Inc. ajoute deux nouvelles solutions de test \u00e0 son offre automobile, en pleine expansion. Le simulateur de cible radar et le logiciel Advanced Automotive Ethernet ont \u00e9t\u00e9 con\u00e7us pour aider les ing\u00e9nieurs, les concepteurs et les industriels automobile \u00e0 d\u00e9velopper des produits performants pour am\u00e9liorer la s\u00e9curit\u00e9 dans toutes les conditions de conduite et permettre de faire \u00e9merger des syst\u00e8mes avanc\u00e9s d&rsquo;aide \u00e0 la conduite (ADAS).<\/p>\n","protected":false},"author":9,"featured_media":43691,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-43690","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Simulateur de radar \u00e0 cibles multiples et des solutions Ethern...<\/title>\n<meta name=\"description\" content=\"Keysight Technologies, Inc. ajoute deux nouvelles solutions de test \u00e0 son offre automobile, en pleine expansion. Le simulateur de cible radar et le logiciel...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/43690\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Simulateur de radar \u00e0 cibles multiples et des solutions Ethernet avanc\u00e9es pour v\u00e9hicules autonomes\" \/>\n<meta property=\"og:description\" content=\"Keysight Technologies, Inc. ajoute deux nouvelles solutions de test \u00e0 son offre automobile, en pleine expansion. Le simulateur de cible radar et le logiciel Advanced Automotive Ethernet ont \u00e9t\u00e9 con\u00e7us pour aider les ing\u00e9nieurs, les concepteurs et les industriels automobile \u00e0 d\u00e9velopper des produits performants pour am\u00e9liorer la s\u00e9curit\u00e9 dans toutes les conditions de conduite et permettre de faire \u00e9merger des syst\u00e8mes avanc\u00e9s d&#039;aide \u00e0 la conduite (ADAS).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/43690\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-05T07:31:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8847_keysight_technologies.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2063\" \/>\n\t<meta property=\"og:image:height\" content=\"1249\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/simulateur-de-radar-a-cibles-multiples-et-des-solutions-ethernet-avancees-pour-vehicules-autonomes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/simulateur-de-radar-a-cibles-multiples-et-des-solutions-ethernet-avancees-pour-vehicules-autonomes\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Simulateur de radar \u00e0 cibles multiples et des solutions Ethernet avanc\u00e9es pour v\u00e9hicules autonomes\",\"datePublished\":\"2020-10-05T07:31:44+00:00\",\"dateModified\":\"2020-10-05T07:31:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/simulateur-de-radar-a-cibles-multiples-et-des-solutions-ethernet-avancees-pour-vehicules-autonomes\/\"},\"wordCount\":632,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/simulateur-de-radar-a-cibles-multiples-et-des-solutions-ethernet-avancees-pour-vehicules-autonomes\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/simulateur-de-radar-a-cibles-multiples-et-des-solutions-ethernet-avancees-pour-vehicules-autonomes\/\",\"name\":\"Simulateur de radar \u00e0 cibles multiples et des solutions Ethernet avanc\u00e9es pour v\u00e9hicules autonomes -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2020-10-05T07:31:44+00:00\",\"dateModified\":\"2020-10-05T07:31:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/simulateur-de-radar-a-cibles-multiples-et-des-solutions-ethernet-avancees-pour-vehicules-autonomes\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/simulateur-de-radar-a-cibles-multiples-et-des-solutions-ethernet-avancees-pour-vehicules-autonomes\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/simulateur-de-radar-a-cibles-multiples-et-des-solutions-ethernet-avancees-pour-vehicules-autonomes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Simulateur de radar \u00e0 cibles multiples et des solutions Ethernet avanc\u00e9es pour v\u00e9hicules autonomes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Simulateur de radar \u00e0 cibles multiples et des solutions Ethern...","description":"Keysight Technologies, Inc. ajoute deux nouvelles solutions de test \u00e0 son offre automobile, en pleine expansion. Le simulateur de cible radar et le logiciel...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/43690\/","og_locale":"fr_FR","og_type":"article","og_title":"Simulateur de radar \u00e0 cibles multiples et des solutions Ethernet avanc\u00e9es pour v\u00e9hicules autonomes","og_description":"Keysight Technologies, Inc. ajoute deux nouvelles solutions de test \u00e0 son offre automobile, en pleine expansion. Le simulateur de cible radar et le logiciel Advanced Automotive Ethernet ont \u00e9t\u00e9 con\u00e7us pour aider les ing\u00e9nieurs, les concepteurs et les industriels automobile \u00e0 d\u00e9velopper des produits performants pour am\u00e9liorer la s\u00e9curit\u00e9 dans toutes les conditions de conduite et permettre de faire \u00e9merger des syst\u00e8mes avanc\u00e9s d'aide \u00e0 la conduite (ADAS).","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/43690\/","og_site_name":"EENewsEurope","article_published_time":"2020-10-05T07:31:44+00:00","og_image":[{"width":2063,"height":1249,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8847_keysight_technologies.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/simulateur-de-radar-a-cibles-multiples-et-des-solutions-ethernet-avancees-pour-vehicules-autonomes\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/simulateur-de-radar-a-cibles-multiples-et-des-solutions-ethernet-avancees-pour-vehicules-autonomes\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Simulateur de radar \u00e0 cibles multiples et des solutions Ethernet avanc\u00e9es pour v\u00e9hicules autonomes","datePublished":"2020-10-05T07:31:44+00:00","dateModified":"2020-10-05T07:31:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/simulateur-de-radar-a-cibles-multiples-et-des-solutions-ethernet-avancees-pour-vehicules-autonomes\/"},"wordCount":632,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/simulateur-de-radar-a-cibles-multiples-et-des-solutions-ethernet-avancees-pour-vehicules-autonomes\/","url":"https:\/\/www.ecinews.fr\/fr\/simulateur-de-radar-a-cibles-multiples-et-des-solutions-ethernet-avancees-pour-vehicules-autonomes\/","name":"Simulateur de radar \u00e0 cibles multiples et des solutions Ethernet avanc\u00e9es pour v\u00e9hicules autonomes -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2020-10-05T07:31:44+00:00","dateModified":"2020-10-05T07:31:44+00:00","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/simulateur-de-radar-a-cibles-multiples-et-des-solutions-ethernet-avancees-pour-vehicules-autonomes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/simulateur-de-radar-a-cibles-multiples-et-des-solutions-ethernet-avancees-pour-vehicules-autonomes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/simulateur-de-radar-a-cibles-multiples-et-des-solutions-ethernet-avancees-pour-vehicules-autonomes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Simulateur de radar \u00e0 cibles multiples et des solutions Ethernet avanc\u00e9es pour v\u00e9hicules autonomes"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/43690"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=43690"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/43690\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/43691"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=43690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=43690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=43690"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=43690"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=43690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}