{"id":434023,"date":"2023-10-07T15:13:35","date_gmt":"2023-10-07T13:13:35","guid":{"rendered":"https:\/\/www.eenewseurope.com\/?p=434023"},"modified":"2023-10-07T15:17:49","modified_gmt":"2023-10-07T13:17:49","slug":"renault-volvo-et-cma-cgm-creent-une-jv-pour-des-ve-fourgonnettes","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/renault-volvo-et-cma-cgm-creent-une-jv-pour-des-ve-fourgonnettes\/","title":{"rendered":"Renault, Volvo et CMA CGM cr\u00e9ent une JV pour des VE fourgonnettes"},"content":{"rendered":"<h3>Renault, Volvo et CMA CGM s&rsquo;associent dans le cadre d&rsquo;une coentreprise de 750 Millions d&rsquo;euros pour d\u00e9velopper un nouveau fourgon \u00e9lectrique dot\u00e9 d&rsquo;une architecture d\u00e9finie par logiciel.<\/h3>\n<p>Les v\u00e9hicules seront construits sur une nouvelle plate-forme 800V LCV enti\u00e8rement \u00e9lectrique qui offrira une grande modularit\u00e9 pour diff\u00e9rents types de carrosserie \u00e0 faible co\u00fbt. L&rsquo;architecture d\u00e9finie par logiciel permettra la connectivit\u00e9 et diff\u00e9rentes capacit\u00e9s de batterie.<\/p>\n<p>Le groupe Renault et le groupe Volvo, ont sign\u00e9 des accords contraignants en vue de cr\u00e9er une nouvelle entreprise avec une participation de 50 %. Tous deux investiront 300 millions d&rsquo;euros au cours des trois prochaines ann\u00e9es. Le fonds d&rsquo;investissement de CMA CGM a \u00e9galement sign\u00e9 une lettre d&rsquo;intention non contraignante avec le groupe Renault et le groupe Volvo, investissant 120 millions d&rsquo;euros par l&rsquo;interm\u00e9diaire de PULSE, son fonds \u00e9nerg\u00e9tique d\u00e9di\u00e9 aux secteurs du transport et de la logistique.<\/p>\n<p>La nouvelle soci\u00e9t\u00e9 sera bas\u00e9e en France et devrait d\u00e9marrer au d\u00e9but de l&rsquo;ann\u00e9e 2024. Le d\u00e9but de la production est pr\u00e9vu pour 2026.<\/p>\n<p>D&rsquo;ici 2030, le march\u00e9 europ\u00e9en des fourgonnettes \u00e9lectrifi\u00e9es triplera, ce qui promet une \u00e9norme opportunit\u00e9 pour un tout nouveau v\u00e9hicule l\u00e9ger \u00e9lectrique, selon Renault, en particulier pour les secteurs en plein essor du commerce \u00e9lectronique et de la location.<\/p>\n<ul>\n<li><a href=\"https:\/\/www.eenewseurope.com\/en\/renault-geely-to-set-up-global-powertrain-joint-venture-in-the-uk\/\">Renault et Geely vont cr\u00e9er une entreprise commune mondiale dans le domaine des groupes motopropulseurs<\/a><\/li>\n<li><a href=\"https:\/\/www.eenewseurope.com\/en\/renault-plans-extensive-reorganisation-and-massive-digitisation\/\">Renault pr\u00e9voit une vaste r\u00e9organisation<\/a><\/li>\n<li><a href=\"https:\/\/www.eenewseurope.com\/en\/renault-shakes-up-its-development-and-procurement\/\">Renault r\u00e9organise ses activit\u00e9s de d\u00e9veloppement et d&rsquo;approvisionnement<\/a><\/li>\n<\/ul>\n<h3>Une soci\u00e9t\u00e9 ind\u00e9pendante<\/h3>\n<p>La nouvelle soci\u00e9t\u00e9 sera totalement ind\u00e9pendante, combinant l&rsquo;agilit\u00e9 d&rsquo;une start-up avec la cha\u00eene d&rsquo;approvisionnement et les relations des partenaires. Le groupe Renault et le groupe Volvo ont l&rsquo;intention de partager les investissements dans la recherche et le d\u00e9veloppement et de faire b\u00e9n\u00e9ficier la nouvelle soci\u00e9t\u00e9 projet\u00e9e du savoir-faire, des services et de l&#8217;empreinte industrielle existants.<\/p>\n<p>En tant qu&rsquo;acteur mondial sur tous les segments de la cha\u00eene d&rsquo;approvisionnement, CMA CGM a l&rsquo;intention d&rsquo;aider la nouvelle soci\u00e9t\u00e9 \u00e0 construire des solutions appropri\u00e9es qui peuvent r\u00e9pondre aux besoins de tous les acteurs du transport et de la cha\u00eene d&rsquo;approvisionnement, sur la base de solutions efficaces de bout en bout.<\/p>\n<p>\u00ab\u00a0Nous sommes ravis de franchir une nouvelle \u00e9tape dans notre parcours vers des solutions de transport durables gr\u00e2ce \u00e0 la cr\u00e9ation pr\u00e9vue d&rsquo;une nouvelle soci\u00e9t\u00e9. Le groupe Volvo souhaite continuer \u00e0 offrir \u00e0 ses clients des solutions de transport compl\u00e8tes qui les aident \u00e0 d\u00e9carboner leur cha\u00eene de valeur. Nous constatons une demande croissante de transports urbains propres, efficaces et s\u00fbrs, et le partenariat et la collaboration sont essentiels pour y parvenir\u00a0\u00bb, a d\u00e9clar\u00e9 Martin Lundstedt, pr\u00e9sident et directeur g\u00e9n\u00e9ral de Volvo Group.<\/p>\n<ul>\n<li><a href=\"https:\/\/www.eenewseurope.com\/en\/volvo-cars-takes-full-ownership-of-its-driverless-software-subsidiary\/\">Volvo Cars devient propri\u00e9taire \u00e0 part enti\u00e8re de son entreprise de logiciels sans conducteur<\/a><\/li>\n<li><a href=\"https:\/\/www.eenewseurope.com\/en\/volvo-opens-proving-ground-for-next-gen-car-technology\/\">Volvo ouvre un terrain d&rsquo;essai pour la technologie automobile de la prochaine g\u00e9n\u00e9ration<\/a><\/li>\n<\/ul>\n<p>\u00a0\u00bb L&rsquo;\u00e9lectrification et la num\u00e9risation ouvrent la voie \u00e0 une r\u00e9volution du march\u00e9 des v\u00e9hicules utilitaires. Le Groupe Renault entend mener cette transformation tout en assurant une cr\u00e9ation de valeur robuste et efficace. Aujourd&rsquo;hui, nous sommes tr\u00e8s fiers de nous engager dans cette voie avec le Groupe Volvo pour apporter le meilleur des solutions \u00e0 nos clients professionnels. Nous nous r\u00e9jouissons \u00e9galement de l&rsquo;arriv\u00e9e de CMA CGM au sein de la soci\u00e9t\u00e9. La nouvelle soci\u00e9t\u00e9 est la combinaison in\u00e9gal\u00e9e des actifs compl\u00e9mentaires de trois champions : un constructeur de camions de premier plan, expert en services sur mesure, un champion des cha\u00eenes d&rsquo;approvisionnement mondiales, et un pionnier europ\u00e9en des v\u00e9hicules \u00e9lectriques et un leader des v\u00e9hicules utilitaires l\u00e9gers. Tous les ingr\u00e9dients sont r\u00e9unis pour cr\u00e9er quelque chose de vraiment unique\u00a0\u00bb, a d\u00e9clar\u00e9 Luca de Meo, PDG du Groupe Renault.<\/p>\n<p>\u00ab\u00a0En tant que leader du transport et de la logistique, le Groupe CMA CGM est fier de s&rsquo;associer \u00e0 un grand constructeur automobile europ\u00e9en et \u00e0 un grand constructeur mondial de camions, le Groupe Renault et le Groupe Volvo, pour cr\u00e9er cette nouvelle soci\u00e9t\u00e9 de fourgonnettes \u00e9lectriques. Il s&rsquo;agit d&rsquo;un partenariat complet et innovant : non seulement nous investissons dans ce projet, mais nous apporterons \u00e9galement notre savoir-faire et notre expertise pour assurer la logistique amont et aval, tandis que certains de ces v\u00e9hicules pourraient \u00e0 terme \u00eatre utilis\u00e9s pour d\u00e9carboner notre flotte. A travers ce nouvel investissement de notre fonds PULSE dans la mobilit\u00e9 \u00e9lectrique, nous poursuivons notre engagement d&rsquo;acc\u00e9l\u00e9rer la d\u00e9carbonation de notre activit\u00e9 et de notre secteur \u00ab\u00a0, d\u00e9clare Rodolphe Saad\u00e9, Pr\u00e9sident-directeur g\u00e9n\u00e9ral du Groupe CMA CGM.<\/p>\n<p><a title=\"www.renaultgroup.com\" href=\"http:\/\/www.renaultgroup.com\" target=\"_blank\" rel=\"noopener\">www.renaultgroup.com<\/a> <a href=\"http:\/\/www.renaultgroup.com\">;<\/a> <a href=\"http:\/\/www.volvogroup.com\">www.volvogroup.com<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Renault, Volvo et CMA CGM s&rsquo;associent dans le cadre d&rsquo;une coentreprise de 750 Millions d&rsquo;euros pour d\u00e9velopper un nouveau fourgon \u00e9lectrique dot\u00e9 d&rsquo;une architecture d\u00e9finie par logiciel. Les v\u00e9hicules seront construits sur une nouvelle plate-forme 800V LCV enti\u00e8rement \u00e9lectrique qui offrira une grande modularit\u00e9 pour diff\u00e9rents types de carrosserie \u00e0 faible co\u00fbt. L&rsquo;architecture d\u00e9finie par [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":433949,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[880],"tags":[1640,2741],"domains":[47],"ppma_author":[1153,3640],"class_list":["post-434023","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-economiques","tag-automobile","tag-ve","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Renault, Volvo et CMA CGM cr\u00e9ent une JV pour des VE fourgonnet...<\/title>\n<meta name=\"description\" content=\"Une coentreprise Renault et Volvo va d\u00e9velopper une camionnette \u00e9lectrique de 800 V d\u00e9finie par logiciel, avec plusieurs types de carrosserie\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/434023\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Renault, Volvo et CMA CGM cr\u00e9ent une JV pour des VE fourgonnettes\" \/>\n<meta property=\"og:description\" content=\"Une coentreprise Renault et Volvo va d\u00e9velopper une camionnette \u00e9lectrique de 800 V d\u00e9finie par logiciel, avec plusieurs types de carrosserie\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/434023\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-07T13:13:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-07T13:17:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2023\/10\/renault-electric-van.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"375\" \/>\n\t<meta property=\"og:image:height\" content=\"211\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"A Delapalisse, Nick Flaherty\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"A Delapalisse\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/renault-volvo-et-cma-cgm-creent-une-jv-pour-des-ve-fourgonnettes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/renault-volvo-et-cma-cgm-creent-une-jv-pour-des-ve-fourgonnettes\/\"},\"author\":{\"name\":\"A Delapalisse\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/0aa2cfb0bd8949724a68cbac8d8321b4\"},\"headline\":\"Renault, Volvo et CMA CGM cr\u00e9ent une JV pour des VE fourgonnettes\",\"datePublished\":\"2023-10-07T13:13:35+00:00\",\"dateModified\":\"2023-10-07T13:17:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/renault-volvo-et-cma-cgm-creent-une-jv-pour-des-ve-fourgonnettes\/\"},\"wordCount\":848,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"keywords\":[\"Automobile\",\"VE\"],\"articleSection\":[\"Actualit\u00e9s \u00e9conomiques\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/renault-volvo-et-cma-cgm-creent-une-jv-pour-des-ve-fourgonnettes\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/renault-volvo-et-cma-cgm-creent-une-jv-pour-des-ve-fourgonnettes\/\",\"name\":\"Renault, Volvo et CMA CGM cr\u00e9ent une JV pour des VE fourgonnettes -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2023-10-07T13:13:35+00:00\",\"dateModified\":\"2023-10-07T13:17:49+00:00\",\"description\":\"Une coentreprise Renault et Volvo va d\u00e9velopper une camionnette \u00e9lectrique de 800 V d\u00e9finie par logiciel, avec plusieurs types de carrosserie\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/renault-volvo-et-cma-cgm-creent-une-jv-pour-des-ve-fourgonnettes\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/renault-volvo-et-cma-cgm-creent-une-jv-pour-des-ve-fourgonnettes\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/renault-volvo-et-cma-cgm-creent-une-jv-pour-des-ve-fourgonnettes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Renault, Volvo et CMA CGM cr\u00e9ent une JV pour des VE fourgonnettes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/0aa2cfb0bd8949724a68cbac8d8321b4\",\"name\":\"A Delapalisse\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/211ac42237c2e9683c0964086c393cb4\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ad45a8c5da24bc9c7c4940dd1c48a695?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ad45a8c5da24bc9c7c4940dd1c48a695?s=96&d=mm&r=g\",\"caption\":\"A Delapalisse\"},\"sameAs\":[\"http:\/\/ECI\"]}]}<\/script>","yoast_head_json":{"title":"Renault, Volvo et CMA CGM cr\u00e9ent une JV pour des VE fourgonnet...","description":"Une coentreprise Renault et Volvo va d\u00e9velopper une camionnette \u00e9lectrique de 800 V d\u00e9finie par logiciel, avec plusieurs types de carrosserie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/434023\/","og_locale":"fr_FR","og_type":"article","og_title":"Renault, Volvo et CMA CGM cr\u00e9ent une JV pour des VE fourgonnettes","og_description":"Une coentreprise Renault et Volvo va d\u00e9velopper une camionnette \u00e9lectrique de 800 V d\u00e9finie par logiciel, avec plusieurs types de carrosserie","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/434023\/","og_site_name":"EENewsEurope","article_published_time":"2023-10-07T13:13:35+00:00","article_modified_time":"2023-10-07T13:17:49+00:00","og_image":[{"width":375,"height":211,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2023\/10\/renault-electric-van.jpg","type":"image\/jpeg"}],"author":"A Delapalisse, Nick Flaherty","twitter_card":"summary_large_image","twitter_misc":{"Written by":"A Delapalisse","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/renault-volvo-et-cma-cgm-creent-une-jv-pour-des-ve-fourgonnettes\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/renault-volvo-et-cma-cgm-creent-une-jv-pour-des-ve-fourgonnettes\/"},"author":{"name":"A Delapalisse","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/0aa2cfb0bd8949724a68cbac8d8321b4"},"headline":"Renault, Volvo et CMA CGM cr\u00e9ent une JV pour des VE fourgonnettes","datePublished":"2023-10-07T13:13:35+00:00","dateModified":"2023-10-07T13:17:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/renault-volvo-et-cma-cgm-creent-une-jv-pour-des-ve-fourgonnettes\/"},"wordCount":848,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"keywords":["Automobile","VE"],"articleSection":["Actualit\u00e9s \u00e9conomiques"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/renault-volvo-et-cma-cgm-creent-une-jv-pour-des-ve-fourgonnettes\/","url":"https:\/\/www.ecinews.fr\/fr\/renault-volvo-et-cma-cgm-creent-une-jv-pour-des-ve-fourgonnettes\/","name":"Renault, Volvo et CMA CGM cr\u00e9ent une JV pour des VE fourgonnettes -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2023-10-07T13:13:35+00:00","dateModified":"2023-10-07T13:17:49+00:00","description":"Une coentreprise Renault et Volvo va d\u00e9velopper une camionnette \u00e9lectrique de 800 V d\u00e9finie par logiciel, avec plusieurs types de carrosserie","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/renault-volvo-et-cma-cgm-creent-une-jv-pour-des-ve-fourgonnettes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/renault-volvo-et-cma-cgm-creent-une-jv-pour-des-ve-fourgonnettes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/renault-volvo-et-cma-cgm-creent-une-jv-pour-des-ve-fourgonnettes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Renault, Volvo et CMA CGM cr\u00e9ent une JV pour des VE fourgonnettes"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/0aa2cfb0bd8949724a68cbac8d8321b4","name":"A Delapalisse","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/211ac42237c2e9683c0964086c393cb4","url":"https:\/\/secure.gravatar.com\/avatar\/ad45a8c5da24bc9c7c4940dd1c48a695?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad45a8c5da24bc9c7c4940dd1c48a695?s=96&d=mm&r=g","caption":"A Delapalisse"},"sameAs":["http:\/\/ECI"]}]}},"authors":[{"term_id":1153,"user_id":34,"is_guest":0,"slug":"adelapalisse","display_name":"A Delapalisse","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/ad45a8c5da24bc9c7c4940dd1c48a695?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""},{"term_id":3640,"user_id":0,"is_guest":1,"slug":"nick-flaherty","display_name":"Nick Flaherty","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/434023"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=434023"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/434023\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/433949"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=434023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=434023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=434023"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=434023"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=434023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}