{"id":428322,"date":"2023-07-28T17:43:21","date_gmt":"2023-07-28T15:43:21","guid":{"rendered":"https:\/\/www.eenewseurope.com\/?p=428322"},"modified":"2023-07-31T00:01:36","modified_gmt":"2023-07-30T22:01:36","slug":"les-livraisons-de-wafers-de-silicium-sont-en-hausse-selon-semi","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/les-livraisons-de-wafers-de-silicium-sont-en-hausse-selon-semi\/","title":{"rendered":"Des livraisons de wafers de silicium en hausse"},"content":{"rendered":"<h2>Apr\u00e8s deux trimestres de baisse s\u00e9quentielle, les livraisons de plaquettes de silicium ont augment\u00e9 au deuxi\u00e8me trimestre 23, selon le groupe des fabricants de silicium (Silicon Manufacturers Group) au sein de l&rsquo;organisme industriel SEMI<\/h2>\n<p>Les livraisons mondiales de wafers ont augment\u00e9 de 2,0 % en glissement trimestriel pour atteindre 3 331 millions de pouces carr\u00e9s au deuxi\u00e8me trimestre de l&rsquo;ann\u00e9e 2023. Toutefois, apr\u00e8s deux trimestres de baisse s\u00e9quentielle, ce chiffre est inf\u00e9rieur de 10,1 % aux 3 704 millions de pouces carr\u00e9s de silicium exp\u00e9di\u00e9s au deuxi\u00e8me trimestre de l&rsquo;ann\u00e9e 22.<\/p>\n<p>Mais cela indique tout de m\u00eame un point d&rsquo;inflexion du march\u00e9 avec une augmentation saisonni\u00e8re des livraisons au 3e trimestre 23. L&rsquo;augmentation s\u00e9quentielle du march\u00e9 des puces d\u00e9pend des prix de vente moyens et de la capacit\u00e9 de production des wafers dans les usines.<\/p>\n<div id=\"attachment_428075\" style=\"width: 610px\" class=\"wp-caption alignleft\"><img decoding=\"async\" aria-describedby=\"caption-attachment-428075\" class=\"size-full wp-image-428075 lazyload\" data-src=\"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/2023\/07\/SMGtable600.jpg\" alt=\"\" width=\"600\" height=\"43\" data-srcset=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2023\/07\/SMGtable600.jpg 600w, https:\/\/www.ecinews.fr\/wp-content\/uploads\/2023\/07\/SMGtable600-300x22.jpg 300w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/43;\" \/><p id=\"caption-attachment-428075\" class=\"wp-caption-text\"><em><strong>Livraisons trimestrielles de wafers de silicium pour les applications semiconducteurs uniquement. Source : SEMI. (Comprend les wafers de silicium polies, y compris ceux utilis\u00e9s comme wafers de test vierges, ainsi que les wafers de silicium \u00e9pitaxi\u00e9es, et les wafers de silicium non polis exp\u00e9di\u00e9s par les fabricants de wafers aux utilisateurs finaux).<\/strong><\/em><\/p><\/div>\n<p>\u00ab\u00a0L&rsquo;industrie des semiconducteurs continue d&rsquo;\u00eatre confront\u00e9e \u00e0 des stocks exc\u00e9dentaires dans divers segments du march\u00e9, ce qui oblige les usines \u00e0 fonctionner en dessous de leur capacit\u00e9 maximale\u00a0\u00bb, a d\u00e9clar\u00e9 Anna-Riikka Vuorikari-Antikainen, pr\u00e9sidente de SEMI SMG et directrice commerciale du fournisseur de wafers de silicium Okmetic Oy. \u00ab\u00a0En cons\u00e9quence, les livraisons de wafers de silicium sont en retard par rapport au pic de 2022. Les livraisons de wafers du deuxi\u00e8me trimestre sont rest\u00e9s stables d&rsquo;un trimestre \u00e0 l&rsquo;autre, le 300 mm affichant seul une croissance trimestrielle parmi toutes les tailles de wafers\u00a0\u00bb.<\/p>\n<h4>Liens et articles connexes :<\/h4>\n<p><a href=\"http:\/\/www.semi.org\">www.semi.org<\/a><\/p>\n<h4>Articles de presse :<\/h4>\n<p><a href=\"https:\/\/www.eenewseurope.com\/en\/china-is-not-backing-down-on-memory-says-yole\/\">La Chine ne recule pas devant la m\u00e9moire, selon Yole <\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s deux trimestres de baisse s\u00e9quentielle, les livraisons de plaquettes de silicium ont augment\u00e9 au deuxi\u00e8me trimestre 23, selon le groupe des fabricants de silicium (Silicon Manufacturers Group) au sein de l&rsquo;organisme industriel SEMI Les livraisons mondiales de wafers ont augment\u00e9 de 2,0 % en glissement trimestriel pour atteindre 3 331 millions de pouces carr\u00e9s [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":408510,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[880,888],"tags":[1558,1626],"domains":[47],"ppma_author":[1153,3631],"class_list":["post-428322","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-economiques","category-marche","tag-semiconducteurs","tag-wafer-2","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Les livraisons de plaques de silicium sont en hausse, selon SEMI ...<\/title>\n<meta name=\"description\" content=\"Apr\u00e8s deux trimestres de baisse s\u00e9quentielle, les livraisons de plaquettes de silicium ont augment\u00e9 au deuxi\u00e8me trimestre de l&#039;ann\u00e9e 23, selon le...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/428322\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Des livraisons de wafers de silicium en hausse\" \/>\n<meta property=\"og:description\" content=\"Apr\u00e8s deux trimestres de baisse s\u00e9quentielle, les livraisons de plaquettes de silicium ont augment\u00e9 au deuxi\u00e8me trimestre de l&#039;ann\u00e9e 23, selon le Silicon Manufacturers Group.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/428322\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-28T15:43:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-30T22:01:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/2022\/12\/Wafer300_630.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"630\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"A Delapalisse, Peter Clarke\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"A Delapalisse\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/les-livraisons-de-wafers-de-silicium-sont-en-hausse-selon-semi\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/les-livraisons-de-wafers-de-silicium-sont-en-hausse-selon-semi\/\"},\"author\":{\"name\":\"A Delapalisse\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/0aa2cfb0bd8949724a68cbac8d8321b4\"},\"headline\":\"Des livraisons de wafers de silicium en hausse\",\"datePublished\":\"2023-07-28T15:43:21+00:00\",\"dateModified\":\"2023-07-30T22:01:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/les-livraisons-de-wafers-de-silicium-sont-en-hausse-selon-semi\/\"},\"wordCount\":336,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"keywords\":[\"Semiconducteurs\",\"wafer\"],\"articleSection\":[\"Actualit\u00e9s \u00e9conomiques\",\"March\u00e9\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/les-livraisons-de-wafers-de-silicium-sont-en-hausse-selon-semi\/\",\"url\":\"https:\/\/www.eenewseurope.com\/fr\/les-livraisons-de-wafers-de-silicium-sont-en-hausse-selon-semi\/\",\"name\":\"Les livraisons de plaques de silicium sont en hausse, selon SEMI\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2023-07-28T15:43:21+00:00\",\"dateModified\":\"2023-07-30T22:01:36+00:00\",\"description\":\"Apr\u00e8s deux trimestres de baisse s\u00e9quentielle, les livraisons de plaquettes de silicium ont augment\u00e9 au deuxi\u00e8me trimestre de l'ann\u00e9e 23, selon le Silicon Manufacturers Group.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/les-livraisons-de-wafers-de-silicium-sont-en-hausse-selon-semi\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eenewseurope.com\/fr\/les-livraisons-de-wafers-de-silicium-sont-en-hausse-selon-semi\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/les-livraisons-de-wafers-de-silicium-sont-en-hausse-selon-semi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Des livraisons de wafers de silicium en hausse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/0aa2cfb0bd8949724a68cbac8d8321b4\",\"name\":\"A Delapalisse\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/211ac42237c2e9683c0964086c393cb4\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ad45a8c5da24bc9c7c4940dd1c48a695?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ad45a8c5da24bc9c7c4940dd1c48a695?s=96&d=mm&r=g\",\"caption\":\"A Delapalisse\"},\"sameAs\":[\"http:\/\/ECI\"]}]}<\/script>","yoast_head_json":{"title":"Les livraisons de plaques de silicium sont en hausse, selon SEMI ...","description":"Apr\u00e8s deux trimestres de baisse s\u00e9quentielle, les livraisons de plaquettes de silicium ont augment\u00e9 au deuxi\u00e8me trimestre de l'ann\u00e9e 23, selon le...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/428322\/","og_locale":"fr_FR","og_type":"article","og_title":"Des livraisons de wafers de silicium en hausse","og_description":"Apr\u00e8s deux trimestres de baisse s\u00e9quentielle, les livraisons de plaquettes de silicium ont augment\u00e9 au deuxi\u00e8me trimestre de l'ann\u00e9e 23, selon le Silicon Manufacturers Group.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/428322\/","og_site_name":"EENewsEurope","article_published_time":"2023-07-28T15:43:21+00:00","article_modified_time":"2023-07-30T22:01:36+00:00","og_image":[{"width":630,"height":400,"url":"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/2022\/12\/Wafer300_630.jpg","type":"image\/jpeg"}],"author":"A Delapalisse, Peter Clarke","twitter_card":"summary_large_image","twitter_misc":{"Written by":"A Delapalisse","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eenewseurope.com\/fr\/les-livraisons-de-wafers-de-silicium-sont-en-hausse-selon-semi\/#article","isPartOf":{"@id":"https:\/\/www.eenewseurope.com\/fr\/les-livraisons-de-wafers-de-silicium-sont-en-hausse-selon-semi\/"},"author":{"name":"A Delapalisse","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/0aa2cfb0bd8949724a68cbac8d8321b4"},"headline":"Des livraisons de wafers de silicium en hausse","datePublished":"2023-07-28T15:43:21+00:00","dateModified":"2023-07-30T22:01:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eenewseurope.com\/fr\/les-livraisons-de-wafers-de-silicium-sont-en-hausse-selon-semi\/"},"wordCount":336,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"keywords":["Semiconducteurs","wafer"],"articleSection":["Actualit\u00e9s \u00e9conomiques","March\u00e9"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.eenewseurope.com\/fr\/les-livraisons-de-wafers-de-silicium-sont-en-hausse-selon-semi\/","url":"https:\/\/www.eenewseurope.com\/fr\/les-livraisons-de-wafers-de-silicium-sont-en-hausse-selon-semi\/","name":"Les livraisons de plaques de silicium sont en hausse, selon SEMI","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2023-07-28T15:43:21+00:00","dateModified":"2023-07-30T22:01:36+00:00","description":"Apr\u00e8s deux trimestres de baisse s\u00e9quentielle, les livraisons de plaquettes de silicium ont augment\u00e9 au deuxi\u00e8me trimestre de l'ann\u00e9e 23, selon le Silicon Manufacturers Group.","breadcrumb":{"@id":"https:\/\/www.eenewseurope.com\/fr\/les-livraisons-de-wafers-de-silicium-sont-en-hausse-selon-semi\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eenewseurope.com\/fr\/les-livraisons-de-wafers-de-silicium-sont-en-hausse-selon-semi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eenewseurope.com\/fr\/les-livraisons-de-wafers-de-silicium-sont-en-hausse-selon-semi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Des livraisons de wafers de silicium en hausse"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/0aa2cfb0bd8949724a68cbac8d8321b4","name":"A Delapalisse","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/211ac42237c2e9683c0964086c393cb4","url":"https:\/\/secure.gravatar.com\/avatar\/ad45a8c5da24bc9c7c4940dd1c48a695?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad45a8c5da24bc9c7c4940dd1c48a695?s=96&d=mm&r=g","caption":"A Delapalisse"},"sameAs":["http:\/\/ECI"]}]}},"authors":[{"term_id":1153,"user_id":34,"is_guest":0,"slug":"adelapalisse","display_name":"A Delapalisse","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/ad45a8c5da24bc9c7c4940dd1c48a695?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""},{"term_id":3631,"user_id":0,"is_guest":1,"slug":"peter-clarke","display_name":"Peter Clarke","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/428322"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=428322"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/428322\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/408510"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=428322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=428322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=428322"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=428322"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=428322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}