{"id":427956,"date":"2023-07-25T10:29:16","date_gmt":"2023-07-25T08:29:16","guid":{"rendered":"https:\/\/www.eenewseurope.com\/?p=427956"},"modified":"2023-07-25T10:36:20","modified_gmt":"2023-07-25T08:36:20","slug":"sony-augmente-sa-part-de-marche-dans-les-capteurs-dimage-cmos","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/sony-augmente-sa-part-de-marche-dans-les-capteurs-dimage-cmos\/","title":{"rendered":"Sony augmente sa part de march\u00e9 dans les capteurs d&rsquo;image CMOS"},"content":{"rendered":"<h2>Selon Yole Group, le march\u00e9 des capteurs d&rsquo;images CMOS repr\u00e9sentait 21,29 milliards de dollars en 2022, chiffre stable par rapport \u00e0 2021 et refl\u00e9tant les difficult\u00e9s du march\u00e9 des smartphones.<\/h2>\n<p>La stagnation du march\u00e9 refl\u00e8te la faiblesse du secteur de la t\u00e9l\u00e9phonie mobile, qui repr\u00e9sente environ 63 % du march\u00e9. L&rsquo;analyste de march\u00e9 pr\u00e9voit un taux de croissance annuel compos\u00e9 de 5,1 % entre 2022 et 2028.<\/p>\n<div id=\"attachment_427868\" style=\"width: 610px\" class=\"wp-caption alignleft\"><img decoding=\"async\" aria-describedby=\"caption-attachment-427868\" class=\"size-full wp-image-427868 lazyload\" data-src=\"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/2023\/07\/CIS2022_600.jpg\" alt=\"\" width=\"600\" height=\"362\" data-srcset=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2023\/07\/CIS2022_600.jpg 600w, https:\/\/www.ecinews.fr\/wp-content\/uploads\/2023\/07\/CIS2022_600-300x181.jpg 300w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/362;\" \/><p id=\"caption-attachment-427868\" class=\"wp-caption-text\"><em><strong>le march\u00e9 des capteurs d&rsquo;images CMOS et leur part de march\u00e9 en 2021 et 2022. Source : Yole Group : Groupe Yole.<\/strong><\/em><\/p><\/div>\n<p>Sony a augment\u00e9 sa part de march\u00e9 \u00e0 42 % en 2022, contre environ 39 % en 2021. Pendant ce temps, Samsung et Omnivision ont perdu des parts de march\u00e9. L&rsquo;augmentation de la part de Sony refl\u00e8te \u00e9galement son offre plus diversifi\u00e9e en mati\u00e8re de capteurs d&rsquo;images CMOS. Les cinq premiers fournisseurs restent Sony, Samsung, Omnivision, STMicroelectronics et OnSemi.<\/p>\n<p>Cependant, la part des smartphones sur le march\u00e9 des capteurs d&rsquo;image CMOS ne b\u00e9n\u00e9ficiera que d&rsquo;un taux de croissance annuel moyen de 3,7 % sur la p\u00e9riode 2022-2028, estime Yole, ce qui signifie qu&rsquo;elle perdra progressivement des parts de march\u00e9. Yole a d\u00e9clar\u00e9 que 2022 a montr\u00e9 qu&rsquo;une transformation est en cours dans la structure du march\u00e9 avec une croissance du segment automobile et une augmentation du prix de vente moyen des capteurs.<\/p>\n<p>OnSemi a connu une ann\u00e9e 2022 exceptionnelle, doublant presque sa part de march\u00e9 pour atteindre 6 % et se classer cinqui\u00e8me, gr\u00e2ce \u00e0 son exposition aux march\u00e9s de l&rsquo;automobile et de l&rsquo;industrie. Les fournisseurs chinois GalaxyCore et SmartSens se sont repli\u00e9s, apparemment en raison de la d\u00e9sinflation des march\u00e9s des cam\u00e9ras mobiles et de s\u00e9curit\u00e9 bas de gamme.<\/p>\n<p>Les fournisseurs chinois de capteurs d&rsquo;image chercheront \u00e0 r\u00e9duire leur exposition \u00e0 ces march\u00e9s et \u00e0 gagner des parts de march\u00e9 sur ceux qui sont florissants et qui offrent une valeur et un ASP plus \u00e9lev\u00e9s : l&rsquo;automobile et l&rsquo;industrie, a d\u00e9clar\u00e9 Yole.<\/p>\n<h4>Liens et articles connexes :<\/h4>\n<p><a href=\"http:\/\/www.yolegroup.com\">www.yolegroup.com<\/a><\/p>\n<h4>Articles de presse :<\/h4>\n<p><a href=\"https:\/\/www.eenewseurope.com\/en\/cmos-image-sensor-manufacturing-to-grow-13-percent-in-2022\/\">La fabrication de capteurs d&rsquo;images CMOS devrait cro\u00eetre de 13 % en 2022 <\/a><\/p>\n<p><a href=\"https:\/\/www.eenewseurope.com\/en\/sony-maintains-lead-in-smartphone-image-sensor-market\/\">Sony maintient sa position de leader sur le march\u00e9 des capteurs d&rsquo;images pour smartphones <\/a><\/p>\n<p class=\"title\"><a href=\"https:\/\/www.eenewseurope.com\/en\/cmos-image-sensor-market-to-rebound-through-2025\/\">Le march\u00e9 des capteurs d&rsquo;images CMOS va se redresser jusqu&rsquo;en 2025<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Selon Yole Group, le march\u00e9 des capteurs d&rsquo;images CMOS repr\u00e9sentait 21,29 milliards de dollars en 2022, chiffre stable par rapport \u00e0 2021 et refl\u00e9tant les difficult\u00e9s du march\u00e9 des smartphones. La stagnation du march\u00e9 refl\u00e8te la faiblesse du secteur de la t\u00e9l\u00e9phonie mobile, qui repr\u00e9sente environ 63 % du march\u00e9. L&rsquo;analyste de march\u00e9 pr\u00e9voit un [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":157539,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[880,888],"tags":[1787,2327],"domains":[47],"ppma_author":[1153,3631],"class_list":["post-427956","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-economiques","category-marche","tag-capteur-dimages","tag-marche","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Sony augmente sa part de march\u00e9 des capteurs d&#039;image CMOS ...<\/title>\n<meta name=\"description\" content=\"Le march\u00e9 des capteurs d&#039;images CMOS repr\u00e9sentait $21,29 milliards de dollars en 2022, un chiffre stable par rapport \u00e0 2021.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/427956\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sony augmente sa part de march\u00e9 dans les capteurs d&#039;image CMOS\" \/>\n<meta property=\"og:description\" content=\"Le march\u00e9 des capteurs d&#039;images CMOS repr\u00e9sentait $21,29 milliards de dollars en 2022, un chiffre stable par rapport \u00e0 2021.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/427956\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-25T08:29:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-25T08:36:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/manonpie630_4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"630\" \/>\n\t<meta property=\"og:image:height\" content=\"380\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"A Delapalisse, Peter Clarke\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"A Delapalisse\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/sony-augmente-sa-part-de-marche-dans-les-capteurs-dimage-cmos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/sony-augmente-sa-part-de-marche-dans-les-capteurs-dimage-cmos\/\"},\"author\":{\"name\":\"A Delapalisse\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/0aa2cfb0bd8949724a68cbac8d8321b4\"},\"headline\":\"Sony augmente sa part de march\u00e9 dans les capteurs d&rsquo;image CMOS\",\"datePublished\":\"2023-07-25T08:29:16+00:00\",\"dateModified\":\"2023-07-25T08:36:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/sony-augmente-sa-part-de-marche-dans-les-capteurs-dimage-cmos\/\"},\"wordCount\":400,\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"keywords\":[\"Capteur d'images\",\"March\u00e9\"],\"articleSection\":[\"Actualit\u00e9s \u00e9conomiques\",\"March\u00e9\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/sony-augmente-sa-part-de-marche-dans-les-capteurs-dimage-cmos\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/sony-augmente-sa-part-de-marche-dans-les-capteurs-dimage-cmos\/\",\"name\":\"Sony augmente sa part de march\u00e9 des capteurs d'image CMOS\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\"},\"datePublished\":\"2023-07-25T08:29:16+00:00\",\"dateModified\":\"2023-07-25T08:36:20+00:00\",\"description\":\"Le march\u00e9 des capteurs d'images CMOS repr\u00e9sentait $21,29 milliards de dollars en 2022, un chiffre stable par rapport \u00e0 2021.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/sony-augmente-sa-part-de-marche-dans-les-capteurs-dimage-cmos\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/sony-augmente-sa-part-de-marche-dans-les-capteurs-dimage-cmos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/sony-augmente-sa-part-de-marche-dans-les-capteurs-dimage-cmos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sony augmente sa part de march\u00e9 dans les capteurs d&rsquo;image CMOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/0aa2cfb0bd8949724a68cbac8d8321b4\",\"name\":\"A Delapalisse\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/211ac42237c2e9683c0964086c393cb4\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ad45a8c5da24bc9c7c4940dd1c48a695?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ad45a8c5da24bc9c7c4940dd1c48a695?s=96&d=mm&r=g\",\"caption\":\"A Delapalisse\"},\"sameAs\":[\"http:\/\/ECI\"]}]}<\/script>","yoast_head_json":{"title":"Sony augmente sa part de march\u00e9 des capteurs d'image CMOS ...","description":"Le march\u00e9 des capteurs d'images CMOS repr\u00e9sentait $21,29 milliards de dollars en 2022, un chiffre stable par rapport \u00e0 2021.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/427956\/","og_locale":"fr_FR","og_type":"article","og_title":"Sony augmente sa part de march\u00e9 dans les capteurs d'image CMOS","og_description":"Le march\u00e9 des capteurs d'images CMOS repr\u00e9sentait $21,29 milliards de dollars en 2022, un chiffre stable par rapport \u00e0 2021.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/427956\/","og_site_name":"EENewsEurope","article_published_time":"2023-07-25T08:29:16+00:00","article_modified_time":"2023-07-25T08:36:20+00:00","og_image":[{"width":630,"height":380,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/manonpie630_4.jpg","type":"image\/jpeg"}],"author":"A Delapalisse, Peter Clarke","twitter_card":"summary_large_image","twitter_misc":{"Written by":"A Delapalisse","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/sony-augmente-sa-part-de-marche-dans-les-capteurs-dimage-cmos\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/sony-augmente-sa-part-de-marche-dans-les-capteurs-dimage-cmos\/"},"author":{"name":"A Delapalisse","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/0aa2cfb0bd8949724a68cbac8d8321b4"},"headline":"Sony augmente sa part de march\u00e9 dans les capteurs d&rsquo;image CMOS","datePublished":"2023-07-25T08:29:16+00:00","dateModified":"2023-07-25T08:36:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/sony-augmente-sa-part-de-marche-dans-les-capteurs-dimage-cmos\/"},"wordCount":400,"publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"keywords":["Capteur d'images","March\u00e9"],"articleSection":["Actualit\u00e9s \u00e9conomiques","March\u00e9"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/sony-augmente-sa-part-de-marche-dans-les-capteurs-dimage-cmos\/","url":"https:\/\/www.ecinews.fr\/fr\/sony-augmente-sa-part-de-marche-dans-les-capteurs-dimage-cmos\/","name":"Sony augmente sa part de march\u00e9 des capteurs d'image CMOS","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/#website"},"datePublished":"2023-07-25T08:29:16+00:00","dateModified":"2023-07-25T08:36:20+00:00","description":"Le march\u00e9 des capteurs d'images CMOS repr\u00e9sentait $21,29 milliards de dollars en 2022, un chiffre stable par rapport \u00e0 2021.","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/sony-augmente-sa-part-de-marche-dans-les-capteurs-dimage-cmos\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/sony-augmente-sa-part-de-marche-dans-les-capteurs-dimage-cmos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/sony-augmente-sa-part-de-marche-dans-les-capteurs-dimage-cmos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Sony augmente sa part de march\u00e9 dans les capteurs d&rsquo;image CMOS"}]},{"@type":"WebSite","@id":"https:\/\/www.ecinews.fr\/fr\/#website","url":"https:\/\/www.ecinews.fr\/fr\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ecinews.fr\/fr\/#organization","name":"EENewsEurope","url":"https:\/\/www.ecinews.fr\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/0aa2cfb0bd8949724a68cbac8d8321b4","name":"A Delapalisse","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/211ac42237c2e9683c0964086c393cb4","url":"https:\/\/secure.gravatar.com\/avatar\/ad45a8c5da24bc9c7c4940dd1c48a695?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad45a8c5da24bc9c7c4940dd1c48a695?s=96&d=mm&r=g","caption":"A Delapalisse"},"sameAs":["http:\/\/ECI"]}]}},"authors":[{"term_id":1153,"user_id":34,"is_guest":0,"slug":"adelapalisse","display_name":"A Delapalisse","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/ad45a8c5da24bc9c7c4940dd1c48a695?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""},{"term_id":3631,"user_id":0,"is_guest":1,"slug":"peter-clarke","display_name":"Peter Clarke","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/427956"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=427956"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/427956\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/157539"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=427956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=427956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=427956"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=427956"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=427956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}