{"id":4216,"date":"2021-10-10T16:46:09","date_gmt":"2021-10-10T16:46:09","guid":{"rendered":"https:\/\/\/limep-lahc-signe-un-premier-laboratoire-commun-avec-lynred\/"},"modified":"2021-10-10T16:46:09","modified_gmt":"2021-10-10T16:46:09","slug":"limep-lahc-signe-un-premier-laboratoire-commun-avec-lynred","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/limep-lahc-signe-un-premier-laboratoire-commun-avec-lynred\/","title":{"rendered":"L\u2019IMEP-LAHC signe un premier laboratoire commun avec LYNRED"},"content":{"rendered":"<p>Pour mieux comprendre la physique des composants des capteurs infrarouges refroidis, LYNRED, acteur fran\u00e7ais de rang mondial dans ce domaine, s\u2019est rapproch\u00e9 du laboratoire IMEP-LaHC. Le rapprochement s\u2019est concr\u00e9tis\u00e9 apr\u00e8s deux ans de discussions par la cr\u00e9ation toute r\u00e9cente d\u2019un laboratoire commun entre les deux partenaires pour une dur\u00e9e de 5 ans.<\/p>\n<p>Concr\u00e8tement, le laboratoire va mettre \u00e0 profit son exp\u00e9rience en caract\u00e9risation \u00e9lectrique des composants pour mieux comprendre ce qu\u2019il s\u2019y passe au niveau physique. Pour cela, les scientifiques s\u2019appuieront sur des m\u00e9thodes de caract\u00e9risation avanc\u00e9e, sur le d\u00e9veloppement de nouvelles m\u00e9thodes de caract\u00e9risation et sur de la mod\u00e9lisation. \u00ab La caract\u00e9risation \u00e9lectrique des composants, tels que les photodiodes, va permettre de poser un diagnostic pr\u00e9cis sur leur fonctionnement et d\u2019agir en connaissance pour am\u00e9liorer leurs performances. \u00bb<\/p>\n<p>Les principaux march\u00e9s des d\u00e9tecteurs infrarouges d\u00e9velopp\u00e9s par LYNRED sont l\u2019a\u00e9rospatial, la d\u00e9fense, l\u2019industriel ainsi que le grand public. Actuellement, les capteurs infrarouges refroidis doivent \u00eatre abaiss\u00e9s en temp\u00e9rature par un cryostat \u00e9galement int\u00e9gr\u00e9 pour \u00eatre op\u00e9rationnels. \u00ab Si l\u2019on parvenait \u00e0 mieux comprendre les m\u00e9canismes en jeux dans ces composants et donc \u00e0 augmenter leur temp\u00e9rature de fonctionnement, on pourrait diminuer la taille, le poids et la consommation du syst\u00e8me entier \u00bb confie Laurent Rubaldo, Expert senior et responsable du laboratoire commun c\u00f4t\u00e9 LYNRED. En attendant d\u2019atteindre le Graal de l\u2019industrie de l\u2019infrarouge refroidi, ce laboratoire commun est une belle reconnaissance des comp\u00e9tences de l\u2019IMEP-LaHC, et une nouvelle fa\u00e7on de collaborer avec l\u2019industrie pour ce dernier.<\/p>\n<p><a href=\"http:\/\/www.grenoble-inp.fr\/\" target=\"_blank\" rel=\"noopener\">www.grenoble-inp.fr\/<\/a><\/p>\n<p><a href=\"http:\/\/www.lynred.fr\" target=\"_blank\" rel=\"noopener\">www.lynred.fr<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La cr\u00e9ation d\u2019un laboratoire commun entre le sp\u00e9cialiste fran\u00e7ais des d\u00e9tecteurs infrarouges LYNRED et l\u2019IMEP-LAHC, vient d\u2019\u00eatre sign\u00e9e pour une dur\u00e9e de cinq ans. Pour Quentin Rafhay, ma\u00eetre de conf\u00e9rences \u00e0 Grenoble INP \u2013 Phelma et chercheur \u00e0 l\u2019IMEP-LaHC, directeur de la nouvelle entit\u00e9 : \u00ab C\u2019est le premier laboratoire commun que nous signons avec un industriel au laboratoire. Par ailleurs, nous sommes le premier partenaire acad\u00e9mique avec lequel LYNRED signe un contrat de ce type. Nous les connaissions pour avoir d\u00e9j\u00e0 men\u00e9 deux th\u00e8ses en collaboration avec eux. \u00bb<\/p>\n","protected":false},"author":9,"featured_media":4217,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-4216","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","domains-electronique-eci"],"acf":[],"yoast_head":"<title>L\u2019IMEP-LAHC signe un premier laboratoire commun avec LYNRED ...<\/title>\n<meta name=\"description\" content=\"La cr\u00e9ation d\u2019un laboratoire commun entre le sp\u00e9cialiste fran\u00e7ais des d\u00e9tecteurs infrarouges LYNRED et l\u2019IMEP-LAHC, vient d\u2019\u00eatre sign\u00e9e pour une...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/4216\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019IMEP-LAHC signe un premier laboratoire commun avec LYNRED\" \/>\n<meta property=\"og:description\" content=\"La cr\u00e9ation d\u2019un laboratoire commun entre le sp\u00e9cialiste fran\u00e7ais des d\u00e9tecteurs infrarouges LYNRED et l\u2019IMEP-LAHC, vient d\u2019\u00eatre sign\u00e9e pour une dur\u00e9e de cinq ans. Pour Quentin Rafhay, ma\u00eetre de conf\u00e9rences \u00e0 Grenoble INP \u2013 Phelma et chercheur \u00e0 l\u2019IMEP-LaHC, directeur de la nouvelle entit\u00e9 : \u00ab C\u2019est le premier laboratoire commun que nous signons avec un industriel au laboratoire. Par ailleurs, nous sommes le premier partenaire acad\u00e9mique avec lequel LYNRED signe un contrat de ce type. Nous les connaissions pour avoir d\u00e9j\u00e0 men\u00e9 deux th\u00e8ses en collaboration avec eux. \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/4216\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-10T16:46:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9802_lynred_grenoble-inp_actu.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"668\" \/>\n\t<meta property=\"og:image:height\" content=\"377\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/limep-lahc-signe-un-premier-laboratoire-commun-avec-lynred\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/limep-lahc-signe-un-premier-laboratoire-commun-avec-lynred\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"L\u2019IMEP-LAHC signe un premier laboratoire commun avec LYNRED\",\"datePublished\":\"2021-10-10T16:46:09+00:00\",\"dateModified\":\"2021-10-10T16:46:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/limep-lahc-signe-un-premier-laboratoire-commun-avec-lynred\/\"},\"wordCount\":304,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/limep-lahc-signe-un-premier-laboratoire-commun-avec-lynred\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/limep-lahc-signe-un-premier-laboratoire-commun-avec-lynred\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/limep-lahc-signe-un-premier-laboratoire-commun-avec-lynred\/\",\"name\":\"L\u2019IMEP-LAHC signe un premier laboratoire commun avec LYNRED -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2021-10-10T16:46:09+00:00\",\"dateModified\":\"2021-10-10T16:46:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/limep-lahc-signe-un-premier-laboratoire-commun-avec-lynred\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/limep-lahc-signe-un-premier-laboratoire-commun-avec-lynred\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/limep-lahc-signe-un-premier-laboratoire-commun-avec-lynred\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019IMEP-LAHC signe un premier laboratoire commun avec LYNRED\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"L\u2019IMEP-LAHC signe un premier laboratoire commun avec LYNRED ...","description":"La cr\u00e9ation d\u2019un laboratoire commun entre le sp\u00e9cialiste fran\u00e7ais des d\u00e9tecteurs infrarouges LYNRED et l\u2019IMEP-LAHC, vient d\u2019\u00eatre sign\u00e9e pour une...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/4216\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019IMEP-LAHC signe un premier laboratoire commun avec LYNRED","og_description":"La cr\u00e9ation d\u2019un laboratoire commun entre le sp\u00e9cialiste fran\u00e7ais des d\u00e9tecteurs infrarouges LYNRED et l\u2019IMEP-LAHC, vient d\u2019\u00eatre sign\u00e9e pour une dur\u00e9e de cinq ans. Pour Quentin Rafhay, ma\u00eetre de conf\u00e9rences \u00e0 Grenoble INP \u2013 Phelma et chercheur \u00e0 l\u2019IMEP-LaHC, directeur de la nouvelle entit\u00e9 : \u00ab C\u2019est le premier laboratoire commun que nous signons avec un industriel au laboratoire. Par ailleurs, nous sommes le premier partenaire acad\u00e9mique avec lequel LYNRED signe un contrat de ce type. Nous les connaissions pour avoir d\u00e9j\u00e0 men\u00e9 deux th\u00e8ses en collaboration avec eux. \u00bb","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/4216\/","og_site_name":"EENewsEurope","article_published_time":"2021-10-10T16:46:09+00:00","og_image":[{"width":668,"height":377,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9802_lynred_grenoble-inp_actu.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/limep-lahc-signe-un-premier-laboratoire-commun-avec-lynred\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/limep-lahc-signe-un-premier-laboratoire-commun-avec-lynred\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"L\u2019IMEP-LAHC signe un premier laboratoire commun avec LYNRED","datePublished":"2021-10-10T16:46:09+00:00","dateModified":"2021-10-10T16:46:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/limep-lahc-signe-un-premier-laboratoire-commun-avec-lynred\/"},"wordCount":304,"commentCount":0,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ecinews.fr\/fr\/limep-lahc-signe-un-premier-laboratoire-commun-avec-lynred\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/limep-lahc-signe-un-premier-laboratoire-commun-avec-lynred\/","url":"https:\/\/www.ecinews.fr\/fr\/limep-lahc-signe-un-premier-laboratoire-commun-avec-lynred\/","name":"L\u2019IMEP-LAHC signe un premier laboratoire commun avec LYNRED -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2021-10-10T16:46:09+00:00","dateModified":"2021-10-10T16:46:09+00:00","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/limep-lahc-signe-un-premier-laboratoire-commun-avec-lynred\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/limep-lahc-signe-un-premier-laboratoire-commun-avec-lynred\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/limep-lahc-signe-un-premier-laboratoire-commun-avec-lynred\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"L\u2019IMEP-LAHC signe un premier laboratoire commun avec LYNRED"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/4216"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=4216"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/4216\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/4217"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=4216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=4216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=4216"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=4216"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=4216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}